{"id":68783,"date":"2022-05-05T01:21:00","date_gmt":"2022-05-05T05:21:00","guid":{"rendered":"https:\/\/www.jdx.info\/lutte\/?p=68783"},"modified":"2022-05-05T22:24:32","modified_gmt":"2022-05-06T02:24:32","slug":"chris-jericho-a-depasse-shawn-micheals-randy-orton-parle-de-sa-relation-avec-vince-mcmahon","status":"publish","type":"post","link":"https:\/\/www.jdx.info\/lutte\/2022\/05\/05\/chris-jericho-a-depasse-shawn-micheals-randy-orton-parle-de-sa-relation-avec-vince-mcmahon\/","title":{"rendered":"Chris Jericho a d\u00e9pass\u00e9 Shawn Micheals! \/ Randy Orton parle de sa relation avec Vince McMahon!"},"content":{"rendered":"\n<p>En 20 ans de carri\u00e8re, Randy Orton a eu le temps d&rsquo;apprendre \u00e0 connaitre Vince McMahon.<\/p>\n\n\n\n<p>Lors d&rsquo;une r\u00e9cente interview accord\u00e9e \u00e0&nbsp;Metro.co, le 14 fois champion du Monde est revenu sur la relation qu&rsquo;il entretient avec le patron de la WWE. Il en a profit\u00e9 pour raconter une anecdote lorsqu&rsquo;il d\u00e9butait alors tout juste, des p\u00e9riodes \u00ab\u00a0sombres\u00a0\u00bb d&rsquo;apr\u00e8s le catcheur :<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>&lt;&lt; Maintenant que 20 ans se sont \u00e9coul\u00e9s et que j&rsquo;ai lentement appris \u00e0 le connaitre, je pense qu&rsquo;il y a plus de respect dans notre relation d&rsquo;homme \u00e0 homme que dans celle d&rsquo;un mari et un p\u00e8re, puis il a vu que j&rsquo;avais m\u00fbri.<\/p><p>Il m&rsquo;a vu dans des p\u00e9riodes sombres, j&rsquo;ai eu des craquages et des crises devant lui. Je me cognais la t\u00eate contre le mur devant lui, j&rsquo;avais 25 ans, je ne savais pas m&rsquo;exprimer. >><\/p><\/blockquote>\n\n\n\n<p>Un respect qui s&rsquo;est install\u00e9 entre les deux hommes au fil du temps. Randy Orton et Vince McMahon se connaissent aujourd&rsquo;hui tr\u00e8s bien&#8230; que ce soit dans les coulisses ou \u00e0 la t\u00e9l\u00e9vision. Souvenir de 2009 :<\/p>\n\n\n\n<center><p><script async=\"\" src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script>\n<ins class=\"adsbygoogle\" style=\"display:block; text-align:center;\" data-ad-layout=\"in-article\" data-ad-format=\"fluid\" data-ad-client=\"ca-pub-1986975368136072\" data-ad-slot=\"7818521013\"><\/ins>\n<script>\n     (adsbygoogle = window.adsbygoogle || []).push({});\n<\/script><\/p><\/center>\n\n\n\n\n<p>En interview pour Lucha Libre Online, Kurt Angle nous a parl\u00e9 de Chris Jericho et il estime qu\u2019il a d\u00e9pass\u00e9 Shawn Michaels dans la hi\u00e9rarchie des meilleurs de l\u2019histoire.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>\u00ab\u00a0Il est parvenu \u00e0 changer, innover avec ses personnages, et \u00e0 \u00eatre aussi efficace qu&rsquo;il l&rsquo;est dans le m\u00e9tier aussi tard dans sa carri\u00e8re, \u00e0 51 ou 52 ans, alors qu&rsquo;il est dans le m\u00e9tier depuis plus de 30 ans. Il a consacr\u00e9 beaucoup de temps et d&rsquo;efforts, et il est tr\u00e8s talentueux. Donc, je le mets l\u00e0 avec Michaels, mais maintenant, apr\u00e8s avoir \u00e9t\u00e9 \u00e0 l&rsquo;AEW et avoir fait les choses qu&rsquo;il fait maintenant, il doit \u00eatre le plus grand de tous les temps, surtout avec le nombre important d&rsquo;ann\u00e9es \u00e0 un si haut niveau.\u00a0\u00bb<\/p><\/blockquote>\n\n\n\n<p>Chris Jericho n\u2019a eu de cesse de se r\u00e9inventer d\u2019ann\u00e9e en ann\u00e9e et \u00e0 chaque fois que beaucoup pensaient qu\u2019il \u00e9tait termin\u00e9, il nous revient avec une id\u00e9e g\u00e9niale. \u00c0 l\u2019AEW, il refait ce qu\u2019il a produit \u00e0 la WWE en remodelant compl\u00e8tement son personnage en le mettant \u00e0 l\u2019ordre du jour pour qu\u2019il n&rsquo;y ait aucune lassitude des fans. Ce qui est s\u00fbr, c\u2019est que Chris Jericho, Shawn Michaels et Kurt Angle font partie des meilleurs catcheurs de l\u2019histoire du catch en g\u00e9n\u00e9ral.<\/p>\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>En 20 ans de carri\u00e8re, Randy Orton a eu le temps d&rsquo;apprendre \u00e0 connaitre Vince McMahon. Lors d&rsquo;une r\u00e9cente interview accord\u00e9e \u00e0&nbsp;Metro.co, le 14 fois champion du Monde est revenu sur la relation qu&rsquo;il entretient avec le patron de la WWE. Il en a profit\u00e9 pour raconter une anecdote lorsqu&rsquo;il d\u00e9butait alors tout juste, des&#8230;<\/p>\n","protected":false},"author":609,"featured_media":68785,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[30,77,4,23],"tags":[],"ppma_author":[295],"class_list":["post-68783","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ex-wwe","category-hall-of-fame","category-news","category-wwe"],"authors":[{"term_id":295,"user_id":609,"is_guest":0,"slug":"rodrigo","display_name":"Rodrigue Tousignant","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/51fe284bb6dbe8a6b4c2bf998ad658f4a9cd24b7e58f15ec85888070c7340ce6?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/68783","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/users\/609"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/comments?post=68783"}],"version-history":[{"count":1,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/68783\/revisions"}],"predecessor-version":[{"id":68786,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/68783\/revisions\/68786"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media\/68785"}],"wp:attachment":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media?parent=68783"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/categories?post=68783"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/tags?post=68783"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/ppma_author?post=68783"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}