{"id":68652,"date":"2022-05-02T00:58:00","date_gmt":"2022-05-02T04:58:00","guid":{"rendered":"https:\/\/www.jdx.info\/lutte\/?p=68652"},"modified":"2022-05-02T13:06:19","modified_gmt":"2022-05-02T17:06:19","slug":"des-nouvelle-du-prochain-draft-de-la-wwe-smackdown-de-retour-a-montreal-pour-un-taping-tele","status":"publish","type":"post","link":"https:\/\/www.jdx.info\/lutte\/2022\/05\/02\/des-nouvelle-du-prochain-draft-de-la-wwe-smackdown-de-retour-a-montreal-pour-un-taping-tele\/","title":{"rendered":"Des nouvelle du prochain Draft de la WWE! \/ Smackdown de retour \u00e0 Montr\u00e9al pour un taping t\u00e9l\u00e9!"},"content":{"rendered":"\n<p>Il est maintenant officiel que la WWE s&rsquo;arr\u00eatera le vendredi 19 ao\u00fbt 2022 au Centre Bell de Montr\u00e9al pour une \u00e9dition live du WWE Friday Night SmackDown.<\/p>\n\n\n\n<p>C&rsquo;est Evenko qui  a confirm\u00e9 la nouvelle ce matin et les billets seront disponibles \u00e0 partir du 13 mai 2022 \u00e0 10h. Il s&rsquo;agira de la premi\u00e8re \u00e9dition de SmackDown \u00e0 Montr\u00e9al depuis que le show est pass\u00e9 les vendredis soir et du premier show t\u00e9l\u00e9 \u00e0 Montr\u00e9al depuis le d\u00e9but de la pand\u00e9mie.<\/p>\n\n\n\n<p>Nous aurons plus de d\u00e9tails bient\u00f4t au sujet de la vente et de la pr\u00e9vente. Il faudra aussi attendre afin de voir si la WWE va s&rsquo;arr\u00eater dans la ville de Qu\u00e9bec le 21 ao\u00fbt pour un Live Event, comme il \u00e9tait pr\u00e9vu\u00a0sur le calendrier interne. Pour l&rsquo;instant, il n&rsquo;y a eu aucune confirmation \u00e0 ce sujet mais nous suivons le dossier avec un grand int\u00e9r\u00eat! <\/p>\n\n\n\n<center><p><script async=\"\" src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script>\n<ins class=\"adsbygoogle\" style=\"display:block; text-align:center;\" data-ad-layout=\"in-article\" data-ad-format=\"fluid\" data-ad-client=\"ca-pub-1986975368136072\" data-ad-slot=\"7818521013\"><\/ins>\n<script>\n     (adsbygoogle = window.adsbygoogle || []).push({});\n<\/script><\/p><\/center>\n\n\n\n\n<p>Vous le savez, chaque ann\u00e9e, la WWE organisera un Draft en 2022 afin de rebrasser les rosters et proposer de nouveaux matchs ainsi que de nouvelles histoires aux fans.<\/p>\n\n\n\n<p>D&rsquo;apr\u00e8s les informations de nos sources, la WWE pr\u00e9voit bel et bien une autre \u00e9dition de la Draft cette ann\u00e9e. Pour le moment,\u00a0on dit que ce serait pr\u00e9vue pour septembre 2022, soit apr\u00e8s l&rsquo;\u00e9v\u00e8nement de la WWE au Royaume-Uni qui se tiendra le samedi 3 septembre. <\/p>\n\n\n\n<p>Par contre on se souviendra que le brassage des alignements de RAW et Smackdown se fait g\u00e9n\u00e9ralement en octobre lors du d\u00e9but de saison officiel. Nous vous tiendrons au courant d&rsquo;ici l\u00e0!<\/p>\n\n\n\n<p><\/p>\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>Il est maintenant officiel que la WWE s&rsquo;arr\u00eatera le vendredi 19 ao\u00fbt 2022 au Centre Bell de Montr\u00e9al pour une \u00e9dition live du WWE Friday Night SmackDown. C&rsquo;est Evenko qui a confirm\u00e9 la nouvelle ce matin et les billets seront disponibles \u00e0 partir du 13 mai 2022 \u00e0 10h. Il s&rsquo;agira de la premi\u00e8re \u00e9dition&#8230;<\/p>\n","protected":false},"author":609,"featured_media":68657,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4,43,36,23],"tags":[],"ppma_author":[295],"class_list":["post-68652","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news","category-raw-wwe","category-smackdown","category-wwe"],"authors":[{"term_id":295,"user_id":609,"is_guest":0,"slug":"rodrigo","display_name":"Rodrigue Tousignant","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/51fe284bb6dbe8a6b4c2bf998ad658f4a9cd24b7e58f15ec85888070c7340ce6?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/68652","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/users\/609"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/comments?post=68652"}],"version-history":[{"count":1,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/68652\/revisions"}],"predecessor-version":[{"id":68658,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/68652\/revisions\/68658"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media\/68657"}],"wp:attachment":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media?parent=68652"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/categories?post=68652"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/tags?post=68652"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/ppma_author?post=68652"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}