{"id":68608,"date":"2022-04-30T13:08:00","date_gmt":"2022-04-30T17:08:00","guid":{"rendered":"https:\/\/www.jdx.info\/lutte\/?p=68608"},"modified":"2022-05-01T01:12:34","modified_gmt":"2022-05-01T05:12:34","slug":"mise-a-jour-sur-le-depart-des-iiconics-du-monde-du-catch-un-match-de-championnat-aura-lieu-a-smackdown-et-non-a-backlash","status":"publish","type":"post","link":"https:\/\/www.jdx.info\/lutte\/2022\/04\/30\/mise-a-jour-sur-le-depart-des-iiconics-du-monde-du-catch-un-match-de-championnat-aura-lieu-a-smackdown-et-non-a-backlash\/","title":{"rendered":"Mise \u00e0 jour sur le d\u00e9part des Iiconics du monde du catch! \/ Un match de championnat aura lieu \u00e0 SmackDown et non \u00e0 Backlash!"},"content":{"rendered":"\n<p><\/p>\n\n\n\n<p>On est \u00e0 une semaine de WrestleMania Backlash et toujours un seul match de championnat figure sur\u00a0la carte du show. Il s&rsquo;agit de Charlotte Flair contre Ronda Rousey puisque le match pour les titres par \u00e9quipe masculins a \u00e9t\u00e9 annul\u00e9.<\/p>\n\n\n\n<p>Suite au SmackDown du 29 avril, il a \u00e9t\u00e9 confirm\u00e9 que les titres par \u00e9quipe f\u00e9minins vont aussi faire l&rsquo;impasse sur WrestleMania Backlash. En effet, il a \u00e9t\u00e9 confirm\u00e9 que Sasha Banks et Naomi vont d\u00e9fendre les WWE Women&rsquo;s Tag Team Championship contre Natalya et Sasha Banks pour l&rsquo;\u00e9pisode de SmackDown du 13 mai, ce qui sera l&rsquo;\u00e9dition su show bleu post Backlash.<\/p>\n\n\n\n<p>Un match en construction depuis d\u00e9j\u00e0 plusieurs semaines et justement, Sasha Banks va affronter Baszler dans un match simple la semaine prochaine \u00e0 SmackDown.<\/p>\n\n\n\n<center><p><script async=\"\" src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script>\n<ins class=\"adsbygoogle\" style=\"display:block; text-align:center;\" data-ad-layout=\"in-article\" data-ad-format=\"fluid\" data-ad-client=\"ca-pub-1986975368136072\" data-ad-slot=\"7818521013\"><\/ins>\n<script>\n     (adsbygoogle = window.adsbygoogle || []).push({});\n<\/script><\/p><\/center>\n\n\n\n\n<p>Cette semaine on apprenait que Cassie Lee (Peyton Royce) et Jessie McKay (Billie Kay) quittaient Impact Wrestling et le monde du catch pour une p\u00e9riode ind\u00e9termin\u00e9e.<\/p>\n\n\n\n<p>Les deux catcheuses expliquaient vouloir explorer de nouvelles opportunit\u00e9s. Aujourd&rsquo;hui nous avons la confirmation que ces nouvelles opportunit\u00e9s pointent vers le domaine de l&rsquo;acting.<\/p>\n\n\n\n<p>Il semblerait que les deux anciennes Superstars ont expliqu\u00e9 \u00e0 leurs coll\u00e8gues lors des derniers enregistrements d&rsquo;Impact qu&rsquo;elles allaient quitter pour d\u00e9buter cette nouvelle carri\u00e8re selon le Wrestling Observer. En plus, le directeur Michael Matteo Rossi a annonc\u00e9 sur Twitter que Jessie McKay venait d&rsquo;\u00eatre s\u00e9lectionn\u00e9e pour un r\u00f4le pour son prochain film de \u00a0\u00bbCharisma Killers\u00a0\u00bb.<\/p>\n\n\n\n<p>McKay va aussi participer aux films \u00a0\u00bbMaverick\u00a0\u00bb et \u00a0\u00bbProm Night\u00a0\u00bb, des projets dont les tournages devraient d\u00e9buter plus tard dans l&rsquo;ann\u00e9e si tout se d\u00e9roule comme pr\u00e9vu. Du c\u00f4t\u00e9 de Cassie Lee, elle n&rsquo;a pr\u00e9sentement aucun projet mais elle cherche activement.<\/p>\n\n\n\n<p>Une nouvelle carri\u00e8re dans le cin\u00e9ma qui sera \u00e0 surveiller pour les deux femmes.<\/p>\n\n\n\n<center><blockquote class=\"twitter-tweet\"><p lang=\"en\" dir=\"ltr\">Great end to the week as <a href=\"https:\/\/twitter.com\/JessicaMcKay?ref_src=twsrc%5Etfw\">@JessicaMcKay<\/a> has been cast in my feature film The Charisma Killers in the fall, woo! &#x1f3a5;&#x1f973; <a href=\"https:\/\/t.co\/ntnIyNpN3f\">pic.twitter.com\/ntnIyNpN3f<\/a><\/p>&mdash; Michael Matteo Rossi (@MichaelMatteoRo) <a href=\"https:\/\/twitter.com\/MichaelMatteoRo\/status\/1520115729206374400?ref_src=twsrc%5Etfw\">April 29, 2022<\/a><\/blockquote> <script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/center>\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>On est \u00e0 une semaine de WrestleMania Backlash et toujours un seul match de championnat figure sur\u00a0la carte du show. Il s&rsquo;agit de Charlotte Flair contre Ronda Rousey puisque le match pour les titres par \u00e9quipe masculins a \u00e9t\u00e9 annul\u00e9. Suite au SmackDown du 29 avril, il a \u00e9t\u00e9 confirm\u00e9 que les titres par \u00e9quipe&#8230;<\/p>\n","protected":false},"author":609,"featured_media":68609,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[24,52,22,4,41,23],"tags":[],"ppma_author":[295],"class_list":["post-68608","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-aew-impact-njpw-roh","category-backlash","category-indy","category-news","category-tna-impact","category-wwe"],"authors":[{"term_id":295,"user_id":609,"is_guest":0,"slug":"rodrigo","display_name":"Rodrigue Tousignant","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/51fe284bb6dbe8a6b4c2bf998ad658f4a9cd24b7e58f15ec85888070c7340ce6?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/68608","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/users\/609"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/comments?post=68608"}],"version-history":[{"count":1,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/68608\/revisions"}],"predecessor-version":[{"id":68610,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/68608\/revisions\/68610"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media\/68609"}],"wp:attachment":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media?parent=68608"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/categories?post=68608"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/tags?post=68608"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/ppma_author?post=68608"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}