{"id":68375,"date":"2022-04-25T01:13:00","date_gmt":"2022-04-25T05:13:00","guid":{"rendered":"https:\/\/www.jdx.info\/lutte\/?p=68375"},"modified":"2022-04-25T12:19:02","modified_gmt":"2022-04-25T16:19:02","slug":"la-wwe-pourrait-ramener-son-systeme-de-classement","status":"publish","type":"post","link":"https:\/\/www.jdx.info\/lutte\/2022\/04\/25\/la-wwe-pourrait-ramener-son-systeme-de-classement\/","title":{"rendered":"La WWE pourrait ramener son syst\u00e8me de classement!"},"content":{"rendered":"\n<p><\/p>\n\n\n\n<p>Il semble bien que la WWE pourrait r\u00e9-introduire un syst\u00e8me de classement lors des prochains mois.\u00a0L&rsquo;arriv\u00e9 de Cody Rhodes ne doit pas y \u00eatre \u00e9trang\u00e9 car c&rsquo;est ce m\u00eame syst\u00e8me que la AEW utilise de son c\u00f4t\u00e9 depuis son lancement en 2019. Il permet de donner des matchs importants aux stars qui remportent le plus leurs matchs et donc \u00e0 celles qui le m\u00e9ritent bien que le tout demeure que se sont les dirigeants qui en d\u00e9cide quand m\u00eame sur la planche \u00e0 dessins, ce qui donne tout de m\u00eame l&rsquo;impression que c&rsquo;est m\u00e9rit\u00e9 au lieu de toujours sortir demander le match et l&rsquo;avoir comme \u00e7a.<\/p>\n\n\n\n<p>La compagnie des McMahon semble \u00eatre int\u00e9ress\u00e9e par ce syst\u00e8me qui pourrait bient\u00f4t voir le jour. La WWE a m\u00eame envoy\u00e9 un formulaire \u00e0 plusieurs fans afin de leur poser diff\u00e9rentes questions. Parmi elles,\u00a0il est demand\u00e9 aux fans s&rsquo;ils sont int\u00e9ress\u00e9s par un syst\u00e8me de ranking.\u00a0Si la r\u00e9ponse des fans est favorable, peut-\u00eatre que la WWE se penchera ensuite sur la question.<\/p>\n\n\n\n<center><p><script async=\"\" src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script>\n<ins class=\"adsbygoogle\" style=\"display:block; text-align:center;\" data-ad-layout=\"in-article\" data-ad-format=\"fluid\" data-ad-client=\"ca-pub-1986975368136072\" data-ad-slot=\"7818521013\"><\/ins>\n<script>\n     (adsbygoogle = window.adsbygoogle || []).push({});\n<\/script><\/p><\/center>\n\n\n\n\n<p>La derni\u00e8re fois que la WWE a eu son propre syst\u00e8me de ranking, c&rsquo;\u00e9tait les Power Rankings qui se sont finis en 2018. Mais cette version \u00e9tait diff\u00e9rente de celle de la AEW car les victoires ou d\u00e9faites n&rsquo;\u00e9taient pas comptabilis\u00e9es. Le classement \u00e9tait surtout bas\u00e9 sur les Superstars ayant fait le plus gros impact \u00e0 la t\u00e9l\u00e9vision que ce soit donc sur le ring ou en promo.<\/p>\n\n\n\n<p>Dans ce m\u00eame formulaire, la WWE a \u00e9galement pos\u00e9 d&rsquo;autres questions, comme le nombre de fois que le fan regarde un programme de la WWE dans le mois, sa r\u00e9gularit\u00e9 \u00e0 assister \u00e0 un show, ou alors s&rsquo;il est int\u00e9ress\u00e9 par la NFT ou \u00e0 voir ce qu&rsquo;il se passe derri\u00e8re la sc\u00e8ne.<\/p>\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>Il semble bien que la WWE pourrait r\u00e9-introduire un syst\u00e8me de classement lors des prochains mois.\u00a0L&rsquo;arriv\u00e9 de Cody Rhodes ne doit pas y \u00eatre \u00e9trang\u00e9 car c&rsquo;est ce m\u00eame syst\u00e8me que la AEW utilise de son c\u00f4t\u00e9 depuis son lancement en 2019. Il permet de donner des matchs importants aux stars qui remportent le plus&#8230;<\/p>\n","protected":false},"author":4,"featured_media":68376,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4,45,43,36,23],"tags":[],"ppma_author":[292],"class_list":["post-68375","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news","category-ppv-wwe","category-raw-wwe","category-smackdown","category-wwe"],"authors":[{"term_id":292,"user_id":4,"is_guest":0,"slug":"jean","display_name":"Jean Vinnier","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/33aba0263fd870a0b487e0e079ff407e10e3997c9d2987cbcc0db0db2c5c75a9?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/68375","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/comments?post=68375"}],"version-history":[{"count":1,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/68375\/revisions"}],"predecessor-version":[{"id":68377,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/68375\/revisions\/68377"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media\/68376"}],"wp:attachment":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media?parent=68375"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/categories?post=68375"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/tags?post=68375"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/ppma_author?post=68375"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}