{"id":67946,"date":"2022-04-13T23:26:00","date_gmt":"2022-04-14T03:26:00","guid":{"rendered":"https:\/\/www.jdx.info\/lutte\/?p=67946"},"modified":"2022-04-16T00:22:11","modified_gmt":"2022-04-16T04:22:11","slug":"resultats-et-video-du-aew-dynamite-du-13-avril-2022","status":"publish","type":"post","link":"https:\/\/www.jdx.info\/lutte\/2022\/04\/13\/resultats-et-video-du-aew-dynamite-du-13-avril-2022\/","title":{"rendered":"R\u00e9sultats et Vid\u00e9o du AEW Dynamite du 13 Avril 2022!"},"content":{"rendered":"\n<ul class=\"wp-block-list\"><li><strong><a href=\"https:\/\/www.jdx.info\/lutte\/2022\/04\/13\/avant-gout-du-aew-dynamite-du-13-avril-2022\/\" target=\"_blank\" rel=\"noreferrer noopener\">Pour voir ce show, cliquez ici.<\/a><\/strong><\/li><\/ul>\n\n\n\n<p class=\"has-medium-font-size\"><strong>AEW Dynamite Nouvelle-Orl\u00e9ans, Louisiane, 13 avril 2022<\/strong><\/p>\n\n\n\n<p>Les commentateurs sont Jim Ross, Tony Schiavone et Excalibur.<\/p>\n\n\n\n<p>&#8211; Le AEW Dynamite d\u00e9marre avec les commentateurs qui nous souhaitent la bienvenue et CM Punk arrive sur le ring.<\/p>\n\n\n\n<p><strong>CM Punk vs Penta Oscuro<\/strong><\/p>\n\n\n\n<p>En fin de match, Penta bloque un coup de genou et le prend pour son Pile Driver, mais Punk le repousse. Penta enchaine avec un Round Kick et lui applique son Arm Bar, mais Punk le renverse en compte rapide et Penta r\u00e9siste. Penta enchaine avec un Superkick et se lance en Springboard, mais Punk l&rsquo;attrape et lui fait un GTS pour le compte de trois.<\/p>\n\n\n\n<p><em>Gagnant : CM Punk<\/em><\/p>\n\n\n\n<p>&#8211; Dans une vid\u00e9o plus t\u00f4t aujourd&rsquo;hui, le clan de Chris Jericho arrive en jet priv\u00e9 \u00e0 l&rsquo;a\u00e9roport. Jericho dit que les divertisseurs sportif voyagent ainsi. Le clan d&rsquo;Eddie Kingston arrive en voiture sur la piste et dit qu&rsquo;ils vont se vor ce soir. Kingston attaque 2point0 au passage.<\/p>\n\n\n\n<p class=\"has-medium-font-size\"><strong>Championnat Mondial par \u00c9quipe AEW<\/strong><\/p>\n\n\n\n<p><strong>ReDRagon (Bobby Fish et Kyle O&rsquo;Reilly) vs Jurassic Express (Luchasaurus et Jungle Boy)<\/strong><\/p>\n\n\n\n<p>En fin de match, Luchasaurus fait son Round Kick \u00e0 Fish. Jurassic Express enchaine avec leur Powerbomb \u00e0 deux pour le compte de trois.<\/p>\n\n\n\n<p><em>Gagnants : Jurassic Express<\/em><\/p>\n\n\n\n<p>Apr\u00e8s le combat, O&rsquo;Reilly revient sur le ring et frappe Jurassic Express dans le dos avec une chaise pendant leur c\u00e9l\u00e9bration. O&rsquo;Reilly est furieux et hurle que c&rsquo;\u00e9tait un coup de chance. La musique de FTR commence et le duo arrive sur la sc\u00e8ne. FTR fait un face \u00e0 face avec ReDRagon.<\/p>\n\n\n\n<center><p><script async=\"\" src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script>\n<ins class=\"adsbygoogle\" style=\"display:block; text-align:center;\" data-ad-layout=\"in-article\" data-ad-format=\"fluid\" data-ad-client=\"ca-pub-1986975368136072\" data-ad-slot=\"7818521013\"><\/ins>\n<script>\n     (adsbygoogle = window.adsbygoogle || []).push({});\n<\/script><\/p><\/center>\n\n\n\n<p>&#8211; On pr\u00e9sente une vid\u00e9o de Wheeler Yuta qui a \u00e9t\u00e9 recrut\u00e9 par le clan de William Regal \u00e0&nbsp;Rampage vendredi dernier. En coulisse, on retrouve le clan pour avoir leur commentaire. William Regal dit que le Blackpool Combat Club est plein de talents. Bryan Danielson dit qu&rsquo;ils sont en feu car pour la premi\u00e8re fois Yuta va se battre avec eux. Ils vont affronter le Gunn Club qui est 24-0. Jon Moxley dit que le Gunn Club est un groupe d&rsquo;idiots, ils vont briser leur visage. Yuta dit que le vrai boulot commence vendredi.<\/p>\n\n\n\n<p>&#8211; De retour suite \u00e0 la pause, en coulisse, Tony Schiavone est avec Toni Storm et Jamie Hayter pour avoir leur commentaire sur le fait qu&rsquo;elles vont s&rsquo;affronter au premier round du tournoi Owen Hart. Hayter dit qu&rsquo;elle veut le match plus que les fans le veulent. Il y a beaucoup de similirat\u00e9s entre les deux, au Japon et au UK. Mais c&rsquo;est son moment d&rsquo;\u00eatre couronn\u00e9 \u00e0 l&rsquo;AEW et Storm ne pourra pas l&rsquo;arr\u00eater, elle va gagner et lui briser le visage. Storm quitte sans rien dire.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><strong>Shawn Dean vs MJF accompagn\u00e9 de Shawn Spears<\/strong><\/p>\n\n\n\n<p>Le match se lance et MJF s&rsquo;amuse \u00e0 battre Dean. La cam\u00e9ra se d\u00e9place en coulisse et on voit des agents de s\u00e9curit\u00e9 k.o. au sol. Une minute plus tard, Wardlow arrive en ringside v\u00eatu en agent de s\u00e9curit\u00e9. Wardlow pourchasse MJF et il prend la fuite sur la sc\u00e8ne, Spears en profite pour frapper Wardlow avec sa chaise. Wardlow ne tombe pas, des agents de s\u00e9curit\u00e9 arrivent, mais Wardlow les frappe tous un apr\u00e8s l&rsquo;autre. Une dizaine d&rsquo;agents suppl\u00e9mentaire arrivent pour retenir Wardlow. MJF veut remonter sur le ring, mais il est bloqu\u00e9 par la tonne d&rsquo;agents de s\u00e9curit\u00e9 en ringside. MJF prend le micro et dit qu&rsquo;il va tripler le salaire de l&rsquo;arbitre s&rsquo;il arr\u00eate le d\u00e9compte de dix. L&rsquo;arbitre compte jusqu&rsquo;\u00e0 dix !<\/p>\n\n\n\n<p><em>Gagnant : Shawn Dean via count out<\/em><\/p>\n\n\n\n<p>&#8211; Apr\u00e8s le combat, Wardlow se fait sortir. MJF est furieux et pousse l&rsquo;arbitre, mais l&rsquo;arbitre le repousse ! Spears calme MJF.<\/p>\n\n\n\n<p>&#8211; En coulisse, Wardlow poursuit de cogner des agents de s\u00e9curit\u00e9. Wardlow dit qu&rsquo;il ne va pas arr\u00eater tant que MJF ne le lib\u00e8re pas de son contrat !<\/p>\n\n\n\n<p>&#8211; On pr\u00e9sente une vid\u00e9o sur Darby Allin qui fait du skateboard. Allin propose le Coffin Match pour Andrade El Idolo.<\/p>\n\n\n\n<center><p><script async=\"\" src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script>\n<ins class=\"adsbygoogle\" style=\"display:block; text-align:center;\" data-ad-layout=\"in-article\" data-ad-format=\"fluid\" data-ad-client=\"ca-pub-1986975368136072\" data-ad-slot=\"7818521013\"><\/ins>\n<script>\n     (adsbygoogle = window.adsbygoogle || []).push({});\n<\/script><\/p><\/center>\n\n\n\n<p>&#8211; De retour, on pr\u00e9sente une vid\u00e9o sur Aleister Black. Black demande si les r\u00eaves de Fuego Del Sol sont toujours les m\u00eames. Black dit que si on ouvre son cou on retrouverait la grande noirceur. Il esp\u00e8re que Fuego puisse se trouver un appuie. Black dit qu&rsquo;ils vont prendre la lumi\u00e8re la plus brillante pour prendre son \u00e2me et la tuer. Ce soir il est seul, mais il ferait mieux d&rsquo;avoir peur des ombres.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><strong>Jericho Appreciation Society (Chris Jericho, Jake Hager et Daniel Garcia) vs Eddie Kingston, Santana et Ortiz<\/strong><\/p>\n\n\n\n<p>En fin de rencontre, Kingston prend la tag pour aller rouer de coups Garcia. Kingston lui fait un Exploder et se lance pour son finisher, mais Jericho le frappe avec son b\u00e2ton de baseball dans le dos alors que l&rsquo;arbitre est retourn\u00e9. Garcia le couvre pour la victoire.<\/p>\n\n\n\n<p><em>Gagnants : Jericho Appreciatio Society<\/em><\/p>\n\n\n\n<p> Apr\u00e8s le combat, le JAS s&rsquo;amuse \u00e0 attaquer Kingston sur le ring 5 contre 1. Jericho va chercher Ortiz pour lui faire un Judas Effect.<\/p>\n\n\n\n<p>&#8211; De retour, en coulisse, Alex Marvez est avec MJF, Spears et Mark Sterling. MJF demande si on trouve \u00e7a dr\u00f4le. On semble oublier il est qui. Il est l&rsquo;apog\u00e9e du catch professionnel, mais c&rsquo;est dr\u00f4le ce qui arrive. Il n&rsquo;a pas besoin de notre sympathie puisqu&rsquo;il a de l&rsquo;argent. Sterling dit que MJF a le droit de faire le booking de Wardlow contre n&rsquo;importe qui. MJF dit que c&rsquo;est termin\u00e9 pour Wardlow de se pr\u00e9senter et avoir du plaisir, il va faire travailler le gros porc. Le Butcher pourra le trancher.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><strong>Marina Shafir vs Skye Blue<\/strong><\/p>\n\n\n\n<p>En fin de match, Shafir frappe Blue et lui applique un Triangle pour la faire taper en moins de deux minutes.<\/p>\n\n\n\n<p><em>Gagnante : Marina Shafir <\/em><\/p>\n\n\n\n<p>&#8211; On pr\u00e9sente une vid\u00e9o de plus t\u00f4t avec HOOK pour une interview. On lui demande ses commentaires pour son premier match \u00e0 Dynamite, mais Mark Sterling et Tony Nese arrivent. Sterling demande pourquoi ils ne font pas une interview avec le plus grand agent libre. Nese dit qu&rsquo;ils donnent de la place \u00e0 quelqu&rsquo;un qu&rsquo;on lui a donn\u00e9 le succ\u00e8s. Nese et Sterling quittent, on voit que Danhausen regardait de loin.<\/p>\n\n\n\n<p>&#8211; De retour, en coulisse, on retrouve Dan Lambert, Scorpio Sky et Ethan Page. Page dit que Sammy Guevara a suppli\u00e9 les directeurs pour avoir un match de titre TNT. Ils vont se retrouver huer devant les fans. Lambert dit que nous aurons un autre samedi soir o\u00f9 Tay Conti ne sera pas satisfaite par son homme. Sky dit qu&rsquo;\u00e0 Battle of the Belts sa s\u00e9rie de victoires va continuer.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><strong>Ricky Starks et Powerhouse Hobbs vs Keith Lee et Swerve Strickland<\/strong><\/p>\n\n\n\n<p>En fin de match Lee soul\u00e8ve Starks pour uen prise \u00e0 deux, mais Hobbs pousse Strickland en bas du ring. Strickland repousse Hobbs sur le poteau. Starks arrive \u00e0 faire un Spear sur Lee du coin, mais Strickland se lance en 450 Splash pour bloquer le compte. Hobbs charge Strickland contre le coin. Lee se lance dans les c\u00e2bles, mais Taz lui attrape le pied, Hobbs fait un Spinebuster \u00e0 Lee pour le compte de trois !<\/p>\n\n\n\n<p><em>Gagnants : Ricky Starks et Powerhouse Hobbs<\/em><\/p>\n\n\n\n<p>&#8211; On annonce pour Rampage qui va d\u00e9buter sp\u00e9cialement \u00e0 1H Paris ou 19H Montr\u00e9al cette semaine : Texas Death Match pour le titre AEW contre Adam Page et Adam Cole, Blackpool Combat Club vs Gunn Club, et Robyn Renegade vs Ruby Soho pour le tournoi Owen Hart. Pour Battle of the Belts samedi : Guevara vs Sky pour le titre TNT, Jonathan Gresham vs Dalton Castle pour le titre ROH, et Thunder Rosa vs Nyla Rose pour le titre f\u00e9minin AEW. Pour mercredi prochain \u00e0 Dynamite : Wardlow vs Butcher, d\u00e9but de HOOK \u00e0 Dynamite, Britt Baker vs Danille Kamela en tournoi Owen Hart, Jungle Boy vs Kyle O&rsquo;Reilly en tournoi Owen Hart, un Coffin Match entre Andrade et Darby Allin, et Tony Khan aura une grande annonce.<\/p>\n\n\n\n<center><p><script async=\"\" src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script>\n<ins class=\"adsbygoogle\" style=\"display:block; text-align:center;\" data-ad-layout=\"in-article\" data-ad-format=\"fluid\" data-ad-client=\"ca-pub-1986975368136072\" data-ad-slot=\"7818521013\"><\/ins>\n<script>\n     (adsbygoogle = window.adsbygoogle || []).push({});\n<\/script><\/p><\/center>\n\n\n\n<p>&#8211; En coulisse, Tony Schiavone est avec Thunder Rosa pour ses commentaires sur Battle of the Belts, mais Vickie Guerrero et Nyla Rose arrivent. Rose dit qu&rsquo;elles ont un g\u00e2teau pour elle pour c\u00e9l\u00e9brer son r\u00e8gne de championne le plus court de l&rsquo;histoire. Rosa dit qu&rsquo;elle n&rsquo;est pas stupide. Rosa pousse le g\u00e2teau dans le visage de Nyla Rose et commence \u00e0 la frapper. Rose arrive \u00e0 plaquer Rosa contre des caisses et les officiels arrivent pour l&rsquo;arr\u00eater.<\/p>\n\n\n\n<p>&#8211; De retour, on pr\u00e9sente une vid\u00e9o sur l&rsquo;histoire entre Adam Cole et Adam Page qui vont s&rsquo;affronter vendredi.<\/p>\n\n\n\n<p class=\"has-medium-font-size\"><strong>Championnat Mondial TV de la ROH<\/strong><\/p>\n\n\n\n<p><strong>Samoa Joe vs Minoru Suzuki <\/strong>\u00a9<\/p>\n\n\n\n<p>En fin de match, Suzuki veut faire son Pile Driver sur Joe, mais Joe le bloque. Suzuki veut enchainer avec une soumission, mais Joe le repousse contre le coin. Joe le monte sur la troisi\u00e8me corde et lui porte un coup de pied. Joe veut faire un Muscle Buster, mais Suzuki se d\u00e9bat avec un Arm Bar. Joe le frappe et lui fait un Muscle Buster pour le compte de trois !<\/p>\n\n\n\n<p><em>Gagnant et Nouveau Champion: Samoa Joe<\/em><\/p>\n\n\n\n<p> Apr\u00e8s le combat, le nouveau champion ROH World Champion allait c\u00e9l\u00e9brer, mais Jay Lethal et Sonjay Dutt arrivent. Lethal dit qu&rsquo;ils ont un cadeau bien sp\u00e9cial pour lui. Lethal lui fait un doigt d&rsquo;honneur dans la boite cadeau ! Les lumi\u00e8res s&rsquo;\u00e9teignent et s&rsquo;allument. La recrue indienne&nbsp;<strong>Satnam Singh<\/strong>&nbsp;(et ancien joueur NBA) est sur le ring et frappe Joe ! Singh pousse Joe sur la marche d&rsquo;acier et le ram\u00e8ne sur le ring. Singh \u00e9crase le visage de Joe avec ses mains pendant que Lethal le frappe. Lethal termine avec son Lethal Injection. Le show se termine avec une c\u00e9l\u00e9bration du nouveau trio.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<ul class=\"wp-block-list\"><li><strong><a rel=\"noreferrer noopener\" href=\"https:\/\/www.jdx.info\/lutte\/2022\/04\/13\/avant-gout-du-aew-dynamite-du-13-avril-2022\/\" target=\"_blank\">Pour voir ce show, cliquez ici.<\/a><\/strong><\/li><\/ul>\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>Pour voir ce show, cliquez ici. AEW Dynamite Nouvelle-Orl\u00e9ans, Louisiane, 13 avril 2022 Les commentateurs sont Jim Ross, Tony Schiavone et Excalibur. &#8211; Le AEW Dynamite d\u00e9marre avec les commentateurs qui nous souhaitent la bienvenue et CM Punk arrive sur le ring. CM Punk vs Penta Oscuro En fin de match, Penta bloque un coup&#8230;<\/p>\n","protected":false},"author":4,"featured_media":67947,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[38,24,50,30,21],"tags":[],"ppma_author":[292],"class_list":["post-67946","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-aew","category-aew-impact-njpw-roh","category-dynamite","category-ex-wwe","category-resultats"],"authors":[{"term_id":292,"user_id":4,"is_guest":0,"slug":"jean","display_name":"Jean Vinnier","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/33aba0263fd870a0b487e0e079ff407e10e3997c9d2987cbcc0db0db2c5c75a9?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/67946","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/comments?post=67946"}],"version-history":[{"count":3,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/67946\/revisions"}],"predecessor-version":[{"id":68017,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/67946\/revisions\/68017"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media\/67947"}],"wp:attachment":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media?parent=67946"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/categories?post=67946"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/tags?post=67946"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/ppma_author?post=67946"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}