{"id":67582,"date":"2022-04-05T23:51:00","date_gmt":"2022-04-06T03:51:00","guid":{"rendered":"https:\/\/www.jdx.info\/lutte\/?p=67582"},"modified":"2022-04-08T16:35:02","modified_gmt":"2022-04-08T20:35:02","slug":"resultats-et-video-du-wwe-nxt-2-0-du-5-avril-2022","status":"publish","type":"post","link":"https:\/\/www.jdx.info\/lutte\/2022\/04\/05\/resultats-et-video-du-wwe-nxt-2-0-du-5-avril-2022\/","title":{"rendered":"R\u00e9sultats et Vid\u00e9o du WWE NXT 2.0 du 5 Avril 2022!"},"content":{"rendered":"\n<ul class=\"wp-block-list\"><li><strong><a href=\"https:\/\/www.jdx.info\/lutte\/2022\/04\/05\/regardez-le-wwe-nxt-2-0-du-5-avril-2022\/\" target=\"_blank\" rel=\"noreferrer noopener\">Pour voir ce show, cliquez ici.<\/a><\/strong><\/li><\/ul>\n\n\n\n<p class=\"has-medium-font-size\"><strong>WWE NXT, Orlando, Floride, 5 avril 2022<\/strong><\/p>\n\n\n\n<p>Les commentateurs sont Vic Joseph et Wade Barrett.<\/p>\n\n\n\n<p>&#8211; Le NXT 2.0. d\u00e9bute avec une vid\u00e9o des \u00e9v\u00e9nements \u00e0&nbsp;NXT Stand and Deliver, <\/p>\n\n\n\n<p>Le nouveau champion Bron Breakker arrive sur le ring Breakker dit que c&rsquo;\u00e9tait un gros weekend avec des hauts et des bas. Il a eu l&rsquo;honneur d&rsquo;introduire son p\u00e8re et son oncle, les Steiner Brothers, au WWE Hall of Fame. Ensuite aller \u00e0 Stand and Deliver pour le plus grand match et il a \u00e9chou\u00e9. Il n&rsquo;a pas r\u00e9ussi \u00e0 faire le boulot, aucune excuse. Il a ensuite eu la chance de voir WrestleMania 38 et voir des grandes stars comme Bianca Belair, Becky Lynch, Kevin Owens et Stone Cold. Ce qui l&rsquo;a fait r\u00e9fl\u00e9chir sur deux choses, un jour il sera sur la carte de WrestleMania et qu&rsquo;il n&rsquo;allait pas quitter le Texas sans notre titre de NXT. Alors il s&rsquo;est relev\u00e9, il s&rsquo;est pr\u00e9sent\u00e9 au plus grand RAW pour battre Dolph Ziggler et ramener le titre o\u00f9 il doit \u00eatre. La musique d&rsquo;Imperium commence et le clan arrive.<\/p>\n\n\n\n<p>Gunther dit que c&rsquo;\u00e9tait une belle histoire, mais personne ne se pr\u00e9occupe de \u00e7a. Il se pr\u00e9occupe seulement du titre sur le ring. Le titre repr\u00e9sente \u00eatre le meilleur de NXT. Mais le probl\u00e8me est qu&rsquo;on ne peut pas se nommer le meilleur sans affronter le g\u00e9n\u00e9ral du ring Gunther. Breakker dit qu&rsquo;il a eu un gros weekend, mais si Gunther le veut il l&rsquo;aura ce soir !<\/p>\n\n\n\n<center><p><script async=\"\" src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script>\n<ins class=\"adsbygoogle\" style=\"display:block; text-align:center;\" data-ad-layout=\"in-article\" data-ad-format=\"fluid\" data-ad-client=\"ca-pub-1986975368136072\" data-ad-slot=\"7818521013\"><\/ins>\n<script>\n     (adsbygoogle = window.adsbygoogle || []).push({});\n<\/script><\/p><\/center>\n\n\n\n<p>&#8211; De retour suite \u00e0 la pause, on voit qu&rsquo;il y a eu une confrontation entre les Creed Brothers et Imperium pendant la pause.<\/p>\n\n\n\n<p><strong>Creed Brothers&nbsp;(Julius et Brutus Creed) acc de Malcolm Bivens&nbsp;vs Fabian Aichner et Marcel Barthel<\/strong><\/p>\n\n\n\n<p>En fin de match, Aichner d\u00e9cide de partir sans faire la prise \u00e0 deux. Brutus fait une Slam \u00e0 Barthel. Julius prend la tag pour faire leur Powerbomb \u00e0 deux et Julius compl\u00e8te avec une Clothesline pour le compte de trois.<\/p>\n\n\n\n<p><em>Gagnants : Creed Brothers<\/em><\/p>\n\n\n\n<p>&#8211; Apr\u00e8s le combat, les Creed c\u00e9l\u00e8brent la victoire, mais ils se font attaquer par deux hommes masqu\u00e9s ! Ils retirent les masques et il s&rsquo;agit de Pretty Deadly de NXT UK. Ils se pr\u00e9sentent sous les nouveaux noms Elton Prince et Kit Wilson.<\/p>\n\n\n\n<p>&#8211; En coulisse, McKenzie est avec Toxic Attraction. Mandy Rose dit qu&rsquo;elles ne seront pas des anciennes championnes pour si longtemps. Jacy Jayne dit que la r\u00e9union de Gonzalez et Kai la rend malade. Gigi Dolin dit qu&rsquo;elles vont terminer la carri\u00e8re de Gonzalez pour de bon ce soir. Rose dit qu&rsquo;apr\u00e8s ce soir elle sera toujours la championne et Gigi et Jacy seront deux fois championne par \u00e9quipe.<\/p>\n\n\n\n<p>&#8211; De retour, le nouveau champion Nord-Am\u00e9ricain<strong>&nbsp;Cameron Grimes<\/strong>&nbsp;arrive sur le ring. Grimes dit qu&rsquo;on l&rsquo;a fait ! Il a r\u00e9alis\u00e9 sa promesse et il sait que son p\u00e8re est bien souriant. Les gens parlent souvent de monter l&rsquo;\u00e9chelle du succ\u00e8s. \u00c0 Stand and Deliver il a exactement fait \u00e7a. Monter en haut de l&rsquo;\u00e9chelle et prendre le titre, le temps s&rsquo;est arr\u00eat\u00e9. Tous les moments ont pass\u00e9 dans sa t\u00eate, son p\u00e8re qui s&rsquo;est donn\u00e9 pour le business et son p\u00e8re qui l&rsquo;a \u00e9lev\u00e9 en \u00e9tant seul. Pendant les trois derni\u00e8res ann\u00e9es il a travaill\u00e9 doublement fort pour prouver que son p\u00e8re avait raison et il devient une Superstar WWE. Il est notre nouveau champion Nord-Am\u00e9ricain. Il va s&rsquo;assurer que le tour monte et descend plusieurs fois jusqu&rsquo;\u00e0 la lune. Solo Sikoa arrive et dit qu&rsquo;il voulait le f\u00e9liciter. Une belle promesse pour son p\u00e8re et une belle performance. C&rsquo;est cool la victoire du titre, mais la partie difficile arrive o\u00f9 il devra le regarder. Il est venu ici pour affronter les meilleurs et les titres sont dans son sang (Bloodline). Un champion a besoin d&rsquo;un challenger et le challenger est lui. Grimes dit qu&rsquo;il voit un homme qui s&rsquo;est battu chaque jour pour \u00eatre ici.&nbsp;Il doit vaincre des gens comme Sikoa pour \u00eatre nomm\u00e9 un champion, alors il accepte. Les deux se serrent la main.<\/p>\n\n\n\n<p>&#8211; En coulisse, on retrouve Joe Gacy et Harland. Gacy explique que tout le monde a besoin d&rsquo;une famille pour faire face aux vuln\u00e9rabilit\u00e9s. Sinon c&rsquo;est l&rsquo;auto destruction.<\/p>\n\n\n\n<p>&#8211; En coulisse, on retrouve Draco Anthony et Xyon Quinn. Quinn lui dit de ne pas \u00e9couter Joe Gacy. Anthony lui dit de ne pas lui dire quoi faire. Quinn dit qu&rsquo;il veut surveiller ses arri\u00e8res. Anthony dit qu&rsquo;il n&rsquo;a pas besoin de \u00e7a. Quinn dit qu&rsquo;il a besoin d&rsquo;une le\u00e7on de respect.<\/p>\n\n\n\n<center><p><script async=\"\" src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script>\n<ins class=\"adsbygoogle\" style=\"display:block; text-align:center;\" data-ad-layout=\"in-article\" data-ad-format=\"fluid\" data-ad-client=\"ca-pub-1986975368136072\" data-ad-slot=\"7818521013\"><\/ins>\n<script>\n     (adsbygoogle = window.adsbygoogle || []).push({});\n<\/script><\/p><\/center>\n\n\n\n<p>&#8211; De retour, en coulisse, McKenzie est avec Tiffany Stratton. Stratton dit que c&rsquo;est un grand weekend, mais tout le monde a oubli\u00e9 la trag\u00e9die qui lui est arriv\u00e9e. Sarray lui a co\u00fbt\u00e9 son match. Sarray ne pourra plus voir le soleil et son collier. Elle n&rsquo;est pas une perdante.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><strong>Dexter Lumis&nbsp;acc d&rsquo;Indi Hartwell&nbsp;vs Duke Hudson&nbsp;acc de Persia Pirotta<\/strong><\/p>\n\n\n\n<p>En fin de match, les deux s&rsquo;affrontent en bas du ring et se cognent la t\u00eate contre le poteau en voulant se tirer mutuellement. L&rsquo;arbitre compte jusqu&rsquo;\u00e0 dix alors que les catcheuses n&rsquo;arrivent pas \u00e0 les remonter sur le ring.<\/p>\n\n\n\n<p><em>Double d\u00e9compte ext\u00e9rieur<\/em><\/p>\n\n\n\n<p>&#8211; En coulisse, McKenzie est avec Dakota Kai et Raquel Gonzalez pour leur r\u00e9action sur Toxic Attraction. Gonzalez dit que Toxic Attraction a peur, alors elles font des menaces. Gonzalez dit qu&rsquo;elles vont rester les championnes.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<ul class=\"has-medium-font-size wp-block-list\"><li><strong><a href=\"https:\/\/www.jdx.info\/lutte\/2022\/04\/06\/deuxieme-heure-du-wwe-nxt-2-0\/\">Pour la suite de NXT, cliquez ici<\/a><\/strong><\/li><\/ul>\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>Pour voir ce show, cliquez ici. WWE NXT, Orlando, Floride, 5 avril 2022 Les commentateurs sont Vic Joseph et Wade Barrett. &#8211; Le NXT 2.0. d\u00e9bute avec une vid\u00e9o des \u00e9v\u00e9nements \u00e0&nbsp;NXT Stand and Deliver, Le nouveau champion Bron Breakker arrive sur le ring Breakker dit que c&rsquo;\u00e9tait un gros weekend avec des hauts et&#8230;<\/p>\n","protected":false},"author":4,"featured_media":67587,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[21,23],"tags":[],"ppma_author":[292],"class_list":["post-67582","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-resultats","category-wwe"],"authors":[{"term_id":292,"user_id":4,"is_guest":0,"slug":"jean","display_name":"Jean Vinnier","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/33aba0263fd870a0b487e0e079ff407e10e3997c9d2987cbcc0db0db2c5c75a9?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/67582","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/comments?post=67582"}],"version-history":[{"count":3,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/67582\/revisions"}],"predecessor-version":[{"id":67602,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/67582\/revisions\/67602"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media\/67587"}],"wp:attachment":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media?parent=67582"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/categories?post=67582"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/tags?post=67582"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/ppma_author?post=67582"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}