{"id":67444,"date":"2022-04-04T00:09:00","date_gmt":"2022-04-04T04:09:00","guid":{"rendered":"https:\/\/www.jdx.info\/lutte\/?p=67444"},"modified":"2022-04-04T12:09:48","modified_gmt":"2022-04-04T16:09:48","slug":"cody-a-demande-de-ne-jamais-revoir-stardust-pour-revenir-quand-la-roh-pourrait-profiter-des-ppv-aew-au-lieu-de-wrestlemania","status":"publish","type":"post","link":"https:\/\/www.jdx.info\/lutte\/2022\/04\/04\/cody-a-demande-de-ne-jamais-revoir-stardust-pour-revenir-quand-la-roh-pourrait-profiter-des-ppv-aew-au-lieu-de-wrestlemania\/","title":{"rendered":"Cody a demand\u00e9 de ne jamais revoir Stardust pour revenir! \/ Quand la ROH pourrait profiter des PPV AEW au lieu de WrestleMania!"},"content":{"rendered":"\n<p>Vendredi soir, Tony Khan \u00e9tait lui aussi au Texas dans les coulisses du show Supercard of Honor de la ROH. Comme il en a l\u2019habitude apr\u00e8s chaque gros show de la AEW, Tony Khan a accept\u00e9 de r\u00e9pondre aux questions des journalistes. Lors de l\u2019\u00e9change, il s\u2019est montr\u00e9 beaucoup moins cat\u00e9gorique sur le fait que la ROH devrait cesser de profiter de l\u2019engouement du Wrestlemania Weekend pour proposer chaque ann\u00e9e son show Supercard of Honor aux alentours.<\/p>\n\n\n\n<p>Un journaliste a alors sugg\u00e9r\u00e9 une id\u00e9e \u00e0 Tony Khan qui a visiblement fait mouche aupr\u00e8s du pr\u00e9sident de la AEW. L\u2019id\u00e9e \u00e9tait de potentiellement venir proposer les PPVs de la ROH au moment o\u00f9 la AEW tiendra justement l\u2019un de ses quatre PPVs annuels (Revolution, Double Or Nothing, All Out et Full Gear). Cela se mat\u00e9rialisait alors avec le show de la ROH le samedi et celui de la AEW le dimanche.<\/p>\n\n\n\n<p>Dans sa r\u00e9action, Khan a laiss\u00e9 comprendre qu\u2019il n\u2019avait pas song\u00e9 \u00e0 cette id\u00e9e mais que celle-ci lui plaisait bien. Le pr\u00e9sident de la AEW a alors indiqu\u00e9 que cela pourrait coller avec la tenue de Rampage le vendredi et la Fan Fest le samedi. Khan pr\u00e9cise cependant qu\u2019il faut qu\u2019il voit avec WarnerMedia au pr\u00e9alable mais que l\u2019id\u00e9e lui plaisait.<\/p>\n\n\n\n<center><p><script async=\"\" src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script>\n<ins class=\"adsbygoogle\" style=\"display:block; text-align:center;\" data-ad-layout=\"in-article\" data-ad-format=\"fluid\" data-ad-client=\"ca-pub-1986975368136072\" data-ad-slot=\"7818521013\"><\/ins>\n<script>\n     (adsbygoogle = window.adsbygoogle || []).push({});\n<\/script><\/p><\/center>\n\n\n\n\n<p>Avant que Cody Rhodes n&rsquo;effectue son grand retour \u00e0 la WWE lors de la premi\u00e8re soir\u00e9e de WrestleMania 38, bon nombre de fans avaient peur qu&rsquo;il revienne en Stardust, un ancien personnage dans la lign\u00e9 de son fr\u00e8re Goldust, qu&rsquo;il interpr\u00e9tait avant de prendre la poudre d&rsquo;escampette en 2016.<\/p>\n\n\n\n<p>Cette crainte, Cody Rhodes vous rassure puisque lui-m\u00eame a voulu s&rsquo;assurer que son ancien personnage ne reviendrait pas. Lors d&rsquo;une interview accord\u00e9e \u00e0 BT Sport, l&rsquo;ancien VP de la AEW d\u00e9voile en avoir fait la demande \u00e0 la WWE avant son retour. Il ne veut plus jamais revoir Stardust.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>\u00ab\u00a0Il n&rsquo;y avait pas de r\u00e9elles garanties, mais j&rsquo;ai fait une demande. J&rsquo;ai dit que je ne voulais plus jamais revoir Stardust.\u00a0\u00bb<\/p><\/blockquote>\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>Vendredi soir, Tony Khan \u00e9tait lui aussi au Texas dans les coulisses du show Supercard of Honor de la ROH. Comme il en a l\u2019habitude apr\u00e8s chaque gros show de la AEW, Tony Khan a accept\u00e9 de r\u00e9pondre aux questions des journalistes. Lors de l\u2019\u00e9change, il s\u2019est montr\u00e9 beaucoup moins cat\u00e9gorique sur le fait que&#8230;<\/p>\n","protected":false},"author":609,"featured_media":67445,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[38,4,49,42,23],"tags":[],"ppma_author":[295],"class_list":["post-67444","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-aew","category-news","category-roh","category-wrestlemania","category-wwe"],"authors":[{"term_id":295,"user_id":609,"is_guest":0,"slug":"rodrigo","display_name":"Rodrigue Tousignant","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/51fe284bb6dbe8a6b4c2bf998ad658f4a9cd24b7e58f15ec85888070c7340ce6?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/67444","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/users\/609"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/comments?post=67444"}],"version-history":[{"count":1,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/67444\/revisions"}],"predecessor-version":[{"id":67446,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/67444\/revisions\/67446"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media\/67445"}],"wp:attachment":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media?parent=67444"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/categories?post=67444"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/tags?post=67444"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/ppma_author?post=67444"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}