{"id":66602,"date":"2022-03-20T11:56:40","date_gmt":"2022-03-20T15:56:40","guid":{"rendered":"https:\/\/www.jdx.info\/lutte\/?p=66602"},"modified":"2022-03-20T11:56:45","modified_gmt":"2022-03-20T15:56:45","slug":"rhino-espere-combattre-kevin-owens-avant-sa-retraite-et-se-souvient-de-sa-premiere-rencontre-avec-bray-wyatt","status":"publish","type":"post","link":"https:\/\/www.jdx.info\/lutte\/2022\/03\/20\/rhino-espere-combattre-kevin-owens-avant-sa-retraite-et-se-souvient-de-sa-premiere-rencontre-avec-bray-wyatt\/","title":{"rendered":"Rhino esp\u00e8re combattre Kevin Owens avant sa retraite et se souvient de sa premi\u00e8re rencontre avec Bray Wyatt"},"content":{"rendered":"\n<p>La star d&rsquo;IMPACT et l\u00e9gende de la ECW, Rhino, est r\u00e9cemment apparue sur le\u00a0<a href=\"https:\/\/podcasts.apple.com\/us\/podcast\/the-angle-podcast\/id1477487697\">podcast Angle<\/a>\u00a0pour discuter d&rsquo;un large \u00e9ventail de sujets li\u00e9s \u00e0 la lutte professionnelle, o\u00f9 le ma\u00eetre du Gore a nomm\u00e9 Kevin Owens comme son adversaire de r\u00eave avant de prendre sa retraite, et se souvient de sa premi\u00e8re rencontre avec les deux anciens. -time champion universel, Bray Wyatt.\u00a0Les faits saillants ;<\/p>\n\n\n\n<p>Se souvient avoir rencontr\u00e9 Bray Wyatt, qui lui a dit qu&rsquo;il \u00e9tait fan de lui :<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>\u00ab J&rsquo;ai re\u00e7u beaucoup de respect dans les coulisses et, vous savez, de la part des hommes et des femmes.\u00a0Je n&rsquo;oublierai jamais la premi\u00e8re fois que j&rsquo;ai rencontr\u00e9 Bray Wyatt, il a dit: \u00ab\u00a0<em>Oh mec, grand fan.<\/em>\u00a0\u00bb\u00a0Et, tu sais, quand je grandissais, c&rsquo;\u00e9tait un peu tabou pour toi de dire \u00e7a.\u00a0Pendant ce temps, j&rsquo;ai 19 ans et Hulk Hogan est l\u00e0-bas en train de boire de la bi\u00e8re.\u00a0Il n&rsquo;avait rien \u00e0 faire sur le pay-per-view autre que marcher.\u00a0\u00c0 mi-chemin et le gamin \u00e0 l&rsquo;int\u00e9rieur de moi, je pense, je me dis: &lsquo;Il dit de s&rsquo;entra\u00eener, de dire tes pri\u00e8res et de manger tes vitamines.\u00a0Il n&rsquo;a rien dit au sujet de boire de la bi\u00e8re.\u00a0Je me suis senti d\u00e9\u00e7u m\u00eame si j&rsquo;ai 19 ans et que je suis cens\u00e9 faire un match avec l&rsquo;un des Road Warriors, Road Warrior Hawk.\u00a0Et ils ont fini par l&rsquo;enregistrer plus tard et c&rsquo;\u00e9tait en 1995, et je ne l&rsquo;oublierai jamais.<\/p><\/blockquote>\n\n\n\n<center><p><script async=\"\" src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script>\n<ins class=\"adsbygoogle\" style=\"display:block; text-align:center;\" data-ad-layout=\"in-article\" data-ad-format=\"fluid\" data-ad-client=\"ca-pub-1986975368136072\" data-ad-slot=\"7818521013\"><\/ins>\n<script>\n     (adsbygoogle = window.adsbygoogle || []).push({});\n<\/script><\/p><\/center>\n\n\n\n\n<p>Esp\u00e8re avoir un match avec Kevin Owens avant sa retraite :<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>\u00ab\u00a0J&rsquo;aimerais vraiment, je ne sais pas pourquoi le nom de Kevin Owens m&rsquo;est venu \u00e0 l&rsquo;esprit.\u00a0Probablement parce que je suis ici \u00e0 Philadelphie et que je vous parle de Philadelphie et, vous savez, probablement de la [2300] Arena.\u00a0Ce serait vraiment cool.\u00a0J&rsquo;aurais un, vous savez, je suis au point o\u00f9 je commence \u00e0 faire moins sur le ring et plus dans les coulisses et \u00e0 sortir progressivement.\u00a0C&rsquo;est l&rsquo;une des beaut\u00e9s que j&rsquo;aime chez IMPACT.\u00a0L&rsquo;une des nombreuses beaut\u00e9s est que je peux commencer \u00e0 produire.\u00a0Et puis, j&rsquo;esp\u00e8re que je pourrai obtenir, vous savez, si Dieu le veut, je peux passer cinq ans de plus sur le ring \u00e0 plein temps.<\/p><\/blockquote>\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>La star d&rsquo;IMPACT et l\u00e9gende de la ECW, Rhino, est r\u00e9cemment apparue sur le\u00a0podcast Angle\u00a0pour discuter d&rsquo;un large \u00e9ventail de sujets li\u00e9s \u00e0 la lutte professionnelle, o\u00f9 le ma\u00eetre du Gore a nomm\u00e9 Kevin Owens comme son adversaire de r\u00eave avant de prendre sa retraite, et se souvient de sa premi\u00e8re rencontre avec les deux&#8230;<\/p>\n","protected":false},"author":665,"featured_media":66606,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[30,4,41,23],"tags":[],"ppma_author":[289],"class_list":["post-66602","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ex-wwe","category-news","category-tna-impact","category-wwe"],"authors":[{"term_id":289,"user_id":665,"is_guest":0,"slug":"line","display_name":"Line Edmond","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/852de09636413c90cdaa278312f9ea5bc4396768745424755cb63d99a05989d0?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/66602","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/users\/665"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/comments?post=66602"}],"version-history":[{"count":2,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/66602\/revisions"}],"predecessor-version":[{"id":66607,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/66602\/revisions\/66607"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media\/66606"}],"wp:attachment":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media?parent=66602"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/categories?post=66602"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/tags?post=66602"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/ppma_author?post=66602"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}