{"id":66587,"date":"2022-03-18T23:59:00","date_gmt":"2022-03-19T03:59:00","guid":{"rendered":"https:\/\/www.jdx.info\/lutte\/?p=66587"},"modified":"2022-03-21T19:43:12","modified_gmt":"2022-03-21T23:43:12","slug":"resultats-et-video-du-aew-rampage-du-18-mars-2022","status":"publish","type":"post","link":"https:\/\/www.jdx.info\/lutte\/2022\/03\/18\/resultats-et-video-du-aew-rampage-du-18-mars-2022\/","title":{"rendered":"R\u00e9sultats et Vid\u00e9o du AEW Rampage du 18 Mars 2022!"},"content":{"rendered":"\n<ul class=\"wp-block-list\"><li><strong><a rel=\"noreferrer noopener\" href=\"https:\/\/www.jdx.info\/lutte\/2022\/03\/18\/programme-et-liens-pour-le-aew-rampage-de-ce-soir-a-22h-3h-europe\/\" target=\"_blank\">Pour voir ce show, cliquez ici.<\/a><\/strong><\/li><\/ul>\n\n\n\n<p class=\"has-medium-font-size\"><strong>AEW Rampage San Antonio, Texas, 18 mars 2022!<\/strong><\/p>\n\n\n\n<p>Les commentateurs sont Excalibur, Taz, Chris Jericho et Ricky Starks,<\/p>\n\n\n\n<p>&#8211; Le AEW Rampage d\u00e9marre avec les commentateurs qui nous souhaitent la bienvenue et les catcheurs sont sur le ring pour le premier match.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><strong>Darby Allin&nbsp;acc de Sting&nbsp;vs The Butcher&nbsp;acc de Blade et du Bunny<\/strong><\/p>\n\n\n\n<p>En fin de match, Allin et Butcher s&rsquo;affrontent en bas du ring. Darby lui fait un Coffin Drop du ring et Butcher n&rsquo;arrive pas \u00e0 remonter \u00e0 la fin du d\u00e9compte de l&rsquo;arbitre.<\/p>\n\n\n\n<p><em>Gagnant : The Butcher&nbsp;via count out<\/em><\/p>\n\n\n\n<p>Apr\u00e8s le combat, Andrade El Idolo arrive sur la sc\u00e8ne, mais Private Party arrive de l&rsquo;autre c\u00f4t\u00e9 pour attaquer Darby et Sting dans le dos. La musique des Hardy Boyz commence et le clan de Andrade prend la fuite lorsqu&rsquo;ils entrent sur le ring. Matt Hardy prend le micro et dit que maintenant ils sont \u00e9gaux en nombre ils peuvent le faire sur le ring. Le clan d&rsquo;Andrade monte sur le ring, mais d\u00e9cide finalement de partir. Matt dit qu&rsquo;ils sont des poules mouill\u00e9es. Alors \u00e0 Dynamite ils devraient faire un 8-Man Texas Tornado Tag Team Match. Butcher, Blade, Private Party contre les Hardys, Sting et Allin. Andrade fait signe qu&rsquo;il va r\u00e9fl\u00e9chir.<\/p>\n\n\n\n<center><p><script async=\"\" src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script>\n<ins class=\"adsbygoogle\" style=\"display:block; text-align:center;\" data-ad-layout=\"in-article\" data-ad-format=\"fluid\" data-ad-client=\"ca-pub-1986975368136072\" data-ad-slot=\"7818521013\"><\/ins>\n<script>\n     (adsbygoogle = window.adsbygoogle || []).push({});\n<\/script><\/p><\/center>\n\n\n\n<p>&#8211; En coulisse, Scorpio Sky dit qu&rsquo;il entend seulement des excuses depuis la d\u00e9faite de Sammy Guevara. Lui il fait l&rsquo;histoire pendant que les gens disent des excuses. Paige Vanzant dit qu&rsquo;elle est bien meilleure que Tay Conti au niveau athl\u00e8te et elle fait plus d&rsquo;argent. Alors on peut rivaliser ou non.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><strong>Leyla Hirsch vs Red Velvet<\/strong><\/p>\n\n\n\n<p>En fin de match, Hirsch veut appliquer son Arm Bar, mais Velvet attrape un c\u00e2ble pour l&rsquo;arr\u00eater. Velvet \u00e9vite un coup de pied et la sort du ring. Hirsch veut en profiter et prendre un objet de m\u00e9tal, mais Kris Statlander arrive et lui enl\u00e8ve. Velvet en profite pour faire son Corkscrew Kick pour le compte de trois.<\/p>\n\n\n\n<p><em>Gagnante : Red Velvet<\/em><\/p>\n\n\n\n<p>&#8211; On pr\u00e9sente une vid\u00e9o sur QT Marshall et Aaron Solo qui parlent de HOOK. Marshall dit qu&rsquo;il invite son \u00e9tudiant HOOK \u00e0 Rampage pour lui remettre le premier certificat de l&rsquo;accomplissement.<\/p>\n\n\n\n<p><strong>Trios Match<\/strong><\/p>\n\n\n\n<p><strong>Bear Country&nbsp;(Bear Boulder et Bear Bronson)&nbsp;et Fuego Del Sol vs House of Black&nbsp;(Malakai Black, Buddy Matthews et Brody King)<\/strong><\/p>\n\n\n\n<p>En fin de match, la House of Black repousse Bear Country du ring. Del Sol se lance en Missle Drop Kick sur King. Del Sol commence \u00e0 combattre les trois, mais Matthews le bloque avec un coup. Black et King se lancent en saut suicide sur Bear Country. Matthews enchaine avec une Slam pour le compte de trois sur Del Sol.<\/p>\n\n\n\n<p><em>Gagnants : House of Black<\/em><\/p>\n\n\n\n<p>&#8211; En coulisse, on retrouve Penta Oscuro et Alex. Penta remercie la House of Black pour les avoir chang\u00e9s. Penta se sent plus vivant et plus fort que jamais. C&rsquo;est garantie qu&rsquo;il n&rsquo;a aucune peur pour la House of Black.<\/p>\n\n\n\n<p>&#8211; En coulisse, on retrouve Mark Henry avec Keith Lee et The Acclaimed pour l&rsquo;interview du main event. Caster dit qu&rsquo;il n&rsquo;a pas peur de rivaliser, lui aussi est un gros gars. C&rsquo;est leur soir\u00e9e et leur show. Lee peut retourner \u00e0 la rennaissance. Keith Lee dit qu&rsquo;il appr\u00e9cie bien ce que les deux font dans la compagnie. La r\u00e9alit\u00e9 est que lorsqu&rsquo;on monte sur le ring contre lui on va apprendre une le\u00e7on bien douloureuse. The Acclaimed est juste un tremplin vers sa gloire.<\/p>\n\n\n\n<p>&#8211; The Acclaimed arrive. Caster lui rap de changer de tenue puisque c&rsquo;est leur couleur. Apr\u00e8s ce soir personne ne va se souvenir de Lee.<\/p>\n\n\n\n<center><p><script async=\"\" src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script>\n<ins class=\"adsbygoogle\" style=\"display:block; text-align:center;\" data-ad-layout=\"in-article\" data-ad-format=\"fluid\" data-ad-client=\"ca-pub-1986975368136072\" data-ad-slot=\"7818521013\"><\/ins>\n<script>\n     (adsbygoogle = window.adsbygoogle || []).push({});\n<\/script><\/p><\/center>\n\n\n\n<p><strong>Keith Lee vs Max Caster&nbsp;acc de Anthony Bowens<\/strong><\/p>\n\n\n\n<p>En fin de match, Caster repousse Lee avec une s\u00e9rie de coups de pied. Caster veut soulever Lee sur ses \u00e9paules, mais il n&rsquo;arrive pas. Lee frappe Caster avec une Chop et enchaine avec son Big Bang Catastrophe pour le compte de trois.<\/p>\n\n\n\n<p><em>Gagnant : Keith Lee<\/em><\/p>\n\n\n\n<p> Apr\u00e8s le combat, Powerhouse Hobbs arrive en ringside et commence \u00e0 se battre avec Keith Lee. Ricky Starks arrive et s&rsquo;ajoute \u00e0 l&rsquo;action avec The Acclaimed. Caster le frappe avec sa radio pour le sonner pour de bon. Swerve Strickland arrive avec une chaise et les catcheurs prennent la fuite. Lee et Strickland se serrent la main. Le show se termine ainsi.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<ul class=\"wp-block-list\"><li><strong><a rel=\"noreferrer noopener\" href=\"https:\/\/www.jdx.info\/lutte\/2022\/03\/18\/programme-et-liens-pour-le-aew-rampage-de-ce-soir-a-22h-3h-europe\/\" target=\"_blank\">Pour voir ce show, cliquez ici.<\/a><\/strong><\/li><\/ul>\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>Pour voir ce show, cliquez ici. AEW Rampage San Antonio, Texas, 18 mars 2022! Les commentateurs sont Excalibur, Taz, Chris Jericho et Ricky Starks, &#8211; Le AEW Rampage d\u00e9marre avec les commentateurs qui nous souhaitent la bienvenue et les catcheurs sont sur le ring pour le premier match. Darby Allin&nbsp;acc de Sting&nbsp;vs The Butcher&nbsp;acc de&#8230;<\/p>\n","protected":false},"author":4,"featured_media":66589,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[38,24,21],"tags":[],"ppma_author":[292],"class_list":["post-66587","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-aew","category-aew-impact-njpw-roh","category-resultats"],"authors":[{"term_id":292,"user_id":4,"is_guest":0,"slug":"jean","display_name":"Jean Vinnier","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/33aba0263fd870a0b487e0e079ff407e10e3997c9d2987cbcc0db0db2c5c75a9?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/66587","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/comments?post=66587"}],"version-history":[{"count":2,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/66587\/revisions"}],"predecessor-version":[{"id":66653,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/66587\/revisions\/66653"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media\/66589"}],"wp:attachment":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media?parent=66587"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/categories?post=66587"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/tags?post=66587"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/ppma_author?post=66587"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}