{"id":66331,"date":"2022-03-13T15:41:09","date_gmt":"2022-03-13T19:41:09","guid":{"rendered":"https:\/\/www.jdx.info\/lutte\/?p=66331"},"modified":"2022-03-13T15:41:14","modified_gmt":"2022-03-13T19:41:14","slug":"scott-hall-en-tres-mauvais-etat-suite-a-une-operation-de-routine-eric-bishoff-accuse-tony-khan-pour-la-guerre-wwe-vs-aew","status":"publish","type":"post","link":"https:\/\/www.jdx.info\/lutte\/2022\/03\/13\/scott-hall-en-tres-mauvais-etat-suite-a-une-operation-de-routine-eric-bishoff-accuse-tony-khan-pour-la-guerre-wwe-vs-aew\/","title":{"rendered":"Scott Hall en tr\u00e8s mauvais \u00e9tat suite \u00e0 une op\u00e9ration de routine! \/ Eric Bishoff accuse Tony Khan pour la guerre WWE vs AEW!"},"content":{"rendered":"\n<p>L&rsquo;ancien pr\u00e9sident de la WCW et ancien directeur ex\u00e9cutif de SmackDown, Eric Bischoff, a r\u00e9cemment discut\u00e9 de la toxicit\u00e9 de la base de fans de la WWE par rapport \u00e0 celle de l&rsquo;AEW, affirmant qu&rsquo;une grande partie de cette toxicit\u00e9 est due \u00e0 Tony Khan.<\/p>\n\n\n\n<p><strong>Eric Bischoff sur son Podcast 83 Weeks :<\/strong><\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>Ainsi donc, si vous \u00eates un fid\u00e8le fan de l&rsquo;AEW et que vous voulez \u00eatre \u00e0 bord du m\u00eame wagon, vous allez faire ce que Tony Khan fait, et ce que beaucoup de grands talents font chaque semaine sur les m\u00e9dias sociaux ainsi que dans leur \u00e9mission de t\u00e9l\u00e9vision, et vous allez essuyer des attaques tout en essayant d&rsquo;enterrer la concurrence. C&rsquo;est de l\u00e0 que \u00e7a vient, quand on voit que les gens enfoncent des portes pour venir s&rsquo;\u00e9charper \u00e0 ce propos sur les m\u00e9dias sociaux. C&rsquo;est de l\u00e0 que \u00e7a vient, \u00e0 mon avis.<\/p><\/blockquote>\n\n\n\n<p><strong>Eric Bischoff sur Tony Khan le grand coupable :<\/strong><\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>Les gens veulent voir la WWE prendre sa revanche. Les talents au sein de la AEW, dont Tony Khan, s&rsquo;en prennent constamment \u00e0 la WWE afin de fid\u00e9liser davantage leur propre marque. Encore une fois, ce n&rsquo;est pas une critique, mais c&rsquo;est simplement un fait dur et froid, c&rsquo;est de l\u00e0 que \u00e7a vient.<\/p><\/blockquote>\n\n\n\n<p><strong>Eric Bischoff sur la gu\u00e9guerre entre la WWE et la AEW :<\/strong><\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>S&rsquo;il est vrai qu&rsquo;il existe un d\u00e9saccord visible entre certains fans de catch sur le sujet, il est \u00e9galement juste de dire que la All Elite Wrestling a mis de l&rsquo;huile sur le feu en termes de comp\u00e9tition.<\/p><\/blockquote>\n\n\n\n<center><p><script async=\"\" src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script>\n<ins class=\"adsbygoogle\" style=\"display:block; text-align:center;\" data-ad-layout=\"in-article\" data-ad-format=\"fluid\" data-ad-client=\"ca-pub-1986975368136072\" data-ad-slot=\"7818521013\"><\/ins>\n<script>\n     (adsbygoogle = window.adsbygoogle || []).push({});\n<\/script><\/p><\/center>\n\n\n\n\n<p>Et parlant de guerre avec la WWE, un qui a \u00e9t\u00e9 un acteur tr\u00e8s important dans celle des ann\u00e9es 90 ne serait pas en tr\u00e8s grande forme.<\/p>\n\n\n\n<p>En effet, c&rsquo;est une tr\u00e8s mauvaise nouvelle qui vient de tomber concernant Scott Hall alias Razor Ramon qui a maintenant 63 ans. L&rsquo;ancien champion Intercontinental de la WWE et mondial de la WCW, est pr\u00e9sentement dans un \u00e9tat critique.<\/p>\n\n\n\n<p>Le Hall of Famer de la WWE est actuellement sous respirateur artificiel\u00a0apr\u00e8s avoir subi trois crises cardiaques d&rsquo;apr\u00e8s le nos sources. La Superstar de l&rsquo;Attitude Era \u00e0 la WWE et WCW, a eu des complications apr\u00e8s avoir pass\u00e9 une op\u00e9ration \u00e0 la hanche qui \u00e9tait somme toute de routine et qui c&rsquo;\u00e9tait bien d\u00e9roul\u00e9 avant que son coeur ne parte en vrille. <\/p>\n\n\n\n<p>Nous esp\u00e9rons que tout ira bien pour Scott Hall et qu&rsquo;il pourra s&rsquo;en remettre. Nous vous tiendrons inform\u00e9s d\u00e8s que nous aurons plus de d\u00e9tails sur son \u00e9tat de sant\u00e9.<\/p>\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>L&rsquo;ancien pr\u00e9sident de la WCW et ancien directeur ex\u00e9cutif de SmackDown, Eric Bischoff, a r\u00e9cemment discut\u00e9 de la toxicit\u00e9 de la base de fans de la WWE par rapport \u00e0 celle de l&rsquo;AEW, affirmant qu&rsquo;une grande partie de cette toxicit\u00e9 est due \u00e0 Tony Khan. Eric Bischoff sur son Podcast 83 Weeks : Ainsi donc,&#8230;<\/p>\n","protected":false},"author":609,"featured_media":66332,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[38,30,77,4],"tags":[],"ppma_author":[295],"class_list":["post-66331","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-aew","category-ex-wwe","category-hall-of-fame","category-news"],"authors":[{"term_id":295,"user_id":609,"is_guest":0,"slug":"rodrigo","display_name":"Rodrigue Tousignant","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/51fe284bb6dbe8a6b4c2bf998ad658f4a9cd24b7e58f15ec85888070c7340ce6?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/66331","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/users\/609"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/comments?post=66331"}],"version-history":[{"count":1,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/66331\/revisions"}],"predecessor-version":[{"id":66333,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/66331\/revisions\/66333"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media\/66332"}],"wp:attachment":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media?parent=66331"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/categories?post=66331"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/tags?post=66331"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/ppma_author?post=66331"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}