{"id":65819,"date":"2022-03-03T14:11:14","date_gmt":"2022-03-03T19:11:14","guid":{"rendered":"https:\/\/www.jdx.info\/lutte\/?p=65819"},"modified":"2022-03-03T14:14:05","modified_gmt":"2022-03-03T19:14:05","slug":"65819","status":"publish","type":"post","link":"https:\/\/www.jdx.info\/lutte\/2022\/03\/03\/65819\/","title":{"rendered":"Trailer de pr\u00e9sentation des modes 2K Showcase et My Ascension de WWE 2K22"},"content":{"rendered":"\n<p>2K d\u00e9voile un tout nouvel aper\u00e7u de deux modes \u00e0 d\u00e9couvrir dans WWE 2K22 avec ce trailer inspirant ax\u00e9 sur les modes 2K Showcase et My ASCENSION. Ce trailer propose des extraits des moments cl\u00e9s du parcours \u00e9poustouflant de Rey Mysterio, Superstar de la WWE en couverture de WWE 2K22, issus de ses 20 ans de carri\u00e8re \u00e0 la WWE, ainsi qu&rsquo;un aper\u00e7u des sc\u00e9narios uniques pour les divisions hommes et femmes disponibles dans le mode My ASCENSION.<\/p>\n\n\n\n<p>Dans le 2K Showcase bas\u00e9 sur Rey Mysterio, les joueurs affrontent des adversaires l\u00e9gendaires dont Eddie Guerrero, The Undertaker et Shawn Michaels, ainsi que des Superstars actuelles parmi lesquelles The Miz et Dolph Ziggler. Les phases de gameplay s\u2019encha\u00eenent parfaitement et rapidement \u00e0 des images historiques r\u00e9elles en utilisant la nouvelle technologie Slingshot de 2K, pour une exp\u00e9rience vraiment immersive.<\/p>\n\n\n\n<p>My ASCENSION donne l\u2019opportunit\u00e9 aux joueurs de vivre le parcours d\u2019une Superstar de la WWE depuis les humbles d\u00e9buts d\u2019un Rookie au Performance Center de la WWE, jusqu\u2019au chemin \u00e0 parcourir pour devenir une Superstar et \u00eatre immortalis\u00e9 comme une L\u00e9gende de la WWE. Avec des sc\u00e9narios uniques pour les divisions masculines et f\u00e9minines, les joueurs rencontreront au cours de leur progression tout un \u00e9ventail de Superstars et de L\u00e9gendes de la WWE.<\/p>\n\n\n\n<p>WWE 2K22 sera disponible le 11 mars 2022.<\/p>\n\n\n\n<center><p><script async=\"\" src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script>\n<ins class=\"adsbygoogle\" style=\"display:block; text-align:center;\" data-ad-layout=\"in-article\" data-ad-format=\"fluid\" data-ad-client=\"ca-pub-1986975368136072\" data-ad-slot=\"7818521013\"><\/ins>\n<script>\n     (adsbygoogle = window.adsbygoogle || []).push({});\n<\/script><\/p><\/center>\n\n<center><iframe loading=\"lazy\" width=\"560\" height=\"315\" src=\"https:\/\/www.youtube.com\/embed\/prGmt8Kx1Ck\" title=\"YouTube video player\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe>\n\n<iframe loading=\"lazy\" width=\"560\" height=\"315\" src=\"https:\/\/www.youtube.com\/embed\/BcPA6xA6I1c\" title=\"YouTube video player\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><\/center>\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>2K d\u00e9voile un tout nouvel aper\u00e7u de deux modes \u00e0 d\u00e9couvrir dans WWE 2K22 avec ce trailer inspirant ax\u00e9 sur les modes 2K Showcase et My ASCENSION. Ce trailer propose des extraits des moments cl\u00e9s du parcours \u00e9poustouflant de Rey Mysterio, Superstar de la WWE en couverture de WWE 2K22, issus de ses 20 ans&#8230;<\/p>\n","protected":false},"author":4,"featured_media":65822,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[48,4,23],"tags":[],"ppma_author":[292],"class_list":["post-65819","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-2k","category-news","category-wwe"],"authors":[{"term_id":292,"user_id":4,"is_guest":0,"slug":"jean","display_name":"Jean Vinnier","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/33aba0263fd870a0b487e0e079ff407e10e3997c9d2987cbcc0db0db2c5c75a9?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/65819","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/comments?post=65819"}],"version-history":[{"count":2,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/65819\/revisions"}],"predecessor-version":[{"id":65823,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/65819\/revisions\/65823"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media\/65822"}],"wp:attachment":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media?parent=65819"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/categories?post=65819"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/tags?post=65819"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/ppma_author?post=65819"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}