{"id":65620,"date":"2022-02-27T22:19:58","date_gmt":"2022-02-28T03:19:58","guid":{"rendered":"https:\/\/www.jdx.info\/lutte\/?p=65620"},"modified":"2022-02-27T22:21:45","modified_gmt":"2022-02-28T03:21:45","slug":"la-conversation-de-cody-rhodes-avec-ddp-apres-son-annonce-davoir-quitte-la-all-elite-wrestling","status":"publish","type":"post","link":"https:\/\/www.jdx.info\/lutte\/2022\/02\/27\/la-conversation-de-cody-rhodes-avec-ddp-apres-son-annonce-davoir-quitte-la-all-elite-wrestling\/","title":{"rendered":"La conversation de Cody Rhodes avec DDP sur le fait qu&rsquo;il quittait la All Elite Wrestling!"},"content":{"rendered":"\n<p>Une grande histoire en cours dans le monde de la lutte professionnelle a sans doute \u00e9t\u00e9 le d\u00e9part de la All Elite Wrestling de l&rsquo;ancien triple champion TNT Cody Rhodes, en plus du statut de vice-pr\u00e9sident ex\u00e9cutif de la soci\u00e9t\u00e9 qui a rendu cette d\u00e9cision encore plus choquante et surprenante.<\/p>\n\n\n\n<p> Depuis que \u00ab\u00a0the American Nightmare\u00a0\u00bb a annonc\u00e9 que lui et sa femme Brandi partaient, des rumeurs ont circul\u00e9 selon lesquelles il pourrait \u00eatre li\u00e9 \u00e0 la WWE maintenant que son statut dans l&rsquo;industrie a augment\u00e9 en plus de tout les titres majeurs remport\u00e9s juste avant comme celui de la NJPW, iMPACT Wrestling pour ne nommer qu&rsquo;eux. Les rumeurs se sont certainement calm\u00e9es car beaucoup ont suppos\u00e9 que Rhodes \u00e9tait r\u00e9cemment en Floride pour retourner au Performance Center, pour d\u00e9couvrir qu&rsquo;il \u00e9tait en fait en ville pour un mariage. <\/p>\n\n\n\n<center><p><script async=\"\" src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script>\n<ins class=\"adsbygoogle\" style=\"display:block; text-align:center;\" data-ad-layout=\"in-article\" data-ad-format=\"fluid\" data-ad-client=\"ca-pub-1986975368136072\" data-ad-slot=\"7818521013\"><\/ins>\n<script>\n     (adsbygoogle = window.adsbygoogle || []).push({});\n<\/script><\/p><\/center>\n\n\n\n<p>Dans une mise \u00e0 jour dans le dossier, Rhodes a apparemment parl\u00e9 avec le mentor de longue date et l\u00e9gende de la WCW Diamond Dallas Page de sa d\u00e9cision de quitter la AEW, et DDP a transmis ce message. Voici ce qu&rsquo;il avait \u00e0 dire :<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p> \u00ab Cody m&rsquo;a appel\u00e9 deux jours avant. Il a dit : <\/p><p>\u00ab<em> \u00c9coute, je vais te dire quelque chose. Mais je ne peux que t&rsquo;en dire autant. Mais je sais que si je ne t&rsquo;appelle pas pour te le dire, tu vas vouloir me tuer. Tu vas \u00eatre tellement \u00e9nerv\u00e9, alors je dois t&rsquo;appeler et te dire que j&rsquo;aime Tony Khan. C&rsquo;est un gars formidable. Il m&rsquo;aime. Mais on va se s\u00e9parer et je veux partir et faire autre chose. Je ne peux pas te dire de quoi il s&rsquo;agit pour le moment, mais je te promets qu&rsquo;\u00e0 un moment donn\u00e9, je le ferai<\/em>\u00a0\u00bb <\/p><p>Parfois, je ne veux pas savoir. Vous savez ce que je veux dire? Je veux \u00eatre surpris. Je lui ai donn\u00e9 tous mes points de vue sur tout. Je ne sais pas si tu fais ceci, je ne sais pas si tu fais cela, je ne sais pas si tu fais ceci. Mais je lui ai donn\u00e9 mon point de vue et puis Cody est un homme. Il a beaucoup de succ\u00e8s. Pour moi, quoi qu&rsquo;il fasse, je lui souhaite le meilleur. J&rsquo;esp\u00e8re que je l&rsquo;ai aid\u00e9 avec certaines de mes id\u00e9es pour l&rsquo;aider \u00e0 le diriger. Mais il va faire ce qu&rsquo;il va faire. <\/p><\/blockquote>\n\n\n\n<p>Avant ce rapport, la derni\u00e8re mise \u00e0 jour sur Rhodes \u00e9tait qu&rsquo;il appr\u00e9ciait d&rsquo;\u00eatre un \u00abp\u00e8re au foyer\u00bb et ne semblait pas avoir de plan pr\u00e9cis pour un retour sur le ring. Ind\u00e9pendamment de sa d\u00e9cision, la WWE a clairement indiqu\u00e9 qu&rsquo;elle \u00e9tait tr\u00e8s int\u00e9ress\u00e9e \u00e0 ramener Rhodes et en a fait plusieurs allusions \u00e0 RAW et Smackdown de la semaine derni\u00e8re. Du c\u00f4t\u00e9 de la AEW, Tony Khan et Rhodes sont partis en bons termes, et aucun n&rsquo;a, ou n&rsquo;aurait l&rsquo;air de dire du mal de l&rsquo;autre.<\/p>\n\n\n\n<p>En ce qui me concerne personnellement. Le d\u00e9part de Cody Rhodes de la AEW a surement \u00e9t\u00e9 le plus gros coup de publicit\u00e9 pour la compagnie qu&rsquo;il a aid\u00e9 \u00e0 fonder. Quand il sera de retour \u00e0 la WWE car ce n&rsquo;est pas \u00ab\u00a0SI\u00a0\u00bb mais \u00ab\u00a0Quand\u00a0\u00bb, se sera la plus grande visibilit\u00e9 que Tony Khan n&rsquo;aurait jamais  plus esp\u00e9rer, et que c&rsquo;est surement ce bout l\u00e0 que Cody n&rsquo;a pas plus expliquer \u00e0 DDP, voir m\u00eame fait, et lui dire de ne pas en parler car ils sont tout deux de la g\u00e9n\u00e9ration old school qui ont toujours respecter le keyfabe. <\/p>\n\n\n\n<p>Ce qui ajoute du poids \u00e0 la th\u00e9orie sur son avenir, nous avons tent\u00e9 de le booker pour un gala de la GNW \u00e0 Ottawa en avril, et son agent nous a clairement r\u00e9pondu qu&rsquo;il ne prenait aucun booking, ce qui n&rsquo;\u00e9tait pas le cas depuis sont d\u00e9part de la WWE avant de rejoindre la AEW. <\/p>\n\n\n\n<p>En attendant le moment de son retour probablement au lendemain de WrestleMania au plus tard, nous continuons de suivre le dossier pour vous. <\/p>\n\n\n\n<p>Vous voulez faire parti de l&rsquo;\u00e9quipe, contactez moi via Facebook en <a href=\"https:\/\/www.facebook.com\/JasonDarkCashDescoteaux\/\">cliquant ici<\/a><\/p>\n\n\n\n<center><p><script async=\"\" src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script>\n<ins class=\"adsbygoogle\" style=\"display:block; text-align:center;\" data-ad-layout=\"in-article\" data-ad-format=\"fluid\" data-ad-client=\"ca-pub-1986975368136072\" data-ad-slot=\"7818521013\"><\/ins>\n<script>\n     (adsbygoogle = window.adsbygoogle || []).push({});\n<\/script><\/p><\/center>\n\n\n\n<ul class=\"wp-block-list\"><li><strong><a href=\"https:\/\/www.jdx.info\/lutte\/2022\/02\/15\/cody-et-brandi-rhodes-quittent-la-all-elite-wrestling\/\">Annonce du d\u00e9part de la AEW par Cody et Brandi Rhodes.<\/a><\/strong><\/li><li><a href=\"https:\/\/www.jdx.info\/lutte\/2022\/02\/15\/premiere-reaction-sur-le-depart-de-la-aew-par-cody-et-brandi-rhodes\/\"><strong>Premi\u00e8re r\u00e9action sur le d\u00e9part de la AEW par Cody et Brandi Rhodes.<\/strong><\/a><\/li><li><a href=\"https:\/\/www.jdx.info\/lutte\/2022\/02\/15\/cody-et-brandi-rhodes-reagissent-a-leur-depart-de-la-all-elite-wrestling\/\"><strong>Cody et Brandi Rhodes r\u00e9agissent \u00e0 leur d\u00e9part de la AEW<\/strong><\/a><\/li><li><a href=\"https:\/\/www.jdx.info\/lutte\/2022\/02\/15\/des-echos-du-vestiaire-de-raw-sur-la-possibilite-de-voir-cody-rhodes-a-la-wwe\/\"><strong>Des \u00c9chos du Vestiaire de RAW sur la Possibilit\u00e9 de Voir Cody Rhodes \u00e0 la WWE!<\/strong><\/a><\/li><li><a href=\"https:\/\/www.jdx.info\/lutte\/2022\/02\/15\/cody-rhodes-de-plus-en-plus-pret-de-la-wwe-sa-close-de-non-competition-et-plus\/\"><strong>Cody Rhodes de plus en plus pr\u00eat de la WWE! Sa Close de non comp\u00e9tition!<\/strong><\/a><\/li><li><strong><a rel=\"noreferrer noopener\" href=\"https:\/\/www.jdx.info\/lutte\/2022\/02\/16\/la-principale-raison-du-depart-de-cody-rhodes-a-la-aew\/\" target=\"_blank\">La Principale Raison Du D\u00e9part De Cody Rhodes \u00c0 La AEW!<\/a><\/strong><\/li><li><strong><a rel=\"noreferrer noopener\" href=\"https:\/\/www.jdx.info\/lutte\/2022\/02\/16\/cody-rhodes-change-ses-reseaux-sociaux-et-enleve-la-aew\/\" target=\"_blank\">Cody Rhodes Change ses r\u00e9seaux Sociaux et enl\u00e8ve la AEW!<\/a><\/strong><\/li><li><a rel=\"noreferrer noopener\" href=\"https:\/\/www.jdx.info\/lutte\/2022\/02\/18\/reaction-de-sting-sur-le-depart-de-cody-et-brandi-rhodes-de-la-aew\/\" target=\"_blank\"><strong>R\u00e9action de Sting sur le D\u00e9part de Cody et Brandi Rhodes de la AEW!<\/strong><\/a><\/li><li><strong><a rel=\"noreferrer noopener\" href=\"https:\/\/www.jdx.info\/lutte\/2022\/02\/20\/tony-khan-parle-du-depart-de-cody-rhodes-il-sait-quil-prepare-quelque-chose\/\" target=\"_blank\">Tony Khan parle du d\u00e9part de Cody Rhodes. Il sait qu\u2019il pr\u00e9pare quelque chose!<\/a><\/strong><\/li><li><strong><a rel=\"noreferrer noopener\" href=\"https:\/\/www.jdx.info\/lutte\/2022\/02\/19\/kenny-omega-spoil-larrive-de-cody-rhodes-a-lelimination-chamber-miro-rusev-revele-que-sa-carriere-a-pu-decoller-grace-a-dusty-rhodes\/\" target=\"_blank\">Kenny Omega Spoil L\u2019arriv\u00e9 De Cody Rhodes \u00c0 L\u2019Elimination Chamber!\u00a0<\/a><\/strong><\/li><li><strong><a rel=\"noreferrer noopener\" href=\"https:\/\/www.jdx.info\/lutte\/2022\/02\/20\/cody-rhodes-etait-tres-pres-de-la-wwe-durant-lelimination-chamber-lundertaker-etait-prevu-mais-brille-par-son-absence-et-plus\/\" target=\"_blank\">Cody Rhodes \u00c9tait Tr\u00e8s Pr\u00e8s De La WWE Durant L\u2019Elimination Chamber!\u00a0<\/a><\/strong><\/li><li><strong><a rel=\"noreferrer noopener\" href=\"https:\/\/www.jdx.info\/lutte\/2022\/02\/21\/the-miz-fait-reference-a-cody-rhode-en-plein-miz-tv-et-la-wwe-partage-sur-twitter-deux-championnats-pour-le-prochain-raw\/\" target=\"_blank\">The Miz Fait R\u00e9f\u00e9rence \u00c0 Cody Rhode En Plein Miz Tv Et La WWE Partage Sur Twitter!\u00a0<\/a><\/strong><\/li><li><a rel=\"noreferrer noopener\" href=\"https:\/\/www.jdx.info\/lutte\/2022\/02\/24\/eric-bischoff-nest-pas-surpris-par-un-retour-de-cody-rhodes-a-la-wwe-la-aew-annonce-double-or-nothing-2022-danielson-vs-moxley-et-plus\/\" target=\"_blank\"><strong>Eric Bischoff n\u2019est pas surpris par un retour de Cody Rhodes \u00e0 la WWE<\/strong>.<\/a><\/li><li><strong><a rel=\"noreferrer noopener\" href=\"https:\/\/www.jdx.info\/lutte\/2022\/02\/25\/cody-rhodes-qui-quitte-la-aew-un-sujet-hot-sur-internet-bryan-danielson-veut-participer-au-g1-cimax-de-la-njpw\/\" target=\"_blank\">Cody Rhodes qui Quitte la AEW, un sujet \u00ab\u00a0Hot\u00a0\u00bb sur Internet!<\/a><\/strong><\/li><li><strong><a href=\"https:\/\/www.jdx.info\/lutte\/2022\/02\/27\/la-conversation-de-cody-rhodes-avec-ddp-apres-son-annonce-davoir-quitte-la-all-elite-wrestling\/\" target=\"_blank\" rel=\"noreferrer noopener\">La Conversation de Cody Rhodes Avec DDP Apr\u00e8s son Annonce d&rsquo;Avoir Quitt\u00e9 la All Elite Wrestling!<\/a><\/strong><\/li><\/ul>\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>Une grande histoire en cours dans le monde de la lutte professionnelle a sans doute \u00e9t\u00e9 le d\u00e9part de la All Elite Wrestling de l&rsquo;ancien triple champion TNT Cody Rhodes, en plus du statut de vice-pr\u00e9sident ex\u00e9cutif de la soci\u00e9t\u00e9 qui a rendu cette d\u00e9cision encore plus choquante et surprenante. Depuis que \u00ab\u00a0the American Nightmare\u00a0\u00bb&#8230;<\/p>\n","protected":false},"author":2,"featured_media":65622,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[38,24,22,4,23],"tags":[],"ppma_author":[287],"class_list":["post-65620","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-aew","category-aew-impact-njpw-roh","category-indy","category-news","category-wwe"],"authors":[{"term_id":287,"user_id":2,"is_guest":0,"slug":"jason","display_name":"Jason Desc\u00f4teaux","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/f64adf6d13198c3a532c061cecd8672089a1e9a3d07c702dffe886a7e55a15eb?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/65620","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/comments?post=65620"}],"version-history":[{"count":4,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/65620\/revisions"}],"predecessor-version":[{"id":65625,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/65620\/revisions\/65625"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media\/65622"}],"wp:attachment":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media?parent=65620"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/categories?post=65620"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/tags?post=65620"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/ppma_author?post=65620"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}