{"id":65502,"date":"2022-02-25T00:08:00","date_gmt":"2022-02-25T05:08:00","guid":{"rendered":"https:\/\/www.jdx.info\/lutte\/?p=65502"},"modified":"2022-02-25T11:21:37","modified_gmt":"2022-02-25T16:21:37","slug":"la-route-pour-wrestlemania-aide-raw-meme-chose-avec-revolution-du-cote-de-la-aew","status":"publish","type":"post","link":"https:\/\/www.jdx.info\/lutte\/2022\/02\/25\/la-route-pour-wrestlemania-aide-raw-meme-chose-avec-revolution-du-cote-de-la-aew\/","title":{"rendered":"La Route Pour WrestleMania Aide RAW! \/ M\u00eame Chose Avec Revolution du C\u00f4t\u00e9 de la AEW!"},"content":{"rendered":"\n<p>La semaine derni\u00e8re, RAW a gagn\u00e9 un peu plus de 200 000 t\u00e9l\u00e9spectateurs sur SyFy apr\u00e8s un retour sur cette cha\u00eene catastrophique. L&rsquo;hypoth\u00e8se \u00e9tant que les fans avaient enfin \u00e9t\u00e9 mis au courant des changements de diffusion li\u00e9 aux JO d&rsquo;hiver. Ce lundi, le show rouge est revenu sur USA Network et a connu un nouveau gros bond dans les audiences, comme vous pouvez le voir ci-dessous.<\/p>\n\n\n\n<p><strong>RAW &#8212;> 1 825 000 t\u00e9l\u00e9spectateurs (+223 000) \/ 0.51 (+0.07)<\/strong><\/p>\n\n\n\n<p>Semaine du 21 :<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li><strong>RAW<\/strong>\u00a0: Heure 1 : 1.945 \/ Heure 2 : 1.868 \/ Heure 3 : 1.666 \/ En moyenne : 1.826<\/li><li><strong>NXT 2.0<\/strong>\u00a0: En moyenne : 0.612<\/li><li><strong>Dynamite<\/strong>\u00a0: En moyenne : 1.010<\/li><\/ul>\n\n\n\n<ul class=\"has-medium-font-size wp-block-list\"><li><a href=\"https:\/\/www.jdx.info\/lutte\/2022\/02\/21\/resultats-et-video-du-wwe-monday-night-raw-du-21-fevrier-2022\/\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>Pour les r\u00e9sultats complet ou voir ce RAW, cliquez ici.<\/strong><\/a><\/li><\/ul>\n\n\n\n<center><p><script async=\"\" src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script>\n<ins class=\"adsbygoogle\" style=\"display:block; text-align:center;\" data-ad-layout=\"in-article\" data-ad-format=\"fluid\" data-ad-client=\"ca-pub-1986975368136072\" data-ad-slot=\"7818521013\"><\/ins>\n<script>\n     (adsbygoogle = window.adsbygoogle || []).push({});\n<\/script><\/p><\/center>\n\n\n\n\n<p>Les donn\u00e9es d&rsquo;audience de l&rsquo;\u00e9dition du 23 F\u00e9vrier du AEW Dynamite sont enfin connues. Selon le site\u00a0<strong>Showbuzz Daily<\/strong>, Dynamite a attir\u00e9 1 010 000 t\u00e9l\u00e9spectateurs pour une c\u00f4te de 0,40 dans la tranche d\u00e9mographique des 18-49 ans. L&rsquo;\u00e9mission a termin\u00e9 \u00e0 la 3e place dans la cat\u00e9gorie de la d\u00e9mo pour la nuit. <\/p>\n\n\n\n<p>Il s\u2019agit d\u2019une forte augmentation du nombre de t\u00e9l\u00e9spectateurs dans une fourchette exponentielle aux 869 000 t\u00e9l\u00e9spectateurs et au score de 0.31 de la semaine derni\u00e8re, tout en r\u00e9ussissant le tour de force de stagner \u00e0 la m\u00eame place. <\/p>\n\n\n\n<p>Le site\u00a0<strong>Wrestlenomics\u00a0<\/strong>constate que l&rsquo;audience moyenne de Dynamite de la d\u00e9mo cl\u00e9 a atteint son pic \u00e0 partir du fameux moment o\u00f9 Chris Jericho et Eddie Kingston se sont retrouv\u00e9s face \u00e0 face. Il convient de garder \u00e0 l\u2019esprit que les fans n&rsquo;\u00e9taient pas mis sous la confidence selon laquelle Chris Jericho allait se retrouver de la sorte pendant le show.<\/p>\n\n\n\n<p>Il sera int\u00e9ressant de voir si le tout \u00e0 susciter l&rsquo;int\u00e9r\u00eat des fans \u00e0 consommer le produit de la semaine prochaine et \u00e0 m\u00eame commander le pay-per-view\u00a0AEW Revolution\u00a0le\u00a06 prochain.<\/p>\n\n\n\n<p>Un aper\u00e7u des r\u00e9centes audiences de la compagnie et son classement dans la d\u00e9mo 18-49 ans :<\/p>\n\n\n\n<ul class=\"has-medium-font-size wp-block-list\"><li><strong><a href=\"https:\/\/www.jdx.info\/lutte\/2022\/02\/23\/resultats-et-video-du-aew-dynamite-du-23-fevrier-2022\/\" target=\"_blank\" rel=\"noreferrer noopener\">Pour les r\u00e9sultats ou voir le dernier Dynamite, cliquez ici<\/a><\/strong><\/li><\/ul>\n\n\n\n<center><p><script async=\"\" src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script>\n<ins class=\"adsbygoogle\" style=\"display:block; text-align:center;\" data-ad-layout=\"in-article\" data-ad-format=\"fluid\" data-ad-client=\"ca-pub-1986975368136072\" data-ad-slot=\"7818521013\"><\/ins>\n<script>\n     (adsbygoogle = window.adsbygoogle || []).push({});\n<\/script><\/p><\/center>\n\n\n\n\n<p class=\"has-medium-font-size\"><strong>Ratings de Dynamite en 2022<\/strong><\/p>\n\n\n\n<p>5 janvier : 1 010 000 \/ 0,43<br>12 janvier : 969 000 \/ 0,39<br>19 janvier : 1 032 000 \/ 0,44<br>26 janvier : 1 100 000 \/ 0,41<br>2 f\u00e9vrier : 954 000 \/ 0,35<br>9 f\u00e9vrier : 1 129 000 \/ 0,41<br>16 f\u00e9vrier : 869 000 \/ 0,31<br>23 f\u00e9vrier : 1 010 000 \/ 0,40<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p class=\"has-medium-font-size\"><strong><strong>Ratings de Dynamite en 202<\/strong><\/strong>1<\/p>\n\n\n\n<p>24 f\u00e9vrier : 831 000 \/ 0,35<br>3 mars : 934 000 \/ 0,33<br>10 mars : 743 000 \/ 0,32<br>17 mars : 768 000 \/ 0,28<br>24 mars : 757 000 \/ 0,30<br>31 mars : 700 000 \/ 0,26<br>7 avril : 688 000 \/ 0,28<br>14 avril : 1 219 000 \/ 0,44<br>21 avril : 1 104 000 \/ 0,37<br>28 avril : 889 000 \/ 0,33<br>5 mai : 1 090 000 \/ 0,42<br>12 mai : 936 000 \/ 0,31<br>19 mai : 821 000 \/ 0,28<br>28 mai : 526 000 \/ 0,20<br>4 juin : 462,000 \/ 0,19<br>11 juin : 487 000 \/ 0,19<br>18 juin : 551 000 \/ 0,20<br>26 juin : 649,000 \/ 0,21<br>30 juin : 883 000 \/ 0,35<br>7 juillet : 871 000 \/ 0,33<br>14 juillet : 1 025 000 \/ 0,40<br>21 juillet : 1 148 000 \/ 0,44<br>28 juillet : 1 108 000 \/ 0,45<\/p>\n\n\n\n<p>4 ao\u00fbt : 1 102 000 \/ 0,46<br>11 ao\u00fbt : 979 000 \/ 0,35<br>18 ao\u00fbt : 975 000 \/ 0,35<br>25 ao\u00fbt : 1 172 000 \/ 0,48<br>1er septembre : 1 047 000 \/ 0,37<br>8 septembre : 1 319 000 \/ 0,52<br>15 septembre : 1 175 000 \/ 0,44<br>22 septembre : 1 273 000 \/ 0,48<br>29 septembre : 1 152 000 \/ 0,45<br>6 octobre : 1 053 000 \/ 0,37<br>16 octobre : 727 000 \/ 0,28<br>23 octobre : 575 000 \/ 0,22<br>27 octobre : 941 000 \/ 0,40<br>3 novembre : 878 000 \/ 0,33<br>10 nov. : 913 000 \/ 0,35<br>17 novembre : 984 000 \/ 0,37<br>24 novembre : 898 000 \/ 0,31<br>1er d\u00e9cembre : 861 000 \/ 0,31<br>8 d\u00e9c. : 872 000 \/ 0,33<br>15 d\u00e9c. : 948 000 \/ 0,31<br>22 d\u00e9c. : 1 020 000 \/ 0,37<br>29 d\u00e9c. : 975 000 \/ 0,37<\/p>\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>La semaine derni\u00e8re, RAW a gagn\u00e9 un peu plus de 200 000 t\u00e9l\u00e9spectateurs sur SyFy apr\u00e8s un retour sur cette cha\u00eene catastrophique. L&rsquo;hypoth\u00e8se \u00e9tant que les fans avaient enfin \u00e9t\u00e9 mis au courant des changements de diffusion li\u00e9 aux JO d&rsquo;hiver. Ce lundi, le show rouge est revenu sur USA Network et a connu un&#8230;<\/p>\n","protected":false},"author":609,"featured_media":65503,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[38,50,4,43,21,23],"tags":[],"ppma_author":[295],"class_list":["post-65502","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-aew","category-dynamite","category-news","category-raw-wwe","category-resultats","category-wwe"],"authors":[{"term_id":295,"user_id":609,"is_guest":0,"slug":"rodrigo","display_name":"Rodrigue Tousignant","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/51fe284bb6dbe8a6b4c2bf998ad658f4a9cd24b7e58f15ec85888070c7340ce6?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/65502","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/users\/609"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/comments?post=65502"}],"version-history":[{"count":1,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/65502\/revisions"}],"predecessor-version":[{"id":65504,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/65502\/revisions\/65504"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media\/65503"}],"wp:attachment":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media?parent=65502"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/categories?post=65502"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/tags?post=65502"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/ppma_author?post=65502"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}