{"id":65189,"date":"2022-02-19T15:14:45","date_gmt":"2022-02-19T20:14:45","guid":{"rendered":"https:\/\/www.jdx.info\/lutte\/?p=65189"},"modified":"2022-02-19T15:28:34","modified_gmt":"2022-02-19T20:28:34","slug":"deuxieme-partie-du-elimination-chamber","status":"publish","type":"post","link":"https:\/\/www.jdx.info\/lutte\/2022\/02\/19\/deuxieme-partie-du-elimination-chamber\/","title":{"rendered":"Deuxi\u00e8me Partie du Elimination Chamber!"},"content":{"rendered":"\n<ul class=\"wp-block-list\"><li><strong><a href=\"https:\/\/www.jdx.info\/lutte\/2022\/02\/19\/resultats-et-video-du-wwe-elimination-chamber-2022\/\">Pour revenir \u00e0 la premi\u00e8re partie, cliquez ici.<\/a><\/strong><\/li><\/ul>\n\n\n\n<p><strong>Charlotte Flair et Sonya Deville vs Naomi et Ronda Rousey<\/strong><br><em>Ronda Rousey devra catcher avec un bras dans le dos<\/em><\/p>\n\n\n\n<p>En fin de match, Rousey revient dans le match et commence \u00e0 rouer de coups Deville. Rousey fait un Arm Bar \u00e0 Deville pour la faire taper pendant que Charlotte regarde du tablier.<\/p>\n\n\n\n<p><em>Gagnantes : Naomi et Ronda Rousey&nbsp;<\/em><\/p>\n\n\n\n<p>&#8211; On pr\u00e9sente la vid\u00e9o promo du WrestleMania 38 qui aura lieu le 2 et 3 avril 2022.<\/p>\n\n\n\n<center><p><script async=\"\" src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script>\n<ins class=\"adsbygoogle\" style=\"display:block; text-align:center;\" data-ad-layout=\"in-article\" data-ad-format=\"fluid\" data-ad-client=\"ca-pub-1986975368136072\" data-ad-slot=\"7818521013\"><\/ins>\n<script>\n     (adsbygoogle = window.adsbygoogle || []).push({});\n<\/script><\/p><\/center>\n\n\n\n\n<p class=\"has-medium-font-size\"><strong>Falls Count Anywhere Match<\/strong><\/p>\n\n\n\n<p><strong>Madcap Moss\u00a0acc Happy Corbin\u00a0vs Drew McIntyre<\/strong><\/p>\n\n\n\n<p>Le match se lance et McIntyre se fait attaquer par Moss et Corbin puisque c&rsquo;est sans disqualification.<\/p>\n\n\n\n<p>En fin de match, Corbin veut intervenir encore une fois, mais McIntyre sort son \u00e9p\u00e9e pour le faire fuir. McIntyre enchaine avec son Claymore Kick sur Moss pour le compte de trois.<\/p>\n\n\n\n<p><em>Gagnant : Drew McIntyre<\/em><\/p>\n\n\n\n<p>&#8211; En coulisse, Kevin Patrick demande \u00e0 Miz sa r\u00e9action suite \u00e0 sa d\u00e9faite. Miz lui demande le silence. Miz dit que le l\u00e9gendaire Rey Mysterio a trich\u00e9 pour gagner. C&rsquo;\u00e9tait un Handicap Match deux contre un et tout le monde \u00e9tait content. Mais il va trouver une fa\u00e7on d&rsquo;\u00e9galiser les choses pour faire un deux contre deux. Il a d\u00e9j\u00e0 quelqu&rsquo;un en t\u00eate et il va l&rsquo;appeler.<\/p>\n\n\n\n<p class=\"has-medium-font-size\"><strong>Championnat F\u00e9minin de RAW<\/strong><\/p>\n\n\n\n<p><strong>Lita vs Becky Lynch (c)<\/strong><\/p>\n\n\n\n<p>En fin de match, Lita \u00e9vite un Moonsault de Becky et lui fait un Twist of Fate ! Lita monte sur le coin pour son Moonsault et le compl\u00e8te pour la couvrir, mais Becky r\u00e9siste \u00e0 deux. Lita rel\u00e8ve Becky, mais Becky la surprend avec sa Manhandle Slam pour le compte de trois.<\/p>\n\n\n\n<p><em>Gagnante : Becky Lynch<\/em><\/p>\n\n\n\n<p>Apr\u00e8s le combat, Becky quitte et c\u00e9l\u00e8bre sur la sc\u00e8ne. Lita c\u00e9l\u00e8bre ensuite devant les fans pour saluer tout le monde.<\/p>\n\n\n\n<p>&#8211; On pr\u00e9sente une vid\u00e9o sur l&rsquo;Undertaker puisqu&rsquo;il aura sa place au WWE Hall of Fame 2022.<\/p>\n\n\n\n<p>&#8211; Les Viking Raiders arrivent sur le ring pour le match pour les titres par \u00e9quipe de SmackDown, mais ils se font attaquer par les Usos lors de l&rsquo;entr\u00e9e ! Les arbitres arrivent pour repousser les Usos et leur match n&rsquo;aura pas lieu.<\/p>\n\n\n\n<p>&#8211; Les commentateurs pr\u00e9sentent la\u00a0carte de WrestleMania 38.<\/p>\n\n\n\n<p>&#8211; On pr\u00e9sente une vid\u00e9o sur le Chamber Match.<\/p>\n\n\n\n<center><p><script async=\"\" src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script>\n<ins class=\"adsbygoogle\" style=\"display:block; text-align:center;\" data-ad-layout=\"in-article\" data-ad-format=\"fluid\" data-ad-client=\"ca-pub-1986975368136072\" data-ad-slot=\"7818521013\"><\/ins>\n<script>\n     (adsbygoogle = window.adsbygoogle || []).push({});\n<\/script><\/p><\/center>\n\n\n\n\n<p class=\"has-medium-font-size\"><strong>Championnat WWE dans l&rsquo;Elimination Chamber<\/strong><\/p>\n\n\n\n<p><strong>Bobby Lashley (c) vs AJ Styles vs Riddle vs Austin Theory vs Seth Rollins vs Brock Lesnar<\/strong><\/p>\n\n\n\n<p>Theory et Rollins ouvrent le match. Rollins fait une Powerbomb \u00e0 Theory et Lashley tombe par le plexiglas qui se casse. Riddle entre le premier dans le match.<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>Les m\u00e9decins et les officiels arrivent pour sortir Lashley de la Chamber car il est bless\u00e9.<\/li><li>AJ Styles arrive en second.<\/li><li>Toujours aucune \u00e9limination, les lumi\u00e8res s&rsquo;arr\u00eatent sur la capsule de Lashley mais il n&rsquo;est pas l\u00e0. Lesnar brise sa capsule pour entrer dans le match. Il fait un F5 \u00e0 Rollins pour l&rsquo;\u00e9liminer, un F5 \u00e0 Riddle pour l&rsquo;\u00e9liminer aussi. Lesnar fait une Slam \u00e0 AJ Styles et enchaine avec son F5 pour le compte de trois.<\/li><\/ul>\n\n\n\n<p>En fin de match, il reste Theory et Lesnar dans la cage. Theory veut s&rsquo;\u00e9chapper, mais il ne trouve aucune sortie. Lesnar retire ses gants et s&rsquo;approche de Theory qui recule encore et encore. Theory veut se cacher dans une capsule, mais Lesnar brise la capsule avec une Big Boot et lui fait une Suplex. Theory surprend Lesnar avec un Low Blow pour le repousser. Theory enchaine avec un Drop Kick et un DDT pour couvrir Lesnar, mais Lesnar r\u00e9siste et il est furieux. Theory commence \u00e0 monter en haut de la cage et veut sortir par un trou de la cage, mais Lesnar le rejoint en haut de la cage ! Lesnar le tire et les deux s&rsquo;affrontent en haut d&rsquo;une capsule. Lesnar lui cogne la t\u00eate sur le plexiglas et enchaine avec un F5 en haut d&rsquo;une capsule ! Lesnar le ram\u00e8ne sur le ring et le couvre pour la victoire.<\/p>\n\n\n\n<p><em>Gagnant et Nouveau Champion: Brock Lesnar<\/em><\/p>\n\n\n\n<p>Apr\u00e8s le combat, le nouveau champion WWE Brock Lesnar c\u00e9l\u00e8bre sa victoire. La WWE confirme que Lesnar va affronter Reigns \u00e0 WrestleMania 38 dans un Champion contre Champion. Lesnar c\u00e9l\u00e8bre encore sa victoire et prend des photos avec les fans. Le show se termine ainsi.<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li><strong><a rel=\"noreferrer noopener\" href=\"https:\/\/www.jdx.info\/lutte\/2022\/02\/19\/regardez-en-direct-le-wwe-elimination-chamber-2022\/\" target=\"_blank\">Pour voir l&rsquo;Elimination Chamber, cliquez ici.<\/a><\/strong><\/li><\/ul>\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>Pour revenir \u00e0 la premi\u00e8re partie, cliquez ici. Charlotte Flair et Sonya Deville vs Naomi et Ronda RouseyRonda Rousey devra catcher avec un bras dans le dos En fin de match, Rousey revient dans le match et commence \u00e0 rouer de coups Deville. Rousey fait un Arm Bar \u00e0 Deville pour la faire taper pendant&#8230;<\/p>\n","protected":false},"author":4,"featured_media":65204,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[79],"tags":[],"ppma_author":[292],"class_list":["post-65189","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-elimination-chamber"],"authors":[{"term_id":292,"user_id":4,"is_guest":0,"slug":"jean","display_name":"Jean Vinnier","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/33aba0263fd870a0b487e0e079ff407e10e3997c9d2987cbcc0db0db2c5c75a9?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/65189","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/comments?post=65189"}],"version-history":[{"count":4,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/65189\/revisions"}],"predecessor-version":[{"id":65203,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/65189\/revisions\/65203"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media\/65204"}],"wp:attachment":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media?parent=65189"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/categories?post=65189"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/tags?post=65189"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/ppma_author?post=65189"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}