{"id":64903,"date":"2022-02-15T10:11:35","date_gmt":"2022-02-15T15:11:35","guid":{"rendered":"https:\/\/www.jdx.info\/lutte\/?p=64903"},"modified":"2022-02-15T10:18:51","modified_gmt":"2022-02-15T15:18:51","slug":"brock-lesnar-defi-nimporte-quel-fan-et-se-fout-detre-au-hall-of-fame-ou-pas","status":"publish","type":"post","link":"https:\/\/www.jdx.info\/lutte\/2022\/02\/15\/brock-lesnar-defi-nimporte-quel-fan-et-se-fout-detre-au-hall-of-fame-ou-pas\/","title":{"rendered":"Brock Lesnar d\u00e9fi n&rsquo;importe quel fan et se fout d&rsquo;\u00eatre au Hall of Fame ou pas!"},"content":{"rendered":"\n<p>Dernier invit\u00e9 du Pat McAfee show, Brock Lesnar a r\u00e9pondu \u00e0 une question au sujet du Hall Of Fame.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>\u00ab\u00a0Je ne m&rsquo;en soucie pas vraiment et je n&rsquo;en ai rien \u00e0 faire. Je suis s\u00e9rieux, je n&rsquo;en ai rien \u00e0 faire de savoir si je suis dans le Hall Of Fame ou pas. J&rsquo;ai fait ce que j&rsquo;ai fait, je ne me soucie pas de savoir si je laisse un h\u00e9ritage derri\u00e8re moi. Ce qui m&rsquo;importe, c&rsquo;est que je sois une bonne personne et un bon p\u00e8re. C&rsquo;est ce qui est important pour moi. Le Mont Rushmore de la lutte&#8230; il y a beaucoup de gars&#8230; comme si c&rsquo;\u00e9tait un business pour faire de l&rsquo;argent. D&rsquo;accord ? Malheureusement, vous ne feriez pas de podcast si vous n&rsquo;en gagnez pas, car le monde tourne autour de l&rsquo;argent.<\/p><p>Je me sens chanceux de pouvoir encore \u00eatre au sommet, de faire partie d&rsquo;une entreprise que Vince McMahon a aid\u00e9 \u00e0 faire monter en fl\u00e8che et de prendre part \u00e0 ce pay-per-view (Elimination Chamber).\u00a0\u00bb<\/p><\/blockquote>\n\n\n\n<ul class=\"wp-block-list\"><li><strong><a href=\"https:\/\/www.jdx.info\/lutte\/2022\/02\/14\/resultats-et-video-du-wwe-monday-night-raw-du-14-fevrier-2022\/\" target=\"_blank\" rel=\"noreferrer noopener\">Pour les r\u00e9sultats ou voir le dernier RAW, cliquez ici.<\/a><\/strong><\/li><\/ul>\n\n\n\n<center><blockquote class=\"twitter-tweet\"><p lang=\"en\" dir=\"ltr\">\u00ab\u00a0I feel fortunate that I&rsquo;m still on top in the WWE &amp; I feel like wrestling was what I was meant to do\u00a0\u00bb ~<a href=\"https:\/\/twitter.com\/BrockLesnar?ref_src=twsrc%5Etfw\">@BrockLesnar<\/a><a href=\"https:\/\/twitter.com\/hashtag\/PatMcAfeeShowLIVE?src=hash&amp;ref_src=twsrc%5Etfw\">#PatMcAfeeShowLIVE<\/a> <a href=\"https:\/\/t.co\/EBYMnZ2Kk6\">pic.twitter.com\/EBYMnZ2Kk6<\/a><\/p>\u2014 &#x1f17f;&#xfe0f;at McAfee (@PatMcAfeeShow) <a href=\"https:\/\/twitter.com\/PatMcAfeeShow\/status\/1493310135795654657?ref_src=twsrc%5Etfw\">February 14, 2022<\/a><\/blockquote> <script async=\"\" src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script>\n\n<p><script async=\"\" src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script>\n<ins class=\"adsbygoogle\" style=\"display:block; text-align:center;\" data-ad-layout=\"in-article\" data-ad-format=\"fluid\" data-ad-client=\"ca-pub-1986975368136072\" data-ad-slot=\"7818521013\"><\/ins>\n<script>\n     (adsbygoogle = window.adsbygoogle || []).push({});\n<\/script><\/p><\/center>\n\n\n\n<p>Ce ne sont pas des sc\u00e8nes qu&rsquo;on aime voir, mais il arrive parfois que certaines personnes venues assister \u00e0 un show passent de l&rsquo;autre c\u00f4t\u00e9 de la barricade pour s&rsquo;en prendre physiquement \u00e0 un catcheur. Le dernier en date qui en a fait les frais, c&rsquo;est Seth Rollins en novembre dernier.<\/p>\n\n\n\n<p>Brock Lesnar, toujours comme invit\u00e9 du podcast de Pat McAfee. Le commentateur de SmackDown est revenu sur la sc\u00e8ne de Seth Rollins qui s&rsquo;\u00e9tait fait attaquer. Dans un \u00e9lan de folie, l&rsquo;ancien champion de la WWE l&rsquo;a coup\u00e9 pour inviter n&rsquo;importe qui \u00e0 l&rsquo;attaquer de la m\u00eame fa\u00e7on ! Les yeux riv\u00e9s sur la cam\u00e9ra et cassant \u00e0 moiti\u00e9 le mat\u00e9riel, Brock Lesnar \u00ab\u00a0d\u00e9fie le prochain fou\u00a0\u00bb&#8230;<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>&lt;&lt; Je d\u00e9fie n&rsquo;importe qui ! Je d\u00e9fie le prochain fou ! >><\/p><\/blockquote>\n\n\n\n<ul class=\"wp-block-list\"><li><strong><a rel=\"noreferrer noopener\" href=\"https:\/\/www.jdx.info\/lutte\/2022\/02\/14\/resultats-et-video-du-wwe-monday-night-raw-du-14-fevrier-2022\/\" target=\"_blank\">Pour les r\u00e9sultats ou voir le dernier RAW, cliquez ici.<\/a><\/strong><\/li><\/ul>\n\n\n\n<center><blockquote class=\"twitter-tweet\"><p lang=\"en\" dir=\"ltr\">\u00ab\u00a0I FUCKIN DARE THE NEXT FOOL\u00a0\u00bb ~<a href=\"https:\/\/twitter.com\/BrockLesnar?ref_src=twsrc%5Etfw\">@BrockLesnar<\/a><a href=\"https:\/\/twitter.com\/hashtag\/PatMcAfeeShowLIVE?src=hash&amp;ref_src=twsrc%5Etfw\">#PatMcAfeeShowLIVE<\/a> <a href=\"https:\/\/t.co\/ubFhhVKdu5\">pic.twitter.com\/ubFhhVKdu5<\/a><\/p>\u2014 &#x1f17f;&#xfe0f;at McAfee (@PatMcAfeeShow) <a href=\"https\/:\/\/twitter.com\/PatMcAfeeShow\/status\/1493314749580386307?ref_src=twsrc%5Etfw\">February 14, 2022<\/a><\/blockquote> <script async=\"\" src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/center>\n<center><p><script async=\"\" src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script>\n<ins class=\"adsbygoogle\" style=\"display:block; text-align:center;\" data-ad-layout=\"in-article\" data-ad-format=\"fluid\" data-ad-client=\"ca-pub-1986975368136072\" data-ad-slot=\"7818521013\"><\/ins>\n<script>\n     (adsbygoogle = window.adsbygoogle || []).push({});\n<\/script><\/p><\/center>\n\n\n\n\n<p>Toujours lors du Pat McAfee show, o\u00f9 Brock Lesnar nous a offert une superbe performance \u00e0 coeur ouvert. D\u00e8s le d\u00e9but de cet entretien, en s\u2019installant, Brock Lesnar se voit demander par Pat McAfee de faire attention et de ne pas casser la table. Grave erreur parce que Brock Lesnar s&rsquo;ex\u00e9cute et casse la table. Un moment qui laisse hilare les personnes pr\u00e9sentes ainsi que la b\u00eate incarn\u00e9e qui se permet une jolie blague en disant qu\u2019avec l\u2019argent gagn\u00e9 par Pat McAfee, il se dote d\u2019une table aussi bancale. Un pur moment de bonheur.<\/p>\n\n\n\n<center><blockquote class=\"twitter-tweet\"><p lang=\"en\" dir=\"ltr\">DON&#39;T BREAK THE TABLE <a href=\"https:\/\/twitter.com\/BrockLesnar?ref_src=twsrc%5Etfw\">@BrockLesnar<\/a> &#x1f602;&#x1f602;<a href=\"https:\/\/twitter.com\/hashtag\/PatMcAfeeShowLIVE?src=hash&amp;ref_src=twsrc%5Etfw\">#PatMcAfeeShowLIVE<\/a> <a href=\"https:\/\/t.co\/oERbKyQErP\">pic.twitter.com\/oERbKyQErP<\/a><\/p>&mdash; &#x1f17f;&#xfe0f;at McAfee (@PatMcAfeeShow) <a href=\"https:\/\/twitter.com\/PatMcAfeeShow\/status\/1493301125105262596?ref_src=twsrc%5Etfw\">February 14, 2022<\/a><\/blockquote> <script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/center>\n\n\n\n<p>Un peu plus tard durant l&rsquo;entretien, Brock Lesnar s\u2019engage dans une imitation de Stone Cold Steve Austin en citant le type d\u2019animaux pr\u00e9sents du c\u00f4t\u00e9 de sa ferme dans la province du Saskatchewan. Une ferme o\u00f9 il s\u2019adonne \u00e0 la chasse.<\/p>\n\n\n\n<center><blockquote class=\"twitter-tweet\"><p lang=\"en\" dir=\"ltr\">Stone Cold Brock Lesnar era is here. &#x1f602; <a href=\"https:\/\/t.co\/uM49IYcDkC\">pic.twitter.com\/uM49IYcDkC<\/a><\/p>&mdash; Fiending For Followers &#x203c;&#xfe0f; (@Fiend4FolIows) <a href=\"https:\/\/twitter.com\/Fiend4FolIows\/status\/1493313097175605259?ref_src=twsrc%5Etfw\">February 14, 2022<\/a><\/blockquote> <script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/center>\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>Dernier invit\u00e9 du Pat McAfee show, Brock Lesnar a r\u00e9pondu \u00e0 une question au sujet du Hall Of Fame. \u00ab\u00a0Je ne m&rsquo;en soucie pas vraiment et je n&rsquo;en ai rien \u00e0 faire. Je suis s\u00e9rieux, je n&rsquo;en ai rien \u00e0 faire de savoir si je suis dans le Hall Of Fame ou pas. J&rsquo;ai fait&#8230;<\/p>\n","protected":false},"author":609,"featured_media":64904,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[79,4,23],"tags":[],"ppma_author":[295],"class_list":["post-64903","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-elimination-chamber","category-news","category-wwe"],"authors":[{"term_id":295,"user_id":609,"is_guest":0,"slug":"rodrigo","display_name":"Rodrigue Tousignant","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/51fe284bb6dbe8a6b4c2bf998ad658f4a9cd24b7e58f15ec85888070c7340ce6?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/64903","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/users\/609"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/comments?post=64903"}],"version-history":[{"count":2,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/64903\/revisions"}],"predecessor-version":[{"id":64909,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/64903\/revisions\/64909"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media\/64904"}],"wp:attachment":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media?parent=64903"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/categories?post=64903"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/tags?post=64903"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/ppma_author?post=64903"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}