{"id":64853,"date":"2022-02-14T22:04:12","date_gmt":"2022-02-15T03:04:12","guid":{"rendered":"https:\/\/www.jdx.info\/lutte\/?p=64853"},"modified":"2022-02-14T22:10:45","modified_gmt":"2022-02-15T03:10:45","slug":"deuxieme-heure-de-raw-37","status":"publish","type":"post","link":"https:\/\/www.jdx.info\/lutte\/2022\/02\/14\/deuxieme-heure-de-raw-37\/","title":{"rendered":"Deuxi\u00e8me Heure de RAW!"},"content":{"rendered":"\n<ul class=\"wp-block-list\"><li><strong><a href=\"https:\/\/www.jdx.info\/lutte\/2022\/02\/14\/resultats-et-video-du-wwe-monday-night-raw-du-14-fevrier-2022\/\">Pour revenir \u00e0 la premi\u00e8re heure, clique ici.<\/a><\/strong><\/li><\/ul>\n\n\n\n<p>&#8211; <strong>Adam Pearce<\/strong> est sur le ring et nous pr\u00e9sente\u00a0<strong>Lita et Becky Lynch <\/strong>pour la signature de contrat. Pearce les invite \u00e0 signer. Lynch dit \u00e0 Lita de ne pas faire \u00e7a. Elle ne dort plus depuis une semaine en pensant \u00e0 ce moment, son idole d&rsquo;adolescente qui veut lui voler sa place \u00e0 WrestleMania et qui l&rsquo;a attaqu\u00e9 lundi dernier. Elle pourrait tout oublier si Lita d\u00e9chire le contrat et quitte. Lita a eu une belle carri\u00e8re, qu&rsquo;est-ce qu&rsquo;il reste \u00e0 faire ? Lita doit quitter pendant que son h\u00e9ritage est propre. Elles n&rsquo;ont pas besoin de faire \u00e7a. Lita demande aux fans s&rsquo;ils veulent la voir d\u00e9chirer le contrat. La foule hue. Lita demande si elle signe et fait taire Becky pour de bon. La foule approuve. Lita dit qu&rsquo;elle n&rsquo;a pas venu de si loin pour partir, il lui reste un bon match en elle, un grand parcours, un parcours de championne. Elle sait que Becky a peur puisqu&rsquo;elle a vu qu&rsquo;elle a toujours ce qui faut pour la battre. Becky n&rsquo;a pas besoin de l&rsquo;appr\u00e9cier, mais le match aura lieu. Lita signe le contrat.<\/p>\n\n\n\n<p>Becky dit que Lita pousse ses limites \u00e0 un point o\u00f9 elle ne voudra pas revenir. Elle est pr\u00eate \u00e0 beaucoup de choses pour rester championne. Elle a \u00e9tudi\u00e9 la carri\u00e8re de Lita plus que les autres. Elle n&rsquo;a pas peur de s&rsquo;en prendre au cou de Lita. Les gens se souviennent de Lita avec un sourire, mais apr\u00e8s leur match ce sera avec une larme \u00e0 l&rsquo;oeil. Becky signe le contrat. Lita dit que Becky mentionne que sans elle il n&rsquo;y aurait pas de Becky. Lita dit que si elle a cr\u00e9\u00e9 Becky, c&rsquo;est elle qui doit la terminer. Elle va terminer le r\u00e8gne de Becky en devenant la championne. Becky lance le contrat et quitte le ring.<\/p>\n\n\n\n<center><p><script async=\"\" src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script>\n<ins class=\"adsbygoogle\" style=\"display:block; text-align:center;\" data-ad-layout=\"in-article\" data-ad-format=\"fluid\" data-ad-client=\"ca-pub-1986975368136072\" data-ad-slot=\"7818521013\"><\/ins>\n<script>\n     (adsbygoogle = window.adsbygoogle || []).push({});\n<\/script><\/p><\/center>\n\n\n\n\n<p>&#8211; On pr\u00e9sente une vid\u00e9o sur le Elimination Chamber Match.<\/p>\n\n\n\n<p>&#8211; Avant le combat, Nikki dit qu&rsquo;il faut l&rsquo;admirer et comme super h\u00e9ros elle est pr\u00eate \u00e0 d\u00e9masquer le vrai visage de Ripley.<\/p>\n\n\n\n<p class=\"has-medium-font-size\"><strong>Gauntlet Match<\/strong> <strong>Qualification Elimination Chamber <\/strong><\/p>\n\n\n\n<p><strong>Round 1 : Rhea Ripley vs Nikki ASH<\/strong><\/p>\n\n\n\n<p>En fin de round, Ripley bloque un Cross Body de Nikki et\u00a0lui fait son Riptide pour le compte de trois.<\/p>\n\n\n\n<p><strong>Round 2 : Rhea Ripley vs Liv Morgan<\/strong><\/p>\n\n\n\n<p>En fin de round, Ripley lui porte un Superkick pour la repousser et enchaine avec son Riptide pour le compte de trois.<\/p>\n\n\n\n<p><strong>Round 3 : Rhea Ripley vs Doudrop<\/strong><\/p>\n\n\n\n<p>En fin de round, Ripley veut faire son finisher, mais Doudrop la repousse et se lance dans les c\u00e2bles, mais Ripley lui porte un coup de pied. Ripley enchaine avec son Riptide pour le compte de trois.<\/p>\n\n\n\n<p><strong>Round 4 : Rhea Ripley vs Bianca Belair<\/strong><\/p>\n\n\n\n<p>En fin de match, Ripley et Belair \u00e9changent les coups sur le coin. Belair frappe plus fort et lui fait un Body Slam. Belair se lance pour un Handspring Moonsault, mais Ripley la bloque avec ses genoux. Ensuite, Ripley fait un Missle Drop Kick \u00e0 Belair et la couvre, mais elle r\u00e9siste. Ripley enchaine avec son Cloverleaf, mais Belair la repousse et lui fait un Spinebuster. Belair enchaine avec son KOD pour le compte de trois.<\/p>\n\n\n\n<p><em>Gagnante : Bianca Belair<\/em><\/p>\n\n\n\n<p> Apr\u00e8s le combat, Belair et Ripley c\u00e9l\u00e8brent ensemble pour souligner leur performance.<\/p>\n\n\n\n<center><p><script async=\"\" src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script>\n<ins class=\"adsbygoogle\" style=\"display:block; text-align:center;\" data-ad-layout=\"in-article\" data-ad-format=\"fluid\" data-ad-client=\"ca-pub-1986975368136072\" data-ad-slot=\"7818521013\"><\/ins>\n<script>\n     (adsbygoogle = window.adsbygoogle || []).push({});\n<\/script><\/p><\/center>\n\n\n\n\n<p>&#8211; En coulisse, on retrouve les Superstars au RK-Bro-Ga Party. Riddle joue un peu de guitare, mais Chad Gable et Otis le frappent dans le dos pour le sonner !<\/p>\n\n\n\n<p>&#8211; Les Mysterios font leur entr\u00e9e et on part pour la pause avant la troisi\u00e8me heure du show.<\/p>\n\n\n\n<p class=\"has-medium-font-size\"><strong><a href=\"https:\/\/www.jdx.info\/lutte\/2022\/02\/14\/troisieme-heure-de-raw-37\/\">Pour la suite de RAW, cliquez ici.<\/a><\/strong><\/p>\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>Pour revenir \u00e0 la premi\u00e8re heure, clique ici. &#8211; Adam Pearce est sur le ring et nous pr\u00e9sente\u00a0Lita et Becky Lynch pour la signature de contrat. Pearce les invite \u00e0 signer. Lynch dit \u00e0 Lita de ne pas faire \u00e7a. Elle ne dort plus depuis une semaine en pensant \u00e0 ce moment, son idole d&rsquo;adolescente&#8230;<\/p>\n","protected":false},"author":4,"featured_media":64854,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[43],"tags":[],"ppma_author":[292],"class_list":["post-64853","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-raw-wwe"],"authors":[{"term_id":292,"user_id":4,"is_guest":0,"slug":"jean","display_name":"Jean Vinnier","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/33aba0263fd870a0b487e0e079ff407e10e3997c9d2987cbcc0db0db2c5c75a9?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/64853","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/comments?post=64853"}],"version-history":[{"count":6,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/64853\/revisions"}],"predecessor-version":[{"id":64872,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/64853\/revisions\/64872"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media\/64854"}],"wp:attachment":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media?parent=64853"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/categories?post=64853"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/tags?post=64853"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/ppma_author?post=64853"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}