{"id":64813,"date":"2022-02-13T10:03:05","date_gmt":"2022-02-13T15:03:05","guid":{"rendered":"https:\/\/www.jdx.info\/lutte\/?p=64813"},"modified":"2022-02-13T10:03:09","modified_gmt":"2022-02-13T15:03:09","slug":"goldberg-a-vu-la-peur-de-roman-reigns-dans-ses-yeux-finn-balor-le-prefere-de-kross","status":"publish","type":"post","link":"https:\/\/www.jdx.info\/lutte\/2022\/02\/13\/goldberg-a-vu-la-peur-de-roman-reigns-dans-ses-yeux-finn-balor-le-prefere-de-kross\/","title":{"rendered":"Goldberg a vu la peur de Roman Reigns dans ses yeux! \/ Finn Balor le pr\u00e9f\u00e9r\u00e9 de Kross!"},"content":{"rendered":"\n<p>Invit\u00e9 \u00e0 une s\u00e9ance de signature d&rsquo;autographes avec questions r\u00e9ponses pour Signed By Superstars, Karrion Kross nous a r\u00e9v\u00e9l\u00e9 que Finn Balor \u00e9tait son adversaire favori durant son run du c\u00f4t\u00e9 de NXT.<\/p>\n\n\n\n<p>Il nous dit :&nbsp;<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>\u201c\u00c0 NXT, d\u00e9finitivement sans aucun doute, Finn Balor \u00e9tait mon adversaire favori. Lui et moi \u00e9tions toujours sur la m\u00eame page pour mettre en place le match. Il a jou\u00e9 un David parfait dans un David et Goliath et j&rsquo;aime \u00e0 penser que j&rsquo;ai fait ma part en termes de faire croire aux gens qu&rsquo;il est quelqu&rsquo;un qui peut gagner dans ce genre de situation. La direction \u00e9tait inqui\u00e8te \u00e0 ce propos. Ils se demandaient si les gens \u00e9taient investis et sur le fait que personne n&rsquo;allait battre Kross.<\/p><p>C&rsquo;\u00e9tait comme \u00ab\u00a0comment faire, comment faire pour que les gens adh\u00e8rent \u00e0 \u00e7a ?\u00a0\u00bb Il a ce quelque chose en plus et il est si bon, si parfait. Il est le partenaire de danse parfait pour tous ces trucs&rsquo;. Donc lui et moi, apr\u00e8s le premier match, on esp\u00e9rait que la prochaine fois que \u00e7a se produirait, ce serait \u00e0 Mania. C&rsquo;est la premi\u00e8re chose qu&rsquo;il a dit quand il a travers\u00e9 le rideau, j&rsquo;\u00e9tais comme \u00ab\u00a0holy sh-t\u00a0\u00bb. Et puis j&rsquo;ai pens\u00e9 &lsquo;ouais, il a raison&rsquo;. Ca aurait pu \u00eatre face au Demon \u00e0 Mania ou quelque chose comme \u00e7a. Ca aurait \u00e9t\u00e9 g\u00e9nial.\u00a0\u00bb<\/p><\/blockquote>\n\n\n\n<p>L\u2019aventure de Karrion Kross du c\u00f4t\u00e9 de la WWE a malheureusement pris fin quelques mois apr\u00e8s ses d\u00e9buts dans le roster principal avec de nombreux choix plus que discutables concernant la partie cr\u00e9ative et au niveau de son personnage.<\/p>\n\n\n\n<p>Depuis que sa clause de non comp\u00e9tition a pris fin, Karrion Kross a particip\u00e9 au show de la FSW Mecca o\u00f9 il est devenu champion du monde. R\u00e9cemment, il a \u00e9t\u00e9 annonc\u00e9 en tant que participant au show de la MLW : Superfight qui aura lieu le 26 f\u00e9vrier prochain.<\/p>\n\n\n\n<center><p><script async=\"\" src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script>\n<ins class=\"adsbygoogle\" style=\"display:block; text-align:center;\" data-ad-layout=\"in-article\" data-ad-format=\"fluid\" data-ad-client=\"ca-pub-1986975368136072\" data-ad-slot=\"7818521013\"><\/ins>\n<script>\n     (adsbygoogle = window.adsbygoogle || []).push({});\n<\/script><\/p><\/center>\n\n\n\n\n<p>Lors du dernier \u00e9pisode de The Bump, Bill Goldberg a parl\u00e9 de Roman en nous disant qu\u2019il avait vu la peur dans ses yeux.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>\u201cTout ce que j&rsquo;avais \u00e0 faire, c&rsquo;\u00e9tait de me souvenir de l&rsquo;\u00e9poque o\u00f9 j&rsquo;\u00e9tais align\u00e9 contre le garde offensif de Georgia Tech, o\u00f9 je l&rsquo;ai regard\u00e9 dans les yeux et o\u00f9 j&rsquo;ai voulu prendre son \u00e2me au premier engagement. Vous savez, il y a quelques ann\u00e9es, il s&rsquo;est enfui. Je ne sais pas comment il m&rsquo;a \u00e9chapp\u00e9. Mais chaque fois que j&rsquo;ai l&rsquo;opportunit\u00e9 d&rsquo;affronter un homme de la stature de Roman Reigns, un champion comme lui, un homme qui repr\u00e9sente parfaitement notre marque. Pour moi, c&rsquo;est un honneur et un privil\u00e8ge&#8230; Je crois que lorsque je regarde Roman droit dans les yeux, je suis s\u00fbr qu&rsquo;il ressent un peu cette peur.\u00a0\u00bb<\/p><p>\u00a0<\/p><\/blockquote>\n\n\n\n<p>Bill Goldberg a effectu\u00e9 un retour fracassant \u00e0 la WWE en d\u00e9fiant Roman Reigns lors d\u2019un \u00e9pisode de SmackDown apr\u00e8s une absence de quelques mois. Il va tenter de remporter pour la 3e fois le titre Universel lors du show en Arabie Saoudite le 19 f\u00e9vrier, Elimination Chamber.<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li><strong><a href=\"https:\/\/www.jdx.info\/lutte\/2022\/02\/12\/spoilers-wwe-smackdown-du-18-fevrier-2022\/\" target=\"_blank\" rel=\"noreferrer noopener\">L&rsquo;ancien champion de la WCW fera un face \u00e0 face vendredi prochain avec le champion Universal et vous pouvez en savoir plus en cliquant ici.<\/a><\/strong><\/li><\/ul>\n\n\n\n<center><iframe loading=\"lazy\" width=\"560\" height=\"315\" src=\"https:\/\/www.youtube.com\/embed\/yuFQQSNZSZI\" title=\"YouTube video player\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><\/center>\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>Invit\u00e9 \u00e0 une s\u00e9ance de signature d&rsquo;autographes avec questions r\u00e9ponses pour Signed By Superstars, Karrion Kross nous a r\u00e9v\u00e9l\u00e9 que Finn Balor \u00e9tait son adversaire favori durant son run du c\u00f4t\u00e9 de NXT. Il nous dit :&nbsp; \u201c\u00c0 NXT, d\u00e9finitivement sans aucun doute, Finn Balor \u00e9tait mon adversaire favori. Lui et moi \u00e9tions toujours sur&#8230;<\/p>\n","protected":false},"author":609,"featured_media":64814,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[79,30,4,23],"tags":[],"ppma_author":[295],"class_list":["post-64813","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-elimination-chamber","category-ex-wwe","category-news","category-wwe"],"authors":[{"term_id":295,"user_id":609,"is_guest":0,"slug":"rodrigo","display_name":"Rodrigue Tousignant","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/51fe284bb6dbe8a6b4c2bf998ad658f4a9cd24b7e58f15ec85888070c7340ce6?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/64813","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/users\/609"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/comments?post=64813"}],"version-history":[{"count":1,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/64813\/revisions"}],"predecessor-version":[{"id":64815,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/64813\/revisions\/64815"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media\/64814"}],"wp:attachment":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media?parent=64813"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/categories?post=64813"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/tags?post=64813"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/ppma_author?post=64813"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}