{"id":64715,"date":"2022-02-10T10:23:24","date_gmt":"2022-02-10T15:23:24","guid":{"rendered":"https:\/\/www.jdx.info\/lutte\/?p=64715"},"modified":"2022-02-10T10:23:28","modified_gmt":"2022-02-10T15:23:28","slug":"ric-flair-ne-croit-pas-a-lhistoire-de-shane-mcmahon-et-la-wwe-lidee-abandonnee-de-la-wwe-pour-un-retour-de-kurt-angle","status":"publish","type":"post","link":"https:\/\/www.jdx.info\/lutte\/2022\/02\/10\/ric-flair-ne-croit-pas-a-lhistoire-de-shane-mcmahon-et-la-wwe-lidee-abandonnee-de-la-wwe-pour-un-retour-de-kurt-angle\/","title":{"rendered":"Ric Flair ne croit pas \u00e0 l&rsquo;histoire de Shane McMahon et la WWE \/ L\u2019id\u00e9e abandonn\u00e9e de la WWE pour un retour de Kurt Angle!"},"content":{"rendered":"\n<p><\/p>\n\n\n\n<p>R\u00e9cemment, Ric Flair s&rsquo;est exprim\u00e9 durant son podcast au sujet de l\u2019histoire avec Shane McMahon et la WWE.<em><\/em><\/p>\n\n\n\n<p><\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>\u00ab\u00a0J&rsquo;aime Shane McMahon en tant que personne, il a toujours \u00e9t\u00e9 g\u00e9nial avec moi toute ma vie. Bien s\u00fbr, je n&rsquo;ai pas assez de bonnes choses \u00e0 dire sur Vince. C&rsquo;est un sujet et une situation tr\u00e8s inconfortables \u00e0 aborder pour moi, car je n&rsquo;en sais tout simplement pas assez.<\/p><p>Non, mais je ne vois vraiment pas comment Shane a \u00e9t\u00e9 soumis \u00e0 cette br\u00e8ve p\u00e9riode d&rsquo;humiliation pour que ce soit quelque chose qui n&rsquo;est pas r\u00e9el non plus. Si votre famille est aussi soud\u00e9e qu&rsquo;elle l&rsquo;est, pourquoi laisseriez-vous cela \u00eatre le sujet principal de l&rsquo;actualit\u00e9 de la WWE pendant deux semaines ? J&rsquo;esp\u00e8re que ce n&rsquo;est qu&rsquo;une invention.\u00a0\u00bb<\/p><\/blockquote>\n\n\n\n<p>Depuis presque 3 semaines maintenant, cette histoire est au c\u0153ur de toutes les attentions du c\u00f4t\u00e9 de la WWE avec son lot de r\u00e9v\u00e9lations. Il pourrait s\u2019agir d\u2019une histoire mont\u00e9e de toute pi\u00e8ce pour mener \u00e0 une storyline, et pourrait \u00eatre le plus gros \u00ab\u00a0work\u00a0\u00bb depuis le Montreal Screwedjob en 1997. <\/p>\n\n\n\n<center><p><script async=\"\" src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script>\n<ins class=\"adsbygoogle\" style=\"display:block; text-align:center;\" data-ad-layout=\"in-article\" data-ad-format=\"fluid\" data-ad-client=\"ca-pub-1986975368136072\" data-ad-slot=\"7818521013\"><\/ins>\n<script>\n     (adsbygoogle = window.adsbygoogle || []).push({});\n<\/script><\/p><\/center>\n\n\n\n\n<p>Apr\u00e8s son dernier match effectu\u00e9 lors de Wrestlemania 35 (2019) contre Baron Corbin, Kurt Angle avait \u00e9volu\u00e9 vers un r\u00f4le en coulisse au sein de la WWE avant de finalement se faire renvoyer en avril 2020. Deux ans plus tard, le m\u00e9daill\u00e9 d\u2019or olympique aurait pu faire son retour \u00e0 la WWE pour un court programme que le principal concern\u00e9 mentionnait pour une dur\u00e9e de trois \u00e0 quatre semaines. Cette id\u00e9e a cependant \u00e9t\u00e9 abandonn\u00e9e par la compagnie de Stamford, et\u00a0<em>Fightful\u00a0<\/em>indique avoir appris ce que cela aurait pu \u00eatre.<\/p>\n\n\n\n<p>Angle serait ainsi revenu afin de prendre part \u00e0 la rivalit\u00e9 entre les RKBro et l\u2019Alpha Academy. Le v\u00e9t\u00e9ran aurait ainsi particip\u00e9 aux \u00e9preuves acad\u00e9miques, probablement dans un r\u00f4le de juge. Cette comp\u00e9tition aurait alors \u00e9t\u00e9 appel\u00e9e \u00ab\u00a0Three I\u2019s Challenge\u00a0\u00bb en r\u00e9f\u00e9rence \u00e0 sa catchphrase sur les \u00ab\u00a0Three I\u2019s\u00a0\u00bb pour Intensit\u00e9, Int\u00e9grit\u00e9 et Intelligence. Tout cela aurait abouti \u00e0 un r\u00f4le d\u2019arbitre pour le show Elimination Chamber en Arabie Saoudite.<\/p>\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>R\u00e9cemment, Ric Flair s&rsquo;est exprim\u00e9 durant son podcast au sujet de l\u2019histoire avec Shane McMahon et la WWE. \u00ab\u00a0J&rsquo;aime Shane McMahon en tant que personne, il a toujours \u00e9t\u00e9 g\u00e9nial avec moi toute ma vie. Bien s\u00fbr, je n&rsquo;ai pas assez de bonnes choses \u00e0 dire sur Vince. C&rsquo;est un sujet et une situation tr\u00e8s&#8230;<\/p>\n","protected":false},"author":609,"featured_media":64716,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[30,77,4,23],"tags":[],"ppma_author":[295],"class_list":["post-64715","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ex-wwe","category-hall-of-fame","category-news","category-wwe"],"authors":[{"term_id":295,"user_id":609,"is_guest":0,"slug":"rodrigo","display_name":"Rodrigue Tousignant","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/51fe284bb6dbe8a6b4c2bf998ad658f4a9cd24b7e58f15ec85888070c7340ce6?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/64715","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/users\/609"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/comments?post=64715"}],"version-history":[{"count":1,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/64715\/revisions"}],"predecessor-version":[{"id":64717,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/64715\/revisions\/64717"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media\/64716"}],"wp:attachment":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media?parent=64715"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/categories?post=64715"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/tags?post=64715"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/ppma_author?post=64715"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}