{"id":64703,"date":"2022-02-10T00:37:00","date_gmt":"2022-02-10T05:37:00","guid":{"rendered":"https:\/\/www.jdx.info\/lutte\/?p=64703"},"modified":"2022-02-10T09:57:29","modified_gmt":"2022-02-10T14:57:29","slug":"tony-khan-a-massacre-le-fordiden-door-keith-lee-cross-the-line-et-plus","status":"publish","type":"post","link":"https:\/\/www.jdx.info\/lutte\/2022\/02\/10\/tony-khan-a-massacre-le-fordiden-door-keith-lee-cross-the-line-et-plus\/","title":{"rendered":"Tony Khan a massacr\u00e9 le \u00ab\u00a0Fordiden Door\u00a0\u00bb! \/ Keith Lee \u00ab\u00a0Cross The Line\u00a0\u00bb, et plus!"},"content":{"rendered":"\n<p>Comme vous le savez, Tony Khan avait promis une grande surprise pour l&rsquo;\u00e9pisode d&rsquo;AEW Dynamite du 9 f\u00e9vrier 2022\u00a0et il a tenu parole.<\/p>\n\n\n\n<p> Isiah Kassidy \u00e9tait dans un match de qualification pour le Ladder Match du PPV AEW Revolution face \u00e0 un adversaire gard\u00e9 myst\u00e8re jusqu&rsquo;\u00e0 sa sortie sur le ring. C&rsquo;est Keith Lee qui a r\u00e9pondu \u00e0 l&rsquo;appel et il est arriv\u00e9 sur le ring en profitant de l&rsquo;ambiance des fans et bien heureux.<\/p>\n\n\n\n<p>Comme vous pouvez l&rsquo;imaginez, Keith Lee a remport\u00e9 son match avec un  PowerSlam et ainsi \u00eatre le premier \u00e0 se classer pour le Ladder Match de Revolution qui se tiendra le 6 mars 2022. Un match qui permettra au gagnant de devenir le nouvel aspirant au titre TNT. <\/p>\n\n\n\n<p>Pour rappel, Keith Lee avait \u00e9t\u00e9 licenci\u00e9 de la WWE au d\u00e9but novembre 2021 face aux coupures budg\u00e9taires et aujourd&rsquo;hui il se trouve une place au sein d&rsquo;une nouvelle compagnie. La AEW a confirm\u00e9 quelques minutes apr\u00e8s ses d\u00e9buts qu&rsquo;il a sign\u00e9 un contrat \u00e0 temps plein avec la compagnies.<\/p>\n\n\n\n<p>Une semaine bien occup\u00e9e pour l&rsquo;homme sans limite puisqu&rsquo;il\u00a0s&rsquo;est mari\u00e9 avec Mia Yim ce week-end. Voici quelques extraits de ses d\u00e9buts \u00e0 la AEW :<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li><strong><a href=\"https:\/\/www.jdx.info\/lutte\/2022\/02\/09\/resultats-et-video-du-aew-dynamite-du-9-fevrier-2022\/\" target=\"_blank\" rel=\"noreferrer noopener\">Pour les r\u00e9sultats ou voir le dernier Dynamite et les d\u00e9but de Keith Lee, cliquez ici.<\/a><\/strong><\/li><\/ul>\n\n\n\n<center><blockquote class=\"twitter-tweet\"><p lang=\"en\" dir=\"ltr\"><a href=\"https:\/\/twitter.com\/hashtag\/AEW?src=hash&amp;ref_src=twsrc%5Etfw\">#AEW<\/a>&#39;s new free agent is <a href=\"https:\/\/twitter.com\/RealKeithLee?ref_src=twsrc%5Etfw\">@RealKeithLee<\/a>!<br><br>Don\u2019t miss another minute of the action! <a href=\"https:\/\/twitter.com\/hashtag\/AEWDynamite?src=hash&amp;ref_src=twsrc%5Etfw\">#AEWDynamite<\/a> is LIVE on <a href=\"https:\/\/twitter.com\/TBSNetwork?ref_src=twsrc%5Etfw\">@TBSNetwork<\/a> right now! <a href=\"https:\/\/t.co\/Bl2xDiAT2Q\">pic.twitter.com\/Bl2xDiAT2Q<\/a><\/p>&mdash; All Elite Wrestling (@AEW) <a href=\"https:\/\/twitter.com\/AEW\/status\/1491589711059689477?ref_src=twsrc%5Etfw\">February 10, 2022<\/a><\/blockquote> <script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script>\n\n<p><script async=\"\" src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script>\n<ins class=\"adsbygoogle\" style=\"display:block; text-align:center;\" data-ad-layout=\"in-article\" data-ad-format=\"fluid\" data-ad-client=\"ca-pub-1986975368136072\" data-ad-slot=\"7818521013\"><\/ins>\n<script>\n     (adsbygoogle = window.adsbygoogle || []).push({});\n<\/script><\/p><\/center>\n\n\n\n\n<p>&#8211; Alors comme pr\u00e9vu, la AEW nous a r\u00e9serv\u00e9 de belles surprises lors de\u00a0Dynamite\u00a0cette semaine. L&rsquo;une d&rsquo;entre elles \u00e9tait\u00a0l&rsquo;arriv\u00e9e tant attendue de Keith Lee\u00a0qui s&rsquo;est directement qualifi\u00e9 pour le Face of the Revolution Ladder Match du prochain PPV. <\/p>\n\n\n\n<p>La seconde surprise \u00e9tait destin\u00e9e \u00e0 Jay White, catcheur de la New Japan Pro-Wrestling, qui est apparu aux c\u00f4t\u00e9s d&rsquo;Adam Cole et les Young Bucks pour attaquer Trent Baretta.<\/p>\n\n\n\n<p>Quelques minutes apr\u00e8s le show, Tony Khan a fait savoir sur Twitter qu&rsquo;il avait r\u00e9ussi \u00e0\u00a0avoir Jay White seulement dimanche dernier, apr\u00e8s s&rsquo;\u00eatre rendu compte qu&rsquo;il avait \u00ab\u00a0massacr\u00e9\u00a0\u00bb la d\u00e9finition de \u00ab\u00a0Forbidden Door\u00a0\u00bb\u00a0lorsqu&rsquo;il a hyp\u00e9 la soir\u00e9e sur les r\u00e9seaux sociaux. C&rsquo;est apr\u00e8s avoir vu la r\u00e9action des fans qu&rsquo;il a donc cherch\u00e9 \u00e0 avoir un catcheur de cette fameuse porte interdite.<\/p>\n\n\n\n<p>Avec l&rsquo;arriv\u00e9e de Jay White, Tony Khan s&rsquo;est ainsi assur\u00e9 que le terme \u00ab\u00a0Forbidden Door\u00a0\u00bb soit correctement utilis\u00e9, c&rsquo;est-\u00e0-dire faire venir un lutteur qui travaille pour une autre compagnie, en l\u2019occurrence la NJPW et IMPACT Wrestling. Le meilleur exemple ressent est bien s\u00fbre Mickie James dans le Royal Rumble \u00e9tant championne \u00e0 Impact Wrestling. <\/p>\n\n\n\n<ul class=\"wp-block-list\"><li><strong><a rel=\"noreferrer noopener\" href=\"https:\/\/www.jdx.info\/lutte\/2022\/02\/09\/resultats-et-video-du-aew-dynamite-du-9-fevrier-2022\/\" target=\"_blank\">Pour les r\u00e9sultats ou voir le dernier Dynamite et les d\u00e9but de Keith Lee, cliquez ici.<\/a><\/strong><\/li><\/ul>\n\n\n\n<center><blockquote class=\"twitter-tweet\"><p lang=\"en\" dir=\"ltr\">I didn\u2019t secure <a href=\"https:\/\/twitter.com\/JayWhiteNZ?ref_src=twsrc%5Etfw\">@JayWhiteNZ<\/a> until Sunday. I realized after the fact that Friday night I butchered my own definition of Forbidden Door in hyping tonight. I heard the fans\u2019 feedback, &amp; wanted to ensure that tonight was a special <a href=\"https:\/\/twitter.com\/hashtag\/AEWDynamite?src=hash&amp;ref_src=twsrc%5Etfw\">#AEWDynamite<\/a> for all. Thank you everyone who watched!<\/p>&mdash; Tony Khan (@TonyKhan) <a href=\"https:\/\/twitter.com\/TonyKhan\/status\/1491616155554963462?ref_src=twsrc%5Etfw\">February 10, 2022<\/a><\/blockquote> <script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/center>\n\n\n\n<p><\/p>\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>Comme vous le savez, Tony Khan avait promis une grande surprise pour l&rsquo;\u00e9pisode d&rsquo;AEW Dynamite du 9 f\u00e9vrier 2022\u00a0et il a tenu parole. Isiah Kassidy \u00e9tait dans un match de qualification pour le Ladder Match du PPV AEW Revolution face \u00e0 un adversaire gard\u00e9 myst\u00e8re jusqu&rsquo;\u00e0 sa sortie sur le ring. C&rsquo;est Keith Lee qui&#8230;<\/p>\n","protected":false},"author":4,"featured_media":64704,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[38,24,30,4],"tags":[],"ppma_author":[292],"class_list":["post-64703","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-aew","category-aew-impact-njpw-roh","category-ex-wwe","category-news"],"authors":[{"term_id":292,"user_id":4,"is_guest":0,"slug":"jean","display_name":"Jean Vinnier","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/33aba0263fd870a0b487e0e079ff407e10e3997c9d2987cbcc0db0db2c5c75a9?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/64703","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/comments?post=64703"}],"version-history":[{"count":2,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/64703\/revisions"}],"predecessor-version":[{"id":64707,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/64703\/revisions\/64707"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media\/64704"}],"wp:attachment":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media?parent=64703"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/categories?post=64703"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/tags?post=64703"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/ppma_author?post=64703"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}