{"id":64624,"date":"2022-02-08T16:23:33","date_gmt":"2022-02-08T21:23:33","guid":{"rendered":"https:\/\/www.jdx.info\/lutte\/?p=64624"},"modified":"2022-02-08T16:23:37","modified_gmt":"2022-02-08T21:23:37","slug":"chris-jericho-sur-le-fait-que-la-aew-est-plus-chaude-que-la-wwe-et-ayant-un-meilleur-produit-a-offrir-aux-fans","status":"publish","type":"post","link":"https:\/\/www.jdx.info\/lutte\/2022\/02\/08\/chris-jericho-sur-le-fait-que-la-aew-est-plus-chaude-que-la-wwe-et-ayant-un-meilleur-produit-a-offrir-aux-fans\/","title":{"rendered":"Chris Jericho sur le fait que la AEW est plus chaude que la WWE, et ayant un meilleur produit \u00e0 offrir aux fans!"},"content":{"rendered":"\n<p>Le premier champion de la AEW, <strong>Chris Jericho<\/strong>, s&rsquo;est r\u00e9cemment entretenue avec Brian Jones de <strong>PopCulture<\/strong> et a expliqu\u00e9 pourquoi la AEW a suivi une tendance \u00e0 la hausse. Jericho a d\u00e9clar\u00e9 que la AEW \u00e9tait la soci\u00e9t\u00e9 de lutte professionnelle la plus en vogue au monde.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>\u00ab\u00a0Je pense que la chose la plus importante avec la AEW est que nous sommes partis de z\u00e9ro et avons tent\u00e9 de vraiment voir si nous pouvions le faire fonctionner. Et c&rsquo;est arriv\u00e9. Moins de deux ans plus tard, ou un peu plus de deux ans plus tard, nous sommes maintenant la soci\u00e9t\u00e9 de lutte la plus en vogue au monde aujourd&rsquo;hui, avec un \u00e9norme et massif contrat t\u00e9l\u00e9vis\u00e9. Cela va juste grandir \u00e0 mesure que nous grandissons. Et je pense que c&rsquo;est le plus grand changement, c&rsquo;est que c&rsquo;\u00e9tait vraiment sur mon dos au d\u00e9but, pour lancer et d\u00e9marrer. Et je savais que c&rsquo;\u00e9tait une chance, mais je savais que si c&rsquo;\u00e9tait un succ\u00e8s, c&rsquo;est une autre plume dans l&rsquo;h\u00e9ritage de Jericho et cela aide \u00e0 changer \u00e0 jamais l&rsquo;industrie de la lutte pour le mieux.<\/p><\/blockquote>\n\n\n\n<center><p><script async=\"\" src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script>\n<ins class=\"adsbygoogle\" style=\"display:block; text-align:center;\" data-ad-layout=\"in-article\" data-ad-format=\"fluid\" data-ad-client=\"ca-pub-1986975368136072\" data-ad-slot=\"7818521013\"><\/ins>\n<script>\n     (adsbygoogle = window.adsbygoogle || []).push({});\n<\/script><\/p><\/center>\n\n\n\n\n<p>On a \u00e9galement demand\u00e9 \u00e0 Jericho si AEW pouvait surpasser la WWE en tant que meilleure entreprise de lutte professionnelle au monde. Il pense que la AEW est d\u00e9j\u00e0 la promotion n \u00b0 1.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>\u00ab\u00a0Eh bien, \u00e0 mon avis, quelle est la meilleure promotion de lutte? Pour moi, je pense que nous le sommes d\u00e9j\u00e0, en ce qui concerne les produits sur le ring et les spectacles divertissants, les sc\u00e9narios, les personnages, etc. Si vous vous demandez si la AEW d\u00e9passera la WWE en tant que marque de lutte professionnel en Am\u00e9rique du Nord? Je ne sais pas. Mais ce n&rsquo;est pas quelque chose auquel nous pensons vraiment ou dont nous nous inqui\u00e9tons. Tout ce qui nous inqui\u00e8te, c&rsquo;est de continuer \u00e0 d\u00e9velopper notre base de fans, ce que nous sommes, de grandir et de continuer \u00e0 nous am\u00e9liorer et \u00e0 cr\u00e9er des histoires incroyables, ce que nous faisons.<\/p><\/blockquote>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>\u00abNous le tuons vraiment dans les d\u00e9mos, ce qui \u00e9quivaut \u00e0 des contrats de t\u00e9l\u00e9vision plus \u00e9lev\u00e9s lorsque celui-ci expire dans quelques ann\u00e9es. Alors demandez-moi dans quelques ann\u00e9es, si nous allons \u00eatre la promotion la plus dominante. Je sais que nous gagnerons beaucoup plus d&rsquo;argent que nous ne le faisons actuellement, ce qui nous permettra de continuer \u00e0 proposer le meilleur produit de lutte au monde aujourd&rsquo;hui, ce que nous faisons d\u00e9j\u00e0.<\/p><\/blockquote>\n\n\n\n<p>Jericho organisera une r\u00e9union d&rsquo;\u00e9quipe avec The Inner Circle sur AEW Dynamite ce mercredi soir sur TBS.<\/p>\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>Le premier champion de la AEW, Chris Jericho, s&rsquo;est r\u00e9cemment entretenue avec Brian Jones de PopCulture et a expliqu\u00e9 pourquoi la AEW a suivi une tendance \u00e0 la hausse. Jericho a d\u00e9clar\u00e9 que la AEW \u00e9tait la soci\u00e9t\u00e9 de lutte professionnelle la plus en vogue au monde. \u00ab\u00a0Je pense que la chose la plus importante&#8230;<\/p>\n","protected":false},"author":2,"featured_media":64626,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[38,24,4],"tags":[],"ppma_author":[287],"class_list":["post-64624","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-aew","category-aew-impact-njpw-roh","category-news"],"authors":[{"term_id":287,"user_id":2,"is_guest":0,"slug":"jason","display_name":"Jason Desc\u00f4teaux","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/f64adf6d13198c3a532c061cecd8672089a1e9a3d07c702dffe886a7e55a15eb?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/64624","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/comments?post=64624"}],"version-history":[{"count":2,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/64624\/revisions"}],"predecessor-version":[{"id":64627,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/64624\/revisions\/64627"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media\/64626"}],"wp:attachment":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media?parent=64624"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/categories?post=64624"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/tags?post=64624"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/ppma_author?post=64624"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}