{"id":64548,"date":"2022-02-07T15:11:00","date_gmt":"2022-02-07T20:11:00","guid":{"rendered":"https:\/\/www.jdx.info\/lutte\/?p=64548"},"modified":"2022-02-07T15:19:23","modified_gmt":"2022-02-07T20:19:23","slug":"plusieurs-congedies-de-la-wwe-etaient-en-action-un-luchador-a-impact-et-plus","status":"publish","type":"post","link":"https:\/\/www.jdx.info\/lutte\/2022\/02\/07\/plusieurs-congedies-de-la-wwe-etaient-en-action-un-luchador-a-impact-et-plus\/","title":{"rendered":"Plusieurs Cong\u00e9di\u00e9s de la WWE \u00c9taient En Action \/ Un Luchador \u00e0 Impact, et Plus!"},"content":{"rendered":"\n<p>Au Mexique, Laredo Kid fait partie du Top 10 des luchadors du pays o\u00f9 il \u00e9volue principalement \u00e0 la AAA sans pour autant \u00eatre sign\u00e9. Le high-flyer masqu\u00e9 est \u00e9galement tr\u00e8s demand\u00e9 aux USA lors des Lucha Libre shows ou lorsque que les promotions Indy ont besoin d&rsquo;un mexicain sur la carte. Depuis le mois d\u2019ao\u00fbt dernier, Laredo Kid est \u00e9galement un r\u00e9gulier d&rsquo;Impact Wrestling. Alors que jusqu&rsquo;ici il \u00e9tait pens\u00e9 que le mexicain \u00e9tait toujours agent libre, le principal concern\u00e9 vient de r\u00e9v\u00e9ler dans une interview \u00eatre sous contrat. Le lutteur de 35 ans n&rsquo;a cependant pas pr\u00e9cis\u00e9 depuis quand.<\/p>\n\n\n\n<center><p><script async=\"\" src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script>\n<ins class=\"adsbygoogle\" style=\"display:block; text-align:center;\" data-ad-layout=\"in-article\" data-ad-format=\"fluid\" data-ad-client=\"ca-pub-1986975368136072\" data-ad-slot=\"7818521013\"><\/ins>\n<script>\n     (adsbygoogle = window.adsbygoogle || []).push({});\n<\/script><\/p><\/center>\n\n\n\n<p>Le 4 novembre dernier, la WWE a fait une franche coupe dans son roster principal en lib\u00e9rant bon nombre de lutteurs comme Nia Jax. Tout ce monde \u00e9tant soumis \u00e0 la clause de non-comp\u00e9tition de 90 jours, cela signifiait que les lutteurs \u00e9taient libres \u00e0 compter du milieu de la semaine derni\u00e8re de se booker o\u00f9 bon leur voulait plusieurs d&rsquo;entre-eux n&rsquo;ont ainsi pas perdu de temps.<\/p>\n\n\n\n<p><strong>Killer Kross<\/strong>&nbsp;a ainsi \u00e9t\u00e9 le plus actif. Vendredi soir il a fait son retour dans son ancienne promotion de la FSW dans le Nevada o\u00f9 il est tout de suite devenu Mecca Champion. Le lendemain avec sa conjointe&nbsp;<strong>Scarlett Bordeaux<\/strong>, ils \u00e9taient tous les deux en action dans le New Jersey pour chacun une victoire contre Flip Gordon et Harley Cameron.<\/p>\n\n\n\n<p>La Lucha House party \u00e9tait \u00e9galement en action &#8230; mais s\u00e9par\u00e9ment. Vendredi soir, Gran metalik sous son ancien nom de&nbsp;<strong>Mascara Dorada<\/strong>&nbsp;a pris part \u00e0 un 4-Way lors d&rsquo;un show au Texas de la GCW. Le lendemain, son ancien co\u00e9quipier&nbsp;<strong>Lince Dorado<\/strong>&nbsp;a lui fait son retour \u00e0 la CZW pour un match par \u00e9quipe perdu dans le Maryland.<\/p>\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>Au Mexique, Laredo Kid fait partie du Top 10 des luchadors du pays o\u00f9 il \u00e9volue principalement \u00e0 la AAA sans pour autant \u00eatre sign\u00e9. Le high-flyer masqu\u00e9 est \u00e9galement tr\u00e8s demand\u00e9 aux USA lors des Lucha Libre shows ou lorsque que les promotions Indy ont besoin d&rsquo;un mexicain sur la carte. Depuis le mois&#8230;<\/p>\n","protected":false},"author":4,"featured_media":64549,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[24,30,4,41],"tags":[],"ppma_author":[292],"class_list":["post-64548","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-aew-impact-njpw-roh","category-ex-wwe","category-news","category-tna-impact"],"authors":[{"term_id":292,"user_id":4,"is_guest":0,"slug":"jean","display_name":"Jean Vinnier","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/33aba0263fd870a0b487e0e079ff407e10e3997c9d2987cbcc0db0db2c5c75a9?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/64548","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/comments?post=64548"}],"version-history":[{"count":1,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/64548\/revisions"}],"predecessor-version":[{"id":64550,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/64548\/revisions\/64550"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media\/64549"}],"wp:attachment":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media?parent=64548"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/categories?post=64548"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/tags?post=64548"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/ppma_author?post=64548"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}