{"id":63862,"date":"2022-01-25T22:05:00","date_gmt":"2022-01-26T03:05:00","guid":{"rendered":"https:\/\/www.jdx.info\/lutte\/?p=63862"},"modified":"2022-01-26T07:43:46","modified_gmt":"2022-01-26T12:43:46","slug":"resultats-et-video-du-wwe-nxt-2-0-du-25-janvier-2022","status":"publish","type":"post","link":"https:\/\/www.jdx.info\/lutte\/2022\/01\/25\/resultats-et-video-du-wwe-nxt-2-0-du-25-janvier-2022\/","title":{"rendered":"R\u00e9sultats et Vid\u00e9o du WWE NXT 2.0 du 25 Janvier 2022!"},"content":{"rendered":"\n<ul class=\"wp-block-list\"><li><strong><a href=\"https:\/\/www.jdx.info\/lutte\/2022\/01\/25\/63845\/\" target=\"_blank\" rel=\"noreferrer noopener\">Pour voir ce WWE NXT, cliquez ici.<\/a><\/strong><\/li><\/ul>\n\n\n\n<p><strong>WWE NXT, Orlando, Floride, 25 janvier 2021<\/strong><\/p>\n\n\n\n<p>Les commentateurs sont Vic Joseph et Wade Barrett.<\/p>\n\n\n\n<p>&#8211; Le WWE NXT 2.0 d\u00e9marre avec Wes Lee et Nash Carter qui sont sur la sc\u00e8ne avec le troph\u00e9e Dusty Cup. Lee dit que l&rsquo;an dernier ils ont d\u00e9but\u00e9 au Dusty Cup et ils ont tout remport\u00e9. Carter emp\u00eache Lee de toucher la coupe pour \u00e9viter le malheur. Lee dit qu&rsquo;ils vont le remporter une seconde fois.<\/p>\n\n\n\n<p class=\"has-medium-font-size\"><strong>Premier tour Tournoi Dusty Rhodes<\/strong><\/p>\n\n\n\n<p><strong>MSK (Wes Lee et Nash Carter) vs Jacket Time (Kushida et Ikemen Jiro)<\/strong><\/p>\n\n\n\n<p>En fin de match, Kushida applique un Arm Bar sur Carter, mais il r\u00e9siste et le charge contre le coin. Lee prend la tag et ils font leur Blockbuster sur Kushida pour le compte de trois de Lee.<\/p>\n\n\n\n<p><em>Gagnants : MSK<\/em><\/p>\n\n\n\n<p>&#8211; Apr\u00e8s le combat, les deux \u00e9quipes se serrent la main.<\/p>\n\n\n\n<p>&#8211; En coulisse, Zoey Stark est avec Io Shirai pour discuter du tournoi Dusty Rhodes. Stark dit qu&rsquo;elle a d\u00e9but\u00e9 au tournoi f\u00e9minin qui approche. Elle travaille fort pour la r\u00e9habilitation de son genou, mais elle ne sera pas pr\u00eate au bon moment. Shirai doit trouver une nouvelle partenaire pour ajouter son nom au troph\u00e9e apr\u00e8s toutes ces ann\u00e9es \u00e0 NXT. Shirai dit qu&rsquo;elle ne veut pas un nouveau partenaire. Tiffany Stratton arrive et demande \u00e0 Stark si elle a trouv\u00e9 sa tenue au rayon des rabais. Shirai aura la chance de trouver une nouvelle partenaire apr\u00e8s sa d\u00e9faite.<\/p>\n\n\n\n<center><p><script async=\"\" src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script>\n<ins class=\"adsbygoogle\" style=\"display:block; text-align:center;\" data-ad-layout=\"in-article\" data-ad-format=\"fluid\" data-ad-client=\"ca-pub-1986975368136072\" data-ad-slot=\"7818521013\"><\/ins>\n<script>\n     (adsbygoogle = window.adsbygoogle || []).push({});\n<\/script><\/p><\/center>\n\n\n\n\n<p>&#8211; De retour suite \u00e0 la pause, on pr\u00e9sente une vid\u00e9o sur la rivalit\u00e9 entre Tony D&rsquo;Angelo et Cameron Grimes. Grimes dit que ce soir c&rsquo;est le moment de savoir qui est le meilleur entre les deux.<\/p>\n\n\n\n<p>&#8211; Sur le parking, Carmelo Hayes et Trick Williams arrivent avec la chanteuse OllieJayy.<\/p>\n\n\n\n<p>&#8211; On retrouve Legado Del Fantasma sur le ring. Santos Escobar dit que depuis l&rsquo;arriv\u00e9e de Bron Breakker chacun des catcheurs disent la m\u00eame chose. Ils veulent se moquer de son p\u00e8re, de son oncle ou de sa famille pour leur comp\u00e9tence en math\u00e9tique. Apr\u00e8s les blagues les gens disent \u00e0 quel point Bron Breakker sera une grande star ou ils osent m\u00eame dire que Breakker est d\u00e9j\u00e0 une star. Lui ne fera jamais \u00e7a. Depuis le d\u00e9part il dit la v\u00e9rit\u00e9, sa famille fonctionne ainsi. Il n&rsquo;est pas impressionn\u00e9 par Breakker ou sa famille. La v\u00e9rit\u00e9 est qu&rsquo;il n&rsquo;aime pas Breakker, il le m\u00e9prise. Il le m\u00e9prise pour la rapidit\u00e9 qu&rsquo;il est arriv\u00e9 ici, les chances qu&rsquo;il re\u00e7oit et surtout car il a remport\u00e9 le titre NXT avant lui. Breakker le rend malade en moins d&rsquo;un mois. La musique de Bron Breakker commence et il arrive sur le ring.<\/p>\n\n\n\n<p>Breakker dit qu&rsquo;il pense que Santos est un bon catcheur, mais il est ins\u00e9cure. Santos a besoin de deux gars et une fille. Sa famille lui a dit de r\u00e9gler le business en personne, mais la famille de Santos est le contraire. Escobar lui interdit de parler de sa famille. Breakker lui dit de se taire, le champion parle. Suffit de lancer le challenge et il accepte. Escobar dit que Breakker a une grande cible malgr\u00e9 qu&rsquo;il est seul. Il fait les choses \u00e0 son moment. Lorsqu&rsquo;il sera pr\u00eat, Breakker va le savoir. Escobar quitte le ring, Wilde et Mendoza veulent profiter de la distraction pour attaquer Breakker, mais il repousse les deux du ring !<\/p>\n\n\n\n<p>&#8211; En coulisse, on retrouve Boa qui explique qu&rsquo;il est impossible de contr\u00f4ler ses pouvoirs. Il ne comprend pas le feu qu&rsquo;il a allum\u00e9.<\/p>\n\n\n\n<p>&#8211; De retour, Solo arrive pour son match, il se fait directement attaqu\u00e9 par Boa dans le dos.<\/p>\n\n\n\n<p class=\"has-medium-font-size\"><strong>Falls Count Anywhere Match<\/strong><\/p>\n\n\n\n<p><strong>Solo Sikoa vs Boa<\/strong><\/p>\n\n\n\n<p>En fin de match, Sikoa et Boa s&rsquo;affrontent en bas du ring, Sikoa le repousse avec un Samoan Drop sur la table des commentateurs. Sikoa le couche sur une table en bas du ring et lui fait un Splash sur coin pour le compte de trois !<\/p>\n\n\n\n<p><em>Gagnant : Solo Sikoa<\/em><\/p>\n\n\n\n<p>&#8211; De retour, on retrouve Imperium qui explique que leur nom repr\u00e9sente le succ\u00e8s. Gunther dit qu&rsquo;il a \u00e9t\u00e9 nomm\u00e9 par son grand-p\u00e8re qui l&rsquo;a introduit au catch, mais cette \u00e9poque est termin\u00e9e. C&rsquo;est le moment de fermer la porte du pass\u00e9 et c&rsquo;est le moment d&rsquo;une nouvelle \u00e8re d&rsquo;un homme qui va infliger de la douleur et de la peur \u00e0 travers la WWE.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><strong>Duke Hudson vs Guru Raaj<\/strong><\/p>\n\n\n\n<p>\u00c0 la fin du combat, Hudson fait son Splash Mountain pour battre Raaj en moins de deux minutes.<\/p>\n\n\n\n<p><em>Gagnant : Duke Hudson<\/em><\/p>\n\n\n\n<p>&#8211; Apr\u00e8s le combat, Dante Chen arrive et dit qu&rsquo;il va lui donner le respect que Duke ne lui a pas donn\u00e9 la semaine derni\u00e8re. Il annonce qu&rsquo;il va l&rsquo;attaquer. Chen monte sur le ring et les deux \u00e9changent les coups, mais les officiels s\u00e9parent les deux. Duke en profite pour tacler la jambe de Chen et quitte le ring.<\/p>\n\n\n\n<p>&#8211; En coulisse, on retrouve McKenzie avec Persia Pirotta et Indi Hartwell. Pirotta dit qu&rsquo;elle aime bien le c\u00f4t\u00e9 agressif de Duke. Hartwell dit qu&rsquo;elle doit se concentrer sur leur match. Persia dit \u00e0 Mme Lumis qu&rsquo;elle va bien g\u00e9rer en route vers les titres. Kay Lee Ray arrive et dit que Mandy Rose repr\u00e9sente mal le titre. Elle veut le titre solo et elles les titres par \u00e9quipe, le prochain photoshoot de Toxic Attraction pourrait se faire sans les titres.<\/p>\n\n\n\n<center><p><script async=\"\" src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script>\n<ins class=\"adsbygoogle\" style=\"display:block; text-align:center;\" data-ad-layout=\"in-article\" data-ad-format=\"fluid\" data-ad-client=\"ca-pub-1986975368136072\" data-ad-slot=\"7818521013\"><\/ins>\n<script>\n     (adsbygoogle = window.adsbygoogle || []).push({});\n<\/script><\/p><\/center>\n\n\n\n\n<p>&#8211; De retour, en coulisse, McKenzie est avec la Legado Del Fantasma pour savoir pourquoi Escobar n&rsquo;a pas accept\u00e9 l&rsquo;offre de Breakker. Wilde dit que Breakker doit r\u00e9aliser ce qui arrive lorsqu&rsquo;on leur manque du respect. Escobar dit que Breakker a fait une erreur. Breakker devra affronter les deux contre un, \u00e0 moins que Breakker puisse se trouver un ami. C&rsquo;est un boulot bien seul \u00eatre champion de NXT. Lopez dit que c&rsquo;est int\u00e9ressant que Breakker dit qu&rsquo;il est le premier entr\u00e9 et le dernier sorti. Escobar dit qu&rsquo;ils vont rester un peu plus tard ce soir.<\/p>\n\n\n\n<p class=\"has-medium-font-size\"><strong>Six-Woman Tag Team Match<\/strong><\/p>\n\n\n\n<p><strong>Indi Hartwell, Persia Pirotta et Kay Lee Ray vs Mandy Rose, Gigi Dolin et Jacy Jayne<\/strong><\/p>\n\n\n\n<p>En fin de match, Lee Ray va se battre avec Rose en bas du ring et en coulisse. Dolin en profite pour faire un Inside Cradle sur Pirotta, mais elle r\u00e9siste. Pirotta enchaine avec un coup de pied et un TKO pour le compte de trois !<\/p>\n\n\n\n<p><em>Gagnantes : Indi Hartwell, Persia Pirotta et Kay Lee Ray<\/em><\/p>\n\n\n\n<p>&#8211; On voit une vid\u00e9o de pr\u00e9sentation sur Edris Enofe et Malik Blade qui sont heureux d&rsquo;\u00eatre en demi-finale du Dusty Rhodes. Enofe dit que le paris est que Blade devra inviter Mandy Rose pour sortir s&rsquo;ils vont en finale.<\/p>\n\n\n\n<p>&#8211; De retour, on voit Raquel Gonzalez en entrainement. Cora Jade arrive et lui demande si elle a r\u00e9fl\u00e9chi. Gonzalez dit que la r\u00e9ponse est toujours non. Jade demande c&rsquo;est quoi le probl\u00e8me, elle peut lever le m\u00eame poids s&rsquo;il faut. Est-ce que c&rsquo;est New Year&rsquo;s Evil le probl\u00e8me ? Gonzalez dit que non, elle a besoin de quelqu&rsquo;un qui peut se relever sans probl\u00e8me pour passer les \u00e9tapes du tournoi et ce n&rsquo;est pas Jade. Jade dit qu&rsquo;elle veut lui prouver. Les deux veulent se bousculer, mais elles sont s\u00e9par\u00e9es.<\/p>\n\n\n\n<p class=\"has-medium-font-size\"><strong>Premier tour Tournoi Dusty Rhodes <\/strong><\/p>\n\n\n\n<p><strong>Grizzled Young Veterans<em>&nbsp;(James Drake et Zack Gibson)<\/em>&nbsp;vs Andre Chase et Bodhi Hayward<\/strong><\/p>\n\n\n\n<p class=\"has-normal-font-size\">En fin de match, Hayward se fait distraire par Drake et Gibson en profite pour le frapper. Drake repousse Chase en bas du ring et ils font leur Double Code Breaker sur Hayward pour le compte de trois.<\/p>\n\n\n\n<p><em>Gagnants : Grizzled Young Veterans<\/em><\/p>\n\n\n\n<p>&#8211; Apr\u00e8s le combat, Von Wagner entre sur le ring pour attaquer Hayward ! Wagner le frappe et lui fait un Death Valley Driver et il en fait un autre \u00e0 Chase. Robert Stone arrive et remet un veston \u00e0 Wagner. Stone dit que Wagner n&rsquo;est plus suspendu et avec un nouveau manager !<\/p>\n\n\n\n<p>&#8211; On pr\u00e9sente une vid\u00e9o sur Grayson Waller. Waller dit que LA Knight croyait que Dexter Lumis allait faire le boulot, mais maintenant son \u00e9toile brille plus que jamais. Il a un grand homme et la plus grande star de Bollywood avec lui. Il est maintenant sa propre s\u00e9curit\u00e9. Il esp\u00e8re que Knight puisse bien lire l&rsquo;injonction pour ne pas finir en prison. Sinon Saurav va s&rsquo;occuper de lui.<\/p>\n\n\n\n<p>&#8211; De retour, les commentateurs annoncent que Odyssey Jones souffre d&rsquo;une blessure au tendon rotulien et qu&rsquo;il sera bient\u00f4t de retour.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><strong>Io Shirai vs Tiffany Stratton<\/strong><\/p>\n\n\n\n<p>En fin de match, Shirai frappe Stratton et lui fait un Running Knee. Shirai encha\u00eene avec une Slam et son Moonsault du coin pour le compte de trois.<\/p>\n\n\n\n<p><em>Gagnant : Io Shirai<\/em><\/p>\n\n\n\n<p>&#8211; En coulisse, on retrouve Diamond Mine. Malcolm Bivens dit que Gunther est un nom horrible. Il ne peut pas croire que ses parents l&rsquo;ont nomm\u00e9 ainsi. Il aurait pu aussi simplement se nommer IDIOT en caract\u00e8re majuscule. Ce n&rsquo;est pas important pour Diamond Mine le nom, ce n&rsquo;est pas un nouveau d\u00e9but pour Imperium, mais bien la fin puisque les Creed Brothers vont les arr\u00eater dans le tournoi. Roderick Strong va ensuite s&rsquo;occuper de Gunther. La semaine prochaine il lance le challenge pour un Six-Man Tag. Julius dit qu&rsquo;Imperium est seulement de beaux gars europ\u00e9ens. Strong dit que personne ne peut surpasser Diamond Mine. Les \u00e9v\u00e9nements de la semaine derni\u00e8re ne vont jamais se r\u00e9p\u00e9ter.<\/p>\n\n\n\n<p>&#8211; Carmelo Hayes et Trick Williams arrivent pour nous pr\u00e9senter OllieJayy. OllieJayy nous interpr\u00e8te le theme song de NXT sur le ring.<\/p>\n\n\n\n<center><p><script async=\"\" src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script>\n<ins class=\"adsbygoogle\" style=\"display:block; text-align:center;\" data-ad-layout=\"in-article\" data-ad-format=\"fluid\" data-ad-client=\"ca-pub-1986975368136072\" data-ad-slot=\"7818521013\"><\/ins>\n<script>\n     (adsbygoogle = window.adsbygoogle || []).push({});\n<\/script><\/p><\/center>\n\n\n\n\n<p>&#8211; En coulisse, Tony D&rsquo;Angelo dit qu&rsquo;il a entendu Grimes. Tout va s&rsquo;arr\u00eater lorsqu&rsquo;il va l&rsquo;\u00e9craser sur le ring.<\/p>\n\n\n\n<p>&#8211; De retour, en coulisse, Tiffany Stratton discute au t\u00e9l\u00e9phone pour se plaindre du r\u00e9sultat de son match. Wendy Choo la croise et lui dit que tout le monde perd contre Shirai, c&rsquo;est normal. Stratton lance le verre de Choo au sol et quitte.<\/p>\n\n\n\n<p class=\"has-medium-font-size\"><strong>Championnat Nord Americain<\/strong><\/p>\n\n\n\n<p><strong>Cameron Grimes vs Tony D&rsquo;Angelo<\/strong><\/p>\n\n\n\n<p>En fin de match, Grimes fait un Cross Body \u00e0 D&rsquo;Angelo du coin et le couvre, mais il r\u00e9siste. Grimes veut faire son Cave In, mais il quitte le ring. Pete Dunne en profite pour frapper d&rsquo;Angelo avec un b\u00e2ton. Grimes enchaine avec son Cave In pour le compte de trois.<\/p>\n\n\n\n<p><em>Gagnant : Cameron Grimes<\/em><\/p>\n\n\n\n<p>&#8211; En coulisse, on demande \u00e0 Bron Breakker qui sera son partenaire pour la semaine prochaine. Breakker commence \u00e0 expliquer qu&rsquo;il cherche, mais la Legado arrive pour le confronter. Tommaso Ciampa arrive de l&rsquo;autre c\u00f4t\u00e9 en faisant signe qu&rsquo;il sera son partenaire ! Le show se termine ainsi.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p> <li><strong><a rel=\"noreferrer noopener\" href=\"https:\/\/www.jdx.info\/lutte\/2022\/01\/25\/63845\/\" target=\"_blank\">Pour voir ce WWE NXT, cliquez ici.<\/a><\/strong><\/li> <\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><\/p>\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>Pour voir ce WWE NXT, cliquez ici. WWE NXT, Orlando, Floride, 25 janvier 2021 Les commentateurs sont Vic Joseph et Wade Barrett. &#8211; Le WWE NXT 2.0 d\u00e9marre avec Wes Lee et Nash Carter qui sont sur la sc\u00e8ne avec le troph\u00e9e Dusty Cup. Lee dit que l&rsquo;an dernier ils ont d\u00e9but\u00e9 au Dusty Cup&#8230;<\/p>\n","protected":false},"author":2,"featured_media":63876,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4,21],"tags":[],"ppma_author":[287],"class_list":["post-63862","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news","category-resultats"],"authors":[{"term_id":287,"user_id":2,"is_guest":0,"slug":"jason","display_name":"Jason Desc\u00f4teaux","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/f64adf6d13198c3a532c061cecd8672089a1e9a3d07c702dffe886a7e55a15eb?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/63862","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/comments?post=63862"}],"version-history":[{"count":1,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/63862\/revisions"}],"predecessor-version":[{"id":63877,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/63862\/revisions\/63877"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media\/63876"}],"wp:attachment":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media?parent=63862"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/categories?post=63862"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/tags?post=63862"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/ppma_author?post=63862"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}