{"id":63776,"date":"2022-01-24T09:53:45","date_gmt":"2022-01-24T14:53:45","guid":{"rendered":"https:\/\/www.jdx.info\/lutte\/?p=63776"},"modified":"2022-01-24T09:53:48","modified_gmt":"2022-01-24T14:53:48","slug":"mickie-james-veut-avoir-sa-ceinture-de-championne-et-sa-musique-dimpact-pour-le-royal-rumble-britt-baker-rend-hommage-a-jerry-lynn-cora-jade-dans-le-rumble-et-plus","status":"publish","type":"post","link":"https:\/\/www.jdx.info\/lutte\/2022\/01\/24\/mickie-james-veut-avoir-sa-ceinture-de-championne-et-sa-musique-dimpact-pour-le-royal-rumble-britt-baker-rend-hommage-a-jerry-lynn-cora-jade-dans-le-rumble-et-plus\/","title":{"rendered":"Mickie James veut avoir sa ceinture de championne et sa musique d&rsquo;iMPACT pour le Royal Rumble \/ Britt Baker rend hommage \u00e0 Jerry Lynn \/ Cora Jade dans le Rumble ? et Plus !"},"content":{"rendered":"\n<p><\/p>\n\n\n\n<p><\/p>\n\n\n\n<p>R\u00e9cemment invit\u00e9e dans le podcast My Mom\u2019s Baszment, Britt Baker s\u2019est confi\u00e9e au sujet de sa relation avec l\u2019ancien catcheur et aujourd\u2019hui coach et producteur \u00e0 la AEW, Jerry Lynn.\u00a0<\/p>\n\n\n\n<p><\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>\u201cAu cours de l&rsquo;ann\u00e9e derni\u00e8re, il a \u00e9t\u00e9 mon coach, mon principal coach. C&rsquo;est lui que je consulte pour tous les matchs, toutes mes promos, tout, il m&rsquo;a aid\u00e9, peut-\u00eatre plus que n&rsquo;importe qui d&rsquo;autre, l&rsquo;ann\u00e9e derni\u00e8re, \u00e0 lutter et \u00e0 m&rsquo;affirmer en tant que se donner sur le ring. C&rsquo;est un g\u00e9nie. Je l&rsquo;ai dit dans mon tweet, il est vraiment l&rsquo;une des armes secr\u00e8tes de la AEW, et si vous citez quelques-uns de vos matchs pr\u00e9f\u00e9r\u00e9s \u00e0 la AEW, il y a une grande chance qu&rsquo;il ait \u00e9t\u00e9 un coach ou qu&rsquo;il y ait contribu\u00e9. Il est tellement bon. Tout le monde aime travailler avec lui et il est amusant, il rend la lutte amusante. Il est tr\u00e8s l\u00e9ger, il raconte des affreuses blagues tout le temps, et c&rsquo;est comme une blague que vous devez entendre juste avant de passer le rideau.\u00a0\u00bb<\/p><\/blockquote>\n\n\n\n<center><blockquote class=\"twitter-tweet\"><p lang=\"en\" dir=\"ltr\">Last one, I promise! Having Jerry as my coach has been one of my favorite parts of 2021. Jerry is truly one of AEW\u2019s secret weapons and he\u2019s probably had a hand in most of your favorite matches. I owe so much of my growth as a wrestler to <a href=\"https:\/\/twitter.com\/itsjerrylynn?ref_src=twsrc%5Etfw\">@itsjerrylynn<\/a>. <br><br>New&#x1f447;&#x1f3fb;F\u2019n&#x1f447;&#x1f3fb;Show&#x1f447;&#x1f3fb; <a href=\"https:\/\/t.co\/Zp0qYMa2DT\">pic.twitter.com\/Zp0qYMa2DT<\/a><\/p>&mdash; Dr. Britt Baker, D.M.D. (@RealBrittBaker) <a href=\"https:\/\/twitter.com\/RealBrittBaker\/status\/1481371495754604550?ref_src=twsrc%5Etfw\">January 12, 2022<\/a><\/blockquote> <script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script>\n\n<p><script async=\"\" src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script>\n<ins class=\"adsbygoogle\" style=\"display:block; text-align:center;\" data-ad-layout=\"in-article\" data-ad-format=\"fluid\" data-ad-client=\"ca-pub-1986975368136072\" data-ad-slot=\"7818521013\"><\/ins>\n<script>\n     (adsbygoogle = window.adsbygoogle || []).push({});\n<\/script><\/p><\/center>\n\n\n\n\n<p>Invit\u00e9e de l&rsquo;\u00e9mission El Brunch de WWE, Cora Jade  a r\u00e9v\u00e9l\u00e9 qu&rsquo;elle aimerait \u00eatre une entrante surprise du Royal Rumble cette ann\u00e9e.\u00a0<\/p>\n\n\n\n<p><\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>\u00ab\u00a0J\u2019adorerais \u00eatre dans le Royal Rumble, je suppose que nous verrons. C\u2019est d\u00e9finitivement un de mes pay-per-view pr\u00e9f\u00e9r\u00e9s surtout en grandissant, toutes les surprises sont toujours mes favorites. Le Rumble de 2020 \u00e9tait l\u2019un de mes pr\u00e9f\u00e9r\u00e9s parce qu\u2019Edge a fait son retour et je l&rsquo;adore. J\u2019\u00e9tais une grande fan d\u2019Edge en grandissant et je suis rest\u00e9e une grande fan aujourd&rsquo;hui donc c\u2019\u00e9tait un moment cool \u00e0 voir. J\u2019adorerais \u00eatre dans le Rumble, je suppose qu\u2019on ne le saura jamais avant d\u2019y \u00eatre, mais je sais qu\u2019ils ont des places libres. Je sais que beaucoup de femmes ont d\u00e9j\u00e0 \u00e9t\u00e9 annonc\u00e9es, mais il y a de la place pour quelques surprises donc j\u2019esp\u00e8re que je suis l\u2019une d\u2019entre elles.\u00a0\u00bb<\/p><\/blockquote>\n\n\n\n<p>Elle nous parle ensuite du titre qu&rsquo;elle irait chercher si elle remportait le prestigieux Rumble.&nbsp;<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>\u00ab\u00a0\u00c9videmment, le championnat f\u00e9minin NXT est dans ma t\u00eate en ce moment. Mais j\u2019adorerais \u00eatre championne f\u00e9minine de Raw ou SmackDown, peut-\u00eatre. Mais si c\u2019\u00e9tait le cas, et que j\u2019\u00e9tais dans le Royal Rumble et que je le gagnais, je choisirais sans doute Charlotte Flair, dont je suis une grande, grande fan. C\u2019est certainement un de mes matchs de r\u00eave, donc ce serait certainement quelque chose.\u00a0\u00bb<\/p><\/blockquote>\n\n\n\n<center><p><script async=\"\" src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script>\n<ins class=\"adsbygoogle\" style=\"display:block; text-align:center;\" data-ad-layout=\"in-article\" data-ad-format=\"fluid\" data-ad-client=\"ca-pub-1986975368136072\" data-ad-slot=\"7818521013\"><\/ins>\n<script>\n     (adsbygoogle = window.adsbygoogle || []).push({});\n<\/script><\/p><\/center>\n\n\n\n\n<p>Vous le savez, dans les noms contact\u00e9s par la WWE pour avoir droit \u00e0 une place au Royal Rumble 2022 se trouve Mickie James.\u00a0Elle,\u00a0contrairement aux IIconics\u00a0devenues IInspiration \u00e0 IMPACT Wrestling, n&rsquo;a pas refus\u00e9 la proposition de la f\u00e9d\u00e9ration. L&rsquo;actuelle championne Knockouts s&rsquo;est entretenue r\u00e9cemment avec Ariel Helwani pour discuter du deal venu tout droit de la fameuse porte interdite.<\/p>\n\n\n\n<p>Mickie James y d\u00e9voile qu&rsquo;elle est excit\u00e9e de repr\u00e9senter la division Knockouts d&rsquo;IMPACT Wrestling dans l&rsquo;un des \u00e9v\u00e8nements du Big Four de la WWE. Mais ira-t-elle sur le ring avec sa ceinture ? Mickie James r\u00e9pond :<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>&lt;&lt; Je l&rsquo;esp\u00e8re. J&rsquo;ai l&rsquo;intention de le faire. Elle m&rsquo;accompagne partout, alors oui. >><\/p><\/blockquote>\n\n\n\n<p>Mickie James esp\u00e8re \u00e9galement pouvoir faire son entr\u00e9e non pas avec la musique qu&rsquo;elle utilisait du c\u00f4t\u00e9 de la WWE, mais avec son actuel theme song \u00e0 IMPACT Wrestling qu&rsquo;elle a elle-m\u00eame compos\u00e9 avec\u00a0Serg Salinas. <\/p>\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>R\u00e9cemment invit\u00e9e dans le podcast My Mom\u2019s Baszment, Britt Baker s\u2019est confi\u00e9e au sujet de sa relation avec l\u2019ancien catcheur et aujourd\u2019hui coach et producteur \u00e0 la AEW, Jerry Lynn.\u00a0 \u201cAu cours de l&rsquo;ann\u00e9e derni\u00e8re, il a \u00e9t\u00e9 mon coach, mon principal coach. C&rsquo;est lui que je consulte pour tous les matchs, toutes mes promos,&#8230;<\/p>\n","protected":false},"author":609,"featured_media":63777,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[38,24,4,71,41,23],"tags":[],"ppma_author":[295],"class_list":["post-63776","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-aew","category-aew-impact-njpw-roh","category-news","category-royal-rumble","category-tna-impact","category-wwe"],"authors":[{"term_id":295,"user_id":609,"is_guest":0,"slug":"rodrigo","display_name":"Rodrigue Tousignant","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/51fe284bb6dbe8a6b4c2bf998ad658f4a9cd24b7e58f15ec85888070c7340ce6?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/63776","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/users\/609"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/comments?post=63776"}],"version-history":[{"count":1,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/63776\/revisions"}],"predecessor-version":[{"id":63778,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/63776\/revisions\/63778"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media\/63777"}],"wp:attachment":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media?parent=63776"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/categories?post=63776"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/tags?post=63776"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/ppma_author?post=63776"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}