{"id":63759,"date":"2022-01-23T18:12:49","date_gmt":"2022-01-23T23:12:49","guid":{"rendered":"https:\/\/www.jdx.info\/lutte\/?p=63759"},"modified":"2022-01-23T18:12:51","modified_gmt":"2022-01-23T23:12:51","slug":"les-iiconics-invitees-au-royal-rumble-impact-confirme","status":"publish","type":"post","link":"https:\/\/www.jdx.info\/lutte\/2022\/01\/23\/les-iiconics-invitees-au-royal-rumble-impact-confirme\/","title":{"rendered":"Les Iiconics invit\u00e9es au Royal Rumble, iMPACT confirme!"},"content":{"rendered":"\n<p>Comme vous le savez, Mickie James a accept\u00e9 de participer au Royal Rumble 2022 apr\u00e8s avoir \u00e9t\u00e9 renvoy\u00e9e de la WWE en 2021 et \u00eatre devenue champion des Knockouts du c\u00f4t\u00e9 d&rsquo;IMPACT Wrestling, d&rsquo;autres personnes ont quant \u00e0 elles refus\u00e9 de revenir dans la compagnie le temps d&rsquo;un soir.<\/p>\n\n\n\n<p>C&rsquo;est ce que nous d\u00e9voile notre source qu&rsquo;en effet la WWE a contact\u00e9 d&rsquo;autres Superstars ayant \u00e9t\u00e9 lib\u00e9r\u00e9es de leur contrat au cours des deux derni\u00e8res ann\u00e9es pour le Royal Rumble.\u00a0Les IIconics maintenant The Iinspiration \u00e0 Impact Wrestling, ont re\u00e7u une offre de la WWE leur \u00eatre propos\u00e9e afin de participer au Royal Rumble 2022. En revanche, Cassie Lee (Peyton Royce) et Jessie McKay (Billie Kay) ont pr\u00e9f\u00e9r\u00e9 refuser la demande.<\/p>\n\n\n\n<p>Les actuelles championnes par \u00e9quipe des Knockouts pensent que\u00a0ce n&rsquo;est pas encore le bon moment afin de faire un quelconque retour \u00e0 la WWE\u00a0car elles sont aujourd&rsquo;hui heureuses de leur parcours. <\/p>\n\n\n\n<center><p><script async=\"\" src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script>\n<ins class=\"adsbygoogle\" style=\"display:block; text-align:center;\" data-ad-layout=\"in-article\" data-ad-format=\"fluid\" data-ad-client=\"ca-pub-1986975368136072\" data-ad-slot=\"7818521013\"><\/ins>\n<script>\n     (adsbygoogle = window.adsbygoogle || []).push({});\n<\/script><\/p><\/center>\n\n\n\n\n<p>Contact\u00e9 par nos coll\u00e8gues am\u00e9ricains, IMPACT Wrestling a avou\u00e9 que cette apparition au Royal Rumble aurait \u00e9t\u00e9 sign\u00e9e et approuv\u00e9e par la promotion et que la WWE travaillait bien sur un accord similaire \u00e0 celui de Mickie James.<\/p>\n\n\n\n<p>Il se dit pour finir que\u00a0la WWE a pris contact avec d&rsquo;autres personnes renvoy\u00e9es depuis 2020 pour le Royal Rumble, en plus de Mickie James et The IInspiration. <\/p>\n\n\n\n<p>Aucun nom n&rsquo;a encore fuit\u00e9. On en saura probablement plus d&rsquo;ici l&rsquo;\u00e9v\u00e8nement qui aura lieu ce samedi 29 janvier.<\/p>\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>Comme vous le savez, Mickie James a accept\u00e9 de participer au Royal Rumble 2022 apr\u00e8s avoir \u00e9t\u00e9 renvoy\u00e9e de la WWE en 2021 et \u00eatre devenue champion des Knockouts du c\u00f4t\u00e9 d&rsquo;IMPACT Wrestling, d&rsquo;autres personnes ont quant \u00e0 elles refus\u00e9 de revenir dans la compagnie le temps d&rsquo;un soir. C&rsquo;est ce que nous d\u00e9voile notre&#8230;<\/p>\n","protected":false},"author":4,"featured_media":63760,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[24,4,71,41,23],"tags":[],"ppma_author":[292],"class_list":["post-63759","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-aew-impact-njpw-roh","category-news","category-royal-rumble","category-tna-impact","category-wwe"],"authors":[{"term_id":292,"user_id":4,"is_guest":0,"slug":"jean","display_name":"Jean Vinnier","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/33aba0263fd870a0b487e0e079ff407e10e3997c9d2987cbcc0db0db2c5c75a9?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/63759","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/comments?post=63759"}],"version-history":[{"count":1,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/63759\/revisions"}],"predecessor-version":[{"id":63761,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/63759\/revisions\/63761"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media\/63760"}],"wp:attachment":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media?parent=63759"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/categories?post=63759"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/tags?post=63759"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/ppma_author?post=63759"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}