{"id":63208,"date":"2022-01-07T23:44:33","date_gmt":"2022-01-08T04:44:33","guid":{"rendered":"https:\/\/www.jdx.info\/lutte\/?p=63208"},"modified":"2022-01-07T23:44:37","modified_gmt":"2022-01-08T04:44:37","slug":"plusieurs-legendes-annoncees-pour-le-royal-rumble-la-championne-dimpact-wrestling-egalement-dans-le-match-la-compagnie-reagit","status":"publish","type":"post","link":"https:\/\/www.jdx.info\/lutte\/2022\/01\/07\/plusieurs-legendes-annoncees-pour-le-royal-rumble-la-championne-dimpact-wrestling-egalement-dans-le-match-la-compagnie-reagit\/","title":{"rendered":"Plusieurs L\u00e9gendes Annonc\u00e9es pour le Royal Rumble! \/ La Championne d&rsquo;Impact Wrestling \u00e9galement dans le match, la compagnie r\u00e9agit!"},"content":{"rendered":"\n<p>Il ne reste maintenant que trois semaines avant le\u00a0Royal Rumble\u00a0annuel, l&rsquo;\u00e9v\u00e8nement qui lancera la route vers WrestleMania 38. Nous y sommes maintenant habitu\u00e9s depuis 2018, deux Rumble Matchs auront lieu, le premier pour les hommes et le second pour les femmes.<\/p>\n\n\n\n<p>Tandis que la WWE annonce peu \u00e0 peu les participants du match masculin, la f\u00e9d\u00e9ration a d\u00e9voil\u00e9 pendant\u00a0SmackDown\u00a0plusieurs catcheuses qui prendront part \u00e0 la rencontre qui donne droit au championnat de son choix, dont quelques surprises.<\/p>\n\n\n\n<p>Les\u00a0<strong>Bella Twins<\/strong>\u00a0 reviendront sur le ring pour la premi\u00e8re fois depuis fin 2018. Elles ont d\u00e9j\u00e0 fait savoir qu&rsquo;elles souhaitaient revenir pour les titres par \u00e9quipe f\u00e9minins.<\/p>\n\n\n\n<p>Parmi les l\u00e9gendes, nous y trouvons\u00a0<strong>Michelle McCool<\/strong>\u00a0ou encore\u00a0<strong>Lita<\/strong>.\u00a0<strong>Kelly Kelly<\/strong>\u00a0et<strong>\u00a0Summer Rae<\/strong>\u00a0seront \u00e9galement de la partie. Rae n&rsquo;a fait que deux matchs depuis son d\u00e9part de la WWE durant l&rsquo;\u00e9t\u00e9 2016, un en 2018 et le second en 2019 en Australie.\u00a0<\/p>\n\n\n\n<p>Mais le nom le plus surprenant actuellement annonc\u00e9 revient \u00e0 Mickie James.\u00a0Renvoy\u00e9e par la WWE en avril 2021, elle avait fait parler d&rsquo;elle apr\u00e8s avoir montr\u00e9 \u00e0 ses fans qu&rsquo;elle avait re\u00e7u ses affaires dans&#8230; un sac poubelle. Elle est aujourd&rsquo;hui championne d&rsquo;Impact Wrestling et en charge de la division f\u00e9minine de la NWA, et la WWE \u00e0 notre grande surprise, a ouvert la fameuse porte interdite en invitant une catcheuse de la concurrence et le notant sur les r\u00e9seaux sociaux :<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p>Les autres participantes annonc\u00e9es sont: Rhea Ripley, Nikki ASH, Shotzi, Natalya, Dana Brooke, Carmella, Zelina Vega, Tamina, Aliyah, Naomi, Shayna Baszler ou encore l&rsquo;actuelle championne de SmackDown Charlotte Flair. Si cette derni\u00e8re l&#8217;emporte, elle pourra choisir son adversaire. Il reste encore 12 places<\/p>\n\n\n\n<center><blockquote class=\"twitter-tweet\"><p lang=\"en\" dir=\"ltr\">Impact Knockouts World Champion <a href=\"https:\/\/twitter.com\/MickieJames?ref_src=twsrc%5Etfw\">@MickieJames<\/a> will be in the <a href=\"https:\/\/twitter.com\/hashtag\/RoyalRumble?src=hash&amp;ref_src=twsrc%5Etfw\">#RoyalRumble<\/a> Match! <a href=\"https:\/\/twitter.com\/hashtag\/SmackDown?src=hash&amp;ref_src=twsrc%5Etfw\">#SmackDown<\/a> <a href=\"https:\/\/t.co\/TXH0jm6QgE\">pic.twitter.com\/TXH0jm6QgE<\/a><\/p>&mdash; WWE (@WWE) <a href=\"https:\/\/twitter.com\/WWE\/status\/1479630096495489026?ref_src=twsrc%5Etfw\">January 8, 2022<\/a><\/blockquote> <script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/center>\n\n\n\n<p> La WWE a visiblement d\u00e9cid\u00e9 d&rsquo;ouvrir 2022 en nous surprenant. Alors qu&rsquo;elle pr\u00e9sentait son premier\u00a0SmackDown\u00a0de l&rsquo;ann\u00e9e ce vendredi 7 janvier, la f\u00e9d\u00e9ration a annonc\u00e9 que\u00a0Mickie James participera au Royal Rumble  f\u00e9minin. <\/p>\n\n\n\n<p>Depuis son renvoi en avril 2021, elle est devenue championne Knockouts d&rsquo;Impact Wrestling en plus de diriger la division f\u00e9minine de la NWA. La WWE vient d&rsquo;ouvrir une porte qui \u00e9tait toujours rest\u00e9 ferm\u00e9e.<\/p>\n\n\n\n<p>Le directeur d&rsquo;Impact Wrestling, Scott D&rsquo;Amore, a r\u00e9agi \u00e0 la nouvelle en expliquant d&rsquo;o\u00f9 venait le partenariat entre Impact Wrestling et la WWE. Il d\u00e9voile que c&rsquo;est la f\u00e9d\u00e9ration de Vince McMahon qui cherchait \u00e0 avoir Mickie James pour son show, et Impact se dit toujours pr\u00eat \u00e0 travailler avec d&rsquo;autres compagnies majeures :<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>&lt;&lt; La WWE le voulait, Mickie le voulait et la philosophie d&rsquo;Impact Wrestling est de toujours travailler avec les autres promotions majeures afin de cr\u00e9er le buzz pour les fans. Tout est sign\u00e9 et convenu entre la WWE et Impact Wrestling.<\/p><p><strong>[&#8230;]<\/strong><\/p><p>Il n&rsquo;y a jamais eu un moment comme celui-ci pour \u00eatre fan de catch. En l&rsquo;espace de 12 mois, Impact Wrestling a travaill\u00e9 avec la NWA, AAA, NJPW, AEW et maintenant la WWE. Impact Wrestling est le lien de l&rsquo;\u00e8re de la Forbidden Door (porte interdite). >><\/p><\/blockquote>\n\n\n\n<p>Mickie James d\u00e9fendra son championnat Knockouts face \u00e0 Deonna Purrazzo lors de Hard to Kill ce samedi soir. Reste \u00e0 voir si elle arrivera au Royal Rumble avec la ceinture.<\/p>\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>Il ne reste maintenant que trois semaines avant le\u00a0Royal Rumble\u00a0annuel, l&rsquo;\u00e9v\u00e8nement qui lancera la route vers WrestleMania 38. Nous y sommes maintenant habitu\u00e9s depuis 2018, deux Rumble Matchs auront lieu, le premier pour les hommes et le second pour les femmes. Tandis que la WWE annonce peu \u00e0 peu les participants du match masculin, la&#8230;<\/p>\n","protected":false},"author":609,"featured_media":63209,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4,45,71,36,41,23],"tags":[],"ppma_author":[295],"class_list":["post-63208","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news","category-ppv-wwe","category-royal-rumble","category-smackdown","category-tna-impact","category-wwe"],"authors":[{"term_id":295,"user_id":609,"is_guest":0,"slug":"rodrigo","display_name":"Rodrigue Tousignant","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/51fe284bb6dbe8a6b4c2bf998ad658f4a9cd24b7e58f15ec85888070c7340ce6?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/63208","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/users\/609"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/comments?post=63208"}],"version-history":[{"count":1,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/63208\/revisions"}],"predecessor-version":[{"id":63210,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/63208\/revisions\/63210"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media\/63209"}],"wp:attachment":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media?parent=63208"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/categories?post=63208"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/tags?post=63208"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/ppma_author?post=63208"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}