{"id":63192,"date":"2022-01-08T14:09:00","date_gmt":"2022-01-08T19:09:00","guid":{"rendered":"https:\/\/www.jdx.info\/lutte\/?p=63192"},"modified":"2022-01-09T14:11:16","modified_gmt":"2022-01-09T19:11:16","slug":"mise-a-jour-sur-le-contrat-wwe-de-kairi-sane","status":"publish","type":"post","link":"https:\/\/www.jdx.info\/lutte\/2022\/01\/08\/mise-a-jour-sur-le-contrat-wwe-de-kairi-sane\/","title":{"rendered":"Mise \u00e0 jour sur le contrat WWE de Kairi Sane!"},"content":{"rendered":"\n<p>Kairi Sane deviendrait un agent libre de la WWE le mois prochain.<\/p>\n\n\n\n<p>Il a \u00e9t\u00e9 rapport\u00e9 en d\u00e9cembre, via le Wrestling Observer Newsletter, que le contrat WWE de Sane avait d\u00e9j\u00e0 expir\u00e9, mais on dit maintenant que l&rsquo;accord n&rsquo;expire qu&rsquo;en f\u00e9vrier.<\/p>\n\n\n\n<p>Sane voulait auparavant travailler sur une \u00e9mission Stardom au Japon, mais la WWE a rejet\u00e9 la demande.&nbsp;Si elle est int\u00e9ress\u00e9e, elle pourrait continuer \u00e0 travailler au Japon apr\u00e8s l&rsquo;expiration de son contrat avec la WWE et si les restrictions de voyage s&rsquo;am\u00e9liorent, elle pourrait travailler \u00e0 temps partiel pour AEW tout en vivant au Japon.&nbsp;Stardom voudrait ramener Sane dans l&rsquo;entreprise, mais on ne sait pas s&rsquo;il y a eu des discussions r\u00e9centes.<\/p>\n\n\n\n<p>La WWE aurait voulu renouveler le contrat de Sane et la faire revenir au catch, mais elle ne voulait pas vivre aux \u00c9tats-Unis et en raison de COVID-19, un arrangement o\u00f9 elle va et vient n&rsquo;\u00e9tait pas possible.<\/p>\n\n\n\n<p>Sane, qui a r\u00e9cemment annonc\u00e9 un \u00e9ventuel retour sur Twitter, a lanc\u00e9 un gymnase de fitness ouvert 24 heures sur 24 plus t\u00f4t cet hiver, appel\u00e9 PARA-FIT24, dans la r\u00e9gion de Shonan Enonshima au Japon.&nbsp;Elle a document\u00e9 le lancement du gymnase sur les r\u00e9seaux sociaux.<\/p>\n\n\n\n<p>Sane est retourn\u00e9e au Japon en 2020 pour \u00eatre avec son nouveau mari, mais a continu\u00e9 \u00e0 travailler pour la WWE en tant qu&rsquo;ambassadrice dans le pays.&nbsp;Elle a \u00e9galement fait quelques commentaires en japonais sur les \u00e9v\u00e9nements \u00e0 la carte de la WWE.&nbsp;Elle a initialement sign\u00e9 un contrat de trois ans avec la WWE en mars 2017 et a remport\u00e9 le Mae Young Classic 2017.&nbsp;Elle a lutt\u00e9 pour la derni\u00e8re fois en juillet 2020 et a annonc\u00e9 peu de temps apr\u00e8s son retour au Japon.&nbsp;Sane a quitt\u00e9 la comp\u00e9tition sur le ring en tant que championne f\u00e9minine NXT et championne par \u00e9quipe f\u00e9minine de la WWE.<\/p>\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>Kairi Sane deviendrait un agent libre de la WWE le mois prochain. Il a \u00e9t\u00e9 rapport\u00e9 en d\u00e9cembre, via le Wrestling Observer Newsletter, que le contrat WWE de Sane avait d\u00e9j\u00e0 expir\u00e9, mais on dit maintenant que l&rsquo;accord n&rsquo;expire qu&rsquo;en f\u00e9vrier. Sane voulait auparavant travailler sur une \u00e9mission Stardom au Japon, mais la WWE a&#8230;<\/p>\n","protected":false},"author":665,"featured_media":63250,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4,23],"tags":[],"ppma_author":[289],"class_list":["post-63192","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news","category-wwe"],"authors":[{"term_id":289,"user_id":665,"is_guest":0,"slug":"line","display_name":"Line Edmond","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/852de09636413c90cdaa278312f9ea5bc4396768745424755cb63d99a05989d0?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/63192","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/users\/665"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/comments?post=63192"}],"version-history":[{"count":2,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/63192\/revisions"}],"predecessor-version":[{"id":63251,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/63192\/revisions\/63251"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media\/63250"}],"wp:attachment":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media?parent=63192"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/categories?post=63192"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/tags?post=63192"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/ppma_author?post=63192"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}