{"id":62936,"date":"2022-01-01T01:02:00","date_gmt":"2022-01-01T06:02:00","guid":{"rendered":"https:\/\/www.jdx.info\/lutte\/?p=62936"},"modified":"2022-01-02T10:50:58","modified_gmt":"2022-01-02T15:50:58","slug":"backstage-news-et-notes-sur-la-situation-de-la-wwe-covid-19","status":"publish","type":"post","link":"https:\/\/www.jdx.info\/lutte\/2022\/01\/01\/backstage-news-et-notes-sur-la-situation-de-la-wwe-covid-19\/","title":{"rendered":"Backstage News et notes sur la situation de la WWE COVID-19"},"content":{"rendered":"\n<p>La WWE aurait inflig\u00e9 des amendes \u00e0 toute personne prise sans masque dans les coulisses.<\/p>\n\n\n\n<p>Une note COVID-19 a r\u00e9cemment \u00e9t\u00e9 publi\u00e9e au sein de l&rsquo;entreprise et il a \u00e9t\u00e9 d\u00e9cid\u00e9 que les masques sont obligatoires dans les coulisses \u00e0 tout moment, selon Wrestling Observer Radio.&nbsp;Des amendes seront inflig\u00e9es non seulement aux talents de la WWE, mais \u00e0 n&rsquo;importe qui dans les coulisses.<\/p>\n\n\n\n<p>Il a \u00e9galement \u00e9t\u00e9 dit que la WWE a recommand\u00e9, mais pas obligatoire, que tout le monde re\u00e7oive un rappel du vaccin COVID-19.<\/p>\n\n\n\n<p>Il a \u00e9t\u00e9 dit\u00a0plus t\u00f4t cette semaine\u00a0comment la WWE n&rsquo;exige plus de tests COVID-19.\u00a0On pense maintenant que la WWE suit les recommandations du CDC et raccourcit le temps de quarantaine de 10 \u00e0 5 jours, de sorte que ceux qui ont \u00e9t\u00e9 test\u00e9s positifs et ont manqu\u00e9 des \u00e9missions seraient disponibles pour le pay-per-view WWE Day 1 de samedi, \u00e0 condition que le test COVID-19 positif ait pris lieu samedi dernier ou plus t\u00f4t.\u00a0Un talent aurait besoin de deux tests n\u00e9gatifs sur des dits cons\u00e9cutifs, le premier test \u00e9tant autoris\u00e9 le cinqui\u00e8me jour, ce qui correspond essentiellement \u00e0 six jours au total.<\/p>\n\n\n\n<center><p><script async=\"\" src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script>\n<ins class=\"adsbygoogle\" style=\"display:block; text-align:center;\" data-ad-layout=\"in-article\" data-ad-format=\"fluid\" data-ad-client=\"ca-pub-1986975368136072\" data-ad-slot=\"7818521013\"><\/ins>\n<script>\n     (adsbygoogle = window.adsbygoogle || []).push({});\n<\/script><\/p><\/center>\n\n\n\n\n<p>Seth Rollins est le seul positif confirm\u00e9 au COVID-19 au moment de la r\u00e9daction de cet article.\u00a0Sur la base des changements intervenus dans les r\u00e9cents programmes de WWE TV et d&rsquo;\u00e9v\u00e9nements en direct, les principaux lutteurs suivants ont manqu\u00e9 des \u00e9missions la semaine derni\u00e8re \u2013 Rollins, WWE Champion Big E, RAW Women&rsquo;s Champion Becky Lynch, Bianca Belair, WWE Women&rsquo;s Tag Team Champion Queen Zelina Vega et peut-\u00eatre son partenaire Carmella, Bobby Lashley, le roi Xavier Woods, Erik, Austin Theory, Omos, le champion intercontinental de la WWE Shinsuke Nakamura et le champion universel de la WWE Roman Reigns.\u00a0<\/p>\n\n\n\n<p>Dans le cas de The Viking Raiders, ils ont tous les deux travaill\u00e9 pour l&rsquo;\u00e9v\u00e9nement en direct de dimanche \u00e0 Tampa et le spectacle de lundi \u00e0 Orlando, mais Erik a disparu pour le reste de la tourn\u00e9e.<\/p>\n\n\n\n<p>L&rsquo;\u00e9pisode WWE NXT de cette semaine a \u00e9galement connu des changements, car Brian Kendrick, Dexter Lumis et les champions f\u00e9minins par \u00e9quipe NXT Gigi Dolin et Jacy Jayne n&rsquo;apparaissaient pas comme annonc\u00e9.&nbsp;RAW Tag Team Champion Riddle n&rsquo;est pas non plus apparu en direct comme pr\u00e9vu \u00e0 l&rsquo;origine, mais est apparu via une vid\u00e9o avec WALTER pour le segment avec MSK et NXT Tag Team Champions Imperium.&nbsp;Il sera int\u00e9ressant de voir comment l&rsquo;\u00e9pisode NXT New Year&rsquo;s Evil de mardi prochain est affect\u00e9.<\/p>\n\n\n\n<p>En ce qui concerne les lutteurs retir\u00e9s des spectacles la semaine derni\u00e8re, certains n&rsquo;ont pas travaill\u00e9 comme annonc\u00e9 par mesure de pr\u00e9caution.\u00a0<\/p>\n\n\n\n<p>F4Wonline.com rapporte comment les responsables de la WWE ont not\u00e9 que tous les lutteurs absents des \u00e9missions de la semaine derni\u00e8re n&rsquo;ont pas \u00e9t\u00e9 test\u00e9s positifs pour COVID-19.\u00a0Certains ont \u00e9t\u00e9 retir\u00e9s des \u00e9v\u00e9nements en direct parce que la soci\u00e9t\u00e9 a l&rsquo;intention de ne pas risquer certaines personnes cl\u00e9s qui sont pr\u00e9vues pour le pay-per-view WWE Day 1 de samedi, comme Reigns.<\/p>\n\n\n\n<p>Restez \u00e0 l&rsquo;\u00e9coute pour plus.<\/p>\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>La WWE aurait inflig\u00e9 des amendes \u00e0 toute personne prise sans masque dans les coulisses. Une note COVID-19 a r\u00e9cemment \u00e9t\u00e9 publi\u00e9e au sein de l&rsquo;entreprise et il a \u00e9t\u00e9 d\u00e9cid\u00e9 que les masques sont obligatoires dans les coulisses \u00e0 tout moment, selon Wrestling Observer Radio.&nbsp;Des amendes seront inflig\u00e9es non seulement aux talents de la&#8230;<\/p>\n","protected":false},"author":665,"featured_media":62990,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4,23],"tags":[],"ppma_author":[289],"class_list":["post-62936","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news","category-wwe"],"authors":[{"term_id":289,"user_id":665,"is_guest":0,"slug":"line","display_name":"Line Edmond","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/852de09636413c90cdaa278312f9ea5bc4396768745424755cb63d99a05989d0?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/62936","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/users\/665"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/comments?post=62936"}],"version-history":[{"count":3,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/62936\/revisions"}],"predecessor-version":[{"id":62991,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/62936\/revisions\/62991"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media\/62990"}],"wp:attachment":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media?parent=62936"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/categories?post=62936"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/tags?post=62936"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/ppma_author?post=62936"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}