{"id":62507,"date":"2021-12-14T23:57:00","date_gmt":"2021-12-15T04:57:00","guid":{"rendered":"https:\/\/www.jdx.info\/lutte\/?p=62507"},"modified":"2021-12-17T07:06:52","modified_gmt":"2021-12-17T12:06:52","slug":"resultats-et-video-du-wwe-nxt-2-0-du-14-decembre-2021","status":"publish","type":"post","link":"https:\/\/www.jdx.info\/lutte\/2021\/12\/14\/resultats-et-video-du-wwe-nxt-2-0-du-14-decembre-2021\/","title":{"rendered":"R\u00e9sultats et Vid\u00e9o du WWE NXT 2.0 du 14 D\u00e9cembre 2021!"},"content":{"rendered":"\n<ul class=\"wp-block-list\"><li><a href=\"https:\/\/www.jdx.info\/lutte\/2021\/12\/14\/avant-gout-du-wwe-nxt-2-0-pour-le-14-novembre-2021\/\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>Pour voir ce WWE NXT 2.0, cliquez ici.<\/strong><\/a><\/li><\/ul>\n\n\n\n<p>WWE NXT, Orlando, Floride<\/p>\n\n\n\n<p>Les commentateurs sont Vic Joseph et Wade Barrett.<\/p>\n\n\n\n<p>&#8211; Le WWE NXT 2.0. d\u00e9bute avec des \u00e9v\u00e9nements de mardi dernier avec le d\u00e9part de Johnny Gargano. On voit Grayson Waller arriver au Performance Center et il se fait insulter par les fans.<\/p>\n\n\n\n<p>&#8211; Cameron Grimes arrive sur le ring et on voit une vid\u00e9o des \u00e9v\u00e9nements entre les deux.<\/p>\n\n\n\n<p class=\"has-medium-font-size\"><strong>No Holds Barred Match<\/strong><\/p>\n\n\n\n<p><strong>Cameron Grimes vs Duke Hudson<\/strong><\/p>\n\n\n\n<p>\u00c0 la fin du combat, Hudson sort le rasoir et se pr\u00e9pare, mais Grimes le surprend avec un coup de pied. Grimes enchaine avec un Rana et lui fait un Cave In sur une chaise pour le compte de trois.<\/p>\n\n\n\n<p><em>Gagnant : Cameron Grimes<\/em><\/p>\n\n\n\n<p>Apr\u00e8s le combat, Grimes retire la perruque d&rsquo;Hudson et c\u00e9l\u00e8bre avec.<\/p>\n\n\n\n<p>&#8211; En coulisse, McKenzie est avec Cora Jade pour avoir ses commentaires sur Dakota Kai. Jade dit qu&rsquo;elle est contente d&rsquo;avoir \u00e9t\u00e9 lib\u00e9r\u00e9e par le m\u00e9decin et elle est pr\u00eate. Dakota Kai arrive et dit que Jade se r\u00e9p\u00e8te encore. Elle s&rsquo;accroche aux gens qui sont talentueux et profite de leur succ\u00e8s. Peut-\u00eatre qu&rsquo;elles vont gagner le Dusty Cup. Jade dit qu&rsquo;elle n&rsquo;a pas besoin de ses conseils, apr\u00e8s sa victoire ce soir elle sera encore plus pr\u00e8s d&rsquo;un match de titre contre Mandy.<\/p>\n\n\n\n<p>&#8211; De retour suite \u00e0 la pause, on retrouve Josh Briggs et Brooks Jensen \u00e0 l&rsquo;ext\u00e9rieur. Les deux se pr\u00e9parent \u00e0 aller \u00e0 une f\u00eate avec Kacy Catanzaro et Kayden Carter. Les quatre vont danser au festival et s&rsquo;amusent.<\/p>\n\n\n\n<p>&#8211;&nbsp;<strong>Grayson Waller<\/strong>&nbsp;arrive sur le ring sous les hu\u00e9es et prend le micro. Waller dit que c&rsquo;\u00e9tait un beau speech, on ne peut pas \u00e9chouer si on parie sur soit m\u00eame. Il a eu la larme \u00e0 l&rsquo;oeil. Johnny Gargano voulait parler du futur, parler de sa femme et remercier ses fans. La semaine derni\u00e8re il a exactement fait ce qu&rsquo;il a dit. Il avait toutes les vues, c&rsquo;est ce qui arrive lorsqu&rsquo;on parie sur soit m\u00eame. La foule lui chante de se taire, mais Waller nous montre des images de son attaque sur Gargano mardi dernier. Waller dit qu&rsquo;il a confirm\u00e9 qu&rsquo;il est LA Superstar de NXT apr\u00e8s avoir saut\u00e9 de la cage de NXT et ensuite termin\u00e9 la carri\u00e8re d&rsquo;une l\u00e9gende. Il a pass\u00e9 un beau weekend avec des stars pendant que nous on a fait la m\u00eame chose que d&rsquo;habitude, soit se plaindre de quelqu&rsquo;un de meilleur. Waller pr\u00e9sente des Tweets des fans et on voit un Tweet de Wade Barrett. Waller dit que ce n&rsquo;est plus 2010, Barrett n&rsquo;est plus important. Waller dit qu&rsquo;il a attaqu\u00e9 le meilleur ami de Vic Joseph devant le monde entier et il n&rsquo;a rien fait. \u00c7a montre quel genre d&rsquo;homme est Joseph.&nbsp;<strong>Il n&rsquo;a pas besoin d&rsquo;amis, de famille ou des fans. La seule chose dont il a besoin pour aller au top de l&rsquo;industrie est Grayson Waller<\/strong>.<\/p>\n\n\n\n<p>&#8211; On pr\u00e9sente une vid\u00e9o sur MSK qui avait d\u00e9couvert Matt Riddle comme Shaman la semaine derni\u00e8re. La suite ce soir.<\/p>\n\n\n\n<p>&#8211; En coulisse, Malcolm Bivens dit que Diamond Mine est l\u00e0 pour les gros matchs et \u00e7a se poursuit avec Bron Breakker ce soir. Breakker n&rsquo;est pas LE champion de NXT et Strong va le remettre \u00e0 sa place. Strong dit qu&rsquo;il va battre Breakker par lui-m\u00eame.<\/p>\n\n\n\n<p>&#8211; De retour, c&rsquo;est le moment du talkshow \u00a0\u00bbLashing Out\u00a0\u00bb avec Lash Legend. Legend dit qu&rsquo;elle a deux invit\u00e9s ce soir avec Kushida et Ikemen Jiro. Jiro dit qu&rsquo;ils sont de grands fans de Lash, ils sont heureux d&rsquo;\u00eatre ici. Ils discutent de leur style \u00a0\u00bbStyle Strong\u00a0\u00bb. Legend demande ce qui se passe avec eux contre les Grizzled Young Veterans. Kushida dit qu&rsquo;ils ont \u00e9t\u00e9 attaqu\u00e9s la semaine derni\u00e8re et ce soir ils vont nettoyer le sol avec GYV.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><strong>Amari Miller vs Ivy Nile<em>&nbsp;accompagn\u00e9 de Malcolm Bivens<\/em><\/strong><\/p>\n\n\n\n<p>\u00c0 la fin du combat, Nile applique son Dragon Sleeper sur Miller pour la faire taper.<\/p>\n\n\n\n<p><em>Gagnante : Ivy Nile&nbsp;via <\/em><\/p>\n\n\n\n<p>&#8211; En coulisse, McKenzie demande \u00e0 Xyon Quinn ses commentaires au sujet des intentions de Elektra Lopez. Quinn dit qu&rsquo;il connait maintenant les r\u00e8gles avec lesquelles Lopez veut jouer et le jeu commence ! Robert Stone arrive et dit que \u00e7a suffit ce manque de respect de McKenzie et des autres. \u00c0 partir de maintenant les gens vont le prendre au s\u00e9rieux. Von Wagner arrive et dit que la semaine derni\u00e8re n&rsquo;\u00e9tait que le d\u00e9but et la semaine prochaine il va continuer d&rsquo;\u00e9craser des t\u00eates car il le peut. Si on a un probl\u00e8me avec \u00e7a il faut venir lui dire.<\/p>\n\n\n\n<p>&#8211; En coulisse, Joe Gacy dit que c&rsquo;est le moment d&rsquo;Harland. Il n&rsquo;a pas besoin d&rsquo;avoir peur de qui il est.<\/p>\n\n\n\n<center><p><script async=\"\" src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script>\n<ins class=\"adsbygoogle\" style=\"display:block; text-align:center;\" data-ad-layout=\"in-article\" data-ad-format=\"fluid\" data-ad-client=\"ca-pub-1986975368136072\" data-ad-slot=\"7818521013\"><\/ins>\n<script>\n     (adsbygoogle = window.adsbygoogle || []).push({});\n<\/script><\/p><\/center>\n\n\n\n<p>&#8211; De retour, en coulisse,&nbsp;<strong>on retrouve MSK avec Riddle le Shaman<\/strong>. Riddle dit que le Shaman-Bro veut savoir ce qu&rsquo;ils ont dans leur sac. Riddle sort des batteries, lunette et autres objets pour finalement sortir une batte de baseball, un c\u00f4ne de circulation et la ceinture des \u00c9tats-Unis de John Cena. Riddle dit que s&rsquo;ils veulent devenir champions par \u00e9quipe, ils doivent se concentrer sur une seule chose et c&rsquo;est de regagner les titres. MSK demande comment apprendre. Riddle sort sa trottinette du sac et dit que c&rsquo;est ce qui manquait \u00e0 MSK. Le trio quitte en trottinette.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><strong>Guru Raaj vs Harland&nbsp;<em>acc  Joe Gacy<\/em><\/strong><\/p>\n\n\n\n<p>Harland \u00e9crase Raaj au sol et lui porte des coups d&rsquo;avant-bras. Harland enchaine avec une Side Slam pour le compte de trois sur Raaj.<\/p>\n\n\n\n<p><strong>Gagnant : Harland<\/strong><\/p>\n\n\n\n<p>&#8211; Apr\u00e8s le combat, Gacy demande \u00e0 Harland s&rsquo;il se sent mieux. Harland fait signe que non. Harland s&rsquo;amuse \u00e0 \u00e9craser la t\u00eate de Raah \u00e0 plusieurs reprises, les officiels arrivent pour l&rsquo;arr\u00eater.<\/p>\n\n\n\n<p>&#8211; Sur le parking, LA Knight arrive en voiture et on lui demande sa r\u00e9action sur Grayson Waller. Knight dit que Waller c&rsquo;est le gars qui fait une demi-prise cool et il se pense g\u00e9nial. Mais c&rsquo;est bien lui qui ramasse toutes les femmes. Maintenant quelqu&rsquo;un doit aller aviser Waller qu&rsquo;il est \u00e0 sa recherche.<\/p>\n\n\n\n<p>&#8211; Cora Jade arrive sur le ring, mais Mandy Rose prend place avec les commentateurs.<\/p>\n\n\n\n<p>&#8211; De retour, Harland se fait escorter par les officiels, mais il attrape Brian Kendrick par le cou et le balance en bas des escaliers !<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><strong>Cora Jade vs Dakota Kai<\/strong><\/p>\n\n\n\n<p>\u00c0 la fin du combat, Kai va chercher sa pelle en bas du ring, mais l&rsquo;arbitre lui enl\u00e8ve. Jade en profite pour faire un Roll Up \u00e0 Kai pour le compte de trois.<\/p>\n\n\n\n<p><em>Gagnante : Cora Jade<\/em><\/p>\n\n\n\n<p>&#8211; Apr\u00e8s le combat, Kai est furieuse et porte un coup de pied \u00e0 Jade lorsqu&rsquo;elle se retourne. Kai reprend sa pelle, mais Raquel Gonzalez arrive pour la chasser du ring et la pourchasse en coulisse. Gigi Dolin et Jacy Jayne arrivent sur la sc\u00e8ne, mais Mandy Rose en profite pour frapper Jade dans le dos avec son titre f\u00e9minin !<\/p>\n\n\n\n<p>&#8211; En coulisse, Grayson Waller croise Tiffany Stratton et elle lui dit que son p\u00e8re l&rsquo;a avis\u00e9 qu&rsquo;il est une mauvaise personne. Io Shirai arrive et hurle sur Waller en japonais pour ensuite partir. Waller dit qu&rsquo;il pense que Shirai l&rsquo;aime bien.<\/p>\n\n\n\n<center><p><script async=\"\" src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script>\n<ins class=\"adsbygoogle\" style=\"display:block; text-align:center;\" data-ad-layout=\"in-article\" data-ad-format=\"fluid\" data-ad-client=\"ca-pub-1986975368136072\" data-ad-slot=\"7818521013\"><\/ins>\n<script>\n     (adsbygoogle = window.adsbygoogle || []).push({});\n<\/script><\/p><\/center>\n\n\n\n<p>&#8211; De retour, sur le parking, Gonzalez et Kai se font s\u00e9parer par les officiels.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><strong>Tony D&rsquo;Angelo vs Andre Chase<\/strong><\/p>\n\n\n\n<p>\u00c0 la fin du combat, D&rsquo;Angelo fait une Snap Suplex \u00e0 Chase et enchaine avec sa Fisherman Suplex pour le compte de trois sur Chase.<\/p>\n\n\n\n<p><em>Gagnant : Tony D&rsquo;Angelo<\/em><\/p>\n\n\n\n<p>&#8211; Apr\u00e8s le combat, D&rsquo;Angelo prend le micro et dit que depuis ses d\u00e9buts \u00e0 NXT il fait ce qu&rsquo;il a promis. Il a battu Andre Chase, \u00e0 WarGames il avait promis de prendre le prot\u00e8ge dents de Pete Dunne. La musique de Pete Dunne le coupe et il arrive. Dunne dit que D&rsquo;Angelo parle beaucoup pour quelqu&rsquo;un sans palmar\u00e8s. Dunne dit qu&rsquo;il va entrer sur le ring pour voir si D&rsquo;Angelo a la m\u00eame \u00e9nergie. D&rsquo;Angelo dit qu&rsquo;on dirait qu&rsquo;il manque quelque chose \u00e0 Dunne. Dunne dit qu&rsquo;il n&rsquo;est pas ici pour parler. D&rsquo;Angelo lui dit de se calmer, il a du business \u00e0 r\u00e9gler. D&rsquo;Angelo allait quitter le ring et veut le frapper dans le dos, mais Dunne le bloque et lui \u00e9tire un doigt.<\/p>\n\n\n\n<p>&#8211; En coulisse, Grayson Waller entre dans le vestiaire. Bron Breakker dit que Waller n&rsquo;est plus le bienvenu, il doit prendre ses affaires et partir. Waller prend sa valise et dit qu&rsquo;il aura son propre vestiaire.<\/p>\n\n\n\n<p>&#8211; De retour, en coulisse, Brian Kendrick se fait \u00e9valuer par le m\u00e9decin apr\u00e8s sa chute en bas de l&rsquo;escalier.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><strong>Boa vs Edris Enofe<\/strong><\/p>\n\n\n\n<p>\u00c0 la fin du combat, Boa fait un Round Kick \u00e0 Enofe et lui fait un compte de trois.<\/p>\n\n\n\n<p><em>Gagnant : Boa<\/em><\/p>\n\n\n\n<p>&#8211; En coulisse, Raquel Gonzalez dit que son histoire avec Dakota Kai doit se terminer. Elle doit an\u00e9antir Kai. Il faut terminer leur amiti\u00e9 o\u00f9 elle a commenc\u00e9, dans un Street Fight.<\/p>\n\n\n\n<p>&#8211; De retour, sur le parking, on voit Grayson Waller partir dans la voiture de LA Knight avec Tiffany Stratton. On voit ensuite que Knight est K.O. au sol.<\/p>\n\n\n\n<center><p><script async=\"\" src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script>\n<ins class=\"adsbygoogle\" style=\"display:block; text-align:center;\" data-ad-layout=\"in-article\" data-ad-format=\"fluid\" data-ad-client=\"ca-pub-1986975368136072\" data-ad-slot=\"7818521013\"><\/ins>\n<script>\n     (adsbygoogle = window.adsbygoogle || []).push({});\n<\/script><\/p><\/center>\n\n\n\n<p><strong>Jacket Time<em>&nbsp;(Ikemen Jiro et Kushida)<\/em>&nbsp;vs Grizzeld Young Veterans<em>&nbsp;(James Drake et Zack Gibson)<\/em><\/strong><\/p>\n\n\n\n<p>\u00c0 la fin du combat, Julius et Brutus Creed s&rsquo;approchent du ring et Kushida et Jiro en profitent pour se lancer en Moonsault sur leurs adversaires. Ils font ensuite une combinaison de Senton et Reverse DDT sur Drake pour le compte de trois.<\/p>\n\n\n\n<p><em>Gagnants : Jacket Time<\/em><\/p>\n\n\n\n<p>&#8211; En coulisse, Roderick Strong et Bivens vont vers le ring, Carmelo Hayes et Trick Williams l&rsquo;avise de ne pas \u00e9chouer. Bivens dit que eux auront peut-\u00eatre besoin de chance. On voit Dexter Lumis qui fait un dessin de Williams.<\/p>\n\n\n\n<p>&#8211; De retour, on confirme que Kai et Gonzalez vont s&rsquo;affronter dans un Street Fight la semaine prochaine. Les commentateurs annoncent que Cora Jade est bless\u00e9e une nouvelle fois \u00e0 l&rsquo;\u00e9paule, LA Knight est transport\u00e9 \u00e0 l&rsquo;h\u00f4pital apr\u00e8s son attaque et Brian Kendrick est d\u00e9j\u00e0 \u00e0 l&rsquo;h\u00f4pital pour soigner son cou.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><strong>Roderick Strong&nbsp;acc  Malcolm Bivens&nbsp;vs Bron Breakker<\/strong><\/p>\n\n\n\n<p>\u00c0 la fin du combat, Strong porte une s\u00e9rie de coups de pieds \u00e0 Breakker et se lance pour un coup de genou, mais Breakker l&rsquo;attrape et lui fait un Back Breaker. Breakker soul\u00e8ve Strong au dessus de sa t\u00eate et lui fait sa PowerSlam pour le compte de trois.<\/p>\n\n\n\n<p><em>Gagnant : Bron Breakker<\/em><\/p>\n\n\n\n<p> Apr\u00e8s le combat, Breakker c\u00e9l\u00e8bre sa victoire, mais Tommaso Ciampa arrive et lui fait son Willow Bell sur le titre de NXT ! Ciampa lui souhaite la re-bienvenue dans les profondeurs. Le show se termine ainsi.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p> <li><a rel=\"noreferrer noopener\" href=\"https:\/\/www.jdx.info\/lutte\/2021\/12\/14\/avant-gout-du-wwe-nxt-2-0-pour-le-14-novembre-2021\/\" target=\"_blank\"><strong>Pour voir ce WWE NXT 2.0, cliquez ici.<\/strong><\/a><\/li> <\/p>\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>Pour voir ce WWE NXT 2.0, cliquez ici. WWE NXT, Orlando, Floride Les commentateurs sont Vic Joseph et Wade Barrett. &#8211; Le WWE NXT 2.0. d\u00e9bute avec des \u00e9v\u00e9nements de mardi dernier avec le d\u00e9part de Johnny Gargano. On voit Grayson Waller arriver au Performance Center et il se fait insulter par les fans. &#8211;&#8230;<\/p>\n","protected":false},"author":4,"featured_media":62508,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[21],"tags":[],"ppma_author":[292],"class_list":["post-62507","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-resultats"],"authors":[{"term_id":292,"user_id":4,"is_guest":0,"slug":"jean","display_name":"Jean Vinnier","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/33aba0263fd870a0b487e0e079ff407e10e3997c9d2987cbcc0db0db2c5c75a9?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/62507","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/comments?post=62507"}],"version-history":[{"count":7,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/62507\/revisions"}],"predecessor-version":[{"id":62593,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/62507\/revisions\/62593"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media\/62508"}],"wp:attachment":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media?parent=62507"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/categories?post=62507"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/tags?post=62507"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/ppma_author?post=62507"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}