{"id":62423,"date":"2021-12-12T13:30:00","date_gmt":"2021-12-12T18:30:00","guid":{"rendered":"https:\/\/www.jdx.info\/lutte\/?p=62423"},"modified":"2021-12-12T20:34:29","modified_gmt":"2021-12-13T01:34:29","slug":"chris-jericho-est-sorti-de-lhopital-explication-sur-la-roh-qui-a-decide-de-faire-une-pause","status":"publish","type":"post","link":"https:\/\/www.jdx.info\/lutte\/2021\/12\/12\/chris-jericho-est-sorti-de-lhopital-explication-sur-la-roh-qui-a-decide-de-faire-une-pause\/","title":{"rendered":"Chris Jericho est sorti de l&rsquo;h\u00f4pital! \/ Explication sur la ROH qui a d\u00e9cid\u00e9 de faire une pause!"},"content":{"rendered":"\n<p>La star d&rsquo;AEW et ancien champion du monde de ROH, Jay Lethal, est r\u00e9cemment apparu sur Talk Is Jericho pour discuter d&rsquo;un large \u00e9ventail de sujets, notamment la franchise donnant son avis sur la pause de ROH et les raisons pour lesquelles il pense que la soci\u00e9t\u00e9 a d\u00e9cid\u00e9 de prendre cette d\u00e9cision en 2022. de l&rsquo;interview sont ci-dessous.<\/p>\n\n\n\n<p>Dit qu&rsquo;il a \u00e9t\u00e9 pris au d\u00e9pourvu lorsque ROH lui a parl\u00e9, ainsi qu&rsquo;\u00e0 la liste, de la pause&nbsp;:<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>\u00ab Compl\u00e8tement \u00e0 l&rsquo;improviste, et pour ne pas trop en donner \u2013 je ne sais pas qui je vais faire chier en en disant trop, mais nous avions re\u00e7u un e-mail annon\u00e7ant que nous allions avoir cette r\u00e9union Zoom et l&rsquo;e-mail semblait prometteur, du genre \u00ab\u00a0H\u00e9, nous avons un enregistrement qui arrive, nous allons discuter de 2022, des premi\u00e8res parties.\u00a0\u00bb\u00a0Alors nous nous sommes tous dit : &lsquo;Tr\u00e8s bien, c&rsquo;est exactement ce que nous voulions entendre.&rsquo;\u00a0Alors en entrant dans la r\u00e9union, je ne peux pas parler au nom de tout le monde, mais j&rsquo;ai \u00e9t\u00e9 d\u00e9finitivement pris au d\u00e9pourvu.<\/p><\/blockquote>\n\n\n\n<p>Sa r\u00e9flexion sur les raisons pour lesquelles ils ont d\u00e9cid\u00e9 de faire une pause et de r\u00e9inventer l&rsquo;entreprise en 2022&nbsp;:<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>\u00ab Il y a deux raisons, je pense.\u00a0Le principal est que pendant la pand\u00e9mie, ils ont fait de leur mieux pour prendre soin de tout le monde, ce que faisaient de nombreuses entreprises.\u00a0Beaucoup d&rsquo;entreprises prenaient soin de leur personnel, ne lib\u00e9raient pas trop de gens, payaient toujours tout le monde, ce qu&rsquo;elles ont fait.\u00a0Mais je pense qu&rsquo;ils ont essay\u00e9 d&rsquo;aller au-del\u00e0 et nous ont tous prot\u00e9g\u00e9s \u00e0 la maison tout en payant tout le monde.\u00a0Il n&rsquo;y a donc pas de spectacles, pas d&rsquo;argent qui rentre pendant presque toute l&rsquo;ann\u00e9e.\u00a0Ils ont fait du bon travail en essayant de nous prot\u00e9ger et de garder tout le monde en s\u00e9curit\u00e9, m\u00eame si tout le monde sur la liste \u00e9tait pr\u00eat \u00e0 aller voir ces spectacles.\u00a0Nous \u00e9tions tous dispos\u00e9s \u00e0 voyager, mais ils voulaient que nous restions \u00e0 la maison et que nous restions en s\u00e9curit\u00e9.\u00a0Je pense que cela nous met vraiment dans le rouge.\u00a0Les \u00e9missions que nous avons eues, je n&rsquo;en suis pas s\u00fbr,\u00a0mais le montant d&rsquo;argent que j&rsquo;ai entendu dire qu&rsquo;ils d\u00e9pensaient pour les tests et que tout le monde avait sa propre chambre et ce m\u00e9decin et ce m\u00e9decin et tous les cerceaux qu&rsquo;ils devaient traverser, j&rsquo;ai entendu dire que les chiffres \u00e9taient irr\u00e9els.\u00a0Je pense donc que c&rsquo;est la chose la plus importante qui nous a conduits \u00e0 cela.<\/p><\/blockquote>\n\n\n\n<p>Comment ils ont continu\u00e9 \u00e0 organiser des spectacles dans des ar\u00e8nes vides et \u00e0 ne pas g\u00e9n\u00e9rer trop de revenus&nbsp;:<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>\u00abOui, et ils nous prot\u00e9geaient toujours en faisant de ces \u00e9missions des \u00e9missions vides.\u00a0Donc, encore une fois, il n&rsquo;y a pas de revenus.\u00a0Dans ma t\u00eate, je ne peux pas penser \u00e0 l&rsquo;argent qui rentrait.<\/p><\/blockquote>\n\n\n\n<center><p><script async=\"\" src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script>\n<ins class=\"adsbygoogle\" style=\"display:block; text-align:center;\" data-ad-layout=\"in-article\" data-ad-format=\"fluid\" data-ad-client=\"ca-pub-1986975368136072\" data-ad-slot=\"7818521013\"><\/ins>\n<script>\n     (adsbygoogle = window.adsbygoogle || []).push({});\n<\/script><\/p><\/center>\n\n\n\n<p>Une grande histoire qui a circul\u00e9 au cours des derniers jours a \u00e9t\u00e9 l&rsquo;hospitalisation de la meilleure superstar de la AEW Chris Jericho qui lors d&rsquo;une tourn\u00e9e avec Fozzy, a contract\u00e9 une maladie non-covid qui a forc\u00e9 les spectacles \u00e0 \u00eatre annul\u00e9s et le dieu de la promo \u00e0 rechercher les meilleurs soins. <\/p>\n\n\n\n<p>Bonne nouvelle aujourd&rsquo;hui.\u00a0L&rsquo;ancien champion du monde AEW a publi\u00e9 une photo sur Twitter montrant qu&rsquo;il est sorti de l&rsquo;h\u00f4pital et semble \u00eatre en bonne sant\u00e9.\u00a0Il \u00e9crit : <\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>\u00ab De retour dans la rue\u2026 \u00bb<\/p><\/blockquote>\n\n\n\n<p>On ne sait pas actuellement si Fozzy poursuivra sa tourn\u00e9e maintenant que Jericho est en bonne sant\u00e9.&nbsp;Ils ont un dernier rendez-vous \u00e0 Londres (12 d\u00e9cembre)<\/p>\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>La star d&rsquo;AEW et ancien champion du monde de ROH, Jay Lethal, est r\u00e9cemment apparu sur Talk Is Jericho pour discuter d&rsquo;un large \u00e9ventail de sujets, notamment la franchise donnant son avis sur la pause de ROH et les raisons pour lesquelles il pense que la soci\u00e9t\u00e9 a d\u00e9cid\u00e9 de prendre cette d\u00e9cision en 2022&#8230;.<\/p>\n","protected":false},"author":665,"featured_media":62449,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[38,24,4,49],"tags":[],"ppma_author":[289],"class_list":["post-62423","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-aew","category-aew-impact-njpw-roh","category-news","category-roh"],"authors":[{"term_id":289,"user_id":665,"is_guest":0,"slug":"line","display_name":"Line Edmond","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/852de09636413c90cdaa278312f9ea5bc4396768745424755cb63d99a05989d0?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/62423","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/users\/665"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/comments?post=62423"}],"version-history":[{"count":2,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/62423\/revisions"}],"predecessor-version":[{"id":62450,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/62423\/revisions\/62450"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media\/62449"}],"wp:attachment":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media?parent=62423"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/categories?post=62423"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/tags?post=62423"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/ppma_author?post=62423"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}