{"id":62109,"date":"2021-11-30T20:58:26","date_gmt":"2021-12-01T01:58:26","guid":{"rendered":"https:\/\/www.jdx.info\/lutte\/?p=62109"},"modified":"2021-11-30T20:58:31","modified_gmt":"2021-12-01T01:58:31","slug":"vince-mcmahon-confirme-avoir-voulu-tabasser-un-intervieweur-americain","status":"publish","type":"post","link":"https:\/\/www.jdx.info\/lutte\/2021\/11\/30\/vince-mcmahon-confirme-avoir-voulu-tabasser-un-intervieweur-americain\/","title":{"rendered":"Vince McMahon confirme avoir voulu tabasser un intervieweur am\u00e9ricain!"},"content":{"rendered":"\n<p>En 2001, Vince McMahon a particip\u00e9 \u00e0 une c\u00e9l\u00e8bre interview lors du \u00a0\u00bbOn The Record\u00a0\u00bb de HBO qui \u00e9tait anim\u00e9 par Bob Costas.<\/p>\n\n\n\n<p>Une interview qui a \u00e9t\u00e9 produite \u00e0 un moment o\u00f9 la premi\u00e8re XFL s&rsquo;\u00e9croulait en terme d&rsquo;audiences et que le public se demandait si la ligue de football de Vince McMahon allait \u00eatre forc\u00e9e de fermer. L&rsquo;intervieweur a alors pos\u00e9 plusieurs questions \u00e0 Vince au sujet de son \u00e9chec et lui a formul\u00e9 des critiques touchant \u00e9galement \u00e0 la WWF (aujourd&rsquo;hui appel\u00e9 WWE) concernant la mort d&rsquo;Owen Hart ou l&rsquo;utilisation des femmes.<\/p>\n\n\n\n<p>\u00c0 plusieurs moments, on peut sentir la tension entre les deux hommes pour cette entrevue qui \u00e9tait en direct. Justement, dans le nouveau livre \u00a0\u00bbTinderbox: HBO\u2019s Ruthless Pursuit of New Frontiers\u00a0\u00bb \u00e9crit par James Andrew Miller, Vince McMahon et Bob Costas parlent de cette fameuse interview. Costas confirme qu&rsquo;il a tout de suite senti que c&rsquo;\u00e9tait un bon moment de t\u00e9l\u00e9vision et le producteur lui disait dans son oreillette de continuer. Du c\u00f4t\u00e9 de Vince McMahon, il confirme avoir voulu le tabasser :<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>\u00a0\u00bbL&rsquo;autre probl\u00e8me \u00e9tait que Bob est tellement provocateur. Pendant toute la s\u00e9quence, il agit comme s&rsquo;il est au-dessus de moi et m&rsquo;utilisait pour montrer \u00e0 quel point il \u00e9tait bon. J&rsquo;\u00e9tais assis l\u00e0, vraiment frustr\u00e9 et j&rsquo;ai commenc\u00e9 \u00e0 me dire que j&rsquo;aurais souhait\u00e9 qu&rsquo;il ne mesure pas 5 pieds et 140 livres&nbsp;<em>(1M52 et 64KG)<\/em>&nbsp;et que s\u2019il \u00e9tait \u00e0 6 pieds 5 et 295 livres&nbsp;<em>(1M98 et 134KG)<\/em>, il aurait m\u00e9rit\u00e9 que je le tabasse. J&rsquo;aurais vraiment pu leur donner un vrai bon moment de t\u00e9l\u00e9vision.\u00a0\u00bb<\/p><\/blockquote>\n\n\n\n<p>Costas mentionne que Vince McMahon a quitt\u00e9 le plateau en claquant la porte, ce qu&rsquo;il n&rsquo;avait jamais vu puisque la porte \u00e9tait tr\u00e8s lourde et il a r\u00e9alis\u00e9 \u00e0 ce moment-l\u00e0 la puissance du PDG de la WWE. Comme quoi, Bob Costas l&rsquo;a \u00e9chapp\u00e9 belle.<\/p>\n\n\n\n<p>Aujourd&rsquo;hui, on sait que la XFL a malheureusement \u00e9chou\u00e9 en 2001 et une seconde fois en 2020 \u00e0 cause du COVID-19, malgr\u00e9 un  qui deuxi\u00e8me essais qui \u00e9tait cette fois-ci prometteur. The Rock a rachet\u00e9 la XFL et il a pour intention de la relancer en 2023.<\/p>\n\n\n\n<center><iframe loading=\"lazy\" width=\"560\" height=\"315\" src=\"https:\/\/www.youtube.com\/embed\/oQGWhnA24SY\" title=\"YouTube video player\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><\/center>\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>En 2001, Vince McMahon a particip\u00e9 \u00e0 une c\u00e9l\u00e8bre interview lors du \u00a0\u00bbOn The Record\u00a0\u00bb de HBO qui \u00e9tait anim\u00e9 par Bob Costas. Une interview qui a \u00e9t\u00e9 produite \u00e0 un moment o\u00f9 la premi\u00e8re XFL s&rsquo;\u00e9croulait en terme d&rsquo;audiences et que le public se demandait si la ligue de football de Vince McMahon allait&#8230;<\/p>\n","protected":false},"author":4,"featured_media":62110,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4,23],"tags":[],"ppma_author":[292],"class_list":["post-62109","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news","category-wwe"],"authors":[{"term_id":292,"user_id":4,"is_guest":0,"slug":"jean","display_name":"Jean Vinnier","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/33aba0263fd870a0b487e0e079ff407e10e3997c9d2987cbcc0db0db2c5c75a9?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/62109","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/comments?post=62109"}],"version-history":[{"count":1,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/62109\/revisions"}],"predecessor-version":[{"id":62111,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/62109\/revisions\/62111"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media\/62110"}],"wp:attachment":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media?parent=62109"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/categories?post=62109"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/tags?post=62109"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/ppma_author?post=62109"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}