{"id":61821,"date":"2021-11-23T13:24:54","date_gmt":"2021-11-23T18:24:54","guid":{"rendered":"https:\/\/www.jdx.info\/lutte\/?p=61821"},"modified":"2021-11-23T13:24:56","modified_gmt":"2021-11-23T18:24:56","slug":"details-sur-lagresseur-de-seth-rollins-et-son-etat-de-sante","status":"publish","type":"post","link":"https:\/\/www.jdx.info\/lutte\/2021\/11\/23\/details-sur-lagresseur-de-seth-rollins-et-son-etat-de-sante\/","title":{"rendered":"D\u00e9tails sur l&rsquo;Agresseur de Seth Rollins, et son \u00e9tat de sant\u00e9!"},"content":{"rendered":"\n<p>Vous \u00eates surement au courant de l&rsquo;\u00e9v\u00e9nement hors contr\u00f4le \u00e0 RAW alors qu&rsquo;un fan s&rsquo;en est prit physiquement \u00e0 Seth Rollins alors qu&rsquo;il retournait au vestiaire. (<a href=\"https:\/\/www.jdx.info\/lutte\/2021\/11\/23\/un-fan-attaque-seth-rollins-pendant-raw-un-ancien-le-ridiculise\/\" target=\"_blank\" rel=\"noreferrer noopener\">d\u00e9tails ici<\/a>)<\/p>\n\n\n\n<p>Aujourd&rsquo;hui en ce lendemain de veille, Marc Raimondi de la cha\u00eene ESPN et TMZ nous donnent plus d&rsquo;informations sur la personne qui s&rsquo;en est prise \u00e0 Seth Rollins ainsi que s sant\u00e9. <\/p>\n\n\n\n<p>Premi\u00e8rement cet homme s&rsquo;appelle Elisah Spencer et il a 24 ans. Il est accus\u00e9 d&rsquo;une\u00a0tentative d&rsquo;agression et d&rsquo;une tentative de violation des arts ainsi que des affaires culturelles\u00a0(perturbation d&rsquo;un \u00e9v\u00e8nement sportif en direct), apr\u00e8s son attaque sur Seth Rollins \u00e0 RAW. Ce \u00ab\u00a0fan\u00a0\u00bb devra se pr\u00e9senter devant le tribunal le mois prochain.<\/p>\n\n\n\n<p>Concernant l&rsquo;ancien champion Universel,\u00a0il a subi un gonflement de sa l\u00e8vre et il a refus\u00e9 des soins m\u00e9dicaux\u00a0d&rsquo;apr\u00e8s la police.<\/p>\n\n\n\n<center><blockquote class=\"twitter-tweet\"><p lang=\"en\" dir=\"ltr\">Elisah Spencer, 24, has been charged with attempted assault and attempted violation of arts and cultural affairs (disrupting live sporting event) for his attack on WWE wrestler Seth Rollins during the Raw television show Monday night at Barclays Center in Brooklyn, per the NYPD.<\/p>&mdash; Marc Raimondi (@marc_raimondi) <a href=\"https:\/\/twitter.com\/marc_raimondi\/status\/1463045891208609793?ref_src=twsrc%5Etfw\">November 23, 2021<\/a><\/blockquote> <script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script>\n\n<p><script async=\"\" src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script>\n<ins class=\"adsbygoogle\" style=\"display:block; text-align:center;\" data-ad-layout=\"in-article\" data-ad-format=\"fluid\" data-ad-client=\"ca-pub-1986975368136072\" data-ad-slot=\"7818521013\"><\/ins>\n<script>\n     (adsbygoogle = window.adsbygoogle || []).push({});\n<\/script><\/p><\/center>\n\n\n\n\n<p>Bien heureusement, Seth Rollins n&rsquo;a pas \u00e9t\u00e9 gri\u00e8vement bless\u00e9 lors de l&rsquo;attaque. Il s&rsquo;en est d&rsquo;ailleurs amus\u00e9 lors de sa seconde apparition \u00e0 RAW plus tard dans le show :<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li><strong><a href=\"https:\/\/www.jdx.info\/lutte\/2021\/11\/22\/resultats-et-video-du-wwe-monday-night-raw-du-22-novembre-2021\/\" target=\"_blank\" rel=\"noreferrer noopener\">Pour les r\u00e9sultats complet ou voir RAW, cliquez ici.<\/a><\/strong><\/li><\/ul>\n\n\n\n<center><blockquote class=\"twitter-tweet\"><p lang=\"en\" dir=\"ltr\">Seth got a great sense of humor with what happened at least &#x1f602; <a href=\"https:\/\/t.co\/UfoN898QUz\">pic.twitter.com\/UfoN898QUz<\/a><\/p>&mdash; Frank got the BOOSTER &#x1f489; | LET\u2019S GO MAVS (@THENEXTBlGTHlNG) <a href=\"https:\/\/twitter.com\/THENEXTBlGTHlNG\/status\/1462992229228691458?ref_src=twsrc%5Etfw\">November 23, 2021<\/a><\/blockquote> <script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/center>\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>Vous \u00eates surement au courant de l&rsquo;\u00e9v\u00e9nement hors contr\u00f4le \u00e0 RAW alors qu&rsquo;un fan s&rsquo;en est prit physiquement \u00e0 Seth Rollins alors qu&rsquo;il retournait au vestiaire. (d\u00e9tails ici) Aujourd&rsquo;hui en ce lendemain de veille, Marc Raimondi de la cha\u00eene ESPN et TMZ nous donnent plus d&rsquo;informations sur la personne qui s&rsquo;en est prise \u00e0 Seth&#8230;<\/p>\n","protected":false},"author":4,"featured_media":61828,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4,43,23],"tags":[],"ppma_author":[292],"class_list":["post-61821","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news","category-raw-wwe","category-wwe"],"authors":[{"term_id":292,"user_id":4,"is_guest":0,"slug":"jean","display_name":"Jean Vinnier","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/33aba0263fd870a0b487e0e079ff407e10e3997c9d2987cbcc0db0db2c5c75a9?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/61821","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/comments?post=61821"}],"version-history":[{"count":1,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/61821\/revisions"}],"predecessor-version":[{"id":61829,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/61821\/revisions\/61829"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media\/61828"}],"wp:attachment":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media?parent=61821"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/categories?post=61821"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/tags?post=61821"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/ppma_author?post=61821"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}