{"id":61369,"date":"2021-11-17T23:09:37","date_gmt":"2021-11-18T04:09:37","guid":{"rendered":"https:\/\/www.jdx.info\/lutte\/?p=61369"},"modified":"2021-11-17T23:09:41","modified_gmt":"2021-11-18T04:09:41","slug":"cm-punk-a-des-reflexions-interessantes-sur-les-fans-de-catch-daujourdhui-un-hotel-different-par-respect-pour-eddie-guerrero","status":"publish","type":"post","link":"https:\/\/www.jdx.info\/lutte\/2021\/11\/17\/cm-punk-a-des-reflexions-interessantes-sur-les-fans-de-catch-daujourdhui-un-hotel-different-par-respect-pour-eddie-guerrero\/","title":{"rendered":"CM Punk a des r\u00e9flexions int\u00e9ressantes sur les fans de catch d&rsquo;aujourd&rsquo;hui \/ Un H\u00f4tel Diff\u00e9rent par Respect pour Eddie Guerrero!"},"content":{"rendered":"\n<p>Le pay-per-view AEW Full Gear de samedi a vu CM Punk battre Eddie Kingston dans un match aller-retour brutal.&nbsp;Punk a particip\u00e9 \u00e0 la m\u00eal\u00e9e m\u00e9diatique post-spectacle et a d\u00e9clar\u00e9 qu&rsquo;il ne pensait plus qu&rsquo;il y avait de fans de catch occasionnels.<\/p>\n\n\n\n<p>Punk a parl\u00e9 du nombre de fans qu&rsquo;il a amen\u00e9s de la WWE et de ce qu&rsquo;il reconna\u00eet le plus dans la base de fans de la AEW.\u00a0Punk a l&rsquo;impression qu&rsquo;il a lutt\u00e9 devant des fans qu&rsquo;il avait l&rsquo;habitude de voir avant d&rsquo;arriver \u00e0 la WWE et ce sont des fans de catch, ce qui est appropri\u00e9 car AEW leur donne de la lutte.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>\u00ab\u00a0Je pense vraiment qu&rsquo;il y a un chevauchement. Je ne sais pas si tous ceux qui \u00e9taient fans de la WWE sont venus ici sp\u00e9cifiquement juste pour me regarder, mais ce que je reconnais devant un public de la AEW, c&rsquo;est un public devant lequel j&rsquo;avais l&rsquo;habitude de lutter avant d&rsquo;aller \u00e0 la WWE.\u00a0Ce sont des fans de catch Yanno et je ne comprendrai jamais la critique de faire appel \u00e0 votre base de fans.\u00a0Si c&rsquo;est notre base de fans, donnez-leur ce qu&rsquo;ils veulent et tout le monde sera content.<\/p><\/blockquote>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>\u00ab\u00a0Maintenant, je comprends la cr\u00e9ation d&rsquo;une entreprise, les gens parlent d&rsquo;essayer d&rsquo;avoir des occasionnels ici, je ne pense pas qu&rsquo;il y ait plus de fans de catch occasionnels.\u00a0Mon opinion, peut-\u00eatre que je me trompe et peut-\u00eatre que quelqu&rsquo;un chez TNT va se f\u00e2cher parce que je dis cela et je suis de cet avis, mais nos fans sont des fans de catch et nous leur donnons du catch.<\/p><\/blockquote>\n\n\n\n<center><p><script async=\"\" src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script>\n<ins class=\"adsbygoogle\" style=\"display:block; text-align:center;\" data-ad-layout=\"in-article\" data-ad-format=\"fluid\" data-ad-client=\"ca-pub-1986975368136072\" data-ad-slot=\"7818521013\"><\/ins>\n<script>\n     (adsbygoogle = window.adsbygoogle || []).push({});\n<\/script><\/p><\/center>\n\n\n\n\n<p>     <p>Et parlant de Full Gear, tout au long du spectacle, divers lutteurs ont rendu hommage au regrett\u00e9 grand Eddie Guerrero, d\u00e9c\u00e9d\u00e9 dans la m\u00eame ville au Marriott en 2005.\u00a0<\/p><\/p>\n\n\n\n<p><p>Le membre du Temple de la renomm\u00e9e de la WWE, Jim Ross, a r\u00e9v\u00e9l\u00e9 que la AEW avait sp\u00e9cifiquement s\u00e9journ\u00e9 dans un autre h\u00f4tel par respect pour ceux qui \u00e9taient amis avec Guerrerro.\u00a0<\/p>   <blockquote class=\"wp-block-quote\"><p>\u00ab L&rsquo;anniversaire d&rsquo;Eddie de sa mort, ironiquement \u00e0 Minneapolis, \u00e9tait samedi dernier alors que nous \u00e9tions tous en ville.\u00a0Il a \u00e9t\u00e9 port\u00e9 \u00e0 mon attention qu&rsquo;il est d\u00e9c\u00e9d\u00e9 au Marriott, \u00e0 un p\u00e2t\u00e9 de maisons de l&rsquo;endroit o\u00f9 nous avons s\u00e9journ\u00e9.\u00a0Je sais qu&rsquo;il a \u00e9t\u00e9 fait sp\u00e9cifiquement que nous ne devions pas s\u00e9journer au Marriott, car cela aurait \u00e9t\u00e9 un peu difficile \u00e0 avaler pour beaucoup de gens.\u00a0Nous avons s\u00e9journ\u00e9 dans un autre h\u00f4tel, toujours en centre-ville, Lowes, juste en face du Target Center, ce qui est magnifique car vous pouvez traverser la rue jusqu&rsquo;au b\u00e2timent.\u00a0Nous avons vraiment respect\u00e9 cela avec Eddie.\u00a0C&rsquo;est dr\u00f4le que beaucoup de talents aujourd&rsquo;hui respectent encore Eddie comme s&rsquo;il \u00e9tait vivant, toujours dans les vestiaires, toutes ces choses.\u00a0Cela montre un grand amour et un grand respect qu&rsquo;il a gagn\u00e9.\u00a0Nous nous sommes assur\u00e9s que Marriott n&rsquo;\u00e9tait pas dans l&rsquo;image.<\/p><\/blockquote>  <\/p>\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>Le pay-per-view AEW Full Gear de samedi a vu CM Punk battre Eddie Kingston dans un match aller-retour brutal.&nbsp;Punk a particip\u00e9 \u00e0 la m\u00eal\u00e9e m\u00e9diatique post-spectacle et a d\u00e9clar\u00e9 qu&rsquo;il ne pensait plus qu&rsquo;il y avait de fans de catch occasionnels. Punk a parl\u00e9 du nombre de fans qu&rsquo;il a amen\u00e9s de la WWE et&#8230;<\/p>\n","protected":false},"author":665,"featured_media":61438,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[38,24,30,4],"tags":[],"ppma_author":[289],"class_list":["post-61369","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-aew","category-aew-impact-njpw-roh","category-ex-wwe","category-news"],"authors":[{"term_id":289,"user_id":665,"is_guest":0,"slug":"line","display_name":"Line Edmond","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/852de09636413c90cdaa278312f9ea5bc4396768745424755cb63d99a05989d0?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/61369","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/users\/665"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/comments?post=61369"}],"version-history":[{"count":2,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/61369\/revisions"}],"predecessor-version":[{"id":61439,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/61369\/revisions\/61439"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media\/61438"}],"wp:attachment":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media?parent=61369"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/categories?post=61369"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/tags?post=61369"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/ppma_author?post=61369"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}