{"id":61115,"date":"2021-11-12T00:50:00","date_gmt":"2021-11-12T05:50:00","guid":{"rendered":"https:\/\/www.jdx.info\/lutte\/?p=61115"},"modified":"2021-11-12T12:01:55","modified_gmt":"2021-11-12T17:01:55","slug":"charlotte-flair-repond-a-becky-lynch-la-folle-idee-de-beth-phoenix-la-petite-soeur-de-brock-lesnar-et-plus","status":"publish","type":"post","link":"https:\/\/www.jdx.info\/lutte\/2021\/11\/12\/charlotte-flair-repond-a-becky-lynch-la-folle-idee-de-beth-phoenix-la-petite-soeur-de-brock-lesnar-et-plus\/","title":{"rendered":"Charlotte Flair r\u00e9pond \u00e0 Becky Lynch! \/ La folle id\u00e9e de Beth Phoenix la Petite Soeur de Brock Lesnar, et Plus!"},"content":{"rendered":"\n<p> Beth Phoenix  qui est aujourd&rsquo;hui commentatrice de NXT aux c\u00f4t\u00e9s de Wade Barrett et Vic Joseph, a rejoint la WWE en 2004 \u00e0 la Ohio Valley Wrestling, territoire de d\u00e9veloppement de la compagnie \u00e0 ce moment-l\u00e0. Et pour ses d\u00e9buts, la l\u00e9gende avait propos\u00e9 une storyline bien originale !<\/p>\n\n\n\n<p>C&rsquo;est la Hall of Famer elle-m\u00eame qui d\u00e9voile cette anecdote sur Twitter.\u00a0Beth Phoenix avait ainsi propos\u00e9 d&rsquo;\u00eatre la petite s\u0153ur de Brock Lesnar\u00a0! Elle avait soumis cette \u00ab\u00a0storyline d\u00e9taill\u00e9e\u00a0\u00bb \u00e0 Michael Hayes. Bien s\u00fbr, vous vous en doutez, cette storyline n&rsquo;a jamais vu le jour.<\/p>\n\n\n\n<p>Alors,\u00a0Beth Phoenix petite s\u0153ur de Brock Lesnar, cr\u00e9dible \u00e0 votre avis ?<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>Anecdote\u00a0: \u00e0 l&rsquo;un de mes premiers match en tant que<br>@WWE J&rsquo;ai pr\u00e9sent\u00e9 un sc\u00e9nario d\u00e9taill\u00e9 \u00e0 Michael Hayes pour \u00eatre la s\u0153ur de Brock Lesnar. J&rsquo;ai eu ZERO CHILL.<\/p><\/blockquote>\n\n\n\n<p><\/p>\n\n\n\n<p>Finalement, Brock Lesnar quitte la WWE lorsque Beth Phoenix la rejoint, en 2004. Elle commence par \u00eatre la petite-amie de Chris Masters pour une courte p\u00e9riode puis elle devient manager d&rsquo;Aaron Stevens, connu sous le nom de Damien Sandows \u00e0 la WWE. Elle fait ensuite ses d\u00e9buts dans le main roster en 2006 et quitte la WWE en 2012, ann\u00e9e durant laquelle Brock Lesnar effectue quant \u00e0 lui son retour.\u00a0<\/p>\n\n\n\n<p>Beth Phoenix reviendra \u00e0 la WWE en 2017 pour \u00eatre intronis\u00e9e au Hall of Fame, revenir sur le ring de temps en temps et devenir commentatrice de NXT.<\/p>\n\n\n\n<center><blockquote class=\"twitter-tweet\"><p lang=\"en\" dir=\"ltr\">Fun Fact: At one of my first gigs as a <a href=\"https:\/\/twitter.com\/WWE?ref_src=twsrc%5Etfw\">@WWE<\/a> extra I pitched a detailed storyline to Michael Hayes to be brought in as Brock Lesnar\u2019s sister. I had ZERO CHILL. <a href=\"https:\/\/t.co\/OZOH3VgVOe\">pic.twitter.com\/OZOH3VgVOe<\/a><\/p>&mdash; Beth \u201cPhoenix\u201d Copeland (@TheBethPhoenix) <a href=\"https:\/\/twitter.com\/TheBethPhoenix\/status\/1458868481651355648?ref_src=twsrc%5Etfw\">November 11, 2021<\/a><\/blockquote> <script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script>\n\n<p><script async=\"\" src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script>\n<ins class=\"adsbygoogle\" style=\"display:block; text-align:center;\" data-ad-layout=\"in-article\" data-ad-format=\"fluid\" data-ad-client=\"ca-pub-1986975368136072\" data-ad-slot=\"7818521013\"><\/ins>\n<script>\n     (adsbygoogle = window.adsbygoogle || []).push({});\n<\/script><\/p><\/center>\n\n\n\n\n<p>Plus t\u00f4t cette semaine (<a rel=\"noreferrer noopener\" href=\"https:\/\/www.jdx.info\/lutte\/2021\/11\/11\/becky-confirme-avoir-de-vrai-probleme-avec-charlotte\/\" target=\"_blank\">d\u00e9tails ici<\/a>), Becky Lynch\u00a0r\u00e9agissait pour la premi\u00e8re fois\u00a0\u00e0 son altercation avec Charlotte Flair dans les coulisses apr\u00e8s un \u00e9pisode de SmackDown. La championne de RAW a confirm\u00e9 qu&rsquo;elle avait des probl\u00e8mes avec celle de SmackDown et qu&rsquo;elle ne lui faisait pas confiance, malgr\u00e9 qu&rsquo;elles se rencontreront sur le ring lors des Survivor Series la semaine prochaine o\u00f9 la confiance entre diff\u00e9rents talents doit r\u00e9gner.<\/p>\n\n\n\n<p>Becky Lynch se disait \u00e9galement \u00ab\u00a0d&rsquo;accord pour \u00eatre l&rsquo;h\u00e9ro\u00efne\u00a0\u00bb des vestiaires.\u00a0Une phrase \u00e0 laquelle Charlotte Flair a d\u00e9cid\u00e9 de r\u00e9pondre de mani\u00e8re subtile par le biais d&rsquo;un tweet :<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>&lt;&lt; Tout le monde veut \u00eatre le h\u00e9ro \/ l&rsquo;h\u00e9ro\u00efne de sa propre histoire. >><\/p><\/blockquote>\n\n\n\n<p>Encore un indice que cette \u00ab\u00a0histoire vraie\u00a0\u00bb semble \u00eatre un work pour mousser leur affrontement, c&rsquo;est que la WWE ne les laisseraient pas se cr\u00eaper le chignon publiquement. L&rsquo;animosit\u00e9 vient quand m\u00eame de monter d&rsquo;un cran. <\/p>\n\n\n\n<center><blockquote class=\"twitter-tweet\"><p lang=\"en\" dir=\"ltr\">everyone wants to be the hero in their own story &#x1f478;&#x1f3fc; <a href=\"https:\/\/t.co\/SnjcN83bKv\">pic.twitter.com\/SnjcN83bKv<\/a><\/p>&mdash; Charlotte Flair (@MsCharlotteWWE) <a href=\"https:\/\/twitter.com\/MsCharlotteWWE\/status\/1459162283586773001?ref_src=twsrc%5Etfw\">November 12, 2021<\/a><\/blockquote> <script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/center>\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>Beth Phoenix qui est aujourd&rsquo;hui commentatrice de NXT aux c\u00f4t\u00e9s de Wade Barrett et Vic Joseph, a rejoint la WWE en 2004 \u00e0 la Ohio Valley Wrestling, territoire de d\u00e9veloppement de la compagnie \u00e0 ce moment-l\u00e0. Et pour ses d\u00e9buts, la l\u00e9gende avait propos\u00e9 une storyline bien originale ! C&rsquo;est la Hall of Famer elle-m\u00eame&#8230;<\/p>\n","protected":false},"author":609,"featured_media":61116,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4,23],"tags":[],"ppma_author":[295],"class_list":["post-61115","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news","category-wwe"],"authors":[{"term_id":295,"user_id":609,"is_guest":0,"slug":"rodrigo","display_name":"Rodrigue Tousignant","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/51fe284bb6dbe8a6b4c2bf998ad658f4a9cd24b7e58f15ec85888070c7340ce6?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/61115","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/users\/609"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/comments?post=61115"}],"version-history":[{"count":1,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/61115\/revisions"}],"predecessor-version":[{"id":61117,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/61115\/revisions\/61117"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media\/61116"}],"wp:attachment":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media?parent=61115"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/categories?post=61115"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/tags?post=61115"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/ppma_author?post=61115"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}