{"id":61064,"date":"2021-11-14T00:02:00","date_gmt":"2021-11-14T05:02:00","guid":{"rendered":"https:\/\/www.jdx.info\/lutte\/?p=61064"},"modified":"2021-11-14T15:12:59","modified_gmt":"2021-11-14T20:12:59","slug":"darby-allin-sur-sting-nous-avons-tellement-grandi-ensemble-moose-revient-sur-sa-promo-controverse","status":"publish","type":"post","link":"https:\/\/www.jdx.info\/lutte\/2021\/11\/14\/darby-allin-sur-sting-nous-avons-tellement-grandi-ensemble-moose-revient-sur-sa-promo-controverse\/","title":{"rendered":"Darby Allin sur Sting \u00ab Nous avons tellement grandi ensemble \u00bb \/ Moose revient sur sa promo controvers\u00e9!"},"content":{"rendered":"\n<p>  <p>Le champion du monde IMPACT, Moose, est r\u00e9cemment apparu sur le\u00a0podcast\u00a0Juice Pro Wrestling\u00a0pour discuter de sa premi\u00e8re promo en tant que champion il y a quelques semaines, qui a vu le dieu de la lutte faire r\u00e9f\u00e9rence aux meilleurs talents de la AEW et de la WWE.\u00a0Interrog\u00e9 sur la promo, Moose pr\u00e9cise qu&rsquo;il ne tirait pas sur ces talents susmentionn\u00e9s, mais qu&rsquo;il les mettait en place.\u00a0Les faits saillants sont ci-dessous.<\/p><\/p>\n\n\n\n<p><p>Il savait qu&rsquo;il ne voulait pas supprimer la m\u00eame promo g\u00e9n\u00e9rique de champion du monde et qu&rsquo;il \u00e9tait important d&rsquo;attirer l&rsquo;attention d&rsquo;Internet\u00a0:<\/p><blockquote class=\"wp-block-quote\"><p>Ils m&rsquo;ont dit que j&rsquo;aurais trois minutes pour couper une promo et r\u00e9fl\u00e9chir \u00e0 ce que je voulais dire et que c&rsquo;\u00e9tait bien parce que c&rsquo;\u00e9tait la premi\u00e8re fois que je parlais en tant que champion.\u00a0J&rsquo;aurais pu couper la promo typique des conneries sur le fait d&rsquo;\u00eatre un champion de combat.\u00a0Tout ce que je pensais dire, je disais juste des choses que les champions avant moi avaient dites.\u00a0Que pourrais-je dire qui ferait une d\u00e9claration?\u00a0\u00c0 l&rsquo;\u00e8re de la lutte d&rsquo;aujourd&rsquo;hui, les m\u00e9dias sociaux sont l\u00e0 o\u00f9 ils en sont parce que les m\u00e9dias sociaux dirigent le monde.\u00a0Dans mon esprit, je devais couper une promo qui allait faire bourdonner Internet et qui allait \u00eatre controvers\u00e9e sans \u00eatre controvers\u00e9e ou dire quoi que ce soit de mal \u00e0 propos de qui que ce soit.\u00a0J&rsquo;ai attrap\u00e9 mon papier et je me suis assis pendant 20 minutes et c&rsquo;\u00e9tait un peu comme \u00e9crire une chanson de rap.\u00a0Quand j&rsquo;avais fini, je me suis dit : \u00ab\u00a0Putain de merde, \u00e7a pourrait \u00eatre vraiment bien.\u00a0\u00bb\u00a0Avant de penser \u00e0 le dire,\u00a0Je voulais m&rsquo;assurer d&rsquo;avoir l&rsquo;autorisation de le dire.\u00a0Je dois avoir un salaire.\u00a0Je l&rsquo;ai dit aux sc\u00e9naristes et ils ont ador\u00e9 \u00e7a.<\/p><\/blockquote><\/p>\n\n\n\n<center><p><script async=\"\" src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script>\n<ins class=\"adsbygoogle\" style=\"display:block; text-align:center;\" data-ad-layout=\"in-article\" data-ad-format=\"fluid\" data-ad-client=\"ca-pub-1986975368136072\" data-ad-slot=\"7818521013\"><\/ins>\n<script>\n     (adsbygoogle = window.adsbygoogle || []).push({});\n<\/script><\/p><\/center>\n\n\n\n<p><p>Dit qu&rsquo;il ne tirait pas sur les gens de la WWE ou de la AEW, mais qu&rsquo;il les mettait en place\u00a0:<\/p><blockquote class=\"wp-block-quote\"><p>Si vous entendez la promo, tout le monde \u00e9tait comme si j&rsquo;avais tourn\u00e9 \u00e0 la WWE ou \u00e0 l&rsquo;AEW.\u00a0Je n&rsquo;ai jamais tir\u00e9 sur personne.\u00a0Je n&rsquo;ai jamais dit de mal de personne.\u00a0Si quoi que ce soit, je les ai mis partout.\u00a0Je viens de dire que je suis meilleur qu&rsquo;eux tous.\u00a0Je d\u00e9teste mettre ce gars-l\u00e0, mais Don Callis travaillait avec moi sur mes promos et il me disait, &lsquo;une chose que tu ne veux pas faire, c&rsquo;est mettre n&rsquo;importe qui dans tes promos.\u00a0Mettez-les par-dessus et puis quand vous vous mettez par-dessus, vous semblez plus grand qu&rsquo;eux tous.\u00a0J&rsquo;ai utilis\u00e9 cela dans mon esprit comme r\u00e9f\u00e9rence lorsque j&rsquo;ai \u00e9crit cette promo.\u00a0Je les mets partout parce qu&rsquo;ils sont tous l\u00e9gendaires et je pense qu&rsquo;ils sont les meilleurs dans ce domaine, je pense juste que je suis le plus grand de tous les temps.\u00a0En fin de compte, je me suis mis moi-m\u00eame et IMPACT au-dessus dans son ensemble.\u00a0Beaucoup de gens que j&rsquo;ai mentionn\u00e9s, je suis de bons amis ou associ\u00e9s.\u00a0Je pense qu&rsquo;ils sont tous g\u00e9niaux.\u00a0Je viens de me mettre l\u00e0-haut avec eux.\u00a0Quand j&rsquo;ai \u00e9crit la promo, je ne pensais pas qu&rsquo;elle allait avoir le poids et les \u00e9loges et les mentions qu&rsquo;elle aurait eu.<\/p><\/blockquote><p>Sur la r\u00e9ponse \u00e0 la promo :<span style=\"font-size: revert; color: initial;\">   <\/span><\/p><blockquote class=\"wp-block-quote\"><p>J&rsquo;ai fait exploser mon t\u00e9l\u00e9phone \u00e0 cause de gens qui travaillent partout.\u00a0Les gens qui travaillent \u00e0 l&rsquo;AEW, \u00e0 la WWE, tout le monde se disait : \u00ab\u00a0C&rsquo;\u00e9tait une putain de promo.\u00a0\u00bb\u00a0Dans mon esprit, j&rsquo;avais besoin de faire une d\u00e9claration.\u00a0J&rsquo;ai fait une d\u00e9claration.\u00a0J&rsquo;ai eu tout le monde qui m&rsquo;a frapp\u00e9 \u00e0 propos de cette promo.\u00a0Si vous regardez les vues qu&rsquo;il a obtenues avec IMPACT, je ne pense pas que tout ce qu&rsquo;ils ont mis sur Twitter ait obtenu plus de 100 000 vues.\u00a0Cela repr\u00e9sente jusqu&rsquo;\u00e0 300 000 vues.\u00a0Esp\u00e9rons que cela devienne une promotion aussi importante que le \u00ab\u00a0woo off\u00a0\u00bb de Steiner Math et Jay Lethal avec Ric Flair.\u00a0J&rsquo;esp\u00e8re que cela restera dans l&rsquo;histoire comme l&rsquo;une des promotions les plus \u00e9piques de l&rsquo;histoire d&rsquo;IMPACT.\u00a0Il y a eu quelques mentions que j&rsquo;ai vues qui \u00e9taient comme : \u00ab\u00a0Moose parle si lentement qu&rsquo;il m&rsquo;a endormi.\u00a0\u00bb\u00a0C&rsquo;est mon putain de personnage.\u00a0\u00c9videmment, je ne parle pas aussi mena\u00e7ant et lent dans la vraie vie.\u00a0Mon personnage est m\u00e9thodique comme No Country For Old Men.\u00a0C&rsquo;est un peu ce sur quoi mon personnage est bas\u00e9, il parle lentement et mena\u00e7ant pour que vous puissiez comprendre chaque mot.\u00a0Ce n&rsquo;est pas attirant pour certains fans qui pensent \u00ab\u00a0il est stupide et parle lentement\u00a0\u00bb.\u00a0Suce mes fesses.\u00a0Plus de gens m&rsquo;ont parl\u00e9 de cette promo qu&rsquo;ils ne m&rsquo;ont f\u00e9licit\u00e9 pour avoir remport\u00e9 le titre, ce qui \u00e9tait important pour moi.<\/p><\/blockquote>  <\/p>\n\n\n\n<center><p><script async=\"\" src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script>\n<ins class=\"adsbygoogle\" style=\"display:block; text-align:center;\" data-ad-layout=\"in-article\" data-ad-format=\"fluid\" data-ad-client=\"ca-pub-1986975368136072\" data-ad-slot=\"7818521013\"><\/ins>\n<script>\n     (adsbygoogle = window.adsbygoogle || []).push({});\n<\/script><\/p><\/center>\n\n\n\n<p>La superstar de la AEW et ancien champion de la TNT, Darby Allin, est r\u00e9cemment apparu sur&nbsp;<a href=\"https:\/\/podcasts.apple.com\/us\/podcast\/insight-with-chris-van-vliet\/id1468939064\">Insight With Chris Van Vilet<\/a>&nbsp;pour discuter de sa relation avec l&rsquo;ic\u00f4ne Sting, qui comprenait Allin r\u00e9v\u00e9lant qu&rsquo;il \u00e9tait celui qui avait convaincu Sting de lutter en direct \u00e0 Double Or Nothing 2021. Faits saillants de l&rsquo;interview est ci-dessous.<\/p>\n\n\n\n<p>Dit que Sting est super cool et qu&rsquo;il est le plus humble :<\/p>\n\n\n\n<p>\u00abIl est tellement cool dans le sens o\u00f9 il n&rsquo;y a pas d&rsquo;ego avec lui.&nbsp;Plus je suis entour\u00e9 des meilleurs des meilleurs, que ce soit du skateboard quand je suis autour de Tony Hawk ou de Travis Pastrana, c&rsquo;est Sting.&nbsp;Les gars qui ont fait le plus de merde sont les plus humbles.&nbsp;Ils n&rsquo;ont rien \u00e0 prouver.&nbsp;Ce sont tous les faux culs qui n&rsquo;ont jamais r\u00e9ussi qui ont cet ego.&nbsp;\u00ab&nbsp;Vous savez qui je suis, n&rsquo;est-ce pas&nbsp;?&nbsp;\u00bb&nbsp;Non, je ne sais pas qui tu es.&nbsp;C&rsquo;est ce que j&rsquo;ai appris de Sting.&nbsp;Sois juste un putain de bon \u00eatre humain.&nbsp;Soyez humble et cool.<\/p>\n\n\n\n<p>Comment il a convaincu Sting de disputer un match en direct \u00e0 Double Or Nothing 2021 :<\/p>\n\n\n\n<p>\u00ab\u00a0Moi et Sting avons tellement grandi ensemble en dehors de ce que les gens ont vu \u00e0 la t\u00e9l\u00e9vision.&nbsp;Nos personnalit\u00e9s en dehors du ring, nous nous en sommes rapproch\u00e9s et les fans ne voient pas cette partie.&nbsp;\u00c0 l&rsquo;origine, il \u00e9tait cens\u00e9 venir pour quelques matchs cin\u00e9matographiques et je suis all\u00e9 chez lui au Texas o\u00f9 il avait install\u00e9 un ring et nous avons commenc\u00e9 \u00e0 rouler et \u00e0 nous entra\u00eener et je l&rsquo;ai convaincu de lutter devant une foule en direct.&nbsp;Personne ne peut voir ces moments dans les coulisses.&nbsp;C&rsquo;est juste nous qui parlons.&nbsp;&lsquo;Tu as \u00e7a.&nbsp;Je m&rsquo;entra\u00eene avec toi et je vois ce que tu fais, foutons-le.&nbsp;Double or Nothing contre Scorpio Sky et Ethan Page signifiait beaucoup parce que nous n&rsquo;avions jamais pens\u00e9 que cela arriverait.&nbsp;Il donne confiance aux autres et c&rsquo;est cool que je puisse l&rsquo;aider \u00e0 dire : \u00ab&nbsp;Tu as \u00e7a.&nbsp;\u00bb&nbsp;C&rsquo;est cool de faire \u00e7a dans tous les aspects de la vie.<\/p>\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>Le champion du monde IMPACT, Moose, est r\u00e9cemment apparu sur le\u00a0podcast\u00a0Juice Pro Wrestling\u00a0pour discuter de sa premi\u00e8re promo en tant que champion il y a quelques semaines, qui a vu le dieu de la lutte faire r\u00e9f\u00e9rence aux meilleurs talents de la AEW et de la WWE.\u00a0Interrog\u00e9 sur la promo, Moose pr\u00e9cise qu&rsquo;il ne tirait&#8230;<\/p>\n","protected":false},"author":665,"featured_media":61231,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[38,24,22,4,41],"tags":[],"ppma_author":[289],"class_list":["post-61064","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-aew","category-aew-impact-njpw-roh","category-indy","category-news","category-tna-impact"],"authors":[{"term_id":289,"user_id":665,"is_guest":0,"slug":"line","display_name":"Line Edmond","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/852de09636413c90cdaa278312f9ea5bc4396768745424755cb63d99a05989d0?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/61064","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/users\/665"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/comments?post=61064"}],"version-history":[{"count":4,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/61064\/revisions"}],"predecessor-version":[{"id":61243,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/61064\/revisions\/61243"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media\/61231"}],"wp:attachment":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media?parent=61064"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/categories?post=61064"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/tags?post=61064"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/ppma_author?post=61064"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}