{"id":60972,"date":"2021-11-08T16:45:00","date_gmt":"2021-11-08T21:45:00","guid":{"rendered":"https:\/\/www.jdx.info\/lutte\/?p=60972"},"modified":"2021-11-10T11:47:07","modified_gmt":"2021-11-10T16:47:07","slug":"resultats-et-video-du-aew-elevation-du-8-novembre-2021","status":"publish","type":"post","link":"https:\/\/www.jdx.info\/lutte\/2021\/11\/08\/resultats-et-video-du-aew-elevation-du-8-novembre-2021\/","title":{"rendered":"R\u00e9sultats et Vid\u00e9o du AEW Elevation du 8 Novembre 2021!"},"content":{"rendered":"\n<ul class=\"wp-block-list\"><li><strong><a href=\"https:\/\/www.jdx.info\/lutte\/2021\/11\/09\/regardez-le-aew-elevation-du-8-novembre-2021\/\" target=\"_blank\" rel=\"noreferrer noopener\">Pour voir ce DARK Elevation, cliquez ici.<\/a><\/strong><\/li><\/ul>\n\n\n\n<p><strong>R\u00e9sultats du AEW Dark Elevation du 8 novembre<\/strong> <strong>2021<\/strong><\/p>\n\n\n\n<p>Les commentateurs sont Excalibur, Mark Henry et Paul Wight.<\/p>\n\n\n\n<p>&#8211; Le AEW Dark Elevation d\u00e9bute avec le premier combat.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><strong>Powerhouse Hobbs bat Dan The Dad<\/strong> par soumission avec une PowerSlam, mais Hobbs refuse de le couvrir et lui fait un Torture Rack pour le faire taper.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><strong>The Butcher et The Blade battent Best Friends<\/strong> (Chuck Taylor et Wheeler Yuta) avec leur combinaison de Powerbomb et Neck Breaker sur Yuta pour le compte de trois du Butcher pendant que Taylor \u00e9tait sonn\u00e9 en bas du ring.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><strong>Riho bat Tootie Lynn<\/strong> avec son Double Stomp du coin pour le compte de trois.<\/p>\n\n\n\n<center><p><script async=\"\" src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script>\n<ins class=\"adsbygoogle\" style=\"display:block; text-align:center;\" data-ad-layout=\"in-article\" data-ad-format=\"fluid\" data-ad-client=\"ca-pub-1986975368136072\" data-ad-slot=\"7818521013\"><\/ins>\n<script>\n     (adsbygoogle = window.adsbygoogle || []).push({});\n<\/script><\/p><\/center>\n\n\n\n<p>&#8211; Avant le combat, Matt Hardy prend le micro et demande \u00e0 Alexander de se pr\u00e9senter. Il lui demande ensuite son nom, qui est le plus important. Matt dit qu&rsquo;Alexander connait son nom, mais il ne sait pas qui il est. Il est le grand Matt Hardy plein d&rsquo;argent. Il dira son nom avec respect apr\u00e8s lui avoir bott\u00e9 le cul.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><strong>Matt Hardy bat Dean Alexander<\/strong> par soumission avec son Leech pour le faire taper.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><strong>Ryo Mizunami et Ruby Soho battent Emi Sakura et Nyla Rose <\/strong>accompagn\u00e9e de Mei Suruga lorsque Ruby repousse Sakura et lui fait son Riott Kick pour le compte de trois alors que Rose \u00e9tait sonn\u00e9e en bas du ring.<\/p>\n\n\n\n<p> Apr\u00e8s le combat, Suruga et Sakura discutent avec Soho. Nyla Rose en profite pour la frapper dans le dos ! Kris Statlander arrive sur le ring avec une chaise et tout le monde prend la fuite.<\/p>\n\n\n\n<p>&#8211; Avant le combat, The Acclaimed fait leur rap. Max Caster dit que le Dark Order aura une pire ann\u00e9e que les Chiefs de Kansas. Ils vont chier comme les pantalons de Joe Biden.<\/p>\n\n\n\n<p class=\"has-medium-font-size\"><strong>8-Man Tag Team Match<\/strong><br><br>Dark Order (Evil Uno, Stu Grayson, Alex Reynolds et John Silver) battent The Acclaimed (Max Caster et Anthony Bowens) et 2point0 (Matt Lee et Jeff Parker) lorsque les catcheurs enchainent les prises. Le Dark Order commence \u00e0 attaquer Parker \u00e0 quatre et il termine avec leur Fatality pour le compte de trois.<\/p>\n\n\n\n<p>Le show se termine avec une c\u00e9l\u00e9bration du Dark Order.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p> <li><strong><a rel=\"noreferrer noopener\" href=\"https:\/\/www.jdx.info\/lutte\/2021\/11\/09\/regardez-le-aew-elevation-du-8-novembre-2021\/\" target=\"_blank\">Pour voir ce DARK Elevation, cliquez ici.<\/a><\/strong><\/li> <\/p>\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>Pour voir ce DARK Elevation, cliquez ici. R\u00e9sultats du AEW Dark Elevation du 8 novembre 2021 Les commentateurs sont Excalibur, Mark Henry et Paul Wight. &#8211; Le AEW Dark Elevation d\u00e9bute avec le premier combat. Powerhouse Hobbs bat Dan The Dad par soumission avec une PowerSlam, mais Hobbs refuse de le couvrir et lui fait&#8230;<\/p>\n","protected":false},"author":4,"featured_media":60976,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[38,24,76,21],"tags":[],"ppma_author":[292],"class_list":["post-60972","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-aew","category-aew-impact-njpw-roh","category-elevation","category-resultats"],"authors":[{"term_id":292,"user_id":4,"is_guest":0,"slug":"jean","display_name":"Jean Vinnier","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/33aba0263fd870a0b487e0e079ff407e10e3997c9d2987cbcc0db0db2c5c75a9?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/60972","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/comments?post=60972"}],"version-history":[{"count":1,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/60972\/revisions"}],"predecessor-version":[{"id":60977,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/60972\/revisions\/60977"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media\/60976"}],"wp:attachment":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media?parent=60972"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/categories?post=60972"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/tags?post=60972"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/ppma_author?post=60972"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}