{"id":60776,"date":"2021-11-04T01:03:00","date_gmt":"2021-11-04T05:03:00","guid":{"rendered":"https:\/\/www.jdx.info\/lutte\/?p=60776"},"modified":"2021-11-04T17:52:52","modified_gmt":"2021-11-04T21:52:52","slug":"un-cadre-de-longue-date-de-la-wwe-a-quitte-mysterieusement-jeff-jarrett-explique-pourquoi-il-ne-faisait-pas-partie-de-la-nwo","status":"publish","type":"post","link":"https:\/\/www.jdx.info\/lutte\/2021\/11\/04\/un-cadre-de-longue-date-de-la-wwe-a-quitte-mysterieusement-jeff-jarrett-explique-pourquoi-il-ne-faisait-pas-partie-de-la-nwo\/","title":{"rendered":"Un cadre de longue date de la WWE a quitt\u00e9 Myst\u00e9rieusement \/ Jeff Jarrett explique pourquoi il ne faisait pas partie de la nWo!"},"content":{"rendered":"\n<p>Le membre du Temple de la renomm\u00e9e de la WWE, Jeff Jarrett, a parl\u00e9 sur son&nbsp;<a href=\"https:\/\/www.realjeffjarrett.com\/\">podcast My World<\/a>&nbsp;d&rsquo;un large \u00e9ventail de sujets.<\/p>\n\n\n\n<p>Pendant ce temps, il a parl\u00e9 de&nbsp;son passage dans les Four Horsemen \u00e0 la WCW et de la raison pour laquelle il n&rsquo;a pas \u00e9t\u00e9 mis dans le groupe nWo \u00e0 son arriv\u00e9e de la WWF :<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>\u00ab Il n&rsquo;y en avait pas avec moi et j&rsquo;\u00e9tais content.\u00a0J&rsquo;ai v\u00e9cu cela, \u00e9videmment, mais tout le contexte de Hall, Nash, Hogan, Syxx, DiBiase et je pense Virgil, le laps de temps des gars de la WWF parce que Attitude Era et le Nord vs Sud, USA Network vs TBS\/TNT , tout cela \u00e9tait de v\u00e9ritables intrigues tangibles.\u00a0Hulk \u00e9tait un produit du WWF.\u00a0Diesel, eh bien, je n&rsquo;ai pas \u00e0 passer par l\u00e0.\u00a0C&rsquo;\u00e9tait tous les produits du WWF.<\/p><p>Moi en passant la porte, je savais, ok, on va le taquiner, mais je ne pensais pas que \u00e7a allait \u00eatre b\u00e9n\u00e9fique et imm\u00e9diatement perdu dans le remaniement parce que personne ne va dominer Hogan et \u00e0 bien des \u00e9gards , Hall et Nash.\u00a0Hulk est la plus grande attraction au box-office que cette industrie ait jamais cr\u00e9\u00e9e.\u00a0Les gars du territoire n&rsquo;\u00e9taient pas des stars nationales, mais tout le monde connaissait Hulkamania en m\u00eame temps et vendait des billets, des PPV et tout ce genre de choses.\u00a0Le NWO \u00e9tait dominant.<\/p><p>D&rsquo;un autre c\u00f4t\u00e9, c&rsquo;\u00e9tait essentiellement un incontournable de la WCW, The Four Horsemen.\u00a0Je ne connaissais pas exactement le paysage \u00e0 venir, mais les Cavaliers avaient des probl\u00e8mes de sant\u00e9.\u00a0Il n&rsquo;y a eu aucune discussion avec moi s&rsquo;ils ont mis Jeff dans ou hors de NWO, mais je n&rsquo;\u00e9tais pas vraiment amoureux.\u00a0Je me souviens, &lsquo;Qu&rsquo;est-ce que tu veux que je porte ce soir ?&rsquo;\u00a0Ils ont dit: \u00ab\u00a0C&rsquo;est une sorte de taquinerie, mais nous allons y entrer plus tard.\u00a0\u00bb\u00a0Ok, une allumeuse pour NWO, donc je portais du noir et blanc cette nuit-l\u00e0.<\/p><\/blockquote>\n\n\n\n<center><p><script async=\"\" src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script>\n<ins class=\"adsbygoogle\" style=\"display:block; text-align:center;\" data-ad-layout=\"in-article\" data-ad-format=\"fluid\" data-ad-client=\"ca-pub-1986975368136072\" data-ad-slot=\"7818521013\"><\/ins>\n<script>\n     (adsbygoogle = window.adsbygoogle || []).push({});\n<\/script><\/p><\/center>\n\n\n\n\n<p><\/p>\n\n\n\n<p>Il y aurait eu plusieurs d\u00e9parts de bureaux de la WWE cette semaine.<\/p>\n\n\n\n<p>Selon PWInsider, le vice-pr\u00e9sident senior de longue date des services cr\u00e9atifs de la WWE, Stan Stanski, aurait \u00e9t\u00e9 lib\u00e9r\u00e9 mercredi.&nbsp;Stanski faisait partie de l&rsquo;entreprise depuis pr\u00e8s de 15 ans.<\/p>\n\n\n\n<p>Stanski a rejoint la WWE en 2006 en tant que vice-pr\u00e9sident des services cr\u00e9atifs et a \u00e9t\u00e9 promu en mars 2012 au poste de vice-pr\u00e9sident directeur.<\/p>\n\n\n\n<p>Le d\u00e9part de Stanski a choqu\u00e9 de nombreuses personnes au sein de l&rsquo;entreprise mercredi.\u00a0Une personne a d\u00e9crit le d\u00e9part comme \u00ab\u00a0<em>la preuve ultime que personne n&rsquo;est en s\u00e9curit\u00e9<\/em>\u00a0\u00bb et \u00ab\u00a0<em>encore un autre rappel que ce n&rsquo;est plus la m\u00eame entreprise qu&rsquo;avant la pand\u00e9mie<\/em>\u00ab\u00a0. Mais l\u00e0 avant de juger rappeler vous que c&rsquo;est le cas de millions de compagnies dans le monde \u00ab\u00a0normal\u00a0\u00bb.<\/p>\n\n\n\n<p>On s&rsquo;attend \u00e0 ce que d&rsquo;autres d\u00e9parts soient confirm\u00e9s bient\u00f4t, mais Stanski \u00e9tait la sortie la plus m\u00e9diatis\u00e9e de l&rsquo;entreprise mercredi.<\/p>\n\n\n\n<p>Restez \u00e0 l&rsquo;\u00e9coute car la WWE publiera ses r\u00e9sultats du troisi\u00e8me trimestre de 2021 aujourd&rsquo;hui.<\/p>\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>Le membre du Temple de la renomm\u00e9e de la WWE, Jeff Jarrett, a parl\u00e9 sur son&nbsp;podcast My World&nbsp;d&rsquo;un large \u00e9ventail de sujets. Pendant ce temps, il a parl\u00e9 de&nbsp;son passage dans les Four Horsemen \u00e0 la WCW et de la raison pour laquelle il n&rsquo;a pas \u00e9t\u00e9 mis dans le groupe nWo \u00e0 son arriv\u00e9e&#8230;<\/p>\n","protected":false},"author":665,"featured_media":60800,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[30,4,23],"tags":[],"ppma_author":[289],"class_list":["post-60776","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ex-wwe","category-news","category-wwe"],"authors":[{"term_id":289,"user_id":665,"is_guest":0,"slug":"line","display_name":"Line Edmond","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/852de09636413c90cdaa278312f9ea5bc4396768745424755cb63d99a05989d0?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/60776","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/users\/665"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/comments?post=60776"}],"version-history":[{"count":2,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/60776\/revisions"}],"predecessor-version":[{"id":60801,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/60776\/revisions\/60801"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media\/60800"}],"wp:attachment":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media?parent=60776"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/categories?post=60776"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/tags?post=60776"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/ppma_author?post=60776"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}