{"id":60519,"date":"2021-10-28T15:16:00","date_gmt":"2021-10-28T19:16:00","guid":{"rendered":"https:\/\/www.jdx.info\/lutte\/?p=60519"},"modified":"2021-10-29T23:20:30","modified_gmt":"2021-10-30T03:20:30","slug":"bray-wyatt-publie-un-teaser-avant-lexpiration-de-la-non-concurrence-de-la-wwe-katsuyori-shibata-sexprime-sur-son-retour","status":"publish","type":"post","link":"https:\/\/www.jdx.info\/lutte\/2021\/10\/28\/bray-wyatt-publie-un-teaser-avant-lexpiration-de-la-non-concurrence-de-la-wwe-katsuyori-shibata-sexprime-sur-son-retour\/","title":{"rendered":"Bray Wyatt publie un teaser avant l&rsquo;expiration de la non-concurrence de la WWE \/ Katsuyori Shibata s&rsquo;exprime sur son retour!"},"content":{"rendered":"\n<p>Comme vous le savez, Katsuyori Shibata est remont\u00e9 sur un ring lors de la finale du G1 Climax 31 le 21 octobre dernier pour un match de grappling de 5 minutes avec les r\u00e8gles UWF face \u00e0 Zack Sabre Junior.<\/p>\n\n\n\n<p>Apr\u00e8s cette exhibition, Kasutori Shibata prend le micro et prononce une phrase qui nous laisse entrevoir un retour sur les rings pour un match de catch. Shibata a pris sa retraite suite au diagnostic d\u2019un h\u00e9matome sous-dural apr\u00e8s le match lors de Sakura Genesis face \u00e0 Kazuchika Okada. Un match d\u2019une tr\u00e8s grande intensit\u00e9 et tr\u00e8s brutal.<\/p>\n\n\n\n<p>Il y a quelques jours, Katsuyori Shibata \u00e9tait en interview pour Tokyo Sport o\u00f9 il nous a parl\u00e9 de ce retour.<\/p>\n\n\n\n<center><p><script async=\"\" src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script>\n<ins class=\"adsbygoogle\" style=\"display:block; text-align:center;\" data-ad-layout=\"in-article\" data-ad-format=\"fluid\" data-ad-client=\"ca-pub-1986975368136072\" data-ad-slot=\"7818521013\"><\/ins>\n<script>\n     (adsbygoogle = window.adsbygoogle || []).push({});\n<\/script><\/p><\/center>\n\n\n\n\n<p><\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>\u201cJe voulais le faire au bon moment. Je ne voulais pas qu&rsquo;on me pose beaucoup de questions sur mon \u00e9tat de sant\u00e9, alors je me suis content\u00e9 de dire \u00ab\u00a0voir, c&rsquo;est croire\u00a0\u00bb et d&rsquo;exprimer que c&rsquo;est l\u00e0 o\u00f9 je suis maintenant. J&rsquo;ai \u00e9galement pens\u00e9 que ce serait bien de voir un peu d&rsquo;espoir en cette p\u00e9riode de Corona. C&rsquo;\u00e9tait un grand espace.<\/p><p>C&rsquo;est un endroit sp\u00e9cial. C&rsquo;est la seule voie possible pour moi. Mon d\u00e9sir de faire un retour en force semble s&rsquo;\u00eatre renforc\u00e9. Je vis ma vie une \u00e9tape \u00e0 la fois, et d&rsquo;ann\u00e9e en ann\u00e9e, la bague se rapproche de plus en plus. De toute fa\u00e7on, si je n&rsquo;ai pas d&rsquo;objectif, je ne sais pas vraiment qui je suis, alors je m&rsquo;y tiens toujours.<\/p><p>Comme Okada l&rsquo;a dit quand j&rsquo;\u00e9tais bless\u00e9, les lutteurs professionnels sont des surhommes. Trois pas en avant, deux pas en arri\u00e8re. Parfois, je fais trois pas en avant et quatre ou cinq pas en arri\u00e8re. Mais je ne veux pas abandonner. C&rsquo;est tout ce que je peux faire. Je ne vais pas abandonner. Si je ne le faisais pas, je ne ferais pas ce travail.\u201d<\/p><\/blockquote>\n\n\n\n<p>Katsuyori Shibata nous parle ensuite de Zack Sabre Junior.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>\u201cIl est impatient de se battre depuis un certain temps. Je pense que je peux maximiser ce qu&rsquo;il peut exprimer en ce moment, et cela fait longtemps qu&rsquo;il le dit. Je pensais qu&rsquo;apr\u00e8s le combat contre Zack, je serais capable de voir o\u00f9 je vais. Au contraire, je ne pensais \u00e0 personne d&rsquo;autre qu&rsquo;\u00e0 Zack.\u00a0\u00bb<\/p><\/blockquote>\n\n\n\n<p><\/p>\n\n\n\n<center><blockquote class=\"twitter-tweet\"><p lang=\"en\" dir=\"ltr\">2 more days<\/p>&mdash; Windham (@Windham6) <a href=\"https:\/\/twitter.com\/Windham6\/status\/1453534881762275333?ref_src=twsrc%5Etfw\">October 28, 2021<\/a><\/blockquote> <script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script>\n\n<p><script async=\"\" src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script>\n<ins class=\"adsbygoogle\" style=\"display:block; text-align:center;\" data-ad-layout=\"in-article\" data-ad-format=\"fluid\" data-ad-client=\"ca-pub-1986975368136072\" data-ad-slot=\"7818521013\"><\/ins>\n<script>\n     (adsbygoogle = window.adsbygoogle || []).push({});\n<\/script><\/p><\/center>\n\n\n\n\n<p> Windham Rotunda que vous connaissez sous le nom de Bray Wyatt \u00e0 la WWE s&rsquo;est rendu sur Twitter mercredi soir avec un teaser alors qu&rsquo;il se pr\u00e9pare \u00e0 l&rsquo;expiration de sa clause de non-concurrence de 90 jours avec la WWE.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>\u00ab\u00a02 jours de plus\u00a0\u00bb, <\/p><\/blockquote>\n\n\n\n<p>La WWE a sorti Rotunda le 31 juillet et il deviendra officiellement un agent libre demain, le 29 octobre.<\/p>\n\n\n\n<p>Il y a des rumeurs sur ce que Rotunda a pr\u00e9vu pour son avenir dans la lutte, mais il se dit qu&rsquo;il se dirigerait vers Impact Wrestling ou AEW.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><\/p>\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>Comme vous le savez, Katsuyori Shibata est remont\u00e9 sur un ring lors de la finale du G1 Climax 31 le 21 octobre dernier pour un match de grappling de 5 minutes avec les r\u00e8gles UWF face \u00e0 Zack Sabre Junior. Apr\u00e8s cette exhibition, Kasutori Shibata prend le micro et prononce une phrase qui nous laisse&#8230;<\/p>\n","protected":false},"author":665,"featured_media":60580,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[24,30,22,4],"tags":[],"ppma_author":[289],"class_list":["post-60519","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-aew-impact-njpw-roh","category-ex-wwe","category-indy","category-news"],"authors":[{"term_id":289,"user_id":665,"is_guest":0,"slug":"line","display_name":"Line Edmond","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/852de09636413c90cdaa278312f9ea5bc4396768745424755cb63d99a05989d0?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/60519","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/users\/665"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/comments?post=60519"}],"version-history":[{"count":2,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/60519\/revisions"}],"predecessor-version":[{"id":60581,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/60519\/revisions\/60581"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media\/60580"}],"wp:attachment":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media?parent=60519"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/categories?post=60519"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/tags?post=60519"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/ppma_author?post=60519"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}