{"id":60499,"date":"2021-10-28T02:17:55","date_gmt":"2021-10-28T06:17:55","guid":{"rendered":"https:\/\/www.jdx.info\/lutte\/?p=60499"},"modified":"2021-10-29T23:56:21","modified_gmt":"2021-10-30T03:56:21","slug":"regardez-le-aew-dynamite-du-27-octobre-2021","status":"publish","type":"post","link":"https:\/\/www.jdx.info\/lutte\/2021\/10\/28\/regardez-le-aew-dynamite-du-27-octobre-2021\/","title":{"rendered":"R\u00e9sultats et vid\u00e9os du AEW Dynamite du 27 Octobre 2021!"},"content":{"rendered":"\n<p><\/p>\n\n\n\n<p><strong>WATCH DAILYMOTION 720p<\/strong><\/p>\n\n\n\n<p><a href=\"https:\/\/t.co\/k7YSpi6ZJa?amp=1\" target=\"_blank\" rel=\"noreferrer noopener\">Part 1<\/a>&nbsp;<a href=\"https:\/\/t.co\/kk2FwJPsBe?amp=1\" target=\"_blank\" rel=\"noreferrer noopener\">Part 2<\/a><\/p>\n\n\n\n<p><strong>ALT Dailymotion<\/strong><\/p>\n\n\n\n<p><a rel=\"noreferrer noopener\" href=\"http:\/\/onlytechdiary.com\/watch\/o.php?id=y%26minify=M%26lister=none%26mirror=pvp1%26mainid=568131\" target=\"_blank\">Part 1<\/a>&nbsp;<a rel=\"noreferrer noopener\" href=\"http:\/\/onlytechdiary.com\/watch\/o.php?id=y%26minify=M%26lister=none%26mirror=pvp2%26mainid=568131\" target=\"_blank\">Part 2<\/a><\/p>\n\n\n\n<p><strong>R\u00e9sum\u00e9 de AEW Dynamite du 27 octobre<\/strong><\/p>\n\n\n\n<p>AEW Dynamite Boston, Massachusetts<\/p>\n\n\n\n<p>Les commentateurs sont Jim Ross, Tony Schiavone et Excalibur.<\/p>\n\n\n\n<p>&#8211; Ce soir c&rsquo;est AEW Dynamite, le show d\u00e9marre avec les pyros et les commentateurs qui nous souhaitent la bienvenue.<\/p>\n\n\n\n<p><strong>Singles Match<\/strong><\/p>\n\n\n\n<p><strong>CM Punk vs Bobby Fish<\/strong><\/p>\n\n\n\n<p>\u00c0 la fin du combat, Punk fait un compte Jacknife, mais Fish le repousse. Fish le prend pour une prise, mais Punk le renverse avec un GTS pour le compte de trois.<\/p>\n\n\n\n<p><strong>Gagnant : CM Punk<\/strong><\/p>\n\n\n\n<p>&#8211; En coulisse, Malakai Black dit que la famille de Cody a perdu espoir en lui, il a divis\u00e9 la Nightmare Familly, il a forc\u00e9 Cody \u00e0 prendre de nouvelles mesures et avoir une foule qui le d\u00e9teste. La maison gagne toujours !<\/p>\n\n\n\n<p>&#8211; De retour suite \u00e0 la pause, MJF arrive sur le ring.<\/p>\n\n\n\n<p><strong>Singles Match<\/strong><\/p>\n\n\n\n<p><strong>MJF&nbsp;<em>accompagn\u00e9 de Wardlow et Shawn Spears<\/em>&nbsp;vs Bryce Donovan (catcheur local)<\/strong><\/p>\n\n\n\n<p>MJF prend directement l&rsquo;avantage et fait un Pile Driver \u00e0 l&rsquo;aide des cordes pour un compte de trois.<\/p>\n\n\n\n<p><strong>Gagnant : MJF<\/strong><\/p>\n\n\n\n<p>&#8211; Apr\u00e8s le combat, MJF prend le micro et dit que Boston n&rsquo;a pas chang\u00e9 depuis la derni\u00e8re fois, un vrai trou \u00e0 merde. On est chanceux de l&rsquo;avoir vu remporter son match. Ce soir par contre il va rester loin des femmes d\u00e9goutantes de Boston. Leur accent est d\u00e9goutant. En parlant de trucs d\u00e9goutants, il y a Darby Allin. Allin a fait une erreur le 29 septembre en coupant son discours. Allin a aussi d\u00e9clar\u00e9 qu&rsquo;il ne pouvait pas \u00eatre bris\u00e9 mentalement, mais c&rsquo;est ironique puisque Darby a peur de venir au boulot maintenant. Il a aussi \u00e9cras\u00e9 Sting avec sa bague en diamant. Rien ne peut l&rsquo;arr\u00eater dans sa destin\u00e9. Ce qui se passera \u00e0 Full Gear n&rsquo;a aucune importance, on regarde pr\u00e9sentemment le futur champion mondial. Il est le pr\u00e9sent, le pass\u00e9 et le futur. La musique de Sting commence, mais personne n&rsquo;arrive. MJF commence \u00e0 rigoler en disant qu&rsquo;on est tous tomb\u00e9 dans le pi\u00e8ge. Les lumi\u00e8res s&rsquo;\u00e9teignent encore et Sting est sur le ring ! Sting frappe Spears et Wardlow avec son b\u00e2ton, mais MJF en profite pour prendre la fuite. Darby Allin retire son masque en ringside et veut s&rsquo;approcher de MJF, mais Spears lui bloque le chemin et MJF prend la fuite sur la sc\u00e8ne. Allin prend son skateboard avec des punaises pour frapper Wardlow sur le dos avec.&nbsp;<strong>Allin prend le micro et dit que lui et MJF vont se voir \u00e0 Full Gear<\/strong>.<\/p>\n\n\n\n<p>&#8211; De retour, en coulisse, Tony Schiavone est avec le clan Britt Baker. Schiavone dit que Baker a refus\u00e9 d&rsquo;affronter Abadon sur la Jericho Cruise, alors Tony Khan a organis\u00e9 un match sans disqualification contre Abadon \u00e0 Rampage (Trick or Street Fight Match). Si Abadon gagne, elle aura un match de titre. Baker dit qu&rsquo;elle aussi a quelques tours dans son sac.<\/p>\n\n\n\n<p><strong>TNT Championship &#8211; Singles Match<\/strong><\/p>\n\n\n\n<p><em>Si Guevara perd, il devra quitter l&rsquo;Inner Circle.<\/em><\/p>\n\n\n\n<p><strong>Ethan Page vs Sammy Guevara (c)<\/strong><\/p>\n\n\n\n<p>\u00c0 la fin du combat, Page monte sur le coin, Guevara se rel\u00e8ve et monte avec lui, mais Page lui fait un Body Slam du coin. Page enchaine avec un coup d&rsquo;\u00e9paule et le couvre, mais Guevara r\u00e9siste. Page monte Guevara sur le coin pour son finisher, mais Guevara le renverse avec un Head Scissors ! Page \u00e9vite un Shooting Star Press de Guevara, mais Guevara le surprend avec un compte rapide pour la victoire !<\/p>\n\n\n\n<p><strong>Gagnant : Sammy Guevara<\/strong><\/p>\n\n\n\n<p>&#8211; Apr\u00e8s le combat, Page est furieux et frappe Guevara dans le dos ! Les deux \u00e9changent des coups, Guevara prend l&rsquo;avantage, mais Scorpio Sky arrive pour sauver Page. L&rsquo;Inner Circle arrive sur le ring et Page prend la fuite avec Sky. Chris Jericho prend le micro et dit que les idiots de l&rsquo;ann\u00e9e voulaient attaquer Guevara, c&rsquo;\u00e9tait \u00e9vident. Mais au moins Scorpio Sky l&rsquo;a battu deux fois, il a du respect. Mais la seule chose que Page bat c&rsquo;est lui-m\u00eame dans sa chambre d&rsquo;h\u00f4tel hier soir. Mais&nbsp;<strong>le plus important est que Guevara a remport\u00e9 son match alors nous aurons un 10-Man Tag Team Match \u00e0 Full Gear. Page, Sky et American Top Team contre l&rsquo;Inner Circle<\/strong>&nbsp;! Et ce match sera un Street Fight Match, gracieuset\u00e9 de Tony Khan. La semaine prochaine ils vont choisir les membres de l&rsquo;American Top Team, alors la t\u00eate de citrouille de merde doit venir pour entendre la newz. Pour terminer, ils vont leur botter le cul \u00e0 Full Gear.<\/p>\n\n\n\n<p>&#8211; En coulisse, Tony Schiavone est avec Eddie Kingston et Bryan Danielson pour avoir leur commentaire sur le tournoi avant leur match de Rampage. Kingston dit que chaque matin il prend une pilule pour ne pas taper sur tout le monde, il est tomb\u00e9 en d\u00e9pression et on ne sait jamais ce qu&rsquo;il va faire. Il travaille dur tous les jours pour se tenir pr\u00e9sent ici et il est impr\u00e9visible. Kingston quitte. Danielson dit que c&rsquo;est le Kingston qu&rsquo;il veut voir, le Kingston qu&rsquo;il veut affronter. Lui aussi a affront\u00e9 la d\u00e9pression et il ne va pas se plaindre. Beaucoup de gens ont v\u00e9cu la m\u00eame chose et vont livrer la marchandise. Kingston et Jon Moxley sont les catcheurs les plus solides, mais vendredi il va prouver qu&rsquo;il est le meilleur et il va le battre.<\/p>\n\n\n\n<p>&#8211; De retour, en coulisse, Tony Schiavone est avec les Lucha Bros qui ont un challenge pour FTR. Rey Fenix dit qu&rsquo;ils savent ce que FTR veut.&nbsp;<strong>Ils vont mettre les titres par \u00e9quipe AEW en jeux \u00e0 Full Gear<\/strong>. Penta El Zero M dit que les FTR disent \u00eatre les meilleurs, mais ils n&rsquo;ont aucune id\u00e9e des sacrifices qu&rsquo;ils ont fait. Alors \u00e0 Full Gear ils vont mettre les titres AEW en jeux !<\/p>\n\n\n\n<p><strong>Tournoi TBS Championship &#8211; Premier tour<\/strong><\/p>\n\n\n\n<p><strong>Serena Deeb vs Hikaru Shida<\/strong><\/p>\n\n\n\n<p>\u00c0 la fin du combat, Shida fait son Falcon Arrow sur Deeb et la couvre, mais elle r\u00e9siste. Shida enchaine avec son Running Knee pour la couvrir, mais elle r\u00e9siste encore. Shida se lance pour un coup de genou, mais Deeb la bloque. Deeb repousse Shida au sol pour lui attaquer le genou. Ensuite, Deeb applique un Half Crab \u00e0 Shida et enchaine avec un Figure Four. Shida r\u00e9siste et attrape un c\u00e2ble. Deeb veut frapper Shida avec la plaque des 50 victoires, mais Shida la bloque avec un coup de pied. Shida prend la plaque, mais l&rsquo;arbitre lui enl\u00e8ve. Deeb en profite avec un compte rapide, mais Shida r\u00e9siste. Deeb veut faire son D-Tox, mais Shida la renverse avec un compte rapide pour la victoire.<\/p>\n\n\n\n<p><strong>Gagnante : Hikaru Shida (qui remporte sa 50\u00e8me victoire)<\/strong><\/p>\n\n\n\n<p>&#8211; Apr\u00e8s le combat, Deeb n&rsquo;est pas contente et frappe Shida dans le dos. Deeb va chercher une chaise pour frapper Shida sur sa jambe avec. Deeb enchaine avec un Half Crab et les officiels arrivent pour l&rsquo;arr\u00eater.<\/p>\n\n\n\n<p>&#8211; En coulisse, Tony Schiavone est avec Lio Rush et Dante Martin pour avoir leur ressenti avant Rampage. Tony dit que Mike est bless\u00e9, alors nous aurons un match simple contre Matt. Lio Rush dit qu&rsquo;il n&rsquo;est pas surpris, nous aurons ses d\u00e9buts \u00e0 l&rsquo;AEW plus tard. Martin va affronter Matt Sydal une troisi\u00e8me fois. Cette fois-ci il sera dans le coin de Dante pour le soutenir. Matt Sydal va re\u00e7evoir une le\u00e7on vendredi.<\/p>\n\n\n\n<p>&#8211; De retour, les catcheurs arrivent.<\/p>\n\n\n\n<p><strong>Tournoi World Championship Eliminator &#8211; Premier tour<\/strong><\/p>\n\n\n\n<p><strong>#10 vs Jon Moxley<\/strong><\/p>\n\n\n\n<p>Moxley \u00e9crase #10 contre le coin et commence \u00e0 le mordre. #10 saigne. Moxley le ram\u00e8ne sur le ring et lui fait un Paradigm Shift pour le compte de trois.<\/p>\n\n\n\n<p><strong>Gagnant : Jon Moxley<\/strong><\/p>\n\n\n\n<p>&#8211; En coulisse, Tony Schiavone est avec FTR pour leur r\u00e9ponse aux Lucha Bros. Cash Wheeler dit qu&rsquo;ils ont attendu un an, ils acceptent, c&rsquo;est \u00e9vident. Tully Blanchard dit que les Lucha Bros ne savent pas ce qui les attendent. Dax Harwood dit qu&rsquo;\u00e0 Full Gear ils seront reconnus comme la meilleure \u00e9quipe de tous les temps.<\/p>\n\n\n\n<p>&#8211;<strong>&nbsp;Cody Rhodes et Arn Anderson<\/strong>&nbsp;arrivent sur le ring. De retour, Cody se fait toujours huer. Cody dit qu&rsquo;il nous entend. Samedi il a utilis\u00e9 le Tiger Driver pour vaincre Malakai Black, mais pendant un moment, il pensait faire une prise diff\u00e9rente. Mais qu&rsquo;est-ce qui serait arriv\u00e9 ? Il ne l&rsquo;a pas fait car \u00e7a aurait \u00e9t\u00e9 trop facile. C&rsquo;est la mani\u00e8re facile. On peut le soutenir ou le huer, mais il ne faut jamais oublier qu&rsquo;il est l&rsquo;homme qui a aid\u00e9 \u00e0 construire cette f\u00e9d\u00e9ration. Encore une fois c&rsquo;est l&rsquo;option facile. Il a commenc\u00e9 \u00e0 20 ans sans muscle, il a une femme trop chaude, un fr\u00e8re bien meilleur que lui et il \u00e9tait d&rsquo;une g\u00e9n\u00e9ration qui devait assumer l&rsquo;h\u00e9ritage gigantesque de ses parents. Il ne va pas tourner heel. La raison est simple, il nous aime tous et il va nous aimer tous sa vie. C&rsquo;est aussi un honneur d&rsquo;\u00eatre sur le ring avec Anderson, il s&rsquo;excuse, il avait raison.<\/p>\n\n\n\n<p>Andrade El Idolo arrive et lui demande pour qui il se prend. Andrade dit que les gens n&rsquo;aiment pas Cody, ni lui. Mais la diff\u00e9rence est qu&rsquo;il ne se pr\u00e9occupe pas des gens. Cody a fait un choix stupide. D&rsquo;abord le choix d\u00e9bile de se faire ce tatouage sur son cou. Deuxi\u00e8mement mettre son nez dans ses affaires. Il faut le regarder, il est Andrade El Idolo. Andrade entre sur le ring et dit qu&rsquo;il peut faire de Cody sa petite chienne. Les lumi\u00e8res s&rsquo;\u00e9teignent et Malakai Black est sur le ring du c\u00f4t\u00e9 d&rsquo;Andrade ! Black asperge Cody avec son Black Mist. Ils attaquent Cody et Anderson ! Pac arrive sur le ring et il expulse Black et Andrade avec une s\u00e9rie de coups de pied.<\/p>\n\n\n\n<p>&#8211; Pour Rampage vendredi : Danielson vs Kingston dans le tournoi World Title, Matt Sydal vs Dante Martin, et Baker vs Abadon dans un Street Dight. Pour mercredi prochain \u00e0 Dynamite : Cody vs Andrade, le tournoi TBS avec Jamie Hayter vs Anna Jay, Cassidy vs Moxley en demi-finale du tournoi World Title.<\/p>\n\n\n\n<p>&#8211; De retour, les \u00e9quipes arrivent sur le ring sous leur costume d&rsquo;halloween.<\/p>\n\n\n\n<p><strong>8-Man Tag Team Match<\/strong><\/p>\n\n\n\n<p><strong>Dark Order&nbsp;<em>(John Silver, Colt Cabana, Stu Grayson et Evil Uno)<\/em>&nbsp;vs The Elite&nbsp;<em>(Adam Cole, Kenny Omega, Nick et Matt Jackson)<\/em><\/strong><\/p>\n\n\n\n<p>\u00c0 la fin du combat, les deux \u00e9quipes \u00e9changent les coups de partout et Matt sonne l&rsquo;arbitre par erreur ! Grayson veut faire son finisher sur Matt, mais lui fait un Low Blow. Ils s&rsquo;amusent ensuite avec un Triple Low Blow sur le reste du Dark Order. The Elite va chercher ses pistolets de chasseur de fant\u00f4mes pour charger le Dark Order avec. Ils font une Triple Powerbomb \u00e0 Cabana sur les pistolets. Le reste du Dark Order arrive sur le ring, mais The Elite les expulse. Le bonhomme blanc du Elite retire son costume et ce n&rsquo;est pas Brandon Cutler, mais Adam Page ! Page fait sa Clothesline sur Matt. Grayson se lance en Moonsault sur Nick et Cole. Page enchaine avec son Death Eye sur Omega. Silver fait un Spin Doctor sur Matt pour le compte de trois.<\/p>\n\n\n\n<p><strong>Gagnants : Dark Order<\/strong><\/p>\n\n\n\n<p>Le show se termine avec une c\u00e9l\u00e9bration du Dark Order et Adam Page<\/p>\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>WATCH DAILYMOTION 720p Part 1&nbsp;Part 2 ALT Dailymotion Part 1&nbsp;Part 2 R\u00e9sum\u00e9 de AEW Dynamite du 27 octobre AEW Dynamite Boston, Massachusetts Les commentateurs sont Jim Ross, Tony Schiavone et Excalibur. &#8211; Ce soir c&rsquo;est AEW Dynamite, le show d\u00e9marre avec les pyros et les commentateurs qui nous souhaitent la bienvenue. Singles Match CM Punk&#8230;<\/p>\n","protected":false},"author":748,"featured_media":60504,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[24],"tags":[],"ppma_author":[296],"class_list":["post-60499","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-aew-impact-njpw-roh"],"authors":[{"term_id":296,"user_id":748,"is_guest":0,"slug":"hugo","display_name":"Hugo Real","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/7d05f3aafc80eb9bfb175c9a798607523338469284125bea10e5e84ab44decf7?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/60499","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/users\/748"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/comments?post=60499"}],"version-history":[{"count":3,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/60499\/revisions"}],"predecessor-version":[{"id":60505,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/60499\/revisions\/60505"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media\/60504"}],"wp:attachment":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media?parent=60499"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/categories?post=60499"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/tags?post=60499"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/ppma_author?post=60499"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}