{"id":60355,"date":"2021-10-26T02:02:00","date_gmt":"2021-10-26T06:02:00","guid":{"rendered":"https:\/\/www.jdx.info\/lutte\/?p=60355"},"modified":"2021-10-26T14:03:13","modified_gmt":"2021-10-26T18:03:13","slug":"une-autre-superstar-de-la-wwe-serait-contrariee-par-charlotte-flair-plus-de-details-sur-la-saga-flair-lynch-hors-des-ondes","status":"publish","type":"post","link":"https:\/\/www.jdx.info\/lutte\/2021\/10\/26\/une-autre-superstar-de-la-wwe-serait-contrariee-par-charlotte-flair-plus-de-details-sur-la-saga-flair-lynch-hors-des-ondes\/","title":{"rendered":"Une autre Superstar de la WWE serait contrari\u00e9e par Charlotte Flair, plus de d\u00e9tails sur la saga Flair &#038; Lynch hors des ondes!"},"content":{"rendered":"\n<p>Sonya Deville aurait \u00e9t\u00e9 furieuse contre la championne f\u00e9minine de SmackDown Charlotte Flair lors de l&rsquo;enregistrement de la WWE SmackDown vendredi.<\/p>\n\n\n\n<p>Comme nous l&rsquo;avons not\u00e9, il y a eu une vraie confrontation dans les coulisses entre Flair et la championne f\u00e9minine de RAW Becky Lynch au sujet du segment de l&rsquo;\u00e9change des titres f\u00e9minin RAW et Smackdown, qui a \u00e9t\u00e9 mod\u00e9r\u00e9 sur le ring par Deville.\u00a0La tension sur le ring aurait conduit \u00e0 des paroles entre Flair et Lynch dans les coulisses comme nous vous avons racont\u00e9 lors du week-end.<\/p>\n\n\n\n<p>Dans une mise \u00e0 jour, PWInsider rapporte que Deville aurait \u00e9t\u00e9 \u00ab assez folle pour vouloir combattre Flair \u00bb \u00e0 un moment donn\u00e9.\u00a0Deville et Flair ont \u00e9galement eu une dispute dans les coulisses de l&rsquo;ar\u00e9na.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p>La confrontation Lynch \u2013 Flair a eu lieu dans les coulisses de la Gorilla, sous les yeux du pr\u00e9sident et chef de la direction de la WWE, Vince McMahon et du vice-pr\u00e9sident senior Bruce Prichard, entre autres.\u00a0Cette confrontation a re\u00e7u le plus d&rsquo;attention au d\u00e9part, mais Deville a \u00e9galement eu des probl\u00e8mes avec Flair \u00e0 SmackDown.<\/p>\n\n\n\n<center><p><script async=\"\" src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script>\n<ins class=\"adsbygoogle\" style=\"display:block; text-align:center;\" data-ad-layout=\"in-article\" data-ad-format=\"fluid\" data-ad-client=\"ca-pub-1986975368136072\" data-ad-slot=\"7818521013\"><\/ins>\n<script>\n     (adsbygoogle = window.adsbygoogle || []).push({});\n<\/script><\/p><\/center>\n\n\n\n\n<p>Dans une mise \u00e0 jour sur les retomb\u00e9es de cette histoire entre Flair et Lynch, le PWInsider ajoute que l&rsquo;argumentation de Lynch avec Flair aurait \u00e9t\u00e9 bruyant et en col\u00e8re contre Lynch d\u00e9crit comme se d\u00e9fendant apr\u00e8s avoir \u00e9t\u00e9 manqu\u00e9 de respect.\u00a0Jusqu&rsquo;\u00e0 pr\u00e9sent, la responsabilit\u00e9 de la situation est tomb\u00e9e sur Flair, plusieurs personnes affirmant que la situation a commenc\u00e9 apr\u00e8s que Flair a clairement indiqu\u00e9 qu&rsquo;elle sentait que le segment la rendait faible et que son r\u00e8gne de titre paraissait faible.\u00a0Il y a eu plusieurs cas pr\u00e9sum\u00e9s o\u00f9 le comportement de Flair a conduit \u00e0 des probl\u00e8mes ces derniers mois, y compris le r\u00e9cent va-et-vient l\u00e9gitime sur le ring avec Nia Jax.<\/p>\n\n\n\n<p>La critique sur Flair est qu&rsquo;elle a \u00e9t\u00e9 indulgente envers elle-m\u00eame pour se prot\u00e9ger et s&rsquo;assurer que toute l&rsquo;attention soit sur elle, mais une source non proche de Flair a d\u00e9clar\u00e9: <\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>\u00ab<em>Soyons honn\u00eates, c&rsquo;est ce que font les stars.\u00a0Ils s&rsquo;assurent que leur puissance d&rsquo;\u00e9toile reste la m\u00eame ou sup\u00e9rieure.<\/em>\u00ab\u00a0<\/p><\/blockquote>\n\n\n\n<p>Une autre source a not\u00e9 que le ressentiment envers Flair s&rsquo;\u00e9tait accru ces derni\u00e8res semaines et que ce n&rsquo;\u00e9tait <\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>\u00ab qu&rsquo;une question de temps \u00bb avant que quelque chose ne se produise.<\/p><\/blockquote>\n\n\n\n<p>Flair a \u00e9t\u00e9 escort\u00e9e hors du b\u00e2timent par des responsables de la WWE vendredi soir, ce que certains de ses proches consid\u00e9raient comme un \u00ab\u00a0<em>signe de manque de respect<\/em>\u00a0\u00bb en soi, compte tenu de l&rsquo;histoire de sa famille avec l&rsquo;entreprise et de son importance pour la marque SmackDown.\u00a0Un talent qui \u00e9tait dans le b\u00e2timent, mais n&rsquo;a pas vu l&rsquo;argument, a estim\u00e9 que la WWE avait fait la bonne chose car c&rsquo;\u00e9tait juste sa fa\u00e7on de d\u00e9samorcer la situation sur le moment.<\/p>\n\n\n\n<center><p><script async=\"\" src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script>\n<ins class=\"adsbygoogle\" style=\"display:block; text-align:center;\" data-ad-layout=\"in-article\" data-ad-format=\"fluid\" data-ad-client=\"ca-pub-1986975368136072\" data-ad-slot=\"7818521013\"><\/ins>\n<script>\n     (adsbygoogle = window.adsbygoogle || []).push({});\n<\/script><\/p><\/center>\n\n\n\n\n<p>Il ne semble pas y avoir de chaleur sur Lynch pour le moment car l&rsquo;incident n&rsquo;est jamais devenu physique.<\/p>\n\n\n\n<p>Pour \u00e9carter toute sp\u00e9culation, Flair n&rsquo;\u00e9tait pas dans les coulisses d&rsquo;AEW Dynamite \u00e0 Orlando ce week-end, mais il y aurait des gens dans son entourage qui poussaient en priv\u00e9 l&rsquo;id\u00e9e qu&rsquo;elle essaie de sortir de son contrat avec la WWE, mais de mani\u00e8re r\u00e9aliste, personne s&rsquo;attend \u00e0 ce que cela se produise r\u00e9ellement du moins pas \u00e0 cours ou moyen terme. Il ne faut par contre jamais dire jamais mais nous n&rsquo;en somme pas l\u00e0.<\/p>\n\n\n\n<p>Il y a un certain nombre de personnes \u00e0 la WWE qui gardent un \u0153il sur Flair pour voir ce qui se passera avec elle et comment elle se comportera lorsqu&rsquo;elle se rendra \u00e0 SmackDown vendredi \u00e0 Wilkes-Barre, PA.&nbsp;Flair et Lynch ne se croiseront probablement pas jusqu&rsquo;\u00e0 ce que les sc\u00e9narios de la WWE appellent les sc\u00e9narios de la s\u00e9rie Survivor le mois prochain.<\/p>\n\n\n\n<p>Comme indiqu\u00e9, la WWE a \u00e9dit\u00e9 une partie du segment d&rsquo;\u00e9change Flair &#8211; Lynch de la rediffusion de SmackDown qui a \u00e9t\u00e9 diffus\u00e9e sur FOX samedi soir dernier.\u00a0Le segment sera \u00e9galement probablement modifi\u00e9 lorsque l&rsquo;\u00e9pisode sera archiv\u00e9 sur le r\u00e9seau WWE dans les prochaines semaines.<\/p>\n\n\n\n<p><\/p>\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>Sonya Deville aurait \u00e9t\u00e9 furieuse contre la championne f\u00e9minine de SmackDown Charlotte Flair lors de l&rsquo;enregistrement de la WWE SmackDown vendredi. Comme nous l&rsquo;avons not\u00e9, il y a eu une vraie confrontation dans les coulisses entre Flair et la championne f\u00e9minine de RAW Becky Lynch au sujet du segment de l&rsquo;\u00e9change des titres f\u00e9minin RAW&#8230;<\/p>\n","protected":false},"author":665,"featured_media":60419,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4,36,23],"tags":[],"ppma_author":[289],"class_list":["post-60355","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news","category-smackdown","category-wwe"],"authors":[{"term_id":289,"user_id":665,"is_guest":0,"slug":"line","display_name":"Line Edmond","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/852de09636413c90cdaa278312f9ea5bc4396768745424755cb63d99a05989d0?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/60355","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/users\/665"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/comments?post=60355"}],"version-history":[{"count":2,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/60355\/revisions"}],"predecessor-version":[{"id":60420,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/60355\/revisions\/60420"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media\/60419"}],"wp:attachment":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media?parent=60355"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/categories?post=60355"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/tags?post=60355"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/ppma_author?post=60355"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}