{"id":60014,"date":"2021-10-17T00:01:00","date_gmt":"2021-10-17T04:01:00","guid":{"rendered":"https:\/\/www.jdx.info\/lutte\/?p=60014"},"modified":"2021-10-17T10:05:52","modified_gmt":"2021-10-17T14:05:52","slug":"the-rock-parle-encore-de-faire-de-la-politique-orton-encore-dans-le-business-pour-longtemps-et-plus","status":"publish","type":"post","link":"https:\/\/www.jdx.info\/lutte\/2021\/10\/17\/the-rock-parle-encore-de-faire-de-la-politique-orton-encore-dans-le-business-pour-longtemps-et-plus\/","title":{"rendered":"The Rock Parle Encore de Faire de la Politique! \/ Orton Encore Dans Le Business Pour Longtemps! Ric Flair Travail pour Trump, et Plus!"},"content":{"rendered":"\n<p>Randy Orton est \u00e0 la WWE depuis 2001, un vrai v\u00e9t\u00e9ran de l&rsquo;industrie, mais alors, comment notre homme planifie sa deuxi\u00e8me partie de vie et une potentielle retraite des rings ?<\/p>\n\n\n\n<p>Le personnage nonchalant de Randy Orton et ses messages sur les r\u00e9seaux sociaux laissent parfois pr\u00e9sager une sortie de la WWE et m\u00eame de l&rsquo;univers catchesque en g\u00e9n\u00e9ral. Il est aussi difficile de savoir ce qu&rsquo;il pense r\u00e9ellement puisqu&rsquo;il fait souvent usage de sarcasme et ne fait presque aucune interview hors WWE.<\/p>\n\n\n\n<p>Cette semaine, le p\u00e8re de Randy Orton, Bob Orton, \u00e9tait en interview pour \u00a0\u00bbAppalachian Expose\u00a0\u00bb et il a d\u00e9clar\u00e9 que selon lui, son fils ne quittera jamais le business. Il explique que Randy adore \u00e9voluer dans le monde du catch et voudra probablement se concentrer sur la formation des jeunes s&rsquo;il prend sa retraite des rings :<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>\u00a0\u00bbJe suis s\u00fbr qu&rsquo;il voudra rester dans l&rsquo;industrie et peut-\u00eatre aider les jeunes comme il a \u00e9t\u00e9 aid\u00e9 par le pass\u00e9, des choses comme \u00e7a. Je ne sais pas s&rsquo;il a quelque chose de pr\u00e9vu, mais je crois qu&rsquo;il aime suffisamment le business pour vouloir rester impliqu\u00e9 d&rsquo;une mani\u00e8re ou d&rsquo;une autre.\u00a0\u00bb<\/p><\/blockquote>\n\n\n\n<p><\/p>\n\n\n\n<center><p><script async=\"\" src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script>\n<ins class=\"adsbygoogle\" style=\"display:block; text-align:center;\" data-ad-layout=\"in-article\" data-ad-format=\"fluid\" data-ad-client=\"ca-pub-1986975368136072\" data-ad-slot=\"7818521013\"><\/ins>\n<script>\n     (adsbygoogle = window.adsbygoogle || []).push({});\n<\/script><\/p><\/center>\n\n\n\n<p>Ce n&rsquo;est pas nouveau, on parle souvent de la possibilit\u00e9 de voir The Rock comme pr\u00e9sident des \u00c9tats-Unis. Un sc\u00e9nario lanc\u00e9 ces derni\u00e8res ann\u00e9es face \u00e0 la popularit\u00e9 de The Rock et son admiration par le public am\u00e9ricain, que ce soit \u00e0 cause du catch ou du cin\u00e9ma.<\/p>\n\n\n\n<p>En 2017, les rumeurs avaient \u00e9t\u00e9 bon train apr\u00e8s son passage chez SNL o\u00f9 il jouait le r\u00f4le de pr\u00e9sident et ensuite, un&nbsp;comit\u00e9 de soutien de campagne avait \u00e9t\u00e9 lanc\u00e9. Aujourd&rsquo;hui, nous avons la s\u00e9rie Young Rock, produite par The Rock qui met en sc\u00e8ne sa vie d&rsquo;enfant jusqu&rsquo;\u00e0 aujourd&rsquo;hui o\u00f9 il devient pr\u00e9sident des \u00c9tats-Unis.<\/p>\n\n\n\n<p>Ce qui lance encore plus de rumeurs pour les prochaines \u00e9lections. Cette semaine, le Rock \u00e9tait en interview pour Vanity Flair et il a confirm\u00e9 avoir r\u00e9ellement analys\u00e9 le dossier :<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>\u00a0\u00bbJ&rsquo;ai fait des petites recherches et analyses pour voir d&rsquo;o\u00f9 venait cet engouement et \u00e0 quoi cela pourrait ressembler \u00e0 l&rsquo;avenir.\u00a0\u00bb<\/p><\/blockquote>\n\n\n\n<p>The Rock ne veut pas en dire beaucoup plus sur le sujet, mais il pr\u00e9cise que les indicateurs sont \u00a0\u00bbtr\u00e8s positifs\u00a0\u00bb pour une course \u00e0 la pr\u00e9sidentielle en 2024 ou en 2028 s&rsquo;il d\u00e9cide de se lancer. Il ajoute qu&rsquo;aujourd&rsquo;hui, il ne pense pas \u00eatre un excellent candidat :<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>\u00a0\u00bbJe me soucie beaucoup de notre pays. Je me soucie de tous les putains d&rsquo;Am\u00e9ricains qui ont du sang rouge. Et il n&rsquo;y a pas d&rsquo;illusion ici, j&rsquo;ai peut-\u00eatre des qualit\u00e9s de leadership d\u00e9centes, mais \u00e7a ne fait pas n\u00e9cessairement de moi un bon candidat \u00e0 la pr\u00e9sidentielle. C&rsquo;est l\u00e0 o\u00f9 j&rsquo;en suis aujourd&rsquo;hui.\u00a0\u00bb<\/p><\/blockquote>\n\n\n\n<center><p><script async=\"\" src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script>\n<ins class=\"adsbygoogle\" style=\"display:block; text-align:center;\" data-ad-layout=\"in-article\" data-ad-format=\"fluid\" data-ad-client=\"ca-pub-1986975368136072\" data-ad-slot=\"7818521013\"><\/ins>\n<script>\n     (adsbygoogle = window.adsbygoogle || []).push({});\n<\/script><\/p><\/center>\n\n\n\n\n<p>Parlant de Politique, Ric Flair n&rsquo;a jamais vraiment cach\u00e9e son all\u00e9geance et c&rsquo;est presque sans surprise que le Nature Boy a \u00e9t\u00e9 annonc\u00e9 pour une soir\u00e9e organis\u00e9e par les R\u00e9publicains. Celle-ci aura lieu le 1er d\u00e9cembre \u00e0 Palm Beach en Floride. L&rsquo;organisateur est \u00e9tonnant vu qu&rsquo;il s&rsquo;agira de Donald Trump. L&rsquo;ancien pr\u00e9sident am\u00e9ricain a ainsi pr\u00e9vu pour ce jour une lev\u00e9e de fond en faveur d&rsquo;Herschel Walker, candidat pour se pr\u00e9senter au nom des R\u00e9publicains pour le S\u00e9nat en G\u00e9orgie. <\/p>\n\n\n\n<p>Depuis son passage \u00e0 la WCW, Flair a toujours \u00e9t\u00e9 proche de cet Etat.L&rsquo;invitation ne dit cependant pas pourquoi la c\u00e9r\u00e9monie est pr\u00e9vue en Floride pour un homme politique souhaitant se pr\u00e9senter en G\u00e9orgie.<\/p>\n\n\n\n<center><blockquote class=\"twitter-tweet\"><p lang=\"en\" dir=\"ltr\">Trump is hosting a fundraiser for Senate candidate <a href=\"https:\/\/twitter.com\/HerschelWalker?ref_src=twsrc%5Etfw\">@HerschelWalker<\/a> in Florida with several sports figures serving as honorary hosts including Tom Glavine, Doug Flutie and \u2026 Ric Flair. <a href=\"https:\/\/twitter.com\/hashtag\/gapol?src=hash&amp;ref_src=twsrc%5Etfw\">#gapol<\/a> <a href=\"https:\/\/twitter.com\/hashtag\/gasen?src=hash&amp;ref_src=twsrc%5Etfw\">#gasen<\/a> <a href=\"https:\/\/t.co\/ZCUnH5MCwQ\">pic.twitter.com\/ZCUnH5MCwQ<\/a><\/p>&mdash; Greg Bluestein (@bluestein) <a href=\"https:\/\/twitter.com\/bluestein\/status\/1449016675819573250?ref_src=twsrc%5Etfw\">October 15, 2021<\/a><\/blockquote> <script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/center>\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>Randy Orton est \u00e0 la WWE depuis 2001, un vrai v\u00e9t\u00e9ran de l&rsquo;industrie, mais alors, comment notre homme planifie sa deuxi\u00e8me partie de vie et une potentielle retraite des rings ? Le personnage nonchalant de Randy Orton et ses messages sur les r\u00e9seaux sociaux laissent parfois pr\u00e9sager une sortie de la WWE et m\u00eame de&#8230;<\/p>\n","protected":false},"author":609,"featured_media":60015,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[30,4,23],"tags":[],"ppma_author":[295],"class_list":["post-60014","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ex-wwe","category-news","category-wwe"],"authors":[{"term_id":295,"user_id":609,"is_guest":0,"slug":"rodrigo","display_name":"Rodrigue Tousignant","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/51fe284bb6dbe8a6b4c2bf998ad658f4a9cd24b7e58f15ec85888070c7340ce6?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/60014","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/users\/609"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/comments?post=60014"}],"version-history":[{"count":3,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/60014\/revisions"}],"predecessor-version":[{"id":60021,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/60014\/revisions\/60021"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media\/60015"}],"wp:attachment":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media?parent=60014"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/categories?post=60014"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/tags?post=60014"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/ppma_author?post=60014"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}