{"id":59741,"date":"2021-10-11T21:53:31","date_gmt":"2021-10-11T21:53:31","guid":{"rendered":"https:\/\/www.jdx.info\/lutte\/?p=59741"},"modified":"2021-10-11T23:17:21","modified_gmt":"2021-10-11T23:17:21","slug":"deuxieme-heure-de-raw-23","status":"publish","type":"post","link":"https:\/\/www.jdx.info\/lutte\/2021\/10\/11\/deuxieme-heure-de-raw-23\/","title":{"rendered":"Deuxi\u00e8me Heure de RAW"},"content":{"rendered":"\n<ul class=\"wp-block-list\"><li><a href=\"https:\/\/www.jdx.info\/lutte\/2021\/10\/11\/resultats-et-video-du-wwe-monday-night-raw-du-11-octobre-2021\/\"><strong>Pour revenir \u00e0 la premi\u00e8re heure de RAW, cliquez ici<\/strong><\/a><\/li><\/ul>\n\n\n\n<p>\u2013 De retour, les catcheurs arrivent. Riddle prend le micro et dit qu\u2019il aimerait parler avant de commencer. Il a beaucoup r\u00e9fl\u00e9chi. Il peut dire qu\u2019Omos a pris quelques notes pour son look, beaucoup plus styl\u00e9 qu\u2019AJ. Riddle dit qu\u2019il a oubli\u00e9 de quoi il parlait. Riddle appel Randy Orton, mais personne n\u2019arrive. Riddle dit qu\u2019Orton est surement trop occup\u00e9. AJ Styles dit que c\u2019est ridicule, l\u2019arbitre voit bien que Riddle renonce au match. \u00c7a va arriver, Omos va lui arracher la t\u00eate. Riddle chante le nom de Randy. AJ demande de lancer le match.<\/p>\n\n\n\n<p><strong>Riddle vs Omos&nbsp;acc AJ Styles<\/strong><\/p>\n\n\n\n<p>En fin de match, Omos \u00e9crase Riddle et lui fait un ChokeSlam pour le couvrir, mais AJ Styles lui dit d\u2019arr\u00eater. AJ dit qu\u2019ils peuvent le battre comme ils veulent, alors c\u2019est le moment. Il veut voir un Round House Kick. Omos porte le coup de pied. AJ demande de voir des reprises. Omos enchaine avec un Double Hand ChokeSlam pour le compte de trois.<\/p>\n\n\n\n<p><em>Gagnant : Omos<\/em><\/p>\n\n\n\n<p>\u2013 Apr\u00e8s le combat, AJ dit que lui n\u2019a pas termin\u00e9. AJ rel\u00e8ve Riddle pour son finisher, mais la musique de Randy Orton commence et personne n\u2019arrive. AJ demande \u00e0 Omos de quitter le ring pour prot\u00e9ger ses arri\u00e8res. Orton arrive de nulle part et fait un RKO \u00e0 AJ pour ensuite prendre la fuite avec Riddle.<\/p>\n\n\n\n<p>\u2013 En coulisse, Drew McIntyre dit \u00e0 Big E qu\u2019il est responsable pour les Superkicks. Big E dit qu\u2019ils vont se battre \u00e0 Crown Jewel, mais ce soir ils doivent bien s\u2019entendre. McIntyre dit que le Chef de la Tribu fait bien d\u2019avoir peur contre eux. McIntyre et Big E se serrent la main.<\/p>\n\n\n\n<center><p><script async=\"\" src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script>\n<ins class=\"adsbygoogle\" style=\"display:block; text-align:center;\" data-ad-layout=\"in-article\" data-ad-format=\"fluid\" data-ad-client=\"ca-pub-1986975368136072\" data-ad-slot=\"7818521013\"><\/ins>\n<script>\n     (adsbygoogle = window.adsbygoogle || []).push({});\n<\/script><\/p><\/center>\n\n\n\n\n<p>\u2013&nbsp;<strong>Bobby Lashley<\/strong>&nbsp;arrive sur le ring. De retour, on pr\u00e9sente une vid\u00e9o de la confrontation entre Lashley et Goldberg&nbsp;lundi dernier \u00e0 RAW. Lashley que beaucoup de personnes lui demande pourquoi il a challeng\u00e9 Goldberg dans un No Holds Barred. Mais avant de r\u00e9pondre est-ce qu\u2019on a vu Goldberg le menac\u00e9 de terminer sa vie ? Il n\u2019est pas seulement le prochain, mais aussi le prochain \u00e0 mourir. Ce comportement ne repr\u00e9sente pas un WWE Superstar, un Hall of Famer ou un p\u00e8re. Est-ce qu\u2019on veut voir quelqu\u2019un chaque semaine v\u00eatu en or qui d\u00e9fend le titre WWE chaque semaine ? Ou quelqu\u2019un avec un tee-shirt coup\u00e9 criant au sujet d\u2019un meurtre. Il a challeng\u00e9 Goldberg au No Holds Barred car il ne peut pas aller dans un match contre un homme qui hurle comme un animal. La l\u00e9gende de Goldberg crie fort, mais le chien doit \u00eatre tu\u00e9. \u00c0 Crown Jewel il va finalement terminer la carri\u00e8re de Goldberg. Termin\u00e9 d\u2019avoir Goldberg qui arrive \u00e0 RAW, essayer de battre quelqu\u2019un et ensuite repartir.&nbsp;Lashley dit qu\u2019il n\u2019y aura pas de confusion. Goldberg ne peut pas battre le tout puissant, Goldberg ne peut pas blesser le tout puissant et Goldberg ne peut assur\u00e9ment pas tuer le tout puissant.<\/p>\n\n\n\n<p>\u2013 En coulisse, Sasha Banks dit que depuis l\u2019\u00e9change de Charlotte \u00e0 SmackDown elle agit comme elle est en charge. Alors que la championne de SmackDown c\u2019est elle qui d\u00e9cide. Ce soir elle doit faire confiance avec Bianca Belair, celle qui a perdu le titre en 30 secondes. Belair doit simplement suivre ses directives puisqu\u2019elle est la patronne. Becky et Charlotte ne peut pas se comparer \u00e0 elle. Elle va battre Bianca et Becky pour devenir notre nouvelle championne de SmackDown \u00e0 Crown Jewel.<\/p>\n\n\n\n<p><strong>Jeff Hardy vs Austin Theory<\/strong><\/p>\n\n\n\n<p>En fin de match, Theory applique une soumission \u00e0 Jeff, mais Reggie arrive sur le ring alors qu\u2019il est pourchass\u00e9 par un groupe de catcheurs. Jeff en profite pour faire un Atomic Drop et un Twist of Fate sur Theory. Jeff se lance en Swanton, mais Theory l\u2019\u00e9vite et lui fait un Roll Up en tirant sur le pantalon pour compl\u00e9ter le trois.<\/p>\n\n\n\n<p><em>Gagnant : Austin Theory<\/em><\/p>\n\n\n\n<p>\u2013 En coulisse, Bianca Belair dit qu\u2019elle vient d\u2019un parcours diff\u00e9rent de Charlotte. D\u2019o\u00f9 elle vient \u00e7a prend du coeur pour gagner. Charlotte c\u2019est aucune piti\u00e9 pour tricher et gagner. Elle se souvient d\u2019avoir battu Sasha Banks au main event de WrestleMania, ce n\u2019est pas plus dur. Pour Becky Lynch \u00e7a ira rapidement pour voir Becky aucun titre.<\/p>\n\n\n\n<center><p><script async=\"\" src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script>\n<ins class=\"adsbygoogle\" style=\"display:block; text-align:center;\" data-ad-layout=\"in-article\" data-ad-format=\"fluid\" data-ad-client=\"ca-pub-1986975368136072\" data-ad-slot=\"7818521013\"><\/ins>\n<script>\n     (adsbygoogle = window.adsbygoogle || []).push({});\n<\/script><\/p><\/center>\n\n\n\n\n<p class=\"has-medium-font-size\"><strong>Premier tour King of the Ring<\/strong><\/p>\n\n\n\n<p><strong>Jinder Mahal&nbsp;acc Veer et Shanky&nbsp;vs Kofi Kingston&nbsp;acc  de Xavier Woods<\/strong><\/p>\n\n\n\n<p>En fin de match, Shany veut intervenir, mais Woods le frappe. Veer fait une Clothesline \u00e0 Woods pour le sonner. Mahal en profite avec un Roll Up sur Kofi, mais il r\u00e9siste. Kofi le repousse et se lance du coin, mais Mahal le renverse avec sa Full Nelson Slam pour le compte de trois.<\/p>\n\n\n\n<p><em>Gagnant : Jinder Mahal<\/em><\/p>\n\n\n\n<p>&#8211; En coulisse, Becky Lynch dit qu&rsquo;elles n&rsquo;ont pas beaucoup \u00e0 dire Sasha, Bianca ou Charlotte. Elle a battu chacune d&rsquo;entre elles. Elle a \u00e9t\u00e9 la championne de RAW avec le plus long r\u00e8gne car elle pense toujours plus loin. Elle va mener son \u00e9quipe \u00e0 la victoire au contraire de Belair qui perd en quelques secondes ou Sasha qui pleure apr\u00e8s ses matchs. Elle va entrer et sortir de Crown Jewel comme la championne.<\/p>\n\n\n\n<p>&#8211; The Boss Sasha Banks fait son entr\u00e9e et on part \u00e0 la pause.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p class=\"has-medium-font-size\"><strong><a href=\"https:\/\/www.jdx.info\/lutte\/2021\/10\/11\/troisieme-heure-de-raw-24\/\">Pour la suite de RAW et actualiser la page, cliquez ici.<\/a><\/strong><\/p>\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>Pour revenir \u00e0 la premi\u00e8re heure de RAW, cliquez ici \u2013 De retour, les catcheurs arrivent. Riddle prend le micro et dit qu\u2019il aimerait parler avant de commencer. Il a beaucoup r\u00e9fl\u00e9chi. Il peut dire qu\u2019Omos a pris quelques notes pour son look, beaucoup plus styl\u00e9 qu\u2019AJ. Riddle dit qu\u2019il a oubli\u00e9 de quoi il&#8230;<\/p>\n","protected":false},"author":4,"featured_media":59742,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[43],"tags":[],"ppma_author":[292],"class_list":["post-59741","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-raw-wwe"],"authors":[{"term_id":292,"user_id":4,"is_guest":0,"slug":"jean","display_name":"Jean Vinnier","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/33aba0263fd870a0b487e0e079ff407e10e3997c9d2987cbcc0db0db2c5c75a9?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/59741","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/comments?post=59741"}],"version-history":[{"count":10,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/59741\/revisions"}],"predecessor-version":[{"id":59786,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/59741\/revisions\/59786"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media\/59742"}],"wp:attachment":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media?parent=59741"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/categories?post=59741"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/tags?post=59741"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/ppma_author?post=59741"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}