{"id":59710,"date":"2021-10-10T14:47:00","date_gmt":"2021-10-10T14:47:00","guid":{"rendered":"https:\/\/www.jdx.info\/lutte\/?p=59710"},"modified":"2021-10-10T22:48:09","modified_gmt":"2021-10-10T22:48:09","slug":"le-recent-match-de-wwe-smackdown-aurait-eu-un-vainqueur-different-que-prevu-de-la-frustration-au-sein-de-la-division-feminine-et-plus","status":"publish","type":"post","link":"https:\/\/www.jdx.info\/lutte\/2021\/10\/10\/le-recent-match-de-wwe-smackdown-aurait-eu-un-vainqueur-different-que-prevu-de-la-frustration-au-sein-de-la-division-feminine-et-plus\/","title":{"rendered":"Le r\u00e9cent match de WWE SmackDown aurait eu un vainqueur diff\u00e9rent que pr\u00e9vu! De la frustration au sein de la division f\u00e9minine, et plus!"},"content":{"rendered":"\n<p>Vendredi soir durant le WWE SmackDown sur FOX qui mettait en vedette l&rsquo;ancienne championne f\u00e9minine Carmella battant Liv Morgan lors du match d&rsquo;ouverture du tournoi  Queen&rsquo;s Crown l&rsquo;\u00e9quivalent du King of the Ring.<\/p>\n\n\n\n<p>Selon&nbsp;Fightful Select&nbsp;, les cr\u00e9atifs de la WWE avait&nbsp;inscrit&nbsp;Morgan comme vainqueur du match avant la diffusion de l&rsquo;\u00e9mission mais \u00e0 un moment donn\u00e9, la d\u00e9cision a \u00e9t\u00e9 modifi\u00e9e.&nbsp;Le rapport ajoute qu&rsquo;il y a eu une frustration importante dans les coulisses de la part des talents et du personnel concernant le booking de la division f\u00e9minine, un probl\u00e8me avec lequel ils ont \u00e9t\u00e9 en proie \u00e0 plusieurs reprises.<\/p>\n\n\n\n<p>Il est \u00e0 se demander \u00e0 quel moment Liv Morgan arrivera \u00e0 remporter une rencontre importante au sein de la WWE. Apr\u00e8s avoir perdu au Royal Rumble, \u00e0 WrestleMania ou encore \u00e0 Money in the Bank cette ann\u00e9e,&nbsp;l&rsquo;ancienne membre du Riott Squad n&rsquo;a pas r\u00e9ussi \u00e0 vaincre Carmella lors du dernier \u00e9pisode de SmackDown. Cette d\u00e9faite en moins de 2 minutes, l&rsquo;\u00e9limine directement du tournoi Queen&rsquo;s Crown, malgr\u00e9 le soutien bien pr\u00e9sent de ses fans.<\/p>\n\n\n\n<p>Cependant,&nbsp;Fightful&nbsp;nous d\u00e9voile qu&rsquo;il \u00e9tait pr\u00e9vu un moment donn\u00e9 avant le match que Liv Morgan gagne face \u00e0 Carmella comme mentionn\u00e9 en d\u00e9but d&rsquo;article. <\/p>\n\n\n\n<p>Sa victoire a finalement \u00e9t\u00e9 annul\u00e9e au profit de celle de son adversaire du soir, qui affrontera alors Zelina Vega ce vendredi dans les demi-finales du tournoi. En revanche, la raison de ce changement n&rsquo;a pas \u00e9t\u00e9 expliqu\u00e9e. <\/p>\n\n\n\n<p>Notez que c&rsquo;\u00e9tait la cinqui\u00e8me fois que Liv Morgan et Carmella s&rsquo;affronter depuis juin, et la deuxi\u00e8me fois que Carmella l&#8217;emporte.<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li><strong><a href=\"https:\/\/www.jdx.info\/lutte\/2021\/10\/08\/resultats-et-video-du-wwe-friday-night-smackdown-premiere-de-la-saison\/\" target=\"_blank\" rel=\"noreferrer noopener\">Pour les r\u00e9sultats complets ou voir ce Smackdown, cliquez ici.<\/a><\/strong><\/li><\/ul>\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>Vendredi soir durant le WWE SmackDown sur FOX qui mettait en vedette l&rsquo;ancienne championne f\u00e9minine Carmella battant Liv Morgan lors du match d&rsquo;ouverture du tournoi Queen&rsquo;s Crown l&rsquo;\u00e9quivalent du King of the Ring. Selon&nbsp;Fightful Select&nbsp;, les cr\u00e9atifs de la WWE avait&nbsp;inscrit&nbsp;Morgan comme vainqueur du match avant la diffusion de l&rsquo;\u00e9mission mais \u00e0 un moment donn\u00e9,&#8230;<\/p>\n","protected":false},"author":665,"featured_media":59715,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4,36,23],"tags":[],"ppma_author":[289],"class_list":["post-59710","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news","category-smackdown","category-wwe"],"authors":[{"term_id":289,"user_id":665,"is_guest":0,"slug":"line","display_name":"Line Edmond","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/852de09636413c90cdaa278312f9ea5bc4396768745424755cb63d99a05989d0?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/59710","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/users\/665"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/comments?post=59710"}],"version-history":[{"count":3,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/59710\/revisions"}],"predecessor-version":[{"id":59717,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/59710\/revisions\/59717"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media\/59715"}],"wp:attachment":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media?parent=59710"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/categories?post=59710"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/tags?post=59710"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/ppma_author?post=59710"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}