{"id":59008,"date":"2021-09-28T08:06:00","date_gmt":"2021-09-28T08:06:00","guid":{"rendered":"https:\/\/www.jdx.info\/lutte\/?p=59008"},"modified":"2021-09-28T16:12:28","modified_gmt":"2021-09-28T16:12:28","slug":"trois-dream-matchs-pour-cm-punk-ladiction-de-kurt-angle-nouveau-match-pour-le-strong-showdown-et-plus","status":"publish","type":"post","link":"https:\/\/www.jdx.info\/lutte\/2021\/09\/28\/trois-dream-matchs-pour-cm-punk-ladiction-de-kurt-angle-nouveau-match-pour-le-strong-showdown-et-plus\/","title":{"rendered":"Trois Dream Matchs pour CM Punk \/ L&rsquo;Adiction de Kurt Angle! \/ Nouveau match pour le Strong Showdown, Et Plus!"},"content":{"rendered":"\n<p>Apr\u00e8s avoir officialis\u00e9\u00a0quelques affiches\u00a0r\u00e9cemment, la NJPW en a confirm\u00e9 une nouvelle, qui verra Minoru Suzuki et Lance Archer prendre leur revanche contre le duo compos\u00e9 de Jon Moxley et Eddie Kingston, il s&rsquo;agira d&rsquo;un Philadelphia Street Fight. On rappelle que ces deux-l\u00e0 ont battu les premiers cit\u00e9s lors du dernier \u00e9pisode de Rampage.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large\"><img decoding=\"async\" src=\"https:\/\/411mania.com\/wp-content\/uploads\/2021\/09\/moxkingsuzarch-645x370.jpeg\" alt=\"\"\/><\/figure><\/div>\n\n\n\n<p>CM Punk n&rsquo;est jamais contre, lorsqu&rsquo;il s&rsquo;agit de r\u00e9pondre \u00e0 quelques questions sur Twitter. R\u00e9cemment, il a fait plaisir \u00e0 une fan, qui lui demandait ses trois matchs de r\u00eave \u00e0 l&rsquo;AEW. Le Best In The World a ainsi list\u00e9 les matchs ci-dessous :<\/p>\n\n\n\n<p>1. CM Punk vs. Bryan Danielson<br>2. CM Punk vs. Kenny Omega<br>3. CM Punk &amp; Bryan Danielson vs. Lucha Bros (Hair\/Beard vs. Mask\/Titles) \u00e0 Mexico City (Mexique)<\/p>\n\n\n\n<center><blockquote class=\"twitter-tweet\"><p lang=\"en\" dir=\"ltr\">Bryan, omega, me\/bryan vs lucha bros mask\/titles vs hair\/beard Mexico City.<\/p>&mdash; player\/coach (@CMPunk) <a href=\"https:\/\/twitter.com\/CMPunk\/status\/1441500915853262851?ref_src=twsrc%5Etfw\">September 24, 2021<\/a><\/blockquote> <script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script> <\/center>\n<center><p><script async=\"\" src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script>\n<ins class=\"adsbygoogle\" style=\"display:block; text-align:center;\" data-ad-layout=\"in-article\" data-ad-format=\"fluid\" data-ad-client=\"ca-pub-1986975368136072\" data-ad-slot=\"7818521013\"><\/ins>\n<script>\n     (adsbygoogle = window.adsbygoogle || []).push({});\n<\/script><\/p><\/center>\n\n\n\n\n<p>Dans un r\u00e9cent \u00e9pisode du Kurt Angle Show, le m\u00e9daill\u00e9 d&rsquo;or olympique est revenu sur son d\u00e9part de la WWE en 2006 et notamment son rendez-vous avec Vince McMahon o\u00f9 il se rendit compte de tous ses probl\u00e8mes li\u00e9 \u00e0 l&rsquo;addiction.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>Quand je suis all\u00e9 le voir avant un show TV, je suis all\u00e9 \u00e0 la r\u00e9union entre les producteurs et Vince McMahon, qui pr\u00e9paraient le show. Ils venaient de finir leur r\u00e9union et quittaient la salle, donc je suis entr\u00e9 et j&rsquo;ai baiss\u00e9 mon pantalon devant Vince (McMahon) jusqu&rsquo;aux genoux et je lui ai dit que c&rsquo;\u00e9tait \u00e0 cause de ce qu&rsquo;il s&rsquo;\u00e9tait pass\u00e9 la veille et que j&rsquo;avais dor\u00e9navant tout le bassin noir, les genoux noirs \u00e9galement, mes jambes aussi, ainsi que mon abdomen. Il m&rsquo;a alors dit \u00ab\u00a0J&rsquo;imagine que tu ne voudras pas lutter dans le Triple Threat Ladder Match de ce soir\u00a0\u00bb et je lui ai bien \u00e9videmment r\u00e9pondu que non et que je voulais lui parler. Il \u00e9tait d&rsquo;accord pour qu&rsquo;on se parle \u00e0 l&rsquo;instant, mais je lui ai fait savoir que j&rsquo;avais besoin de le voir au si\u00e8ge social, il m&rsquo;a alors dit que ce n&rsquo;\u00e9tait pas un probl\u00e8me. Du coup, plus tard dans la semaine, j&rsquo;ai pris un vol pour Stamford (Connecticut) et je vous pr\u00e9viens, je n&rsquo;ai jamais racont\u00e9 cela publiquement par le pass\u00e9, c&rsquo;est vraiment la premi\u00e8re fois que j&rsquo;en parle. Je suis all\u00e9 dans son bureau, j&rsquo;\u00e9tais avec mon agent et dans le bureau, il y avait Shane McMahon, John Laurinaitis et Vince.<\/p><p>Je rentre et Vince me demande de m&rsquo;assoir. Je regarde donc devant moi et je vois sept pages de textes imprim\u00e9s et je suis l\u00e0 \u00ab\u00a0Putain, c&rsquo;est quoi \u00e7a ?\u00a0\u00bb j&rsquo;ai pris une feuille et j&rsquo;ai vu que c&rsquo;\u00e9tait des texto ou des messages vocaux que j&rsquo;avais envoy\u00e9 \u00e0 Vince, qui disaient \u00ab\u00a0Vince, je vais te botter le cul quand je te croiserai\u00a0\u00bb ou encore \u00a0\u00bb Vince, si tu ne me r\u00e9pond pas, je vais te casser la gueule\u00a0\u00bb, bref il y avait plein de menaces.<\/p><p>J&rsquo;\u00e9tais perdu, je ne me souvenais pas avoir envoy\u00e9 de tels messages, puis je me suis souvenu des anti-douleurs que je prenais. Je n&rsquo;ai jamais lutt\u00e9 en planant, pas une seule fois et je prenais que la dose de ce que j&rsquo;\u00e9tais cens\u00e9 prendre, c&rsquo;est-\u00e0-dire un anti-douleur tous les 4 \u00e0 6 heures. Mais quand le show se terminait, le Kurt Angle addict refaisait surface et prenait 20 \u00e0 25 comprim\u00e9s, je ne savais m\u00eame pas ce que je faisais. Je calmais mes nerfs sur les messages que j&rsquo;envoyais \u00e0 Vince, parce qu&rsquo;il prenait ses distances de moi dans ces moments difficiles, je le prenais s\u00fbrement mal. Mon comportement \u00e9tait difficile \u00e0 pr\u00e9voir, personne ne savait comment j&rsquo;allais r\u00e9agir \u00e0 un moment donn\u00e9, je me blessais souvent et pourtant, je le poussais \u00e0 ce qu&rsquo;il me donne un titre, qu&rsquo;il m&rsquo;ajoute dans les pay-per-views, pour avoir une meilleure paie. Bref, pas mal de trucs se passaient, sans que je m&rsquo;en rende toujours compte.<\/p><\/blockquote>\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>Apr\u00e8s avoir officialis\u00e9\u00a0quelques affiches\u00a0r\u00e9cemment, la NJPW en a confirm\u00e9 une nouvelle, qui verra Minoru Suzuki et Lance Archer prendre leur revanche contre le duo compos\u00e9 de Jon Moxley et Eddie Kingston, il s&rsquo;agira d&rsquo;un Philadelphia Street Fight. On rappelle que ces deux-l\u00e0 ont battu les premiers cit\u00e9s lors du dernier \u00e9pisode de Rampage. CM Punk&#8230;<\/p>\n","protected":false},"author":609,"featured_media":59009,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[38,24,30,22,55,4],"tags":[],"ppma_author":[295],"class_list":["post-59008","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-aew","category-aew-impact-njpw-roh","category-ex-wwe","category-indy","category-njpw","category-news"],"authors":[{"term_id":295,"user_id":609,"is_guest":0,"slug":"rodrigo","display_name":"Rodrigue Tousignant","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/51fe284bb6dbe8a6b4c2bf998ad658f4a9cd24b7e58f15ec85888070c7340ce6?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/59008","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/users\/609"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/comments?post=59008"}],"version-history":[{"count":1,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/59008\/revisions"}],"predecessor-version":[{"id":59010,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/59008\/revisions\/59010"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media\/59009"}],"wp:attachment":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media?parent=59008"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/categories?post=59008"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/tags?post=59008"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/ppma_author?post=59008"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}