{"id":58991,"date":"2021-09-28T05:29:00","date_gmt":"2021-09-28T05:29:00","guid":{"rendered":"https:\/\/www.jdx.info\/lutte\/?p=58991"},"modified":"2021-09-28T15:30:03","modified_gmt":"2021-09-28T15:30:03","slug":"cody-rhodes-hue-a-cause-de-sa-femme-brandi-eva-marie-hors-service-et-plus","status":"publish","type":"post","link":"https:\/\/www.jdx.info\/lutte\/2021\/09\/28\/cody-rhodes-hue-a-cause-de-sa-femme-brandi-eva-marie-hors-service-et-plus\/","title":{"rendered":"Cody Rhodes Hu\u00e9 \u00e0 Cause de sa Femme Brandi! \/ Eva Marie Hors Service, et Plus!"},"content":{"rendered":"\n<p><\/p>\n\n\n\n<p><\/p>\n\n\n\n<p>Il n&rsquo;y a pas longtemps, c&rsquo;\u00e9tait  Nia Jax et maintenant au tour d&rsquo;Eva Marie de recevoir le traitement Baszler.<\/p>\n\n\n\n<p>Lundi soir \u00e0 RAW, Eva Marie a \u00e9t\u00e9 attaqu\u00e9 par la championne f\u00e9minine de RAW Charlotte Flair et par la suite, Shayna Baszler cest venue terminer le boulot de la m\u00eame mani\u00e8re que Nia Jax a \u00e9t\u00e9 sortie de la comp\u00e9tition. <\/p>\n\n\n\n<p>Aujourd&rsquo;hui la WWE annonce qu&rsquo;Eva Marie souffre d&rsquo;une possible dislocation au coude et qu&rsquo;elle subit pr\u00e9sentement des traitements.<\/p>\n\n\n\n<p>Nia Jax se retrouve \u00e0 l&rsquo;\u00e9cart pour une dur\u00e9e ind\u00e9termin\u00e9e, pour Eva Marie la situation reste \u00e0 suivre. La WWE pr\u00e9cise que le m\u00e9decin donnera plus de d\u00e9tails \u00e0 la compagnie plus tard. Eva Marie a r\u00e9agi \u00e0 la nouvelle sur Twitter indiquant qu&rsquo;elle allait entamer une poursuite.<\/p>\n\n\n\n<p>Si on porte attention au Tweet, on peut voir qu&rsquo;Eva Marie a partag\u00e9 une ancienne photo. On peut voir qu&rsquo;il s&rsquo;agit d&rsquo;une photo du 6 septembre 2021 datant du moment o\u00f9 elle a re\u00e7u un traitement de cellules souches pour am\u00e9liorer sa condition physique.<\/p>\n\n\n\n<center><blockquote class=\"twitter-tweet\"><p lang=\"en\" dir=\"ltr\">Lawsuit Incoming ! <a href=\"https:\/\/twitter.com\/hashtag\/JusticeForEvaMarie?src=hash&amp;ref_src=twsrc%5Etfw\">#JusticeForEvaMarie<\/a> <a href=\"https:\/\/t.co\/qcFs4xRAM6\">https:\/\/t.co\/qcFs4xRAM6<\/a> <a href=\"https:\/\/t.co\/lvIUi3z4i1\">pic.twitter.com\/lvIUi3z4i1<\/a><\/p>&mdash; Eva Marie (@natalieevamarie) <a href=\"https:\/\/twitter.com\/natalieevamarie\/status\/1442891145445404674?ref_src=twsrc%5Etfw\">September 28, 2021<\/a><\/blockquote> <script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/center>\n\n<center><p><script async=\"\" src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script>\n<ins class=\"adsbygoogle\" style=\"display:block; text-align:center;\" data-ad-layout=\"in-article\" data-ad-format=\"fluid\" data-ad-client=\"ca-pub-1986975368136072\" data-ad-slot=\"7818521013\"><\/ins>\n<script>\n     (adsbygoogle = window.adsbygoogle || []).push({});\n<\/script><\/p><\/center>\n\n\n\n\n<p>Lors du dernier \u00e9pisode de son podcast The Jim Cornette Experience, Jim Cornette nous a parl\u00e9 des hu\u00e9s pour Cody Rhodes lors de son match \u00e0 Arthur Ashe et il pense que Brandi Rhodes y est pour beaucoup dans cet accueil des fans.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>\u201cUne grande partie de la tension vient du fait que tout le monde peut voir que Brandi est juste ins\u00e9r\u00e9e dans le tableau parce qu&rsquo;elle doit \u00eatre \u00e0 la t\u00e9l\u00e9vision, qu&rsquo;il y ait une raison valable pour qu&rsquo;elle soit l\u00e0 ou pas, et elle n&rsquo;est pas une bonne catcheuse. La seule bonne promo qu&rsquo;elle ait faite dans sa vie \u00e9tait contre Jade Cargill et les gens peuvent dire qu&rsquo;elle est l\u00e0 parce que c&rsquo;est sa femme. Pour un heel, \u00e7a marcherait, pour un face, \u00e7a n&rsquo;a pas march\u00e9.\u201d<\/p><\/blockquote>\n\n\n\n<p><em><\/em>Beaucoup de fans qui ont hu\u00e9 Cody Rhodes et par la m\u00eame occasion Brandi Rhodes (elle a fait une petite intervention dans le match en s\u2019asseyant en face de Malakai Black puis en lui faisant des doigts), l\u2019ont fait pour la raison cit\u00e9e par Jim Cornette. Pour Jim Cornette, peu de fans appr\u00e9cient Brandi Rhodes quand il s\u2019agit d&rsquo;\u00eatre sur un ring ou bien dans des promos.&nbsp;<\/p>\n\n\n\n<p>La ou il n&rsquo;\u00e9tait pas du tout logique de la voir, c&rsquo;\u00e9tait lors de ce match et surtout lorsqu&rsquo;elle fait des gestes obsc\u00e8nes qui n&rsquo;ont rien avoir avec l\u2019attitude de face de son mari. Jim Cornette ajoute que Cody \u00e9tait bel et bien le plus gros heel du show au Arthur Ashe stadium.\u00a0<\/p>\n\n\n\n<p><strong><a href=\"https:\/\/www.jdx.info\/lutte\/2021\/09\/22\/bryan-vs-omega-retour-de-cody-sting-en-action-cm-punk-et-beacoup-daction-pour-le-special-grand-slam-2021-a-dynamite-ce-soir\/\" target=\"_blank\" rel=\"noreferrer noopener\">Pour les r\u00e9sultats complet ou voir le dernier AEW Dynamite, cliquez ici.<\/a><\/strong><\/p>\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>Il n&rsquo;y a pas longtemps, c&rsquo;\u00e9tait Nia Jax et maintenant au tour d&rsquo;Eva Marie de recevoir le traitement Baszler. Lundi soir \u00e0 RAW, Eva Marie a \u00e9t\u00e9 attaqu\u00e9 par la championne f\u00e9minine de RAW Charlotte Flair et par la suite, Shayna Baszler cest venue terminer le boulot de la m\u00eame mani\u00e8re que Nia Jax a&#8230;<\/p>\n","protected":false},"author":609,"featured_media":58993,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[38,24,4,23],"tags":[],"ppma_author":[295],"class_list":["post-58991","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-aew","category-aew-impact-njpw-roh","category-news","category-wwe"],"authors":[{"term_id":295,"user_id":609,"is_guest":0,"slug":"rodrigo","display_name":"Rodrigue Tousignant","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/51fe284bb6dbe8a6b4c2bf998ad658f4a9cd24b7e58f15ec85888070c7340ce6?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/58991","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/users\/609"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/comments?post=58991"}],"version-history":[{"count":1,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/58991\/revisions"}],"predecessor-version":[{"id":58994,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/58991\/revisions\/58994"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media\/58993"}],"wp:attachment":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media?parent=58991"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/categories?post=58991"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/tags?post=58991"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/ppma_author?post=58991"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}