{"id":58555,"date":"2021-09-22T07:53:00","date_gmt":"2021-09-22T07:53:00","guid":{"rendered":"https:\/\/www.jdx.info\/lutte\/?p=58555"},"modified":"2021-09-22T16:01:19","modified_gmt":"2021-09-22T16:01:19","slug":"triple-h-donne-des-nouvelles-de-sa-condition-will-ospreay-recrute-et-plus","status":"publish","type":"post","link":"https:\/\/www.jdx.info\/lutte\/2021\/09\/22\/triple-h-donne-des-nouvelles-de-sa-condition-will-ospreay-recrute-et-plus\/","title":{"rendered":"Triple H Donne des Nouvelles de sa Condition \/ Will Ospreay Recrute , et Plus !"},"content":{"rendered":"\n<p>Ce week-end, la Rev Pro tenait son show High Stakes et durant cet \u00e9v\u00e9nement Will Ospreay affrontait Ricky Knight Jr. pour d\u00e9terminer le champion poids lourds incontest\u00e9 de la f\u00e9d\u00e9ration.<\/p>\n\n\n\n<p>Will Ospreay est ressorti vainqueur de cette confrontation, mais ce n\u2019est pas tout car son groupe qu\u2019il a form\u00e9 \u00e0 la NJPW, l\u2019United Empire, s\u2019agrandit avec les arriv\u00e9es de l&rsquo;\u00e9quipe Aussie Open compos\u00e9e de Kyle Fletcher et de Mark Davis, qui sont aussi les champions par \u00e9quipe de la Rev Pro.<\/p>\n\n\n\n<center><blockquote class=\"twitter-tweet\"><p lang=\"en\" dir=\"ltr\">UNITED EMPIRE <a href=\"https:\/\/t.co\/MevA8xyftN\">pic.twitter.com\/MevA8xyftN<\/a><\/p>&mdash; \u1d42\u2071\u02e1\u02e1 \u1d3c\u02e2\u1d56\u02b3\u1d49\u1d43\u02b8 \u2022 \u30a6\u30a3\u30eb\u30fb\u30aa\u30b9\u30d7\u30ec\u30a4 (@WillOspreay) <a href=\"https:\/\/twitter.com\/WillOspreay\/status\/1439686550347001864?ref_src=twsrc%5Etfw\">September 19, 2021<\/a><\/blockquote> <script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script>\n\n<p><script async=\"\" src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script>\n<ins class=\"adsbygoogle\" style=\"display:block; text-align:center;\" data-ad-layout=\"in-article\" data-ad-format=\"fluid\" data-ad-client=\"ca-pub-1986975368136072\" data-ad-slot=\"7818521013\"><\/ins>\n<script>\n     (adsbygoogle = window.adsbygoogle || []).push({});\n<\/script><\/p><\/center>\n\n\n\n\n<p><\/p>\n\n\n\n<p>Il y a quelques semaines, nous apprenions par un communiqu\u00e9 de la WWE, que Triple H avait \u00e9t\u00e9 hospitalis\u00e9 apr\u00e8s avoir subi un accident cardiaque d\u00fb \u00e0 un probl\u00e8me g\u00e9n\u00e9tique h\u00e9r\u00e9ditaire. Une intervention chirurgicale a ensuite \u00e9t\u00e9 r\u00e9alis\u00e9e avec succ\u00e8s.<\/p>\n\n\n\n<p>Aujourd&rsquo;hui, Triple H a publi\u00e9 un message sur Twitter en nous assurant qu\u2019il allait beaucoup mieux et qu\u2019il lui fallait du repos. Il a aussi \u00e9t\u00e9 tr\u00e8s \u00e9mu par tous les messages de soutien qui lui sont parvenus. Il ajoute qu\u2019il est absolument \u00e9merveill\u00e9 par la r\u00e9ponse et le soutien re\u00e7u par la communaut\u00e9 du catch.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>\u201cJ&rsquo;ai \u00e9t\u00e9 \u00e9poustoufl\u00e9 par l&rsquo;aide et le soutien de tant de personnes. Je me remets, je vais bien et je suis profond\u00e9ment reconnaissant pour tout l&rsquo;amour que j&rsquo;ai dans ma vie. Je suis particuli\u00e8rement reconnaissant envers @ShawnMichaels et toutes les Superstars et l&rsquo;\u00e9quipe @WWENXT ! (Steph et les filles ont ador\u00e9 les collations !) \u00c0 bient\u00f4t.\u201d<\/p><\/blockquote>\n\n\n\n<center><blockquote class=\"twitter-tweet\"><p lang=\"en\" dir=\"ltr\">I\u2019ve been blown away by the outreach and support from so many people. I\u2019m recovering, doing well, &amp; deeply grateful for all the love in my life. Especially grateful for <a href=\"https:\/\/twitter.com\/ShawnMichaels?ref_src=twsrc%5Etfw\">@ShawnMichaels<\/a> &amp; all the Superstars &amp; crew <a href=\"https:\/\/twitter.com\/WWENXT?ref_src=twsrc%5Etfw\">@WWENXT<\/a>! (Steph and the girls loved the snacks!) <br>See you soon &#x1f64f;&#x2764;&#xfe0f;<\/p>&mdash; Triple H (@TripleH) <a href=\"https:\/\/twitter.com\/TripleH\/status\/1440440573337292804?ref_src=twsrc%5Etfw\">September 21, 2021<\/a><\/blockquote> <script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/center>\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>Ce week-end, la Rev Pro tenait son show High Stakes et durant cet \u00e9v\u00e9nement Will Ospreay affrontait Ricky Knight Jr. pour d\u00e9terminer le champion poids lourds incontest\u00e9 de la f\u00e9d\u00e9ration. Will Ospreay est ressorti vainqueur de cette confrontation, mais ce n\u2019est pas tout car son groupe qu\u2019il a form\u00e9 \u00e0 la NJPW, l\u2019United Empire, s\u2019agrandit&#8230;<\/p>\n","protected":false},"author":609,"featured_media":58557,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[24,22,4,23],"tags":[],"ppma_author":[295],"class_list":["post-58555","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-aew-impact-njpw-roh","category-indy","category-news","category-wwe"],"authors":[{"term_id":295,"user_id":609,"is_guest":0,"slug":"rodrigo","display_name":"Rodrigue Tousignant","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/51fe284bb6dbe8a6b4c2bf998ad658f4a9cd24b7e58f15ec85888070c7340ce6?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/58555","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/users\/609"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/comments?post=58555"}],"version-history":[{"count":1,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/58555\/revisions"}],"predecessor-version":[{"id":58556,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/58555\/revisions\/58556"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media\/58557"}],"wp:attachment":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media?parent=58555"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/categories?post=58555"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/tags?post=58555"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/ppma_author?post=58555"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}