{"id":58512,"date":"2021-09-21T06:30:00","date_gmt":"2021-09-21T06:30:00","guid":{"rendered":"https:\/\/www.jdx.info\/lutte\/?p=58512"},"modified":"2021-09-21T14:37:59","modified_gmt":"2021-09-21T14:37:59","slug":"le-new-day-dans-les-griffes-de-lundertaker-des-chants-special-durant-la-celebration-de-big-e-a-raw-et-plus","status":"publish","type":"post","link":"https:\/\/www.jdx.info\/lutte\/2021\/09\/21\/le-new-day-dans-les-griffes-de-lundertaker-des-chants-special-durant-la-celebration-de-big-e-a-raw-et-plus\/","title":{"rendered":"Le New Day Dans Les Griffes de l&rsquo;Undertaker! \/ Des Chants Sp\u00e9cial Durant la C\u00e9l\u00e9bration de Big E \u00e0 RAW, et Plus!"},"content":{"rendered":"\n<p>Au d\u00e9but du mois de septembre on apprenait que Netflix allait lancer un\u00a0nouveau film dans le cadre de son partenariat\u00a0avec la WWE. Il s&rsquo;agit de \u00a0\u00bbEscape the Undertaker\u00a0\u00bb ou en version francophone \u00a0\u00bbDans les griffes de l&rsquo;Undertaker\u00a0\u00bb. <\/p>\n\n\n\n<p>Big E, Xavier Woods et Kofi Kingston seront enferm\u00e9s dans le manoir de l&rsquo;Undertaker et il faudra prendre des d\u00e9cisions pour d\u00e9cider du sort des trois catcheurs. En effet, ce film sera un nouveau projet dans la s\u00e9rie des films interactif. Description du film :<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>\u00a0\u00bbEst-ce que The New Day survivra aux surprises du manoir de l&rsquo;Undertaker ? C&rsquo;est \u00e0 vous de le d\u00e9cider dans ce sp\u00e9cial interactif qui vous plonge dans l&rsquo;univers de la WWE !\u00a0\u00bb<\/p><\/blockquote>\n\n\n\n<center><blockquote class=\"twitter-tweet\"><p lang=\"en\" dir=\"ltr\">Are you brave enough to wield the power of <a href=\"https:\/\/twitter.com\/undertaker?ref_src=twsrc%5Etfw\">@undertaker<\/a>&#39;s urn? <br><br>&#x1f480; Escape The Undertaker premieres October 5 on <a href=\"https:\/\/twitter.com\/netflix?ref_src=twsrc%5Etfw\">@netflix<\/a>! &#x1f480;<a href=\"https:\/\/twitter.com\/WWEBigE?ref_src=twsrc%5Etfw\">@WWEBigE<\/a> <a href=\"https:\/\/twitter.com\/TrueKofi?ref_src=twsrc%5Etfw\">@TrueKofi<\/a> <a href=\"https:\/\/twitter.com\/AustinCreedWins?ref_src=twsrc%5Etfw\">@AustinCreedWins<\/a> <a href=\"https:\/\/t.co\/3suU33j1bx\">pic.twitter.com\/3suU33j1bx<\/a><\/p>&mdash; WWE (@WWE) <a href=\"https:\/\/twitter.com\/WWE\/status\/1440331424565907457?ref_src=twsrc%5Etfw\">September 21, 2021<\/a><\/blockquote> <script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/center>\n\n\n\n<p>Parlant du New Day on ne peut pas, ne pas parler de leur r\u00e9union lundi soir \u00e0 RAW.  La WWE a d\u00e9but\u00e9 le show rouge cette semaine avec la c\u00e9l\u00e9bration de Big E avec le New Day. Pendant ce discours, il a mentionn\u00e9 celui qui personne qui le prenait de haut, chose qui n&rsquo;a \u00e9chapp\u00e9 \u00e0 personne pr\u00e9sent dans les grandins ni \u00e0 celles et ceux qui \u00e9taient derri\u00e8re leur \u00e9cran. Et il y avait de quoi car Big E et Brodie Lee sont des amis tr\u00e8s proches au point o\u00f9 Big E \u00e9tait l&rsquo;une des rares personnes de la WWE \u00e0 \u00eatre au courant de la maladie de l&rsquo;ancien Luke Harper. Il \u00e9tait \u00e9galement pr\u00e9sent pour la famille de Brodie Lee pendant cette p\u00e9riode difficile.<\/p>\n\n\n\n<p>D\u00e8s lors que Big E a mentionn\u00e9 Brodie Lee \u00e0 la t\u00e9l\u00e9vision sans dire vraiment son nom, les fans ont tout de suite encha\u00een\u00e9 avec des chants \u00ab\u00a0BRODIE BRODIE BRODIE\u00a0\u00bb. Big E est rest\u00e9 l\u00e0, debout au milieu de la sc\u00e8ne, le temps de r\u00e9aliser que la foule savait exactement de QUI il parlait, la perte de Brodie Lee \u00e9tant encore ressentie comme une perte terrible pour la communaut\u00e9 de la lutte professionnelle.<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li><strong><a href=\"https:\/\/www.jdx.info\/lutte\/2021\/09\/20\/resultats-et-video-du-wwe-monday-night-raw-du-20-septembre-2021\/\" target=\"_blank\" rel=\"noreferrer noopener\">Pour les r\u00e9sultats ou voir le dernier RAW, cliquez ici.<\/a><\/strong><\/li><\/ul>\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>Au d\u00e9but du mois de septembre on apprenait que Netflix allait lancer un\u00a0nouveau film dans le cadre de son partenariat\u00a0avec la WWE. Il s&rsquo;agit de \u00a0\u00bbEscape the Undertaker\u00a0\u00bb ou en version francophone \u00a0\u00bbDans les griffes de l&rsquo;Undertaker\u00a0\u00bb. Big E, Xavier Woods et Kofi Kingston seront enferm\u00e9s dans le manoir de l&rsquo;Undertaker et il faudra prendre&#8230;<\/p>\n","protected":false},"author":609,"featured_media":58513,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4,43,23],"tags":[],"ppma_author":[295],"class_list":["post-58512","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news","category-raw-wwe","category-wwe"],"authors":[{"term_id":295,"user_id":609,"is_guest":0,"slug":"rodrigo","display_name":"Rodrigue Tousignant","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/51fe284bb6dbe8a6b4c2bf998ad658f4a9cd24b7e58f15ec85888070c7340ce6?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/58512","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/users\/609"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/comments?post=58512"}],"version-history":[{"count":1,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/58512\/revisions"}],"predecessor-version":[{"id":58514,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/58512\/revisions\/58514"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media\/58513"}],"wp:attachment":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media?parent=58512"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/categories?post=58512"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/tags?post=58512"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/ppma_author?post=58512"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}