{"id":58453,"date":"2021-09-20T21:19:48","date_gmt":"2021-09-20T21:19:48","guid":{"rendered":"https:\/\/www.jdx.info\/lutte\/?p=58453"},"modified":"2021-09-20T23:38:10","modified_gmt":"2021-09-20T23:38:10","slug":"deuxieme-heure-de-raw-20","status":"publish","type":"post","link":"https:\/\/www.jdx.info\/lutte\/2021\/09\/20\/deuxieme-heure-de-raw-20\/","title":{"rendered":"Deuxi\u00e8me Heure de RAW!"},"content":{"rendered":"\n<ul class=\"wp-block-list\"><li><a href=\"https:\/\/www.jdx.info\/lutte\/2021\/09\/20\/resultats-et-video-du-wwe-monday-night-raw-du-20-septembre-2021\/\"><strong>Pour revenir \u00e0 la premi\u00e8re heure, cliquez ici.<\/strong><\/a><\/li><\/ul>\n\n\n\n<p>&#8211; De retour, en coulisse, Pearce et Deville discutent au t\u00e9l\u00e9phone pour g\u00e9rer la soir\u00e9e. Paul Heyman arrive et dit que Big E s&rsquo;amuse \u00e0 se plaindre et ils n&rsquo;ont aucune autorit\u00e9. Deville dit que nous aurons&nbsp;un Triple Threat Match alors, Big E contre Reigns contre Lashley. Pearce dit \u00e0 Heyman d&rsquo;aller aviser Reigns.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><strong>Randy Orton&nbsp;acc  de Riddle&nbsp;vs AJ Styles&nbsp;acc  d&rsquo;Omos<\/strong><\/p>\n\n\n\n<p>Pendant le combat, l&rsquo;arbitre expulse Omos qui a voulu intervenir.<\/p>\n\n\n\n<p>En fin de match, AJ veut faire son Phenomenal Forearm, mais il arr\u00eate lorsqu&rsquo;Orton allait le bloquer. Orton en profite pour faire son DDT de la deuxi\u00e8me corde et fait son RKO pour le compte de trois.<\/p>\n\n\n\n<p><em>Gagnant : Randy Orton<\/em><\/p>\n\n\n\n<p>&#8211;&nbsp;On pr\u00e9sente une vid\u00e9o sur l&rsquo;histoire entre Nia Jax et Baszler, et on part \u00e0 la pause.<\/p>\n\n\n\n<p><strong>Nia Jax vs Shayna Baszler<\/strong><\/p>\n\n\n\n<p>En fin de match, Baszler applique sa Kirifuda Clutch sur Jax. Jax fini par tomber au sol et Baszler poursuit la soumission, l&rsquo;arbitre arr\u00eate le match puisque Jax ne r\u00e9pond plus.<\/p>\n\n\n\n<p><em>Gagnante : Shayna Baszler&nbsp;<\/em><\/p>\n\n\n\n<p>Apr\u00e8s le combat, Baszler attaque Jax. Baszer bloque le bras de Jax dans la marche d&rsquo;acier et saute dessus. Baszler saute une seconde fois sur le bras de Jax et le m\u00e9decin arrive pour s&rsquo;occuper de Jax.<\/p>\n\n\n\n<p>&#8211; De retour, les catcheurs arrivent. Avant le match en coulisse, Garza et Carrillo dit qu&rsquo;on regarde aux plus beaux et meilleurs catcheurs de la WWE. Le monde leur appartient.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><strong>Mansoor et Mustafa Ali vs Humberto Carrillo et Angel Garza<\/strong><\/p>\n\n\n\n<p>En fin de match, Carrillo applique un Headlock sur Ali et Garza compl\u00e8te avec un Drop Kick, Carrillo fait le compte de trois pour la victoire alors que Mansoor \u00e9tait sonn\u00e9 en bas du ring.<\/p>\n\n\n\n<p><em>Gagnants : Humberto Carrillo et Angel Garza<\/em><\/p>\n\n\n\n<p>&#8211; On pr\u00e9sente une vid\u00e9o sur Karrion Kross.<\/p>\n\n\n\n<p>&#8211; Nikki ASH et Ripley arrivent sur la sc\u00e8ne. Nikki dit qu&rsquo;avant leur match elles voulaient parler de leur ami Connor. Nikki et Ripley font la promotion de la fondation Connor&rsquo;s Cure. Ripley dit que leur match de ce soir sera d\u00e9di\u00e9 aux enfants, tout le monde qui est affect\u00e9 par le cancer p\u00e9diatrique. Nikki demande aux fans de faire un signe V en signe de la victoire.<\/p>\n\n\n\n<center><p><script async=\"\" src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script>\n<ins class=\"adsbygoogle\" style=\"display:block; text-align:center;\" data-ad-layout=\"in-article\" data-ad-format=\"fluid\" data-ad-client=\"ca-pub-1986975368136072\" data-ad-slot=\"7818521013\"><\/ins>\n<script>\n     (adsbygoogle = window.adsbygoogle || []).push({});\n<\/script><\/p><\/center>\n\n\n\n\n<p class=\"has-medium-font-size\"><strong>Championnat F\u00e9minin par \u00c9quipe WWE<\/strong><\/p>\n\n\n\n<p><strong>Nikki A.S.H et Rhea Ripley vs Tamina et Natalya (c)<\/strong><\/p>\n\n\n\n<p>En fin de match, Ripley fait son Riptide sur Tamina sur le tablier alors que Tamina voulait l&rsquo;attaquer. Nikki en profite pour faire un Small Package \u00e0 Natalya qui \u00e9tait distraite pour le compte de trois.<\/p>\n\n\n\n<p><em>Gagnantes  et Nouvelles Championnes: Nikki A.S.H et Rhea Ripley <\/em><\/p>\n\n\n\n<p>&#8211; On pr\u00e9sente une vid\u00e9o sur l&rsquo;histoire entre Charlotte et Bliss. Alexa Bliss arrive sur le ring et on part \u00e0 la pause.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p class=\"has-medium-font-size\"><strong><a href=\"https:\/\/www.jdx.info\/lutte\/2021\/09\/20\/troisieme-heure-de-raw-21\/\">Pour la suite de RAW, cliquez ici.<\/a><\/strong><\/p>\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>Pour revenir \u00e0 la premi\u00e8re heure, cliquez ici. &#8211; De retour, en coulisse, Pearce et Deville discutent au t\u00e9l\u00e9phone pour g\u00e9rer la soir\u00e9e. Paul Heyman arrive et dit que Big E s&rsquo;amuse \u00e0 se plaindre et ils n&rsquo;ont aucune autorit\u00e9. Deville dit que nous aurons&nbsp;un Triple Threat Match alors, Big E contre Reigns contre Lashley&#8230;.<\/p>\n","protected":false},"author":4,"featured_media":58454,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[43],"tags":[],"ppma_author":[292],"class_list":["post-58453","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-raw-wwe"],"authors":[{"term_id":292,"user_id":4,"is_guest":0,"slug":"jean","display_name":"Jean Vinnier","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/33aba0263fd870a0b487e0e079ff407e10e3997c9d2987cbcc0db0db2c5c75a9?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/58453","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/comments?post=58453"}],"version-history":[{"count":11,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/58453\/revisions"}],"predecessor-version":[{"id":58489,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/58453\/revisions\/58489"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media\/58454"}],"wp:attachment":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media?parent=58453"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/categories?post=58453"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/tags?post=58453"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/ppma_author?post=58453"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}