{"id":58420,"date":"2021-09-21T05:13:00","date_gmt":"2021-09-21T05:13:00","guid":{"rendered":"https:\/\/www.jdx.info\/lutte\/?p=58420"},"modified":"2021-09-21T14:13:54","modified_gmt":"2021-09-21T14:13:54","slug":"ruby-riot-affirme-avoir-retrouve-la-passion-en-venant-a-la-aew-mise-a-jour-sur-mia-yim-a-la-wwe","status":"publish","type":"post","link":"https:\/\/www.jdx.info\/lutte\/2021\/09\/21\/ruby-riot-affirme-avoir-retrouve-la-passion-en-venant-a-la-aew-mise-a-jour-sur-mia-yim-a-la-wwe\/","title":{"rendered":"Ruby Riot affirme avoir retrouv\u00e9 la passion en venant \u00e0 la AEW! \/ Mise \u00e0 jour sur Mia Yim \u00e0 la WWE!"},"content":{"rendered":"\n<p>La superstar de la WWE Mia Yim n&rsquo;a pas du tout \u00e9t\u00e9 utilis\u00e9e \u00e0 la t\u00e9l\u00e9vision cette ann\u00e9e apr\u00e8s s&rsquo;\u00eatre s\u00e9par\u00e9e de l&rsquo;\u00e9curie Retribution \u00e0 la fin de l&rsquo;ann\u00e9e derni\u00e8re.&nbsp;<\/p>\n\n\n\n<p>Yim a \u00e9t\u00e9 test\u00e9 positif au COVID-19 fin janvier.&nbsp;Il avait \u00e9t\u00e9 question de faire ses d\u00e9buts \u00e0 SmackDown quelques mois apr\u00e8s janvier, mais cela ne s&rsquo;est pas produit.&nbsp;<\/p>\n\n\n\n<p>Yim a confirm\u00e9 sur Twitter qu&rsquo;elle n&rsquo;\u00e9tait pas bless\u00e9e.\u00a0Il semble qu&rsquo;il s&rsquo;agisse davantage d&rsquo;une situation dans laquelle l&rsquo;\u00e9quipe cr\u00e9ative n&rsquo;a rien pour Yim en ce moment.\u00a0<\/p>\n\n\n\n<center><blockquote class=\"twitter-tweet\"><p lang=\"en\" dir=\"ltr\">I\u2019m not injured.<\/p>&mdash; The HBIC (@MiaYim) <a href=\"https:\/\/twitter.com\/MiaYim\/status\/1439601256193040390?ref_src=twsrc%5Etfw\">September 19, 2021<\/a><\/blockquote> <script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/center>\n\n\n\n<center><p><script async=\"\" src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script>\n<ins class=\"adsbygoogle\" style=\"display:block; text-align:center;\" data-ad-layout=\"in-article\" data-ad-format=\"fluid\" data-ad-client=\"ca-pub-1986975368136072\" data-ad-slot=\"7818521013\"><\/ins>\n<script>\n     (adsbygoogle = window.adsbygoogle || []).push({});\n<\/script><\/p><\/center>\n\n\n\n\n<p>Ce n&rsquo;est pas la premi\u00e8re fois qu&rsquo;une star du ring affirme avoir perdu la passion \u00e0 la WWE, mais l&rsquo;a retrouv\u00e9e ailleurs. Ruby \u00ab\u00a0Riot\u00a0\u00bb Soho partage le m\u00eame discours, elle qui est devenue All Elite apr\u00e8s ses d\u00e9buts \u00e0 All Out. Alors qu&rsquo;elle s&rsquo;appr\u00eate \u00e0 affronter Britt Baker pour le titre demain, l&rsquo;ancienne lutteuse de la AEW s&rsquo;est exprim\u00e9 sur cette passion retrouv\u00e9e.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>Depuis mon passage \u00e0 la TV, je n&rsquo;ai jamais obtenu de titre. Ma victoire \u00e0 All Out a cependant solidifi\u00e9 mon opportunit\u00e9 de potentiellement devenir championne de l&rsquo;AEW, ce qui serait le plus grand honneur que je pourrais avoir. Du coup, l&rsquo;objectif pour moi sera bien \u00e9videmment de devenir championne pour la premi\u00e8re fois \u00e0 la TV. Ce serait super et ce n&rsquo;est pas un but que je prends \u00e0 la l\u00e9g\u00e8re, mais je pense que je souhaite dans l&rsquo;absolu, retrouver un jour mon amour pour le catch, chose que j&rsquo;ai pu faire (bri\u00e8vement) \u00e0 All Out.<\/p><\/blockquote>\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>La superstar de la WWE Mia Yim n&rsquo;a pas du tout \u00e9t\u00e9 utilis\u00e9e \u00e0 la t\u00e9l\u00e9vision cette ann\u00e9e apr\u00e8s s&rsquo;\u00eatre s\u00e9par\u00e9e de l&rsquo;\u00e9curie Retribution \u00e0 la fin de l&rsquo;ann\u00e9e derni\u00e8re.&nbsp; Yim a \u00e9t\u00e9 test\u00e9 positif au COVID-19 fin janvier.&nbsp;Il avait \u00e9t\u00e9 question de faire ses d\u00e9buts \u00e0 SmackDown quelques mois apr\u00e8s janvier, mais cela ne&#8230;<\/p>\n","protected":false},"author":665,"featured_media":58509,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[38,24,4,23],"tags":[],"ppma_author":[289],"class_list":["post-58420","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-aew","category-aew-impact-njpw-roh","category-news","category-wwe"],"authors":[{"term_id":289,"user_id":665,"is_guest":0,"slug":"line","display_name":"Line Edmond","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/852de09636413c90cdaa278312f9ea5bc4396768745424755cb63d99a05989d0?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/58420","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/users\/665"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/comments?post=58420"}],"version-history":[{"count":3,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/58420\/revisions"}],"predecessor-version":[{"id":58511,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/58420\/revisions\/58511"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media\/58509"}],"wp:attachment":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media?parent=58420"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/categories?post=58420"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/tags?post=58420"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/ppma_author?post=58420"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}