{"id":58329,"date":"2021-09-17T21:12:28","date_gmt":"2021-09-17T21:12:28","guid":{"rendered":"https:\/\/www.jdx.info\/lutte\/?p=58329"},"modified":"2021-09-17T23:54:53","modified_gmt":"2021-09-17T23:54:53","slug":"deuxieme-heure-de-smackdown-18","status":"publish","type":"post","link":"https:\/\/www.jdx.info\/lutte\/2021\/09\/17\/deuxieme-heure-de-smackdown-18\/","title":{"rendered":"Deuxi\u00e8me Heure de Smackdown!"},"content":{"rendered":"\n<ul class=\"wp-block-list\"><li><strong><a href=\"https:\/\/www.jdx.info\/lutte\/2021\/09\/17\/resultats-et-video-du-wwe-smackdown-du-17-septembre-2021\/\">Pour revenir \u00e0 la premi\u00e8re heure de Smackdown, cliquez ici.<\/a><\/strong><\/li><\/ul>\n\n\n\n<p>&#8211; De retour en coulisses, Paul Heyman est avec Kayla Braxton. Cette derni\u00e8re lui dit qu&rsquo;il y a des rumeurs selon lesquelles Brock Lesnar pourrait aller \u00e0 RAW et lui demande son avis \u00e0 ce sujet. Heyman r\u00e9pond qu&rsquo;elle est folle de penser qu&rsquo;il est toujours l&rsquo;avocat de Lesnar et il est choqu\u00e9 que Braxton ait des sources. Son obsession pour lui n&rsquo;est plus possible. Paul Heyman se retourne et Big E se trouve devant lui. Heyman le f\u00e9licite d&rsquo;\u00eatre devenu champion de la WWE, il a pris la d\u00e9cision la plus intelligente car il savait qu&rsquo;il ne r\u00e9ussirait pas son cash-in sur Roman Reigns. Big E dit qu&rsquo;ils verront \u00e7a aux Survivor Series&#8230; mais contre Roman Reigns ou Brock Lesnar ? Les Usos attaquent Big E ! Roman Reigns passe par l\u00e0 et s&rsquo;en va.<\/p>\n\n\n\n<p>&#8211; Seth Rollins est sur le ring et dit que la semaine derni\u00e8re, il a eu l&rsquo;un des plus grands matchs de sa carri\u00e8re apr\u00e8s avoir battu Edge au Madison Square Garden. Ce qui est arriv\u00e9 \u00e0 Edge est malheureux. Lorsque sa botte est tomb\u00e9 sur sa nuque, il a entendu un bruit&#8230; Il a senti un craquement. Il ne sait pas comment le d\u00e9crire&#8230; c&rsquo;\u00e9tait comme si tu marchais sur un cafard, mais que tu ne sais pas sur quoi t&rsquo;as marqu\u00e9 et que tu entends un craquement, tu sais qu&rsquo;il y a un \u00eatre humain en dessous. Seth Rollins nous remontre ce qu&rsquo;il s&rsquo;est pass\u00e9 la semaine derni\u00e8re.<\/p>\n\n\n\n<p>Seth Rollins dit que c&rsquo;est difficile \u00e0 regarder. Il a une question pour tout le monde. Qu&rsquo;est-ce qui allait se passer \u00e0 notre avis ? C&rsquo;\u00e9tait la plus grande victoire de sa carri\u00e8re et il n&rsquo;a pas eu une seconde pour en profiter. Rollins a fait une prise l\u00e9gale dans un match l\u00e9gale et il a gagn\u00e9 de la m\u00eame fa\u00e7on qu&rsquo;il a gagn\u00e9 la plupart des matchs de sa carri\u00e8re. Edge est all\u00e9 trop loin. C&rsquo;est un p\u00e8re de famille et il connaissait les risques. Il connaissait les cons\u00e9quences et il est mont\u00e9 sur le ring avec Rollins. C&rsquo;est \u00e0 cause de nous ce qui est arriv\u00e9 \u00e0 Edge. Lorsque Edge l&rsquo;a appel\u00e9 de \u00ab\u00a0Edge Lite\u00a0\u00bb, on a applaudi.<\/p>\n\n\n\n<p>Cette semaine \u00e0 NXT, Beth Phoenix a d\u00e9clar\u00e9 qu&rsquo;Edge \u00e9tait \u00e0 la maison en train de gu\u00e9rir. Pendant qu&rsquo;il est chez lui, il a une question : pense-t-il \u00eatre capable physiquement et \u00e9motionnellement \u00e0 revenir sur ce ring ? Il a vu son regard lorsqu&rsquo;il \u00e9tait sur la civi\u00e8re, c&rsquo;\u00e9tait la peur. Pendant une seconde, il avait piti\u00e9 pour lui. Mais il ne peut pas vivre en ayant piti\u00e9 de lui. Il doit passer \u00e0 autre chose. Mais avant \u00e7a, il doit le finir. Pour ce faire : deux moyens. Le premier, c&rsquo;est Rollins qui va le voir chez lui en face de sa famille. Le second, c&rsquo;est Edge qui rampe sur le ring pour en finir.<\/p>\n\n\n\n<p><strong>Zelina Vega et Carmella vs Toni Storm et Liv Morgan<\/strong><\/p>\n\n\n\n<p>En fin de match, Carmella tombe et quitte le ring en se tenant le nez. L&rsquo;arbitre compte jusqu&rsquo;\u00e0 10.<\/p>\n\n\n\n<p><em>Gagnantes : Toni Storm et Liv Morgan d\u00e9compte ext\u00e9rieur<\/em><\/p>\n\n\n\n<p> Apr\u00e8s le match, Liv Morgan d\u00e9fie Carmella pour un match \u00e0 Extreme Rules.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p>&#8211; Dans les coulisses, les Street Profits disent que la EST de la WWE est \u00e0 la maison ce soir, \u00e7a veut dire qu&rsquo;ils c\u00e9l\u00e8brent ! Ils font ensuite savoir qu&rsquo;ils veulent les titres par \u00e9quipe.<\/p>\n\n\n\n<center><p><script async=\"\" src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script>\n<ins class=\"adsbygoogle\" style=\"display:block; text-align:center;\" data-ad-layout=\"in-article\" data-ad-format=\"fluid\" data-ad-client=\"ca-pub-1986975368136072\" data-ad-slot=\"7818521013\"><\/ins>\n<script>\n     (adsbygoogle = window.adsbygoogle || []).push({});\n<\/script><\/p><\/center>\n\n\n\n\n<p>&#8211; Dans les coulisses, Carmella est \u00e0 l&rsquo;infirmerie et dit que Liv Morgan a essay\u00e9 de d\u00e9figurer la plus belle femme \u00e0 la WWE, le match d&rsquo;Extreme Rules est accept\u00e9 !<\/p>\n\n\n\n<p>&#8211; Dans les coulisses, Finn Balor dit qu&rsquo;il n&rsquo;est pas n\u00e9 dans une famille de catch. Il n&rsquo;a pas une Bloodline. Il n&rsquo;est pas cens\u00e9 \u00eatre ici, mais il s&rsquo;est battu. Le D\u00e9mon est une manifestation pour tous ceux qui lui ont dit non. \u00c7a lib\u00e8re une rage en lui qui ne peut pas \u00eatre contr\u00f4l\u00e9e. Il n&rsquo;invoque pas le D\u00e9mon, c&rsquo;est le D\u00e9mon qui l&rsquo;invoque. On voit le visage de Finn Balor. \u00c0 Extreme Rules, on verra le visage du D\u00e9mon, champion Universel.<\/p>\n\n\n\n<p>&#8211; Ce lundi \u00e0 RAW, le New Day affrontera Roman Reigns et les Usos.<\/p>\n\n\n\n<p>&#8211; Dans les coulisses, Naomi rejoint Sonya Deville et veut savoir quand aura lieu son match. Deville r\u00e9pond qu&rsquo;il n&rsquo;y a pas assez de temps pour elle ce soir , elle peut revenir la semaine prochaine. Naomi dit qu&rsquo;elle est ici depuis plus longtemps que Deville et elle aura son match d&rsquo;une mani\u00e8re ou d&rsquo;une autre.<\/p>\n\n\n\n<p>&#8211; Rey Mysterio est aux commentaires pour le prochain match.<\/p>\n\n\n\n<p><strong>Dominik Mysterio vs Sami Zayn<\/strong><\/p>\n\n\n\n<p>En fin de match, Dominik Mysterio fait un 619 sur Sami Zayn. Il monte ensuite sur la troisi\u00e8me corde pour un Frog Splash, mais Zayn le contre et arrive \u00e0 lui faire un roll up.<\/p>\n\n\n\n<p><em>Gagnant : Sami Zayn<\/em><\/p>\n\n\n\n<p>&#8211; Apr\u00e8s le match, Sami Zayn dit \u00e0 Rey Mysterio que son fils n&rsquo;est pas pr\u00eat qu&rsquo;il n&rsquo;est peut-\u00eatre pas un aussi bon coach qu&rsquo;il le pense.<\/p>\n\n\n\n<p>&#8211; Kane fait son retour et monte sur le ring. Le maire du comt\u00e9 de Knox nous pr\u00e9sente Bianca Belair qui est chez elle ce soir.<\/p>\n\n\n\n<p>ENCOURS<\/p>\n\n\n\n<p class=\"has-medium-font-size\"><strong><a href=\"https:\/\/www.jdx.info\/lutte\/2021\/09\/17\/deuxieme-heure-de-smackdown-18\/\">Pour la suite de Samckdown, cliquez ici<\/a><\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\"><li><a rel=\"noreferrer noopener\" href=\"https:\/\/www.jdx.info\/lutte\/2021\/09\/17\/regardez-le-wwe-friday-night-smackdown-du-17-septembre-2021\/\" target=\"_blank\"><strong>Pour voir ce Smackdown, cliquez ici.<\/strong><\/a><\/li><\/ul>\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>Pour revenir \u00e0 la premi\u00e8re heure de Smackdown, cliquez ici. &#8211; De retour en coulisses, Paul Heyman est avec Kayla Braxton. Cette derni\u00e8re lui dit qu&rsquo;il y a des rumeurs selon lesquelles Brock Lesnar pourrait aller \u00e0 RAW et lui demande son avis \u00e0 ce sujet. Heyman r\u00e9pond qu&rsquo;elle est folle de penser qu&rsquo;il est&#8230;<\/p>\n","protected":false},"author":4,"featured_media":58330,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[36],"tags":[],"ppma_author":[292],"class_list":["post-58329","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-smackdown"],"authors":[{"term_id":292,"user_id":4,"is_guest":0,"slug":"jean","display_name":"Jean Vinnier","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/33aba0263fd870a0b487e0e079ff407e10e3997c9d2987cbcc0db0db2c5c75a9?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/58329","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/comments?post=58329"}],"version-history":[{"count":15,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/58329\/revisions"}],"predecessor-version":[{"id":58363,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/58329\/revisions\/58363"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media\/58330"}],"wp:attachment":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media?parent=58329"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/categories?post=58329"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/tags?post=58329"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/ppma_author?post=58329"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}