{"id":57774,"date":"2021-09-07T21:07:00","date_gmt":"2021-09-07T21:07:00","guid":{"rendered":"https:\/\/www.jdx.info\/lutte\/?p=57774"},"modified":"2021-09-09T13:13:27","modified_gmt":"2021-09-09T13:13:27","slug":"resultats-et-video-du-aew-dark-du-7-septembre-2021","status":"publish","type":"post","link":"https:\/\/www.jdx.info\/lutte\/2021\/09\/07\/resultats-et-video-du-aew-dark-du-7-septembre-2021\/","title":{"rendered":"R\u00e9sultats et Vid\u00e9o du AEW DARK du 7 Septembre 2021!"},"content":{"rendered":"\n<ul class=\"wp-block-list\"><li><strong><a href=\"https:\/\/www.jdx.info\/lutte\/2021\/09\/07\/regardez-le-aew-dark-du-7-septembre-2021\/\" target=\"_blank\" rel=\"noreferrer noopener\">Pour voir ce AEW DARK, cliquez ici.<\/a><\/strong><\/li><\/ul>\n\n\n\n<p>Les commentateurs sont Taz et Excalibur.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><strong>Lance Archer bat Jason Hutch<\/strong> avec son Blackout pour le compte de trois en moins de deux minutes.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><strong>The Bunny bat Laynie Luck<\/strong> avec son Rabbit Hole pour le compte de trois.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><strong>Evil Uno bat Alan Angels<\/strong> en le repoussant contre la marche d&rsquo;acier et il le ram\u00e8ne sur le ring pour son Flapjack pour le compte de trois.<\/p>\n\n\n\n<p>&#8211; The Acclaimed arrive sur le ring avec une promo scypt\u00e9e. Bowens arr\u00eate Caster et lui prend son texte. Bowens demande si c&rsquo;est s\u00e9rieux. Il a m\u00eame une ligne teasant la t\u00e9l\u00e9-r\u00e9alit\u00e9 des Rhodes. Caster d\u00e9chire la feuille et reprend son rap non scrypt\u00e9. Il dit que Dean a une petite bite et que l&rsquo;autre a des IST.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p>The Acclaimed (Max Caster et Anthony Bowens) battent Robert Anthony et Shawn Dean en moins de deux minutes avec un Back Breaker de Bowens et l&rsquo;Elbow Drop de Caster sur Anthony pour le compte de trois.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><strong>Joey Janela bat Lee Moriarty<\/strong> avec son Death Valley Driver pour le compte de trois.<\/p>\n\n\n\n<p> Apr\u00e8s le combat, Sonny Kiss arrive sur le ring pour rouer de coups Janela, mais Janela prend la fuite.<\/p>\n\n\n\n<center><p><script async=\"\" src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script>\n<ins class=\"adsbygoogle\" style=\"display:block; text-align:center;\" data-ad-layout=\"in-article\" data-ad-format=\"fluid\" data-ad-client=\"ca-pub-1986975368136072\" data-ad-slot=\"7818521013\"><\/ins>\n<script>\n     (adsbygoogle = window.adsbygoogle || []).push({});\n<\/script><\/p><\/center>\n\n\n\n<p><strong>Stu Grayson et Colt Cabana battent Travis Titan et RSP<\/strong> avec un Chicago Skyline de Cabana sur Titan pour le compte de trois pendant que Grayson fait son Nightfall sur RSP.<\/p>\n\n\n\n<p>&#8211; On pr\u00e9sente une vid\u00e9o sur la rivalit\u00e9 entre Diamant\u00e9 et Big Swole.<\/p>\n\n\n\n<p><strong>Three Strikes Match<\/strong><\/p>\n\n\n\n<p> <strong>Strikes <\/strong> <strong>one<\/strong> : Swole fait son Dirty Dancing et enchaine avec un compte rapide pour le compte de trois sur Diamant\u00e9.<\/p>\n\n\n\n<p> <strong>Strikes <\/strong> <strong>Two<\/strong>: Big Swole applique un Ankle Lock sur Diamant\u00e9 pour la faire taper.<\/p>\n\n\n\n<p> <strong>Strikes Tree<\/strong> : Swole fait son Dirty Dancing avec la chaine de Diamant\u00e9 et l&rsquo;arbitre la d\u00e9clare K.O. Swole remporte le match.<\/p>\n\n\n\n<p>L&rsquo;\u00e9pisode se termine avec une c\u00e9l\u00e9bration de Swole.<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li><strong><a rel=\"noreferrer noopener\" href=\"https:\/\/www.jdx.info\/lutte\/2021\/09\/07\/regardez-le-aew-dark-du-7-septembre-2021\/\" target=\"_blank\">Pour voir ce AEW DARK, cliquez ici.<\/a><\/strong><\/li><\/ul>\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>Pour voir ce AEW DARK, cliquez ici. Les commentateurs sont Taz et Excalibur. Lance Archer bat Jason Hutch avec son Blackout pour le compte de trois en moins de deux minutes. The Bunny bat Laynie Luck avec son Rabbit Hole pour le compte de trois. Evil Uno bat Alan Angels en le repoussant contre la&#8230;<\/p>\n","protected":false},"author":4,"featured_media":57775,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[38,24,21],"tags":[],"ppma_author":[292],"class_list":["post-57774","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-aew","category-aew-impact-njpw-roh","category-resultats"],"authors":[{"term_id":292,"user_id":4,"is_guest":0,"slug":"jean","display_name":"Jean Vinnier","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/33aba0263fd870a0b487e0e079ff407e10e3997c9d2987cbcc0db0db2c5c75a9?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/57774","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/comments?post=57774"}],"version-history":[{"count":1,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/57774\/revisions"}],"predecessor-version":[{"id":57776,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/57774\/revisions\/57776"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media\/57775"}],"wp:attachment":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media?parent=57774"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/categories?post=57774"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/tags?post=57774"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/ppma_author?post=57774"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}